{"id":1449439,"date":"2024-05-13T16:03:41","date_gmt":"2024-05-13T23:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/"},"modified":"2024-05-13T16:03:41","modified_gmt":"2024-05-13T23:03:41","slug":"lula-suspende-viaje-inundaciones-sur-brasil-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","title":{"rendered":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, pospuso este lunes su viaje a Chile, previsto para el viernes y s\u00e1bado, debido a la emergencia que atraviesa el sure\u00f1o estado de Rio Grande do Sul, que enfrenta inundaciones hist\u00f3ricas que dejaron al menos 147 personas muertas, 127 desaparecidas y m\u00e1s de 2,1 millones de afectadas.<\/p>\n<p>El Ministerio de Relaciones Exteriores brasile\u00f1o dijo en un comunicado que la decisi\u00f3n fue tomada debido a \u201cla necesidad de monitorear la situaci\u00f3n de las inundaciones\u201d as\u00ed como \u201ccoordinar la asistencia a la poblaci\u00f3n afectada y las tareas de reconstrucci\u00f3n\u201d.<\/p>\n<p>Inundaciones en Brasil ya dejan al menos 147 muertos y m\u00e1s de 800 heridos<\/p>\n<p>El mandatario brasile\u00f1o ten\u00eda previsto reunirse con el presidente de Chile, Gabriel Boric, para discutir, entre otros temas, la \u201cintegraci\u00f3n de Am\u00e9rica del Sur\u201d, dijo Lula en una reuni\u00f3n con periodistas el pasado 23 de abril.<\/p>\n<p>Las tormentas afectaron al 90% del estado, de acuerdo con Agencia Brasil, que asegura que 447 de los 497 municipios de Rio Grande do Sul se vieron perjudicados por las lluvias. Al menos 80.000 personas est\u00e1n en albergues y m\u00e1s de medio mill\u00f3n se encuentran sin hogar, seg\u00fan datos oficiales citados por la agencia estatal.<\/p>\n<p>&#8212; Dar\u00edo Klein y Ver\u00f3nica Calder\u00f3n colaboraron para este reporte.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, pospuso este lunes su viaje a Chile, previsto para el viernes y s\u00e1bado, debido a la emergencia que atraviesa el sure\u00f1o estado de Rio Grande do Sul, que enfrenta inundaciones hist\u00f3ricas que dejaron al menos 147 personas muertas, 127 desaparecidas y m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1449439","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, pospuso este lunes su viaje a Chile, previsto para el viernes y s\u00e1bado, debido a la emergencia que atraviesa el sure\u00f1o estado de Rio Grande do Sul, que enfrenta inundaciones hist\u00f3ricas que dejaron al menos 147 personas muertas, 127 desaparecidas y m\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-13T23:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil\",\"datePublished\":\"2024-05-13T23:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\",\"name\":\"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-13T23:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, pospuso este lunes su viaje a Chile, previsto para el viernes y s\u00e1bado, debido a la emergencia que atraviesa el sure\u00f1o estado de Rio Grande do Sul, que enfrenta inundaciones hist\u00f3ricas que dejaron al menos 147 personas muertas, 127 desaparecidas y m\u00e1s de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-13T23:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/"},"author":{"name":"","@id":""},"headline":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil","datePublished":"2024-05-13T23:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","name":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-13T23:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/13\/lula-suspende-viaje-inundaciones-sur-brasil-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-13T23:03:41Z","datePublished":"2024-05-13T23:03:41Z","dateModified":"2024-05-13T23:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lula suspende su viaje a Chile por las inundaciones en el sur de Brasil\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/13\\\/lula-suspende-viaje-inundaciones-sur-brasil-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/13\\\/lula-suspende-viaje-inundaciones-sur-brasil-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-13T23:03:41Z\",\"datePublished\":\"2024-05-13T23:03:41Z\",\"dateModified\":\"2024-05-13T23:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447345,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/25\/inundaciones-brasil-sureste-espititu-santo-rio-de-janeiro-muertes-trax\/","url_meta":{"origin":1449439,"position":0},"title":"Inundaciones en el sureste de Brasil dejan al menos 27 personas muertas en medio de la devastaci\u00f3n","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) -- Al menos 27 personas han muerto en el sureste de Brasil por las fuertes lluvias que azotan partes del pa\u00eds, inform\u00f3 CNN Brasil, afiliada de CNN, citando a autoridades estatales.El n\u00famero de muertos en el estado brasile\u00f1o de Esp\u00edritu Santo aument\u00f3 a 19, y al menos ocho personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449487,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/15\/lula-visita-rio-grande-de-sul-inundaciones-149-muertos-brasil-orix\/","url_meta":{"origin":1449439,"position":1},"title":"Lula visita Rio Grande de Sul, la regi\u00f3n afectada por las inundaciones que han dejado al menos 149 muertos en el sur de Brasil","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, visit\u00f3 este jueves el estado sure\u00f1o Rio Grande do Sul, afectado por unas hist\u00f3ricas inundaciones que han dejado al menos 149 muertos y m\u00e1s de 2,1 millones de personas afectadas, seg\u00fan las autoridades.Lula aterriz\u00f3 poco despu\u00e9s de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449194,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/lula-da-silva-busca-mas-recursos-para-la-region-afectada-por-las-inundaciones-mientras-el-numero-de-muertos-llega-a-85\/","url_meta":{"origin":1449439,"position":2},"title":"Lula da Silva busca m\u00e1s recursos para la regi\u00f3n afectada por las inundaciones mientras el n\u00famero de muertos llega a 85","author":"","date":"mayo 7, 2024","format":false,"excerpt":"(CNN) -- El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, envi\u00f3 al Congreso un decreto legislativo para acelerar la transferencia de recursos a Rio Grande do Sul, donde al menos 85 personas han muerto debido a las fuertes lluvias e inundaciones de la \u00faltima semana, seg\u00fan la unidad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448815,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/03\/lluvias-inundaciones-muertos-desaparecidos-rio-grande-do-sul-brasil-orix\/","url_meta":{"origin":1449439,"position":3},"title":"Lluvias e inundaciones dejan 31 muertos y 74 desaparecidos en R\u00edo Grande do Sul, Brasil","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Las lluvias e inundaciones que han afectado al estado brasile\u00f1o de R\u00edo Grande do Sul durante los \u00faltimos d\u00edas han dejado un saldo de 31 personas muertas y 74 desaparecidas, de acuerdo con el reporte de Defensa Civil del estado difundido la ma\u00f1ana de este viernes.El gobierno local\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449389,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/10\/lluvias-intensas-numero-muertos-inundaciones-brasil-107-muertos-trax\/","url_meta":{"origin":1449439,"position":4},"title":"Se esperan lluvias m\u00e1s intensas mientras el n\u00famero de muertos por las inundaciones en Brasil asciende a 107","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN) --\u00a0Se espera que m\u00e1s lluvias intensas sigan golpeando a Brasil, mientras la naci\u00f3n sudamericana a\u00fan lidia con las consecuencias mortales del clima extremo de la semana pasada, que sumergi\u00f3 barrios enteros en R\u00edo Grande do Sul.Las fuertes lluvias e inundaciones han provocado la muerte de al menos a 107\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449496,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/15\/brasil-dinero-familias-perdieron-pertenecias-inundaciones-orix\/","url_meta":{"origin":1449439,"position":5},"title":"El Gobierno de Brasil dar\u00e1 unos US$ 990 a las familias que perdieron sus muebles y electrodom\u00e9sticos en Rio Grande do Sul","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Brasil anunci\u00f3 este mi\u00e9rcoles que dar\u00e1 un apoyo de 5.100 reales, unos US$ 990, a las familias que durante las \u00faltimas dos semanas perdieron sus muebles, electrodom\u00e9sticos y otros bienes a causa de las lluvias e inundaciones que afectaron al estado de Rio Grande\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449439"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449439\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}