{"id":1449601,"date":"2024-05-20T11:03:45","date_gmt":"2024-05-20T18:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/"},"modified":"2024-05-20T11:03:45","modified_gmt":"2024-05-20T18:03:45","slug":"elecciones-mexico-verifica-fact-check-tercer-debate-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","title":{"rendered":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Este domingo 19 de mayo se realiz\u00f3 el tercer y \u00faltimo debate presidencial en M\u00e9xico entre los tres candidatos que en la contienda. Se lleva a cabo en el Centro Cultural Universitario Tlatelolco, en la alcald\u00eda Cuauht\u00e9moc, de la Ciudad de M\u00e9xico.<\/p>\n<p>En el debate participaron Claudia Sheinbaum, candidata del oficialismo por los partidos Morena, PT y PVEM; X\u00f3chitl G\u00e1lvez, candidata de la oposici\u00f3n conformada por los partidos PAN, PRI y PRD; y Jorge \u00c1lvarez M\u00e1ynez, candidato del partido Movimiento Ciudadano.<\/p>\n<p>El debate const\u00f3 de cuatro segmentos con varios temas: 1) pol\u00edtica social; 2) inseguridad y crimen organizado; 3) migraci\u00f3n y pol\u00edtica exterior; y 4) democracia, divisi\u00f3n de poderes y pluralismo.<\/p>\n<p>El evento comenz\u00f3 primero con una breve introducci\u00f3n al debate y la presentaci\u00f3n de candidaturas. Luego, la discusi\u00f3n se dividi\u00f3 en los cuatro segmentos mencionados, con los primeros tres subdivididos en dos bloques cada uno. El \u00faltimo segmento fue una ronda final de preguntas a Sheinbaum, G\u00e1lvez y M\u00e1ynez a trav\u00e9s de los moderadores.<\/p>\n<p>Mira aqu\u00ed las verificaciones del primer debate y del segundo debate<\/p>\n<p>CNN en Espa\u00f1ol revis\u00f3 los discursos de los candidatos para evaluar la veracidad de algunos datos que mencionaron en el tercer debate presidencial. Este es el an\u00e1lisis de cada afirmaci\u00f3n seleccionada.<\/p>\n<p>Claudia Sheinbaum<\/p>\n<p>Frase: \u201cLos homicidios dolosos en la Ciudad de M\u00e9xico, de 2018 a 2023, disminuyeron 51%\u201d.<\/p>\n<p>CNN VERIFICA: INEXACTO<\/p>\n<p>De acuerdo con los datos de incidencia delictiva del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica, de 2019 (primer a\u00f1o completo del Gobierno de Claudia Sheinbaum) a 2023 (\u00faltimo a\u00f1o con datos completos) se registr\u00f3 una reducci\u00f3n de 44,19% en el delito de homicidio doloso, al pasar de 1.396 a 779 en ese lapso.<\/p>\n<p>Sin embargo, para hablar de violencia e inseguridad en el pa\u00eds es necesario contar, adem\u00e1s de los homicidios dolosos, los feminicidios (que tienen su propio apartado en las cifras del Secretariado desde 2015). Ambos delitos, en su conjunto, engloban las muertes violentas en M\u00e9xico. Si contamos tanto homicidios dolosos y feminicidios, la reducci\u00f3n de 2019 a 2023 es de 42,91%.<\/p>\n<p>En su frase durante el debate, Sheinbaum se\u00f1ala el periodo en el que estuvo en el cargo de jefa de Gobierno capitalina, de diciembre de 2018 a mediados de junio de 2023. Si tomamos como lapsos comparables sus primeros seis meses de gobierno (diciembre de 2018 a mayo de 2019) y los \u00faltimos seis (diciembre de 2022 a mayo de 2023), los delitos relacionados con muertes violentas en la Ciudad de M\u00e9xico en su gesti\u00f3n se redujeron 50,17%, al pasar de 841 en sus primeros seis meses de gobierno a 419 en sus \u00faltimos seis meses.<\/p>\n<p>Frase: \u201cLa reducci\u00f3n promedio de delitos de alto impacto (entre enero-mayo de 2019 y enero-mayo de 2023) disminuy\u00f3 en 58%\u201d.<\/p>\n<p>CNN VERIFICA: NECESITA CONTEXTO<\/p>\n<p>Si bien es verdadero el dato que ofreci\u00f3 Sheinbaum, se necesitan hacer varias precisiones.<\/p>\n<p>La candidata presidencial oficialista dijo en el debate que los delitos de alto impacto en la Ciudad de M\u00e9xico se redujeron 58% en los cuatro a\u00f1os que abarcan el periodo indicado, lo que brinda una comparaci\u00f3n correcta entre los primeros meses de su gobierno y los \u00faltimos antes de dejar el cargo. Sheinbaum ya ha utilizado ese dato de 58% en varias ocasiones.<\/p>\n<p>Con base en los datos de 13 delitos de alto impacto que la Fiscal\u00eda General de la Ciudad de M\u00e9xico tiene en cuenta para sus mediciones de incidencia delictiva, entre enero y mayo de 2019 se registraron 23.438 de estos delitos, mientras que en el mismo lapso de 2023 fueron 10.360. Por tanto, la disminuci\u00f3n de un periodo a otro se ubica en 55,79%, cerca de los 58% que menciona Sheinbaum.<\/p>\n<p>Frase: &#171;Un fraude (electoral) en 2006&#187;.<\/p>\n<p>CNN VERIFICA: FALSO<\/p>\n<p>En las elecciones de 2006, los principales candidatos a la presidencia eran Felipe Calder\u00f3n (PAN), Andr\u00e9s Manuel L\u00f3pez Obrador (PRD, PT y Convergencia) y Roberto Madrazo (PRI y PVEM). Al inicio de las campa\u00f1as, L\u00f3pez Obrador estaba a la cabeza de las encuestas con una amplia ventaja sobre sus contrincantes. Sin embargo, dos meses antes de los comicios la historia cambi\u00f3 y Calder\u00f3n acort\u00f3 la diferencia, seg\u00fan un an\u00e1lisis del Centro de Investigaci\u00f3n y Docencia Econ\u00f3micas (CIDE).<\/p>\n<p>Los resultados electorales dieron como ganador a Calder\u00f3n con el 35,89% de los votos, por encima del 35,33% alcanzado por L\u00f3pez Obrador, lo que represent\u00f3 una diferencia de solo 0,56%.<\/p>\n<p>La noche de la elecci\u00f3n, el consejero presidente del extinto Instituto Federal Electoral (IFE), Luis Carlos Ugalde, explic\u00f3 que la distancia entre los dos candidatos punteros ca\u00eda dentro de los m\u00e1rgenes de error estad\u00edstico.<\/p>\n<p>Los resultados llevaron a L\u00f3pez Obrador a afirmar que le robaron la presidencia a trav\u00e9s de la manipulaci\u00f3n de los resultados y llam\u00f3 a pedir un recuento \u201cvoto por voto\u201d. El Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF) orden\u00f3 un recuento parcial de los votos. Dos meses despu\u00e9s de la elecci\u00f3n, el tribunal valid\u00f3 la victoria de Felipe Calder\u00f3n, afirmando que no hubo inconsistencias en el conteo de sufragios por lo que no existi\u00f3 evidencia de una interferencia en los resultados.<\/p>\n<p>Calder\u00f3n ha negado alguna anomal\u00eda electoral a su favor.<\/p>\n<p>X\u00f3chitl G\u00e1lvez<\/p>\n<p>Frase: \u201cLa seguridad ha sido un fracaso en este sexenio: 186.000 personas asesinadas, 50.000 personas desaparecidas\u201d.<\/p>\n<p>CNN VERIFICA: NECESITA CONTEXTO<\/p>\n<p>De acuerdo con el Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP), del 1 de diciembre de 2018 al 31 de marzo de 2024, se registraron 146.719 homicidio dolosos y 4.945 feminicidios en M\u00e9xico, lo cual en suma nos da un total de 151.664 homicidios dolosos y feminicidios, lejos de la cifra mencionada por G\u00e1lvez. Se toman los datos de homicidio doloso y feminicidio porque son los que representan las muertes violentas en el pa\u00eds y brindan mayor claridad de la situaci\u00f3n de inseguridad que viven los mexicanos.<\/p>\n<p>Si se consideran todos los delitos de homicidio registrados en ese mismo lapso (tanto dolosos como culposos) y los de feminicidio, el total llega a 189.522. Esa cifra es m\u00e1s cercana a la de G\u00e1lvez, pero toma en cuenta homicidios culposos (que son los de naturaleza imprudente e irresponsable, mas no con dolo).<\/p>\n<p>Al tomar en cuenta los datos de v\u00edctimas de homicidio doloso y feminicidio, en el lapso de diciembre de 2018 a marzo de 2024, el n\u00famero total de muertes violentas es de 181.151 personas, de las cuales 176.000 son v\u00edctimas de homicidio doloso y 5.151 son v\u00edctimas de feminicidio. Por tanto, se puede decir que en el actual gobierno se han registrado m\u00e1s de 180.000 muertes relacionadas con la inseguridad en el pa\u00eds, pero no 186.000 como se\u00f1ala G\u00e1lvez.<\/p>\n<p>En cuanto al dato sobre desapariciones, el Registro Nacional de Personas Desaparecidas y No Localizadas (RNPDNO) indica que, del 1 de diciembre de 2018 al 19 de mayo de 2024, se han registrado en el pa\u00eds 41.721 personas desaparecidas, lejos de las 50.000 que mencion\u00f3 G\u00e1lvez.<\/p>\n<p>Frase: \u201cLos homicidios dolosos crecieron, respecto a Mancera, 22%\u201d.<\/p>\n<p>CNN VERIFICA: NECESITA CONTEXTO<\/p>\n<p>X\u00f3chitl G\u00e1lvez asegur\u00f3 que, en los primeros cinco a\u00f1os del Gobierno de Claudia Sheinbaum en la Ciudad de M\u00e9xico (diciembre de 2018 a diciembre de 2023), los homicidios dolosos crecieron 22% en comparaci\u00f3n con los primeros cinco a\u00f1os de Miguel \u00c1ngel Mancera (del Partido de la Revoluci\u00f3n Democr\u00e1tica, al que tambi\u00e9n pertenec\u00edan L\u00f3pez Obrador y Sheinbaum, diciembre de 2012 a diciembre de 2017).<\/p>\n<p>G\u00e1lvez dijo que, en el lapso de Mancera, se registraron 4.465 homicidios dolosos, mientras que en el de Sheinbaum fueron 5.436, lo que representa un aumento de 21,7%.Sin embargo, las cifras que present\u00f3 G\u00e1lvez incluyen no solo homicidios dolosos, sino tambi\u00e9n feminicidios, algo que la candidata no aclar\u00f3 en el debate.<\/p>\n<p>Seg\u00fan el Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP), en los primeros cinco a\u00f1os de Mancera se registraron 4.326 homicidios dolosos y 139 feminicidios (los registros de este delito comenzaron en 2015), lo que da un total de 4.465, exactamente el dato que ofreci\u00f3 G\u00e1lvez.<\/p>\n<p>En tanto, durante los primeros cinco a\u00f1os de Sheinbaum, se registraron 5.080 homicidios dolosos y 356 de feminicidio, que en conjunto dan 5.436, el mismo dato que dio G\u00e1lvez en el debate.<\/p>\n<p>Si bien la suma de homicidios dolosos y feminicidios es correcta para dar cuenta de las muertes violentas que han ocurrido en un lugar \u2014en este caso, la Ciudad de M\u00e9xico \u2014, X\u00f3chitl G\u00e1lvez no aclara en ning\u00fan momento que su cifra incluye los feminicidios en la comparaci\u00f3n.<\/p>\n<p>Frase: &#171;La \u00fanica manera de salir adelante es con la educaci\u00f3n (&#8230;). El gobierno que ella representa cerr\u00f3 las estancias de tiempo completo&#187;.<\/p>\n<p>CNN VERIFICA: VERDADERO<\/p>\n<p>El 28 de febrero de 2022, la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) public\u00f3 en el Diario Oficial de la Federaci\u00f3n las reglas de operaci\u00f3n del Programa La Escuela es Nuestra, en donde ya no aparece el formato propuesto en el Programa Escuelas de Tiempo Completo, en el que se especificaba el monto y las reglas de operaci\u00f3n para la seguridad alimentaria con enfoque en las escuelas en zonas vulnerables.<\/p>\n<p>Ante esto, la organizaci\u00f3n de la sociedad civil Mexicanos Primero se pronunci\u00f3 en contra de la medida. En un mensaje en X, antes Twitter, se\u00f1al\u00f3: \u201c@SEP_mx elimina las #EscuelasTiempoCompleto de \u201cLa Escuela es Nuestra\u201d y viola as\u00ed los derechos humanos de 3,6 millones de estudiantes que se quedan sin horas extra de aprendizaje y sin alimentaci\u00f3n. Impidamos tan deplorable e injustificada acci\u00f3n\u201d.<\/p>\n<p>Sheinbaum afirm\u00f3, cuando era jefa de Gobierno de la Ciudad de M\u00e9xico, que las escuelas de tiempo completo se mantendr\u00edan en la capital del pa\u00eds.<\/p>\n<p>\u201cVamos a mantener las escuelas de tiempo completo en la capital. Estamos trabajando con recurso propios. Obviamente la Secretar\u00eda de Educaci\u00f3n P\u00fablica participa porque lo m\u00e1s importante es el personal docente\u201d, afirm\u00f3.<\/p>\n<p>Frase: \u201cDejaron morir a 40 personas en una estaci\u00f3n migratoria en Ciudad Ju\u00e1rez\u201d.<\/p>\n<p>CNN VERIFICA: VERDADERO<\/p>\n<p>La noche del lunes 27 de marzo de 2023, se registr\u00f3 un incendio en una estaci\u00f3n del Instituto Nacional de Migraci\u00f3n en Ciudad Ju\u00e1rez que dej\u00f3 40 migrantes muertos y 27 lesionados. Los migrantes fallecieron al no lograr salir de la estaci\u00f3n.<\/p>\n<p>Una investigaci\u00f3n, realizada por La Verdad, Lighthouse Reports y El Paso Matters, revel\u00f3 que los migrantes ped\u00edan a gritos que los dejaran salir, pero funcionarios se negaron. Adem\u00e1s, se\u00f1al\u00f3 una serie de irregularidades en la estaci\u00f3n migratoria que habr\u00edan desencadenado la tragedia.<\/p>\n<p>\u201cA ellos no les vamos a abrir\u201d, se escucha decir a agentes migratorios en un video captado por una c\u00e1mara de circuito cerrado de la estaci\u00f3n del Instituto Nacional de Migraci\u00f3n, seg\u00fan la investigaci\u00f3n de La Verdad Ju\u00e1rez.<\/p>\n<p>\u201cSalieron a la luz una serie de irregularidades (&#8230;), abusos, omisiones graves que derivaron en la letalidad de este incendio, que se registra en una celda cerrada bajo llave, que es una celda y un espacio que estaban saturados, sin extintores, sin ventilaci\u00f3n, sin detectores de humo\u201d, dijo Roc\u00edo Gallegos, directora de La Verdad Ju\u00e1rez, en entrevista con Carmen Aristegui en CNN en Espa\u00f1ol.<\/p>\n<p>El 27 de marzo de 2024, a un a\u00f1o del incendio, el Gobierno de M\u00e9xico inform\u00f3 en un comunicado que 29 de las 40 familias de migrantes fallecidos ya hab\u00edan recibido indemnizaci\u00f3n.<\/p>\n<p>Jorge \u00c1lvarez M\u00e1ynez<\/p>\n<p>Frase: \u201cSi la educaci\u00f3n es un derecho, \u00bfpor qu\u00e9 este sexenio es el sexenio en el que m\u00e1s j\u00f3venes han tenido que ingresar a una universidad privada porque no hay lugares en las universidades p\u00fablicas?&#187;.<\/p>\n<p>CNN VERIFICA: ENGA\u00d1OSO<\/p>\n<p>Seg\u00fan la Encuesta Nacional sobre Acceso y Permanencia en la Educaci\u00f3n (Enape) 2021, realizada por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi), el 54% de los estudiantes inscritos en los ciclos escolares 2020-2021 y 2021-2022 migraron del sistema p\u00fablico al sistema privado. Entre las razones principales est\u00e1n la b\u00fasqueda de una educaci\u00f3n de mejor calidad; razones personales; y por no encontrar lugar o no tener las posibilidades de ingresar en un plantel p\u00fablico.<\/p>\n<p>40,3% dijo que lo hizo por buscar una educaci\u00f3n de mejor calidad<br \/>\n29% por razones personales<br \/>\n12% por no encontrar lugar o no tener las posibilidades de ingresar en un plantel p\u00fablico<\/p>\n<p>Frase: \u201cEn el 2007, la tasa de homicidios por cada 100.000 habitantes era de 8, al finalizar el sexenio de Calder\u00f3n ya hab\u00eda m\u00e1s del doble, al finalizar el sexenio de Pe\u00f1a Nieto ya era casi 4 veces m\u00e1s, y el actual gobierno, que prometi\u00f3 una nueva estrategia de seguridad no la cambi\u00f3, sigui\u00f3 el militarismo, sigui\u00f3 el prohibicionismo y sigui\u00f3 el punitivismo\u201d.<\/p>\n<p>CNN VERIFICA: INEXACTO<\/p>\n<p>En 2007, primer a\u00f1o completo del gobierno de Felipe Calder\u00f3n, se registraron 9,92 homicidios dolosos por cada 100.000 habitantes, mientras que para 2011 (quinto a\u00f1o de su administraci\u00f3n), esa tasa hab\u00eda subido a 19,94, un incremento de 101%.<\/p>\n<p>En 2013, primero a\u00f1o completo de gobierno de Pe\u00f1a Nieto, la tasa de homicidios dolosos fue de 16,11 por cada 100.000 habitantes; en tanto, para 2017 (quinto a\u00f1o) la tasa de muertes violentas subi\u00f3 a 21,49 por cada 100.000 habitantes, lo que se traduce en un aumento de 33,4%.<\/p>\n<p>Por su parte, en 2019, primero a\u00f1o completo del gobierno de L\u00f3pez Obrador, se registr\u00f3 una tasa de muertes violentas de 25,38 por cada 100.000 habitantes, mientras que en el quinto a\u00f1o de su sexenio la tasa fue de 20,72 muertes violentas por cada 100.000 habitantes, lo cual significa una reducci\u00f3n de 18,36%.<\/p>\n<p>Prechequeo de datos de los candidatos presidenciales de M\u00e9xico<\/p>\n<p>Previamente, CNN en Espa\u00f1ol cheque\u00f3 los discursos de los candidatos para evaluar la veracidad de algunos datos que mencionaron a lo largo de la campa\u00f1a sobre pol\u00edtica social, inseguridad, crimen organizado, migraci\u00f3n, pol\u00edtica exterior, democracia, pluralismo y divisi\u00f3n de poderes. Este es el an\u00e1lisis de cada afirmaci\u00f3n seleccionada.<\/p>\n<p>Pol\u00edtica Social<\/p>\n<p>CLAUDIA SHEINBAUM<\/p>\n<p>Frase de Claudia Sheinbaum: \u201cSe est\u00e1 haciendo este a\u00f1o un fondo de pensiones que est\u00e1 haciendo el presidente de la Rep\u00fablica de cerca de 60.000 millones de pesos que permita que aumente las pensiones de las personas que entraron despu\u00e9s del 97\u201d.<\/p>\n<p>CNN VERIFICA: NECESITA CONTEXTO<\/p>\n<p>Seg\u00fan el decreto firmado por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador, el Fondo de Pensiones para el Bienestar \u2013que entr\u00f3 en vigor el 1 de mayo\u2013 contempla la creaci\u00f3n de un fondo p\u00fablico con cerca de 40.000 millones de pesos (unos US$ 2.351 millones) y se espera que necesite de 130.000 millones de pesos (unos US$ 7.793 millones) para los pr\u00f3ximos 10 a\u00f1os.<\/p>\n<p>Los fondos provendr\u00e1n de ahorros no reclamados de las Administradoras de Fondos para el Retiro (Afores) de personas de 70 a\u00f1os o m\u00e1s y que est\u00e9n inactivas, de acuerdo con los c\u00e1lculos del Gobierno. Este fideicomiso p\u00fablico que se utilizar\u00e1 para complementar las pensiones de los trabajadores cuyo monto sea menor o igual al salario promedio mensual de los empleados afiliados al Instituto Mexicano del Seguro Social.<\/p>\n<p>X\u00d3CHITL G\u00c1LVEZ<\/p>\n<p>Frase de X\u00f3chitl G\u00e1lvez: \u201cSe qued\u00f3 calladita cuando quitaron el programa de infraestructura para los pueblos ind\u00edgenas, que le permit\u00eda a las mujeres tener energ\u00eda el\u00e9ctrica, una bomba para no tener que acarrear a las universidades interculturales, ya no se siguieron, que permit\u00eda a las mujeres prepararse y realmente educarse\u201d.<\/p>\n<p>CNN VERIFICA: INEXACTO<\/p>\n<p>Si bien en 2020 la Comisi\u00f3n de Pueblos ind\u00edgenas report\u00f3 que se eliminar\u00eda el Programa de Infraestructura Ind\u00edgena, as\u00ed como una disminuci\u00f3n del 40.6 por ciento del presupuesto para el Instituto Nacional para los Pueblos Ind\u00edgenas (INPI), organismo del que depende dicho programa, las funciones del Programa de Infraestructura Ind\u00edgena se asignaron en 2023 en el Programa para el Bienestar Integral de los Pueblos Ind\u00edgenas, lo que se constata en el documento de modificaci\u00f3n de Reglas de Operaci\u00f3n para el ejercicio fiscal 2024.<\/p>\n<p>Por lo que no podr\u00eda afirmarse que se quit\u00f3 o desapareci\u00f3 totalmente, ya que, aunque no opera bajo los t\u00e9rminos exactos que el pasado, los temas de infraestructura para comunidades ind\u00edgenas est\u00e1n contemplados en el Programa para el Bienestar Integral de los Pueblos Ind\u00edgenas en el PEF 2024 como parte de los recursos del INPI (p\u00e1gina 69).<\/p>\n<p>De acuerdo con un informe de 2020, el objetivo de este programa es realizar acciones de infraestructura b\u00e1sica para el bienestar de los pueblos y comunidades ind\u00edgenas y afromexicanas elegibles, que contribuyan a la disminuci\u00f3n de las carencias sociales.<\/p>\n<p>Inseguridad<\/p>\n<p>CLAUDIA SHEINBAUM<\/p>\n<p>Frase de Claudia Sheinbaum: \u201cCuando ubicas la Ciudad de M\u00e9xico en homicidios por 100 mil habitantes, la Ciudad de M\u00e9xico es mucho m\u00e1s segura que much\u00edsimas ciudades de Estados Unidos\u201d.<\/p>\n<p>CNN VERIFICA: VERDADERO<\/p>\n<p>De acuerdo con estad\u00edsticas de incidencia delictiva del \u00a0Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica, en la Ciudad de M\u00e9xico se registraron 779 delitos de homicidio doloso y 59 de feminicidio en 2023, dando un total de 838 muertes violentas.<\/p>\n<p>Al tomar en cuenta el \u00faltimo dato de poblaci\u00f3n disponible para la CDMX, es posible calcular que la tasa de muertes violentas en la capital mexicana durante 2023 fue de 9 por cada 100.000 habitantes.<\/p>\n<p>Esto coloca a la Ciudad de M\u00e9xico como un lugar m\u00e1s seguro en 2023 que muchas ciudades de Estados Unidos, seg\u00fan datos del Council on Criminal Justice (CCJ). Por ejemplo, las 10 m\u00e1s inseguras en 2023 fueron:<\/p>\n<p>Memphis \u2013 63,12 homicidios por cada 100.000 habitantes.<br \/>\nLouis \u2013 50,25<br \/>\nBaltimore \u2013 45,62<br \/>\nDetroit \u2013 42,55<br \/>\nWashington \u2013 39,05<br \/>\nLittle Rock \u2013 30,56<br \/>\nAtlanta \u2013 26,05<br \/>\nFiladelfia \u2013 25,91<br \/>\nRichmond \u2013 25,72<br \/>\nRochester \u2013 23,88<\/p>\n<p>X\u00d3CHITL G\u00c1LVEZ<\/p>\n<p>Frase de X\u00f3chitl G\u00e1lvez: \u201cHoy hay m\u00e1s de 180.000 personas asesinadas\u201d<\/p>\n<p>CNN VERIFICA: VERDADERO<\/p>\n<p>De acuerdo con el Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP), del 1 de diciembre de 2018 al 31 de marzo de 2024, se registraron 151.664 delitos de homicidios dolosos y feminicidios en M\u00e9xico, lo cual est\u00e1 lejos de la cifra mencionada por G\u00e1lvez. Se toman los datos de homicidios dolosos y feminicidios porque son los que representan las muertes violentas en el pa\u00eds y brindan mayor claridad de la situaci\u00f3n de inseguridad que viven los mexicanos.<\/p>\n<p>Ahora bien, si tomamos todos los delitos de homicidio registrados en ese mismo lapso (es decir, tanto dolosos como culposos) y tambi\u00e9n los de feminicidio, el total llega a 189.522, lo que coincide m\u00e1s con la cifra de G\u00e1lvez, pero toma en cuenta homicidios culposos (que son los de naturaleza imprudente e irresponsable, mas no con dolo).<\/p>\n<p>En tanto, si consideramos los datos de v\u00edctimas de homicidios dolosos y feminicidios, en el lapso de diciembre de 2018 a marzo de 2024, el n\u00famero total de muertes violentas es de 181.151 personas. La diferencia en incidencia delictiva y v\u00edctimas recae en que estas \u00faltimas representan a personas, mientras la incidencia se refiere a delitos registrados en carpetas de investigaci\u00f3n o averiguaciones previas.<\/p>\n<p>Por tanto, podemos decir que es verdadero que en el actual gobierno se han registrado m\u00e1s de 180.000 muertes relacionadas con la inseguridad en el pa\u00eds.<\/p>\n<p>Frase de X\u00f3chitl G\u00e1lvez: \u201cMe preocupa que en M\u00e9xico la principal causa de muerte entre j\u00f3venes de 15 a 35 a\u00f1os sea el homicidio\u201d.<\/p>\n<p>CNN VERIFICA: INEXACTO<\/p>\n<p>En su informe correspondiente a enero-junio de 2023, el INEGI se\u00f1ala en la secci\u00f3n de las 10 principales causas y n\u00fameros de muerte, seg\u00fan grupos de edad, que el homicidio fue la principal causa de muerte de personas de entre 25 y 44 a\u00f1os.<\/p>\n<p>Las cifras que cita G\u00e1lvez corresponden al informe del INEGI del 2022\u00a0 En donde, en la misma secci\u00f3n (p\u00e1g 17), el homicidio fue la principal causa de muerte de personas de entre 15 y 44 a\u00f1os.<\/p>\n<p>JORGE \u00c1LVAREZ M\u00c1YNEZ<\/p>\n<p>Frase de Jorge \u00c1lvarez M\u00e1ynez:\u00a0 \u201cTenemos 370.000 polic\u00edas contra 12.000 agentes del Ministerio P\u00fablico y los polic\u00edas no tienen capacidad de investigaci\u00f3n, capacidad jur\u00eddica ilegal\u201d<\/p>\n<p>CNN VERIFICA: INEXACTO<\/p>\n<p>Si bien es cierto que hay m\u00e1s polic\u00edas que agentes del Ministerio P\u00fablico en M\u00e9xico (agentes que se encargan de realizar las investigaciones de los delitos), las cifras que da M\u00e1ynez son inexactas.<\/p>\n<p>En 2017 se estimaba que hab\u00eda 384.900 elementos de polic\u00eda a nivel nacional. De ellos, 76,1% se encontraban adscritos a las Polic\u00edas Preventivas Estatales o Municipales, de acuerdo a la Encuesta Nacional de Est\u00e1ndares y Capacitaci\u00f3n Profesional Policial del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi) de 2017, la m\u00e1s reciente publicada.<\/p>\n<p>En 2022 sumaban 14.098 agentes del Ministerio P\u00fablico tanto en la Fiscal\u00eda General de la Rep\u00fablica (nivel federal) como en las Fiscalias Estatales, de acuerdo con el Censo Nacional de Procuraci\u00f3n de Justicia Estatal y Federal del Inegi.<\/p>\n<p>Frase de Jorge \u00c1lvarez M\u00e1ynez: De 2022 a 2023 en Nuevo Le\u00f3n bajaron los homicidios dolosos y en la Ciudad de M\u00e9xico aumentaron.<\/p>\n<p>CNN VERIFICA: ENGA\u00d1OSO<\/p>\n<p>La comparaci\u00f3n que hace M\u00e1ynez sobre los \u00edndices de violencia en Nuevo Le\u00f3n y la Ciudad de M\u00e9xico es enga\u00f1osa porque el n\u00famero de homicidios dolosos s\u00ed aument\u00f3 en la capital del pa\u00eds de 2022 a 2023 pero tambi\u00e9n en el estado gobernado por Movimiento Ciudadano, contrario a lo que dice el candidato.<\/p>\n<p>En 2022 se registraron 1.328 homicidios dolosos en Nuevo Le\u00f3n, seg\u00fan datos del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP). Mientras que en 2023, hubo 1.338. Esto representa un ligero aumento del 0,75%.<\/p>\n<p>El n\u00famero de homicidios dolosos en la Ciudad de M\u00e9xico pas\u00f3 de 795 en 2022 a 873 en 2023, lo que representa un aumento del 9,8%, mayor al que se registr\u00f3 en Nuevo Le\u00f3n.<\/p>\n<p>Pol\u00edtica exterior y migraci\u00f3n<\/p>\n<p>CLAUDIA SHEINBAUM<\/p>\n<p>Frase de Claudia Sheinbaum: \u201cTenemos (M\u00e9xico) una integraci\u00f3n econ\u00f3mica muy fuerte con Estados Unidos. Somos hoy el principal socio comercial\u201d.<\/p>\n<p>CNN VERIFICA: VERDADERO<\/p>\n<p>Seg\u00fan datos de la Oficina del Censo de Estados Unidos, en 2023 M\u00e9xico export\u00f3 m\u00e1s bienes y servicios al pa\u00eds vecino que ning\u00fan otro pa\u00eds en el mundo y desplaz\u00f3 a China por primera vez en dos d\u00e9cadas.<\/p>\n<p>M\u00e9xico export\u00f3 bienes por US$ 475.600 millones el a\u00f1o pasado que represent\u00f3 un 5% m\u00e1s que en 2022. Mientras que China export\u00f3 bienes por valor de 427.200 millones de d\u00f3lares a Estados Unidos el a\u00f1o pasado, una ca\u00edda del 20% con respecto a 2022.<\/p>\n<p>X\u00d3CHITL G\u00c1LVEZ<\/p>\n<p>Frase de X\u00f3chitl G\u00e1lvez: \u201cEl presidente acept\u00f3 ser tercer pa\u00eds seguro, sin una condici\u00f3n. A cambio no logramos establecer alg\u00fan convenio que permitiera la plena protecci\u00f3n de los derechos humanos de estos migrantes\u201d.<\/p>\n<p>CNN VERIFICA: NECESITA CONTEXTO<\/p>\n<p>M\u00e9xico nunca ha aceptado un convenio que lo convierta en tercer pa\u00eds seguro. En julio de 2019, la canciller\u00eda neg\u00f3 que existiera un acuerdo bilateral con Estados Unidos que estableciera que los migrantes deb\u00edan pedir y pasar por el proceso para entrar en Estados Unidos en territorio mexicano.<\/p>\n<p>Sin embargo, algunos personajes como Porfirio Mu\u00f1oz Ledo, entonces presidente de la C\u00e1mara de Diputados, aseguraron que M\u00e9xico acept\u00f3 ser tercer pa\u00eds seguro \u201cde facto\u201d, pues, aunque no se haya firmado ning\u00fan acuerdo, una gran cantidad de migrantes esperan su proceso de asilo en territorio mexicano.<\/p>\n<p>En diciembre de 2023, CNN report\u00f3 que m\u00e1s de 11.000 migrantes esperaban en albergues y campamentos en el lado mexicano de la frontera, muchos de los cuales esperaban entrar en EE.UU. a trav\u00e9s de v\u00edas legales establecidas por la Administraci\u00f3n Biden, como CBP One.<\/p>\n<p>JORGE \u00c1LVAREZ M\u00c1YNEZ<\/p>\n<p>Frase de Jorge \u00c1lvarez M\u00e1ynez: \u201cLo que hemos hecho con la frontera sur es inhumano. La militarizaci\u00f3n no ha vuelto m\u00e1s segura a nuestra frontera, pero s\u00ed la ha vuelto m\u00e1s cruel\u201d<\/p>\n<p>CNN VERIFICA: VERDADERO<\/p>\n<p>La Guardia Nacional complet\u00f3 su despliegue en la frontera sur de M\u00e9xico en junio de 2019, anunci\u00f3 entonces Marcelo Ebrard, exsecretario de Relaciones Exteriores, a ra\u00edz del acuerdo que el pa\u00eds firm\u00f3 con Estados Unidos en el que se comprometi\u00f3 a enviar 6.000 elementos del cuerpo militar para controlar el flujo de migrantes hacia EE.UU.<\/p>\n<p>Dos a\u00f1os despu\u00e9s de la presencia de la Guardia Nacional en la frontera sur de M\u00e9xico, la organizaci\u00f3n de derechos humanos WOLA dijo que el despliegue militar en la frontera sur en M\u00e9xico pon\u00eda \u201cen peligro los derechos humanos de las personas que migran\u201d.<\/p>\n<p>WOLA asegura que la estrategia de contenci\u00f3n \u201corill\u00f3 a las personas migrantes a viajar por zonas m\u00e1s remotas donde corr\u00edan un mayor riesgo de sufrir ataques criminales\u201d y, a su vez, los traficantes de personas \u201cmodificaron sus rutas y m\u00e9todos para seguir operando a pesar del despliegue\u201d.<\/p>\n<p>Democracia, Pluralismo y divisi\u00f3n de poderes<\/p>\n<p>X\u00d3CHITL G\u00c1LVEZ<\/p>\n<p>Frase de X\u00f3chitl G\u00e1lvez: \u201cSu intenci\u00f3n de regresar a desaparecer el INE ah\u00ed va a estar. No lo lograron porque no ten\u00edan mayor\u00eda calificada\u201d.<\/p>\n<p>CNN VERIFICA: INEXACTO<\/p>\n<p>Si bien L\u00f3pez Obrador nunca ha propuesto \u201cdesaparecer\u201d al Instituto Nacional Electoral (INE), \u2015\u00e9l mismo asegur\u00f3 en su conferencia matutina del 31 de octubre de 2022: \u201cAprovecho para informar que es una reforma electoral para que haya democracia, no es desaparecer al \u00f3rgano encargado de organizar las elecciones\u201d\u2015 s\u00ed lo ha criticado constantemente y ha encabezado tres intentos de reformarlo.<\/p>\n<p>En abril de 2022, el presidente propuso una reforma constitucional con la intenci\u00f3n, de acuerdo con sus propias palabras, de abaratar los costos del sistema electoral en M\u00e9xico. Ese proyecto no obtuvo la mayor\u00eda especial necesaria en el Congreso y, como resultado, el mandatario respondi\u00f3 con el &#171;Plan B&#8217;, basado en reformas de leyes secundarias, que s\u00ed logr\u00f3 pasar la C\u00e1mara Alta.<\/p>\n<p>El proyecto de ley buscaba recortar el presupuesto del INE, lo que podr\u00eda reducir el 85 % en su personal y cerrar varias oficinas locales de la autoridad electoral. Los funcionarios electorales advirtieron que el cambio afectar\u00eda la capacidad de la instituci\u00f3n para realizar elecciones libres y justas, pues se disminu\u00eda al m\u00ednimo el Servicio Profesional Electoral, pues se encarga de la realizaci\u00f3n de los procesos electorales a lo largo y ancho del pa\u00eds.<\/p>\n<p>Aunque el llamado \u201cPlan B\u201d fue respaldado por ambas c\u00e1maras, la Suprema Corte de Justicia de la Naci\u00f3n invalid\u00f3 el paquete de reformas el 22 de junio de 2023, argumentando violaciones al procedimiento legislativo.<\/p>\n<p>Sin embargo, L\u00f3pez Obrador present\u00f3 otro intento de reformar el INE. La m\u00e1s reciente propuesta de reforma electoral, presentada el 5 de febrero de 2024, propone sustituir al INE con el Instituto Nacional de Elecciones y Consultas (INEC) y absorber las funciones de los 32 Organismos P\u00fablicos Locales (OPLEs), de modo que una sola instituci\u00f3n ser\u00eda la encargada de las elecciones federales y locales.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Este domingo 19 de mayo se realiz\u00f3 el tercer y \u00faltimo debate presidencial en M\u00e9xico entre los tres candidatos que en la contienda. Se lleva a cabo en el Centro Cultural Universitario Tlatelolco, en la alcald\u00eda Cuauht\u00e9moc, de la Ciudad de M\u00e9xico. En el debate participaron Claudia Sheinbaum, candidata del oficialismo por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449601","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Este domingo 19 de mayo se realiz\u00f3 el tercer y \u00faltimo debate presidencial en M\u00e9xico entre los tres candidatos que en la contienda. Se lleva a cabo en el Centro Cultural Universitario Tlatelolco, en la alcald\u00eda Cuauht\u00e9moc, de la Ciudad de M\u00e9xico. En el debate participaron Claudia Sheinbaum, candidata del oficialismo por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-20T18:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez\",\"datePublished\":\"2024-05-20T18:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\"},\"wordCount\":4518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\",\"name\":\"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-20T18:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","og_locale":"es_ES","og_type":"article","og_title":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Este domingo 19 de mayo se realiz\u00f3 el tercer y \u00faltimo debate presidencial en M\u00e9xico entre los tres candidatos que en la contienda. Se lleva a cabo en el Centro Cultural Universitario Tlatelolco, en la alcald\u00eda Cuauht\u00e9moc, de la Ciudad de M\u00e9xico. En el debate participaron Claudia Sheinbaum, candidata del oficialismo por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-20T18:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/"},"author":{"name":"","@id":""},"headline":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez","datePublished":"2024-05-20T18:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/"},"wordCount":4518,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","name":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-20T18:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"CNN verifica: verificaci\u00f3n de datos del tercer debate entre Sheinbaum, G\u00e1lvez y M\u00e1ynez","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-20T18:03:45Z","datePublished":"2024-05-20T18:03:45Z","dateModified":"2024-05-20T18:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"CNN verifica: verificaci\\u00f3n de datos del tercer debate entre Sheinbaum, G\\u00e1lvez y M\\u00e1ynez\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/20\\\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/20\\\/elecciones-mexico-verifica-fact-check-tercer-debate-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-20T18:03:45Z\",\"datePublished\":\"2024-05-20T18:03:45Z\",\"dateModified\":\"2024-05-20T18:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1449591,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/tercer-debate-presidencial-mexico-lo-mejor-del-ultimo-cara-a-cara-entre-sheinbaum-galvez-y-maynez-trax\/","url_meta":{"origin":1449601,"position":0},"title":"Tercer debate presidencial en M\u00e9xico: lo mejor del \u00faltimo cara a cara entre Sheinbaum, G\u00e1lvez y M\u00e1ynez","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) --\u00a0 Este domingo se realiz\u00f3 el tercer y \u00faltimo debate presidencial rumbo a las elecciones generales del 2 de junio en M\u00e9xico. En el encuentro se discuti\u00f3, entre otros temas, el problema de la inseguridad, uno de los asuntos m\u00e1s preocupantes para los electores.El debate cont\u00f3 con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449588,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/19\/tercer-debate-presidencial-mexico-sheinbaum-xochitl-maynez-que-dijeron-discursos-reacciones-orix\/","url_meta":{"origin":1449601,"position":1},"title":"Tercer debate presidencial en M\u00e9xico entre Sheinbaum, G\u00e1lvez y M\u00e1ynez, en vivo: reacciones, discursos, fact-check","author":"","date":"mayo 19, 2024","format":false,"excerpt":"Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesLa candidata Claudia Sheinbaum del partido Movimiento de Regeneraci\u00f3n Nacional saluda a sus simpatizantes a su llegada a un mitin de campa\u00f1a en el municipio de \u00c1lvaro Obreg\u00f3n, Ciudad de M\u00e9xico, el 16 de mayo de 2024. (YURI CORTEZ\/AFP v\u00eda Getty Images)La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449602,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/marea-rosa-galvez-morena-guinda-sede-debate-orix\/","url_meta":{"origin":1449601,"position":2},"title":"La \u201cMarea rosa\u201d arropa a G\u00e1lvez; Morena \u2018salpica\u2019 de guinda la sede del debate","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Las campa\u00f1as de las candidatas que encabezan las encuestas a la Presidencia de M\u00e9xico tomaron este domingo la zona centro de la capital del pa\u00eds con eventos masivos \u2015uno rosa y el otro guinda\u2015, como pre\u00e1mbulo al tercer debate presidencial que marca la recta final hacia las elecciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449573,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/18\/tercer-debate-presidencial-elecciones-mexico-2024-tema-moderadores-cuando-horario-donde-ver\/","url_meta":{"origin":1449601,"position":3},"title":"Tercer debate presidencial por las elecciones en M\u00e9xico 2024: tema, moderadores, cu\u00e1ndo, a qu\u00e9 hora y c\u00f3mo ver por TV e internet","author":"","date":"mayo 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Los candidatos a la presidencia de M\u00e9xico estar\u00e1n cara a cara en el tercer y \u00faltimo debate rumbo a las elecciones generales del 2 de junio.Claudia Sheinbaum, de la coalici\u00f3n oficialista Sigamos Haciendo Historia, X\u00f3chitl G\u00e1lvez, abanderada opositora de Fuerza y Coraz\u00f3n por M\u00e9xico, y Jorge \u00c1lvarez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447817,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/06\/claudia-sheinbaum-ausenta-ensayo-general-debate-orix\/","url_meta":{"origin":1449601,"position":4},"title":"Claudia Sheinbaum se ausenta a ensayo general previo al debate de candidatos presidenciales para &#171;no interrumpir su preparaci\u00f3n&#187;","author":"","date":"abril 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 La candidata presidencial del partido oficialista Morena, Claudia Sheinbaum, cancel\u00f3 este s\u00e1bado su asistencia al ensayo general en la sede del Instituto Nacional Electoral (INE) previo al debate de este domingo \u201cpara no interrumpir su preparaci\u00f3n\u201d, dijo a CNN la oficina de prensa del partido Morena.\u201cLa candidata\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449951,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/03\/amlo-celebra-victoria-claudia-sheinbaum-orix\/","url_meta":{"origin":1449601,"position":5},"title":"L\u00f3pez Obrador celebra la victoria de Sheinbaum: &#171;El pueblo de M\u00e9xico decidi\u00f3 libre y democr\u00e1ticamente&#187;","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, celebr\u00f3 que la candidata oficialista Claudia Sheinbaum resultara ganadora de la Presidencia de M\u00e9xico en los resultados preliminares reportados este domingo por el Instituto Nacional Electoral (INE).\"Hoy es un d\u00eda de gloria porque el pueblo de M\u00e9xico decidi\u00f3 libre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449601"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449601\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}