{"id":1449634,"date":"2024-05-21T12:03:43","date_gmt":"2024-05-21T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/"},"modified":"2024-05-21T12:03:43","modified_gmt":"2024-05-21T19:03:43","slug":"conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","title":{"rendered":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0La defensa concluy\u00f3 este martes la presentaci\u00f3n de su caso en el juicio penal de Donald Trump por el pago de dinero por silencio, tras unos 90 minutos de testimonios y sin que el expresidente subiera al estrado.<\/p>\n<p>Los abogados de Trump llamaron a dos testigos: un asistente legal que introdujo registros telef\u00f3nicos en las pruebas y Robert Costello, un abogado que estuvo en conversaciones con Michael Cohen para representarlo despu\u00e9s de los allanamientos del FBI en su casa y oficina en 2018.<\/p>\n<p>P\u00fablicamente, Trump dej\u00f3 abierta la posibilidad de que pudiera testificar en su propia defensa, pero sus abogados siempre parecieron descartar esa posibilidad.<\/p>\n<p>En \u00faltima instancia, el testigo m\u00e1s importante para la defensa fue Cohen, que testific\u00f3 en el caso de la Fiscal\u00eda pero fue sometido a un contrainterrogatorio que se extendi\u00f3 durante tres d\u00edas por m\u00e1s de ocho horas en conjunto.<\/p>\n<p>Ahora el jurado tendr\u00e1 una semana de descanso con motivo del D\u00eda de los Ca\u00eddos, y los alegatos finales est\u00e1n previstos para el pr\u00f3ximo martes. Es posible que se emita un veredicto a finales de la pr\u00f3xima semana.<\/p>\n<p>Estas son las conclusiones del \u00faltimo d\u00eda de testimonios en el juicio de Trump:<\/p>\n<p>Trump no sube al estrado<\/p>\n<p>En los \u00faltimos meses, Trump insinu\u00f3 repetidamente que subir\u00eda al estrado en su propia defensa.<\/p>\n<p>&#171;Bueno, lo har\u00eda si es necesario&#187;, dijo Trump en una entrevista el 25 de abril en Newsmax.<\/p>\n<p>&#171;Probablemente s\u00ed, me gustar\u00eda, quiero decir, creo que s\u00ed&#187;, dijo Trump a un canal de televisi\u00f3n de Wisconsin el 7 de mayo.<\/p>\n<p>Pero el martes, la oportunidad de que Trump testificara lleg\u00f3 y se fue r\u00e1pidamente, con el abogado Todd Blanche dici\u00e9ndole al juez una vez que Costello baj\u00f3 del estrado: &#171;La defensa descansa&#187;.<\/p>\n<p>En \u00faltima instancia, hubo poco misterio en la decisi\u00f3n: los abogados y el juez han estado calculando el calendario del final del juicio durante la \u00faltima semana suponiendo que Trump no testificar\u00eda.<\/p>\n<p>Parte de la raz\u00f3n por la que no se esperaba que Trump subiera al estrado era el alcance del interrogatorio. Los fiscales pidieron al juez que les permitiera interrogar al expresidente sobre una letan\u00eda de sus fechor\u00edas relacionadas con otros casos con el fin de impugnar la credibilidad de Trump como testigo.<\/p>\n<p>Tras una audiencia rutinaria sobre lo que se permitir\u00eda -conocida como audiencia Sandoval-, el juez dictamin\u00f3 que se habr\u00eda permitido a los fiscales interrogar a Trump sobre el veredicto por fraude civil de 464 d\u00f3lares del caso presentado el pasado oto\u00f1o por el fiscal general de Nueva York, las dos violaciones por parte de Trump de la orden de silencio del juez en ese caso, los veredictos contra Trump en los dos casos de difamaci\u00f3n de E. Jean Carroll y el acuerdo al que lleg\u00f3 Trump con el fiscal general de Nueva York que llev\u00f3 a la disoluci\u00f3n de la fundaci\u00f3n Donald J. Trump.<\/p>\n<p>Adem\u00e1s, Trump habr\u00eda sido sometido a preguntas relacionadas con el caso, por supuesto, incluyendo sus presuntos amor\u00edos con Stormy Daniels y Karen McDougal.<\/p>\n<p>Todo se sumaba al c\u00e1lculo de Trump y sus abogados de que era mejor que no subiera al estrado como testigo.<\/p>\n<p>La defensa m\u00e1s importante fue el contrainterrogatorio de Cohen<\/p>\n<p>El contrainterrogatorio de Cohen, el \u00faltimo testigo de la acusaci\u00f3n, dur\u00f3 ocho horas, aproximadamente cuatro veces m\u00e1s que toda la presentaci\u00f3n de la defensa.<\/p>\n<p>La diferencia subray\u00f3 la importancia de Cohen, tanto para el caso de la fiscal\u00eda contra Trump como para el hecho de que los esfuerzos de la defensa por desacreditar como testigo al ex asesor de Trump podr\u00edan ser clave para una absoluci\u00f3n o un jurado en desacuerdo.<\/p>\n<p>Blanche trat\u00f3 de restar credibilidad a Cohen, acus\u00e1ndole de inventarse sus conversaciones con Trump, de robar a su antiguo jefe y de seguir mintiendo incluso despu\u00e9s de declararse culpable de perjurio en 2018.<\/p>\n<p>El momento m\u00e1s dram\u00e1tico del contrainterrogatorio se produjo cuando Blanche confront\u00f3 a Cohen sobre una llamada que tuvo el 24 de octubre de 2016 con el guardaespaldas de Trump, Keith Schiller, a las 20:02, en la que Cohen testific\u00f3 que Schiller puso a Trump al tel\u00e9fono y Cohen le dijo que proced\u00eda con el pago a Daniels.<\/p>\n<p>Pero Blanche mostr\u00f3 a Cohen mensajes de texto que intercambi\u00f3 con Schiller antes y despu\u00e9s de esa llamada, mostrando que estaba tratando con un adolescente que le hac\u00eda bromas telef\u00f3nicas y le ped\u00eda ayuda a Schiller.<\/p>\n<p>&#171;Eso era mentira&#187;, aleg\u00f3 Blanche sobre el testimonio de Cohen de que habl\u00f3 con Trump sobre seguir adelante con el acuerdo de dinero por silencio. &#171;En realidad estaba hablando con el se\u00f1or Schiller sobre el hecho de que estaba recibiendo llamadas acosadoras de un ni\u00f1o de 14 a\u00f1os, \u00bfcorrecto?&#187;.<\/p>\n<p>&#171;En parte era el ni\u00f1o de 14 a\u00f1os, pero s\u00e9 que Keith estaba con el Sr. Trump en ese momento y hab\u00eda m\u00e1s que potencialmente s\u00f3lo esto. Eso es lo que recuerdo bas\u00e1ndome en los documentos que revis\u00e9&#187;, respondi\u00f3 Cohen.<\/p>\n<p>Los fiscales trataron de legitimar el testimonio de Cohen, introduciendo una captura de pantalla de C-SPAN que mostraba a Trump abandonando el escenario de un mitin en Florida con Schiller cinco minutos antes de la llamada.<\/p>\n<p>La fiscal Susan Hoffinger tambi\u00e9n trat\u00f3 de recordar a los miembros del jurado que era Trump, y no Cohen, quien estaba siendo juzgado en este caso.<\/p>\n<p>&#171;Ahora, s\u00e9 que puede sentirse como si estuviera en juicio aqu\u00ed despu\u00e9s del contrainterrogatorio. \u00bfEst\u00e1 usted realmente en juicio aqu\u00ed?&#187;, pregunt\u00f3 Hoffinger a Cohen.<br \/>\n&#171;No, se\u00f1ora&#187;, respondi\u00f3 Cohen.<\/p>\n<p>Despu\u00e9s de que los fiscales dieran por concluido el interrogatorio, Blanche pidi\u00f3 al juez Juan Merchan que desestimara el caso, una petici\u00f3n t\u00edpica presentada por los acusados que rara vez tiene \u00e9xito. Blanche argument\u00f3 que Cohen hab\u00eda mentido en su testimonio en este caso y que deb\u00eda ser desestimado.<\/p>\n<p>&#171;Entonces, \u00bfquiere que se lo quite de las manos al jurado y decida antes incluso de que llegue al jurado que, como cuesti\u00f3n de derecho, esta persona es tan poco digna de cr\u00e9dito que no deber\u00eda ser considerada por el jurado? \u00bfEso es lo que est\u00e1s planteando?&#187;, pregunt\u00f3 Merchan.<\/p>\n<p>&#171;Que todo su testimonio no debe ser considerado por el jurado. Por supuesto. Eso es exactamente lo que pedimos al tribunal&#187;, respondi\u00f3 Blanche.<\/p>\n<p>Merchan se mostr\u00f3 esc\u00e9ptico y m\u00e1s tarde pregunt\u00f3 a Blanche: &#171;Dijiste que sus mentiras son &#8216;irrefutables&#8217;, pero \u00bfcrees que va a enga\u00f1ar a 12 neoyorquinos para que crean esta mentira?&#187;.<\/p>\n<p>Costello tuvo una experiencia dif\u00edcil<\/p>\n<p>Argumentando contra los esfuerzos de los fiscales para impedir que Costello testificara, los abogados de Trump dijeron que Costello refutar\u00eda la sugerencia de los fiscales de que Trump puso en marcha una &#171;campa\u00f1a de presi\u00f3n&#187; para intimidar a Cohen para que se mantuviera callado en 2018.<\/p>\n<p>Merchan dictamin\u00f3 que Costello pod\u00eda testificar, pero dijo que no permitir\u00eda que el testimonio se convirtiera en un mini juicio sobre si de hecho hubo una campa\u00f1a de presi\u00f3n sobre Cohen y c\u00f3mo afect\u00f3 al exabogado de Trump en ese momento.<\/p>\n<p>El abogado de Trump, Emil Bove, trat\u00f3 de demostrar que Cohen utiliz\u00f3 los servicios legales de Costello, y como canal de contacto con Trump, aunque nunca firm\u00f3 un acuerdo de retenci\u00f3n y en \u00faltima instancia se fue con otro abogado para manejar su caso federal.<\/p>\n<p>En su primera reuni\u00f3n, Costello dijo que Cohen estaba &#171;absolutamente man\u00edaco&#187; y suicida despu\u00e9s del allanamiento del FBI en sus propiedades. Seg\u00fan Costello, Cohen dijo entre 10 y 12 veces durante la reuni\u00f3n: &#171;Te juro por Dios, Bob, que no tengo nada contra Donald Trump&#187;.<\/p>\n<p>El testimonio de Costello ante el jurado el lunes deriv\u00f3 r\u00e1pidamente en tensi\u00f3n entre Costello y el juez. Merchan desaloj\u00f3 la sala para reprender a Costello por hacer gestos y murmurar sobre las resoluciones del juez que limitaban lo que pod\u00eda decir en el estrado.<\/p>\n<p>Conclusiones del d\u00eda 19 del juicio penal a Donald Trump por el pago de dinero por silencio<\/p>\n<p>En el contrainterrogatorio, Hoffinger trat\u00f3 de desacreditar a Costello, sugiriendo que estaba m\u00e1s alineado con los intereses de Trump que Cohen cuando le asesoraba en la primavera de 2018.<\/p>\n<p>Hoffinger sugiri\u00f3 que Costello, que estaba en contacto frecuente con su \u00edntimo amigo Rudy Giuliani, formaba parte de la campa\u00f1a de presi\u00f3n para mantener a raya a Cohen. Costello reconoci\u00f3 que ofreci\u00f3 a Cohen un canal extraoficial con Trump a trav\u00e9s de Giuliani, pero dijo que era para el beneficio de Cohen.<\/p>\n<p>Alegatos finales fijados para el martes<\/p>\n<p>Ambas partes regresan al tribunal el martes por la tarde, sin los miembros del jurado presentes, para discutir las instrucciones que el juez dar\u00e1 al jurado antes de las deliberaciones de la pr\u00f3xima semana.<\/p>\n<p>A continuaci\u00f3n, el tribunal permanecer\u00e1 a oscuras durante una semana, una decisi\u00f3n de programaci\u00f3n que Merchan eligi\u00f3 para que las etapas finales del juicio no se vieran interrumpidas por un fin de semana de cuatro d\u00edas del D\u00eda de los Ca\u00eddos.<\/p>\n<p>Merchan dijo a los miembros del jurado que volver\u00e1n el pr\u00f3ximo martes para los alegatos finales, que se espera que duren todo el d\u00eda. Una vez que el jurado reciba sus instrucciones, el destino de Trump estar\u00e1 en sus manos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0La defensa concluy\u00f3 este martes la presentaci\u00f3n de su caso en el juicio penal de Donald Trump por el pago de dinero por silencio, tras unos 90 minutos de testimonios y sin que el expresidente subiera al estrado. Los abogados de Trump llamaron a dos testigos: un asistente legal que introdujo registros telef\u00f3nicos en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449634","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0La defensa concluy\u00f3 este martes la presentaci\u00f3n de su caso en el juicio penal de Donald Trump por el pago de dinero por silencio, tras unos 90 minutos de testimonios y sin que el expresidente subiera al estrado. Los abogados de Trump llamaron a dos testigos: un asistente legal que introdujo registros telef\u00f3nicos en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio\",\"datePublished\":\"2024-05-21T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\"},\"wordCount\":1630,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\",\"name\":\"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-21T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio - Noticias","og_description":"(CNN) &#8212;\u00a0La defensa concluy\u00f3 este martes la presentaci\u00f3n de su caso en el juicio penal de Donald Trump por el pago de dinero por silencio, tras unos 90 minutos de testimonios y sin que el expresidente subiera al estrado. Los abogados de Trump llamaron a dos testigos: un asistente legal que introdujo registros telef\u00f3nicos en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-21T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio","datePublished":"2024-05-21T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/"},"wordCount":1630,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","name":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-21T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-21T19:03:43Z","datePublished":"2024-05-21T19:03:43Z","dateModified":"2024-05-21T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conclusiones del \\u00faltimo d\\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/21\\\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/21\\\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-21T19:03:43Z\",\"datePublished\":\"2024-05-21T19:03:43Z\",\"dateModified\":\"2024-05-21T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1449610,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/conclusiones-dia-19-juicio-penal-donald-trump-trax\/","url_meta":{"origin":1449634,"position":0},"title":"Conclusiones del d\u00eda 19 del juicio penal a Donald Trump por el pago de dinero por silencio","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- La fiscal\u00eda concluy\u00f3 su caso contra Donald J. Trump este lunes en el juicio del expresidente por el pago de dinero por silencio, que se dirige hacia una conclusi\u00f3n tan pronto como la pr\u00f3xima semana.El testimonio de Michael Cohen finalmente termin\u00f3 este lunes despu\u00e9s de cuatro d\u00edas, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449535,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/17\/analisis-michael-cohen-interrogatorio-juicio-sobornos-donald-trump-trax\/","url_meta":{"origin":1449634,"position":1},"title":"AN\u00c1LISIS | Michael Cohen regala a Donald Trump su mejor d\u00eda en el juicio por sobornos hasta ahora","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- Donald Trump finalmente tuvo un buen d\u00eda en la corte.El posible candidato republicano ha parecido a menudo avergonzado y enfurecido por su primer juicio penal, en el que se han expuesto salazmente su vida personal y detalles de sus presuntos intentos de encubrirla.Pero este jueves pudo saborear a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449393,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/10\/conclusiones-dia-15-juicio-penal-donald-trump-dinero-silencio-trax\/","url_meta":{"origin":1449634,"position":2},"title":"Conclusiones del d\u00eda 15 del juicio penal a Donald Trump por el pago de dinero por silencio","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN) --\u00a0Una de las asesoras m\u00e1s cercanas de Donald Trump en la Casa Blanca termin\u00f3 su testimonio este viernes en el juicio del expresidente por el dinero pago de dinero por silencio, despejando el camino para que el testigo clave de la fiscal\u00eda suba al estrado el lunes.Se espera que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447855,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/08\/trump-abogados-juicio-pago-stormy-daniel-trax\/","url_meta":{"origin":1449634,"position":3},"title":"Abogados de Trump apelan la orden de silencio y el lugar del juicio por pago a Stormy Daniels, una semana antes del inicio","author":"","date":"abril 8, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El equipo legal del expresidente Donald Trump present\u00f3 un aviso de apelaci\u00f3n en el caso penal que el exmandatario enfrenta en Manhattan, seg\u00fan muestran registros judiciales, una semana antes de que comience su juicio.Dictan orden de silencio a Trump en juicio por pago a Stormy Daniels tras declaraciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448156,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/16\/conclusiones-primer-dia-juicio-trump-dinero-silencio-trax\/","url_meta":{"origin":1449634,"position":4},"title":"Conclusiones del primer d\u00eda del juicio a Trump por el pago de dinero por silencio","author":"","date":"abril 16, 2024","format":false,"excerpt":"(CNN) -- Lleg\u00f3 el primer juicio penal al expresidente Donald Trump.La jornada inaugural del primer juicio penal contra un expresidente de Estados Unidos comenz\u00f3 este lunes, dando un golpe de realidad al hecho de que el presunto candidato republicano a la presidencia se sentar\u00e1 en una sala de Manhattan como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449480,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/15\/michael-cohen-toma-respiro-interrogatorio-donald-trump-mira-trax\/","url_meta":{"origin":1449634,"position":5},"title":"AN\u00c1LISIS | Cohen toma un respiro tras interrogatorio mientras Trump mira","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN) -- No ser\u00eda una sorpresa si el jurado en el primer juicio penal de Donald Trump ahora vea a su exapa\u00f1ador, Michael Cohen, como un troll profano de las redes sociales y un mentiroso vengativo que sue\u00f1a con ver tras las rejas al jefe al que una vez ador\u00f3.Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449634"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449634\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}