{"id":1449731,"date":"2024-05-24T01:03:50","date_gmt":"2024-05-24T08:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/"},"modified":"2024-05-24T01:03:50","modified_gmt":"2024-05-24T08:03:50","slug":"hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","title":{"rendered":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial"},"content":{"rendered":"<p>(CNN) &#8212; Los restos de uno de los submarinos m\u00e1s famosos de la Marina de los EE.UU. durante la Segunda Guerra Mundial fueron encontrados en el Mar de China Meridional ocho d\u00e9cadas despu\u00e9s de su \u00faltima patrulla, dijo el jueves el Comando de Historia y Patrimonio de la Marina.<\/p>\n<p>El USS Harder yace a unos 900 metros de profundidad frente a la isla septentrional filipina de Luz\u00f3n. Se encuentra en posici\u00f3n vertical e intacto, excepto por los da\u00f1os sufridos detr\u00e1s de la torre de mando por una carga de profundidad japonesa, seg\u00fan inform\u00f3 el Comando de Historia y Patrimonio Naval (NHHC, por sus siglas en ingl\u00e9s) en un comunicado.<\/p>\n<p>El Harder se perdi\u00f3 en combate el 24 de agosto de 1944, junto con toda la tripulaci\u00f3n de 79 submarinistas. Esto sucedi\u00f3 mientras realizaba su sexta patrulla de la guerra en un momento en que EE.UU. trataba de recuperar Filipinas de manos de las fuerzas de ocupaci\u00f3n japonesas.<\/p>\n<p>&#171;El Harder se perdi\u00f3 en el transcurso de la victoria. No debemos olvidar que la victoria tiene un precio, al igual que la libertad&#187;, declar\u00f3 en el comunicado el director del NHHC, Samuel J. Cox, almirante retirado de la Marina estadounidense.<\/p>\n<p>Seg\u00fan la historia de la Marina estadounidense, el Harder hundi\u00f3 dos buques escolta japoneses frente a la pen\u00ednsula de Bata\u00e1n el 22 de agosto de 1944, y luego se dirigi\u00f3 al norte por la costa de Luz\u00f3n con otros dos submarinos en busca de m\u00e1s objetivos.<\/p>\n<p>De la batalla del R\u00edo de la Plata a los combates en Italia y Filipinas: Am\u00e9rica Latina en la Segunda Guerra Mundial<\/p>\n<p>USS Harder, foto de archivo de la Marina estadounidense (Comando de Historia y Patrimonio Naval)<\/p>\n<p>En un combate con el buque escolta japon\u00e9s CD-22 en la ma\u00f1ana del 24 de agosto, el Harder dispar\u00f3 tres torpedos que fallaron y posteriormente fue hundido por el quinto ataque con carga de profundidad del buque japon\u00e9s, seg\u00fan los registros japoneses citados por el NHHC.<\/p>\n<p>El NHHC declar\u00f3 que el naufragio del Harder fue confirmado gracias a los datos otorgados por el Proyecto Lost 52. Este proyecto est\u00e1 dirigido por Tim Taylor, CEO de Tiburon Subsea, y realiza tareas para encontrar los 52 submarinos estadounidenses perdidos en la Segunda Guerra Mundial.<\/p>\n<p>Seg\u00fan el NHHC, el grupo ya ha localizado al menos seis submarinos de la Segunda Guerra Mundial.<\/p>\n<p>&#171;Estamos agradecidos de que Lost 52 nos haya dado la oportunidad de honrar una vez m\u00e1s el valor de la tripulaci\u00f3n del submarino &#8216;Hit &#8216;em Harder'&#187;, dijo Cox del NHHC, en referencia al lema del buque.<\/p>\n<p>El sitio del naufragio es &#171;el lugar de descanso final de los marineros que dieron su vida en defensa de la naci\u00f3n y debe ser respetado por todas las partes como una sepultura de guerra&#187;, agreg\u00f3 el NHHC.<\/p>\n<p>Las batallas del USS Harder<\/p>\n<p>Filipinas fue un territorio estadounidense atacado por Jap\u00f3n inmediatamente despu\u00e9s del ataque a Pearl Harbor en diciembre de 1941. En la primavera de 1942, las fuerzas estadounidenses y filipinas en Luz\u00f3n se rindieron ante las fuerzas de Tokio y Jap\u00f3n utiliz\u00f3 el archipi\u00e9lago capturado para proteger sus l\u00edneas de suministro desde las Indias Orientales y el sudeste asi\u00e1tico.<\/p>\n<p>Pero a mediados de 1944, Estados Unidos estaba haciendo retroceder a las fuerzas japonesas en todo el Pac\u00edfico y planeaba desembarcos para hacer lo mismo en Filipinas.<\/p>\n<p>El Harder, cuyo lema era &#171;Golp\u00e9alos m\u00e1s fuerte&#187;, estaba capitaneado por el comandante Samuel Dealey. El comandante recibir\u00eda a t\u00edtulo p\u00f3stumo la Medalla de Honor, la m\u00e1s alta condecoraci\u00f3n del ej\u00e9rcito estadounidense, por sus acciones en la quinta patrulla del Harder, de marzo a julio de 1944.<\/p>\n<p>Durante ese tiempo, Harder hundi\u00f3 tres destructores japoneses y probablemente destruy\u00f3 o da\u00f1\u00f3 gravemente otros dos en el transcurso de s\u00f3lo cuatro d\u00edas, seg\u00fan el Museo Nacional de la Medalla de Honor.<\/p>\n<p>En la p\u00e1gina que el museo le dedica a Dealey se describe un encuentro especialmente desgarrador.<\/p>\n<p>Al verse atacado por un destructor japon\u00e9s, Dealey orden\u00f3 disparar un torpedo de frente a la proa del enemigo, lo que se conoce como &#171;tiro al cuello&#187;, seg\u00fan el relato del museo.<\/p>\n<p>&#171;A 1.400 metros, Dealey dispar\u00f3 tres torpedos y orden\u00f3 al submarino que se sumergiera. Cuando el Harder pas\u00f3 25 metros por debajo del destructor, dos de los torpedos impactaron en el barco, enviando ondas de choque a trav\u00e9s del submarino&#187;.<\/p>\n<p>En sus cuatro primeras patrullas, tras su entrada en servicio el 2 de diciembre de 1942, el Harder hundi\u00f3 14 buques de guerra y mercantes japoneses, seg\u00fan el Museo de la Medalla de Honor.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los restos de uno de los submarinos m\u00e1s famosos de la Marina de los EE.UU. durante la Segunda Guerra Mundial fueron encontrados en el Mar de China Meridional ocho d\u00e9cadas despu\u00e9s de su \u00faltima patrulla, dijo el jueves el Comando de Historia y Patrimonio de la Marina. El USS Harder yace a unos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449731","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los restos de uno de los submarinos m\u00e1s famosos de la Marina de los EE.UU. durante la Segunda Guerra Mundial fueron encontrados en el Mar de China Meridional ocho d\u00e9cadas despu\u00e9s de su \u00faltima patrulla, dijo el jueves el Comando de Historia y Patrimonio de la Marina. El USS Harder yace a unos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T08:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial\",\"datePublished\":\"2024-05-24T08:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\",\"name\":\"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-24T08:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial - Noticias","og_description":"(CNN) &#8212; Los restos de uno de los submarinos m\u00e1s famosos de la Marina de los EE.UU. durante la Segunda Guerra Mundial fueron encontrados en el Mar de China Meridional ocho d\u00e9cadas despu\u00e9s de su \u00faltima patrulla, dijo el jueves el Comando de Historia y Patrimonio de la Marina. El USS Harder yace a unos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-24T08:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/"},"author":{"name":"","@id":""},"headline":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial","datePublished":"2024-05-24T08:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","name":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-24T08:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\u00f3 en la II Guerra Mundial","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-24T08:03:50Z","datePublished":"2024-05-24T08:03:50Z","dateModified":"2024-05-24T08:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hallan restos del USS Harder, el famoso submarino de la Armada de EE.UU. que se hundi\\u00f3 en la II Guerra Mundial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/24\\\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/24\\\/hallan-restos-submarino-uss-harder-ii-guerra-mundial-filipinas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-24T08:03:50Z\",\"datePublished\":\"2024-05-24T08:03:50Z\",\"dateModified\":\"2024-05-24T08:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455880,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/11\/17\/hallan-restos-buque-segunda-guerra-mundial-bailarin-marina-estados-unidos-costas-australia-trax\/","url_meta":{"origin":1449731,"position":0},"title":"Hallan restos del heroico buque de guerra de la Segunda Guerra Mundial, el &#8216;rat\u00f3n bailar\u00edn&#8217;, de la Marina de Estados Unidos, frente a las costas de Australia","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN) --\u00a0 Los restos de un buque de guerra estadounidense hundido en una batalla de la Segunda Guerra Mundial, considerada una de las m\u00e1s valientes jam\u00e1s libradas por un buque de la Armada de Estados Unidos, fueron encontrados en las profundidades del Pac\u00edfico, anunciaron este lunes funcionarios estadounidenses y australianos.Conocido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460287,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/22\/despliegue-segundo-buque-de-guerra-frontera-mexico-trax\/","url_meta":{"origin":1449731,"position":1},"title":"EE.UU. despliega un segundo buque de guerra en la frontera con M\u00e9xico mientras Trump intensifica la pol\u00edtica antimigratoria","author":"","date":"marzo 22, 2025","format":false,"excerpt":"Estados Unidos despleg\u00f3 un destructor de misiles guiados a la frontera con M\u00e9xico este s\u00e1bado, mientras el presidente Donald Trump intensifica su campa\u00f1a contra la inmigraci\u00f3n, seg\u00fan un comunicado de prensa del Comando Norte de EE.UU.El USS Spruance, que parti\u00f3 de la base naval de San Diego, ayudar\u00e1 en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472491,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/24\/uss-nimitz-portaaviones-america-latina-orix\/","url_meta":{"origin":1449731,"position":2},"title":"As\u00ed es el USS Nimitz, el longevo portaviones de EE.UU. que ser\u00e1 enviado a Am\u00e9rica Latina en una de sus \u00faltimas misiones","author":"","date":"marzo 24, 2026","format":false,"excerpt":"El portaviones m\u00e1s antiguo de EE.UU., el USS Nimitz, visitar\u00e1 al menos cuatro pa\u00edses durante una extensa gira por Am\u00e9rica Latina que llega en el contexto de crecientes tensiones entre Washington y La Habana, y a casi tres meses de la operaci\u00f3n militar estadounidense que llev\u00f3 a la captura del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460191,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/20\/buques-guerra-eeuu-frontera-sur-mexico-orix\/","url_meta":{"origin":1449731,"position":3},"title":"\u00bfPor qu\u00e9 hay buques de guerra de EE.UU. desplegados en la frontera sur?","author":"","date":"marzo 20, 2025","format":false,"excerpt":"En medio de tensiones creciente en la frontera entre Estados Unidos y M\u00e9xico por las duras medidas migratorias del Gobierno de Donald Trump, y ante la amenaza de una guerra comercial en Norteam\u00e9rica debido a los aranceles que Washington dice buscan mitigar el comercio de drogas il\u00edcitas, la Armada de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460179,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/20\/armada-eeuu-destructor-mexico-frontera-sur-trax\/","url_meta":{"origin":1449731,"position":4},"title":"La Armada de Estados Unidos desplegar\u00e1 un segundo buque de guerra en la frontera sur","author":"","date":"marzo 20, 2025","format":false,"excerpt":"La Armada de EE.UU. desplegar\u00e1 un segundo buque de guerra en zonas cercanas a la frontera sur de Estados Unidos. Se espera un anuncio sobre el despliegue para finales de esta semana, seg\u00fan inform\u00f3 un funcionario estadounidense a CNN.Un segundo destructor se unir\u00e1 al USS Gravely, desplegado por el Comando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449362,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/09\/venezuela-rechaza-presencia-portaaviones-uss-george-washington-caribe-orix\/","url_meta":{"origin":1449731,"position":5},"title":"Venezuela rechaza presencia del portaaviones USS George Washington en el Caribe","author":"","date":"mayo 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En un nuevo episodio de tensi\u00f3n entre Washington, Georgetown y Caracas, el ministro de la Defensa de Venezuela, Vladimir Padrino L\u00f3pez, consider\u00f3 como una amenaza contra la paz regional la presencia del portaaviones estadounidense USS George Washington en el Caribe y, con un mensaje en su cuenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449731"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449731\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}