{"id":1449737,"date":"2024-05-24T09:03:55","date_gmt":"2024-05-24T16:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/"},"modified":"2024-05-24T09:03:55","modified_gmt":"2024-05-24T16:03:55","slug":"milei-canta-economia-argentina-desempleo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","title":{"rendered":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cuando el presidente de Argentina, Javier Milei, sub\u00eda este mi\u00e9rcoles a cantar en el escenario del Luna Park, estadio emblem\u00e1tico de la ciudad de Buenos Aires, hab\u00edan pasado alrededor de cinco horas desde que el Instituto Nacional de Estad\u00edstica y Censos (Indec) daba la noticia de que la econom\u00eda del pa\u00eds ca\u00eda como no lo hac\u00eda desde la pandemia. El contraste no pod\u00eda ser m\u00e1s evidente: el mandatario entonando canciones de rock pesado, en el marco del festejo por la presentaci\u00f3n de su libro, justo cuando las estad\u00edsticas econ\u00f3micas de marzo de este a\u00f1o se parec\u00edan m\u00e1s a la tristeza de la letra de un tango.<\/p>\n<p>Valores pand\u00e9micos<\/p>\n<p>La econom\u00eda argentina se desplom\u00f3 en marzo un 8,4% contra el mismo mes de 2023. Pero no solo eso: tambi\u00e9n descendi\u00f3 en la comparaci\u00f3n con febrero. Lo hizo 1,4% y profundiz\u00f3 de esta manera una racha intermensual de siete meses sin crecimiento. La \u00faltima vez que se registr\u00f3 un avance fue en agosto de 2023, de 0,8% en relaci\u00f3n con julio. El crecimiento se interrumpi\u00f3 en ese momento producto de una devaluaci\u00f3n de casi el 22%, en medio de la campa\u00f1a electoral por la presidencia, y la econom\u00eda no ha vuelto a recuperarse, al menos hasta marzo, seg\u00fan los datos del Estimador Mensual de Actividad Econ\u00f3mica (EMAE) del Indec.<\/p>\n<p>Milei y su \u201cplan radical para transformar Argentina\u201d llegan a la portada de la revista Time<\/p>\n<p>La comparaci\u00f3n interanual arroja tambi\u00e9n n\u00fameros negativos desde que Milei es presidente. La \u00faltima vez que se registr\u00f3 un crecimiento interanual fue en octubre de 2023, bajo los \u00faltimos meses de la presidencia de Alberto Fern\u00e1ndez y en medio de la campa\u00f1a electoral, cuando la actividad subi\u00f3 1% con respecto a igual mes de 2022.<\/p>\n<p>Pero la retracci\u00f3n interanual de marzo es la m\u00e1s significativa en a\u00f1os: la ca\u00edda del 8,4% representa la peor desde agosto de 2020 (-11,5%), ocurrida en plena pandemia, durante la cual Argentina sobrellev\u00f3 un aislamiento prolongado que min\u00f3 la actividad durante todo ese a\u00f1o. Para decirlo de otro modo: en marzo, la econom\u00eda cay\u00f3 tanto como si el pa\u00eds estuviera cerrado, paralizado, algo que ocurri\u00f3 durante las restricciones por el coronavirus. Adem\u00e1s, la base de comparaci\u00f3n (marzo 2023) tampoco result\u00f3 muy alta, aunque la econom\u00eda hab\u00eda terminado ese mes con signo positivo (1,3%).<\/p>\n<p>El campo y la miner\u00eda, otra vez a la cabeza<\/p>\n<p>Los dos sectores de mejor rendimiento interanual fueron Agricultura, ganader\u00eda, pesca y silvicultura (14,1%) y Explotaci\u00f3n de minas y canteras (5,9%). Esta vez, fueron seis los rubros que crecieron, contra siete que lo hab\u00edan hecho en febrero, otra muestra del deterioro de la actividad. Entre las principales ca\u00eddas en los \u00faltimos doce meses, se destacan Construcci\u00f3n (29,9%) e Industria manufacturera (19,6%). Adem\u00e1s, se contrajo Comercio mayorista, minorista y reparaciones (16,7%), el cual era el rubro m\u00e1s din\u00e1mico en t\u00e9rminos de creaci\u00f3n de empleo, de acuerdo con el \u00faltimo dato oficial correspondiente al cuarto trimestre de 2023.<\/p>\n<p>Al ritmo del derrape, vuelve el fantasma del desempleo<\/p>\n<p>La \u00faltima encuesta de Indicadores laborales, publicada por el Ministerio de Trabajo en mayo con datos de marzo de 2024, da cuenta de que se acumulan cuatro meses consecutivos de ca\u00edda neta del empleo, con una reducci\u00f3n del 1,4% en marzo. Entre los rubros m\u00e1s afectados, se encuentra la construcci\u00f3n. Desde que asumi\u00f3 Javier Milei, se perdieron 100.000 puestos de trabajo directos, seg\u00fan asegur\u00f3 el presidente de la C\u00e1mara Argentina de la Construcci\u00f3n, Gustavo Weiss.<\/p>\n<p>La industria, segundo sector de mayor ca\u00edda en marzo de 2024, tambi\u00e9n registra datos negativos en t\u00e9rminos de empleo. Si bien la \u00faltima medici\u00f3n corresponde a febrero, un informe de la Uni\u00f3n Industrial Argentina permite apreciar que el desempleo fabril viene creciendo ininterrumpidamente desde septiembre del a\u00f1o pasado, algo que no se detuvo a partir de diciembre de 2023, con la llegada de Milei a la presidencia, sino que se profundiz\u00f3, hasta alcanzar una merma intermensual del 2% en el segundo mes de este a\u00f1o. Se espera que la situaci\u00f3n se haya agravado al menos en marzo, de acuerdo con las estad\u00edsticas oficiales sobre el derrumbe de la actividad. El Indec publicar\u00e1 su pr\u00f3ximo informe sobre el mercado de trabajo el 24 de junio.<\/p>\n<p>El presidente Milei no hizo referencia a ninguno de estos temas durante su presentaci\u00f3n en el Luna Park. En una dimensi\u00f3n paralela, mezcla de rock and roll y teor\u00eda literaria, pas\u00f3 de largo la peor estad\u00edstica econ\u00f3mica de la que se tenga registro en los \u00faltimos cuatro a\u00f1os.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Cuando el presidente de Argentina, Javier Milei, sub\u00eda este mi\u00e9rcoles a cantar en el escenario del Luna Park, estadio emblem\u00e1tico de la ciudad de Buenos Aires, hab\u00edan pasado alrededor de cinco horas desde que el Instituto Nacional de Estad\u00edstica y Censos (Indec) daba la noticia de que la econom\u00eda del pa\u00eds ca\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449737","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Cuando el presidente de Argentina, Javier Milei, sub\u00eda este mi\u00e9rcoles a cantar en el escenario del Luna Park, estadio emblem\u00e1tico de la ciudad de Buenos Aires, hab\u00edan pasado alrededor de cinco horas desde que el Instituto Nacional de Estad\u00edstica y Censos (Indec) daba la noticia de que la econom\u00eda del pa\u00eds ca\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T16:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo\",\"datePublished\":\"2024-05-24T16:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\"},\"wordCount\":831,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\",\"name\":\"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-24T16:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Cuando el presidente de Argentina, Javier Milei, sub\u00eda este mi\u00e9rcoles a cantar en el escenario del Luna Park, estadio emblem\u00e1tico de la ciudad de Buenos Aires, hab\u00edan pasado alrededor de cinco horas desde que el Instituto Nacional de Estad\u00edstica y Censos (Indec) daba la noticia de que la econom\u00eda del pa\u00eds ca\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-24T16:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/"},"author":{"name":"","@id":""},"headline":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo","datePublished":"2024-05-24T16:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/"},"wordCount":831,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","name":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-24T16:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mientras Milei canta, la econom\u00eda argentina se desploma a niveles de pandemia y crece el desempleo","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/milei-canta-economia-argentina-desempleo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-24T16:03:55Z","datePublished":"2024-05-24T16:03:55Z","dateModified":"2024-05-24T16:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mientras Milei canta, la econom\\u00eda argentina se desploma a niveles de pandemia y crece el desempleo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/24\\\/milei-canta-economia-argentina-desempleo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/24\\\/milei-canta-economia-argentina-desempleo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-24T16:03:55Z\",\"datePublished\":\"2024-05-24T16:03:55Z\",\"dateModified\":\"2024-05-24T16:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448401,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/23\/milei-cadena-nacional-superavit-financiero-orix\/","url_meta":{"origin":1449737,"position":0},"title":"Javier Milei habl\u00f3 en cadena nacional y dijo que el super\u00e1vit financiero alcanzado por su Gobierno en el primer trimestre es &#171;un hito&#187;","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) --El presidente de Argentina, Javier Milei, habl\u00f3 en cadena nacional para hacer un balance de los tres primeros meses de su gesti\u00f3n.Rodeado por su equipo econ\u00f3mico -encabezado por el ministro de Econom\u00eda, Luis Caputo-, el mandatario inform\u00f3 en su discurso que \u201cel sector p\u00fablico nacional registr\u00f3 durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448277,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/19\/milei-deficit-fiscal-de-argentina-orix\/","url_meta":{"origin":1449737,"position":1},"title":"Milei frente al desaf\u00edo del perro que se muerde la cola con el d\u00e9ficit fiscal de Argentina","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- No hay alternativa. El camino es uno solo\u2026 al menos para Javier Milei.Parece que nada ni nadie har\u00e1 mover al presidente de su rumbo. \u201cEl d\u00e9ficit cero no se negocia\u201d, ha repetido en todos lados y a toda hora en referencia a su pol\u00edtica fiscal.Pero ese objetivo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463589,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/16\/argentina-baja-inflacion-economia-consumo-analisis-orix\/","url_meta":{"origin":1449737,"position":2},"title":"\u00bfMilagro argentino? Milei logra la inflaci\u00f3n m\u00e1s baja en cinco a\u00f1os, pero la econom\u00eda enciende alarmas","author":"","date":"junio 16, 2025","format":false,"excerpt":"Se suele decir que un pa\u00eds o regi\u00f3n atraviesa un \u201cmilagro econ\u00f3mico\u201d cuando logra por un determinado per\u00edodo, generalmente algunos a\u00f1os, un alto nivel de tasas de crecimiento de su Producto Bruto Interno (PBI). Por diferentes factores \u2015como pol\u00edticas activas que impulsen los resortes de un aparato productivo, una buena\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443971,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/17\/que-busca-javier-milei-presidente-de-argentina-en-el-foro-de-davos\/","url_meta":{"origin":1449737,"position":3},"title":"\u00bfQu\u00e9 busca Javier Milei, presidente de Argentina, en el Foro de Davos?","author":"","date":"enero 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente de Argentina, Javier Milei, se encuentra desde este martes en Suiza para participar del Foro Econ\u00f3mico Mundial, que se realiza cada a\u00f1o en la ciudad de Davos. El encuentro, en el que participan l\u00edderes econ\u00f3micos, financieros y pol\u00edticos de todo el mundo, \u201ces la plataforma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450807,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/30\/analisis-milei-ley-bases-fantasea-premio-nobel-economia-argentina-orix\/","url_meta":{"origin":1449737,"position":4},"title":"AN\u00c1LISIS | Milei ya tiene la Ley Bases y fantasea con el\u00a0premio Nobel, pero la econom\u00eda argentina no arranca","author":"","date":"junio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Despu\u00e9s de batallar durante casi seis meses, el gobierno argentino consigui\u00f3 que el Congreso sancionara en la madrugada de este viernes las primeras normas desde la asunci\u00f3n de Javier Milei: la denominada Ley Bases y un paquete de reformas fiscales.Con esto, el presidente sostuvo que ha terminado una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455372,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/10\/26\/milei-economia-argentina-analisi-orix\/","url_meta":{"origin":1449737,"position":5},"title":"Milei dice que acelera como Colapinto, pero la econom\u00eda argentina reci\u00e9n arranca","author":"","date":"octubre 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol)-- El presidente de Argentina, Javier Milei, cumpli\u00f3 54 a\u00f1os el martes. Como parte de las celebraciones ese d\u00eda, fue entrevistado por el presentador Alejandro Fantino en la plataforma de streaming Neura. En un momento, el presidente traz\u00f3 una perspectiva de lo que pretende de su Gobierno y compar\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449737"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449737\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}