{"id":1449780,"date":"2024-05-27T03:03:43","date_gmt":"2024-05-27T10:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/"},"modified":"2024-05-27T03:03:43","modified_gmt":"2024-05-27T10:03:43","slug":"artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","title":{"rendered":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024"},"content":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8211; &#8211;\u00a0 La Fundaci\u00f3n de Derechos Humanos (HRF) anunci\u00f3 los ganadores del Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024, entre los que figura la pianista y artista venezolana Gabriela Montero.<\/p>\n<p>Montero, de 54 a\u00f1os, es una pianista y compositora venezolana de renombre internacional. El viaje de Montero hacia la disidencia creativa comenz\u00f3 en 2011 con su primera composici\u00f3n orquestal, \u201cEx Patria\u201d, un poema sinf\u00f3nico dise\u00f1ado para ilustrar y protestar por el descenso de Venezuela hacia la anarqu\u00eda, la corrupci\u00f3n y la violencia, explic\u00f3 el comunicado.<\/p>\n<p>Montero gan\u00f3 un Latin Grammy al mejor \u00e1lbum de m\u00fasica cl\u00e1sica en 2015 y entre sus obras mas conocidas, resaltan el \u201cConcierto Latino\u201d (2016), \u201cBabel\u201d (2018) y \u201cCanaima: un quinteto para piano y cuerdas\u201d (2024).<\/p>\n<p>\u201cCada a\u00f1o, el Premio Havel rinde homenaje a las personas que, con valent\u00eda y creatividad, desenmascaran la tiran\u00eda y encarnan el concepto de &#8216;Vivir en la verdad&#8217;, tan relevante hoy como cuando lo articul\u00f3 V\u00e1clav Havel hace casi 45 a\u00f1os. Su trabajo es un testimonio de una valent\u00eda e ingenio extraordinarios\u201d, dijo el fundador de HRF, Thor Halvorssen Mendoza.<\/p>\n<p>Los galardonados que acompa\u00f1an a Montero son el artista de hip-hop iran\u00ed Toomaj Salehi y el poeta y activista uigur Tahir Hamut Izgil.<\/p>\n<p>Los galardonados ser\u00e1n reconocidos durante una ceremonia este martes 4 de junio en el Foro de la Libertad de Oslo (OFF) 2024 en Oslo, Noruega. Montero interpretar\u00e1 su \u00faltima composici\u00f3n, \u201cCanaima\u201d, inform\u00f3 el comunicado.<\/p>\n<p>El Premio Havel lleva el nombre del fallecido presidente checo, poeta, dramaturgo, disidente, estadista y expresidente de la HRF, V\u00e1clav Havel. Havel lider\u00f3 la revoluci\u00f3n no violenta que liber\u00f3 a Checoslovaquia del r\u00e9gimen comunista.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8211; &#8211;\u00a0 La Fundaci\u00f3n de Derechos Humanos (HRF) anunci\u00f3 los ganadores del Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024, entre los que figura la pianista y artista venezolana Gabriela Montero. Montero, de 54 a\u00f1os, es una pianista y compositora venezolana de renombre internacional. El viaje de Montero hacia la disidencia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449780","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN en Espa\u00f1ol) &#8211; &#8211;\u00a0 La Fundaci\u00f3n de Derechos Humanos (HRF) anunci\u00f3 los ganadores del Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024, entre los que figura la pianista y artista venezolana Gabriela Montero. Montero, de 54 a\u00f1os, es una pianista y compositora venezolana de renombre internacional. El viaje de Montero hacia la disidencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-27T10:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024\",\"datePublished\":\"2024-05-27T10:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\",\"name\":\"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-27T10:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024 - Noticias","og_description":"(CNN en Espa\u00f1ol) &#8211; &#8211;\u00a0 La Fundaci\u00f3n de Derechos Humanos (HRF) anunci\u00f3 los ganadores del Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024, entre los que figura la pianista y artista venezolana Gabriela Montero. Montero, de 54 a\u00f1os, es una pianista y compositora venezolana de renombre internacional. El viaje de Montero hacia la disidencia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-27T10:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/"},"author":{"name":"","@id":""},"headline":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024","datePublished":"2024-05-27T10:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","name":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-27T10:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\u00e1clav Havel a la Disidencia Creativa 2024","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/27\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-27T10:03:43Z","datePublished":"2024-05-27T10:03:43Z","dateModified":"2024-05-27T10:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La artista venezolana Gabriela Montero entre galardonados por el Premio Internacional V\\u00e1clav Havel a la Disidencia Creativa 2024\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/27\\\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/27\\\/artista-gabriela-montero-galardonada-premio-internacional-disidencia-creativa-2024-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-27T10:03:43Z\",\"datePublished\":\"2024-05-27T10:03:43Z\",\"dateModified\":\"2024-05-27T10:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467253,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/10\/premio-nobel-paz-maria-corina-machado-lider-opositora-venezolana-trax\/","url_meta":{"origin":1449780,"position":0},"title":"Premio Nobel de la Paz para Mar\u00eda Corina Machado, l\u00edder opositora venezolana","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El Premio Nobel de la Paz 2025 fue otorgado a Mar\u00eda Corina Machado por \u201cpromover los derechos democr\u00e1ticos del pueblo de Venezuela\u201d.El Comit\u00e9 Noruego del Nobel afirm\u00f3 que Mar\u00eda Corina Machado hab\u00eda ayudado a \u201cmantener encendida la llama de la democracia frente a una oscuridad creciente\u201d.Al anunciar el premio en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467258,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/10\/maria-corina-machado-nobel-impacto-futuro-orix\/","url_meta":{"origin":1449780,"position":1},"title":"Mar\u00eda Corina Machado recibi\u00f3 el Nobel de la Paz. As\u00ed puede impactar su premio en el futuro de Venezuela, seg\u00fan expertos","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El Nobel de la Paz otorgado a la dirigente venezolana Mar\u00eda Corina Machado, en la clandestinidad desde las elecciones de 2024 por las acciones del Gobierno del presidente Nicol\u00e1s Maduro contra la disidencia, ser\u00e1 un impulso para las aspiraciones de la oposici\u00f3n de lograr un cambio de r\u00e9gimen a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450631,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/23\/alejandro-sanz-apoyo-lider-opositora-venezolana-maria-corina-machado-orix\/","url_meta":{"origin":1449780,"position":2},"title":"Alejandro Sanz expresa su apoyo a la l\u00edder opositora venezolana Mar\u00eda Corina Machado","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El cantante y compositor espa\u00f1ol Alejandro Sanz mostr\u00f3 este domingo su apoyo a la l\u00edder opositora venezolana Mar\u00eda Corina Machado a trav\u00e9s de un mensaje en sus redes sociales.\"Hay nombres que son llaves capaces de abrir las puertas a un futuro esperanzador\", escribi\u00f3 Sanz en su cuenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467277,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/10\/trump-habla-machado-premio-nobel-paz-trax\/","url_meta":{"origin":1449780,"position":3},"title":"Trump habla con Machado despu\u00e9s de que su Gobierno criticara la decisi\u00f3n de otorgarle el Premio Nobel de la Paz","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, habl\u00f3 este viernes con la opositora venezolana y ganadora del Premio Nobel de la Paz, Mar\u00eda Corina Machado, seg\u00fan inform\u00f3 la Casa Blanca, despu\u00e9s de que el Gobierno de EE.UU. criticara al comit\u00e9 que le otorg\u00f3 el galard\u00f3n.Trump ha manifestado en varias ocasiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452414,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/04\/represion-disidencia-politica-mas-mortifera-ultimos-anos-trax\/","url_meta":{"origin":1449780,"position":4},"title":"La represi\u00f3n de la disidencia pol\u00edtica en Venezuela es la m\u00e1s mort\u00edfera de los \u00faltimos a\u00f1os, seg\u00fan Human Rights Watch","author":"","date":"septiembre 4, 2024","format":false,"excerpt":"(CNN) -- La represi\u00f3n de la disidencia pol\u00edtica en Venezuela con motivo de las controvertidas elecciones presidenciales es la m\u00e1s mort\u00edfera de los \u00faltimos a\u00f1os, seg\u00fan un nuevo an\u00e1lisis de Human Rights Watch.El grupo de derechos humanos dice que ha documentado 11 asesinatos que, seg\u00fan afirma, tuvieron lugar en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472263,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/16\/resultado-venezuela-italia-clasico-mundial-beisbol-orix\/","url_meta":{"origin":1449780,"position":5},"title":"\u00a1Hist\u00f3rico! Venezuela llega a la final del Cl\u00e1sico Mundial de B\u00e9isbol tras vencer a Italia","author":"","date":"marzo 16, 2026","format":false,"excerpt":"El seleccionado de Venezuela escribi\u00f3 este lunes una de las p\u00e1ginas m\u00e1s importantes de su historia en el b\u00e9isbol, al derrotar al combinado nacional de Italia por 4 a 2 en las semifinales del Cl\u00e1sico Mundial, gan\u00e1ndose un boleto directo a la gran final del torneo ante Estados Unidos, este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449780"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449780\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}