{"id":1449824,"date":"2024-05-29T01:03:51","date_gmt":"2024-05-29T08:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/"},"modified":"2024-05-29T01:03:51","modified_gmt":"2024-05-29T08:03:51","slug":"suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","title":{"rendered":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia"},"content":{"rendered":"<p>(CNN) &#8212; A Jenna Ellis, quien asisti\u00f3 como abogada a Donald Trump despu\u00e9s de las elecciones de 2020 y luego se declar\u00f3 culpable el a\u00f1o pasado en el caso de interferencia electoral de Georgia, se le suspendi\u00f3 su licencia de abogada en Colorado.<\/p>\n<p>La suspensi\u00f3n comienza este 2 de julio, seg\u00fan una orden firmada por un juez estatal de Colorado. Ellis ha sido una abogada con licencia para ejercer la abogac\u00eda en Colorado durante m\u00e1s de una d\u00e9cada, seg\u00fan registros judiciales.<\/p>\n<p>Ellis no podr\u00e1 ejercer la abogac\u00eda durante tres a\u00f1os en el estado. Es probable que otros estados que puedan reconocer su licencia de abogada tambi\u00e9n se nieguen a permitirle ejercer la abogac\u00eda.<\/p>\n<p>Esta \u00faltima acci\u00f3n se suma a las consecuencias para otros que ayudaron a Trump, como Rudy Giuliani y John Eastman, quienes tambi\u00e9n est\u00e1n perdiendo su capacidad para ejercer la abogac\u00eda. Las autoridades disciplinarias de abogados de Colorado aprobaron la suspensi\u00f3n debido a las confesiones de Ellis en el caso de Georgia, donde otros como Eastman, Giuliani y el propio Trump a\u00fan enfrentan cargos.<\/p>\n<p>Ellis se declar\u00f3 culpable el a\u00f1o pasado de un delito grave de complicidad en declaraciones falsas y cooperar\u00e1 con los fiscales del condado de Fulton. Fue sentenciada a cinco a\u00f1os de libertad condicional y se le orden\u00f3 pagar US$ 5.000 en restituci\u00f3n.<\/p>\n<p>Jenna Ellis, exabogada de campa\u00f1a de Trump, se declara culpable en el caso de interferencia electoral de Georgia (2023)<\/p>\n<p>Otra excolaboradora de Trump se declara culpable 3:42<\/p>\n<p>Pronunci\u00f3 una declaraci\u00f3n entre l\u00e1grimas ante el juez mientras se declaraba culpable, negando su participaci\u00f3n en los intentos sin precedentes de Trump de anular las elecciones de 2020.<\/p>\n<p>\u201cSi hubiera sabido entonces lo que s\u00e9 ahora, habr\u00eda rechazado representar a Donald Trump en estas impugnaciones postelectorales. Recuerdo esta experiencia con profundo remordimiento\u201d, dijo Ellis.<\/p>\n<p>Antes de su declaraci\u00f3n de culpabilidad en Georgia, el mismo juez disciplinar que la suspendi\u00f3 en Colorado aprob\u00f3 censurar p\u00fablicamente a Ellis por 10 tergiversaciones que hizo despu\u00e9s de las elecciones de 2020, como en apariciones en los medios, en las que insisti\u00f3 en que Trump gan\u00f3 \u201cde manera aplastante\u201d.<\/p>\n<p>La semana pasada, Ellis escribi\u00f3 a las autoridades disciplinarias de la Corte Suprema de Colorado, en un desmesurado mea culpa por su papel en la difusi\u00f3n de las mentiras electorales de Trump, seg\u00fan documentos hechos p\u00fablicos relacionados con sus procedimientos disciplinarios.<\/p>\n<p>Exabogada de Trump admite que las declaraciones sobre las elecciones de 2020 fueron falsas (2023)<\/p>\n<p>Esta carta de Ellis va incluso m\u00e1s all\u00e1 de la disculpa que dio ante el tribunal de Georgia cuando se declar\u00f3 culpable, que se centr\u00f3 m\u00e1s en su propio remordimiento y no describi\u00f3 tan detalladamente c\u00f3mo cre\u00eda que las mentiras de Trump penetraron en su campa\u00f1a y en el pa\u00eds despu\u00e9s de las elecciones de 2020.<\/p>\n<p>\u201cQuiero decir la verdad. Al hacerlo, deseo expresar mi profundo remordimiento y reconocer el da\u00f1o que caus\u00f3 mi mala conducta\u201d, escribi\u00f3 Ellis.<\/p>\n<p>En la carta de dos p\u00e1ginas, Ellis dijo que inicialmente cre\u00eda que las impugnaciones electorales del equipo de Trump se estaban haciendo \u201cde buena fe\u201d, pero fue demasiado entusiasta y tom\u00f3 las mentiras de sus colegas al pie de la letra, alimentando la creencia del p\u00fablico en afirmaciones falsas sobre las elecciones.<\/p>\n<p>&#171;Si hubiera sabido lo que s\u00e9 ahora, no habr\u00eda estado involucrada&#187;, escribi\u00f3.<\/p>\n<p>Jueza aplaza el juicio contra Trump en el caso federal de interferencia electoral<\/p>\n<p>Ellis tambi\u00e9n dijo que esperaba que su repudio p\u00fablico a la posici\u00f3n de Trump despu\u00e9s de las elecciones de 2020 aliente a otros que a\u00fan niegan los resultados de las elecciones a cambiar sus opiniones.<\/p>\n<p>\u201cAceptar\u00e9 con gratitud una suspensi\u00f3n de tres a\u00f1os en mi ejercicio de la abogac\u00eda como consecuencia de mis acciones&#8230; Espero alentar a otros que todav\u00eda crean que las elecciones fueron &#8216;robadas&#8217; a considerar cambiar su posici\u00f3n. Todo lo que ha salido a la luz desde entonces no ha probado esa afirmaci\u00f3n\u201d, escribi\u00f3 Ellis.<\/p>\n<p>Ellis tambi\u00e9n fue acusada en Arizona el mes pasado por presuntamente conspirar para anular los resultados de las elecciones presidenciales de 2020, junto con varios electores falsos y varias otras personas relacionadas con la campa\u00f1a de Trump. Est\u00e1 previsto que comparezca ante el tribunal el pr\u00f3ximo mes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; A Jenna Ellis, quien asisti\u00f3 como abogada a Donald Trump despu\u00e9s de las elecciones de 2020 y luego se declar\u00f3 culpable el a\u00f1o pasado en el caso de interferencia electoral de Georgia, se le suspendi\u00f3 su licencia de abogada en Colorado. La suspensi\u00f3n comienza este 2 de julio, seg\u00fan una orden firmada por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449824","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; A Jenna Ellis, quien asisti\u00f3 como abogada a Donald Trump despu\u00e9s de las elecciones de 2020 y luego se declar\u00f3 culpable el a\u00f1o pasado en el caso de interferencia electoral de Georgia, se le suspendi\u00f3 su licencia de abogada en Colorado. La suspensi\u00f3n comienza este 2 de julio, seg\u00fan una orden firmada por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T08:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia\",\"datePublished\":\"2024-05-29T08:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\"},\"wordCount\":784,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\",\"name\":\"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-29T08:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia - Noticias","og_description":"(CNN) &#8212; A Jenna Ellis, quien asisti\u00f3 como abogada a Donald Trump despu\u00e9s de las elecciones de 2020 y luego se declar\u00f3 culpable el a\u00f1o pasado en el caso de interferencia electoral de Georgia, se le suspendi\u00f3 su licencia de abogada en Colorado. La suspensi\u00f3n comienza este 2 de julio, seg\u00fan una orden firmada por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-29T08:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/"},"author":{"name":"","@id":""},"headline":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia","datePublished":"2024-05-29T08:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/"},"wordCount":784,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","name":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-29T08:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Suspenden la licencia de abogada de la exabogada de campa\u00f1a de Trump, Jenna Ellis, despu\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/29\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-29T08:03:51Z","datePublished":"2024-05-29T08:03:51Z","dateModified":"2024-05-29T08:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Suspenden la licencia de abogada de la exabogada de campa\\u00f1a de Trump, Jenna Ellis, despu\\u00e9s de declararse culpable en un caso de interferencia electoral en Georgia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/29\\\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/29\\\/suspenden-licencia-abogada-trump-jenna-ellis-georgia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-29T08:03:51Z\",\"datePublished\":\"2024-05-29T08:03:51Z\",\"dateModified\":\"2024-05-29T08:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458924,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/19\/que-pasa-que-hacer-migrante-me-detienen-orix\/","url_meta":{"origin":1449824,"position":0},"title":"\u00bfQu\u00e9 hacer si soy migrante y me detienen en EE.UU.?","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Un mes despu\u00e9s del comienzo del segundo mandato presidencial de Donald Trump, el Gobierno de Estados Unidos ha realizado aproximadamente 14.000 detenciones de migrantes indocumentados, asegur\u00f3 recientemente Tom Homan, el \u201czar de la frontera\u201d del mandatario.Seg\u00fan Homan, una \u201cgran mayor\u00eda\u201d de los detenidos tiene antecedentes penales, pero tambi\u00e9n \u201ctenemos algunos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458704,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/13\/juez-extiende-pausa-desmantelamiento-usaid-trax\/","url_meta":{"origin":1449824,"position":1},"title":"Juez extiende la pausa para el desmantelamiento de USAID por parte de Trump hasta el 21 de febrero","author":"","date":"febrero 13, 2025","format":false,"excerpt":"Un juez federal extendi\u00f3 la pausa en el desmantelamiento de USAID por parte del Gobierno de Trump por otra semana, tras una extensa audiencia este jueves.El caso es una de las pruebas m\u00e1s significativas de la capacidad del presidente Donald Trump para reducir la fuerza laboral federal y cerrar una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456754,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/19\/luigi-mangione-jueves-audiencia-extradicion-trax\/","url_meta":{"origin":1449824,"position":2},"title":"Luigi Mangione comparece este jueves en su audiencia de extradici\u00f3n","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Luigi Mangione, el hombre acusado del asesinato del CEO de UnitedHealthcare, Brian Thompson, comparecer\u00e1 este jueves ante un tribunal de Pensilvania.Un juez celebrar\u00e1 primero una audiencia preliminar sobre los cargos a los que se enfrenta Mangione en Pensilvania, antes de que otro juez presida una audiencia de extradici\u00f3n, durante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457424,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/10\/trump-sentenciado-licencia-incondicional\/","url_meta":{"origin":1449824,"position":3},"title":"Trump es sentenciado a licencia incondicional, sin pena de c\u00e1rcel ni sanciones en el caso de pago de dinero por silencio","author":"","date":"enero 10, 2025","format":false,"excerpt":"El juez Juan Merchan sentenci\u00f3 este viernes a Donald Trump a licencia incondicional en el caso en el que fue condenado el a\u00f1o pasado por 34 cargos de fraude empresarial relacionados con el pago de dinero a Stormy Daniels a cambio de su silencio durante la campa\u00f1a presidencial de 2016.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460694,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/01\/noboa-deja-presidencia-campana-licencia-orix\/","url_meta":{"origin":1449824,"position":4},"title":"Noboa notifica que deja la presidencia para la campa\u00f1a, aunque la Asamblea Nacional lo llama a pedir licencia","author":"","date":"abril 1, 2025","format":false,"excerpt":"El presidente de Ecuador, Daniel Noboa, inform\u00f3 al Consejo Nacional Electoral (CNE) que no ejercer\u00e1 su cargo temporalmente para hacer proselitismo de cara a la segunda vuelta del 13 de abril, lo que reaviv\u00f3 la controversia en torno a si debe solicitar licencia al Congreso para participar en las elecciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465332,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/09\/retiran-cargos-acusado-secuestro-walmart-trax\/","url_meta":{"origin":1449824,"position":5},"title":"Retiran cargos contra acusado de intentar secuestrar a ni\u00f1o en un Walmart tras dudas por im\u00e1genes en c\u00e1mara de seguridad","author":"","date":"agosto 9, 2025","format":false,"excerpt":"Se desestimaron los cargos contra un hombre que enfrentaba acusaciones de intento de secuestro y otros delitos despu\u00e9s de que una madre lo acusara de intentar arrebatarle a su hijo de dos a\u00f1os en un Walmart de Georgia, seg\u00fan muestran los registros judiciales.Mahendra Patel se encontr\u00f3 con Caroline Miller, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449824"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449824\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}