{"id":1450020,"date":"2024-06-04T11:03:50","date_gmt":"2024-06-04T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/"},"modified":"2024-06-04T11:03:50","modified_gmt":"2024-06-04T18:03:50","slug":"carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","title":{"rendered":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes"},"content":{"rendered":"<p>(CNN) &#8212; Un grupo de expertos de OpenAI exige que las empresas de inteligencia artificial sean mucho m\u00e1s transparentes sobre los \u201cgraves riesgos\u201d de la IA y que protejan a los empleados que expresen preocupaciones sobre la tecnolog\u00eda que est\u00e1n desarrollando.<\/p>\n<p>\u201cLas empresas de inteligencia artificial tienen fuertes incentivos financieros para evitar una supervisi\u00f3n efectiva\u201d, se lee en la carta abierta publicada el martes y firmada por empleados actuales y anteriores de empresas de inteligencia artificial, incluido OpenAI, el creador detr\u00e1s de la famosa herramienta ChatGPT.<\/p>\n<p>Tambi\u00e9n pidieron a las empresas de inteligencia artificial que fomenten \u201cuna cultura de cr\u00edtica abierta\u201d que d\u00e9 la bienvenida, en lugar de castigar, a las personas que expresan sus preocupaciones, especialmente cuando la ley lucha por ponerse al d\u00eda con el r\u00e1pido avance de la tecnolog\u00eda.<\/p>\n<p>Las empresas han reconocido los &#171;graves riesgos&#187; que plantea la IA &#8211;desde la manipulaci\u00f3n hasta una p\u00e9rdida de control, conocida como &#171;singularidad, que podr\u00eda resultar potencialmente en la extinci\u00f3n humana&#8211;, pero deber\u00edan hacer m\u00e1s para educar al p\u00fablico sobre los riesgos y las medidas de protecci\u00f3n, escribi\u00f3 el grupo.<\/p>\n<p>Tal como est\u00e1 vigente la ley, dijeron los empleados de IA, no creen que las empresas de IA compartan informaci\u00f3n clave sobre la tecnolog\u00eda de forma voluntaria.<\/p>\n<p>Es esencial, entonces, que los empleados actuales y anteriores hablen y que las empresas no apliquen acuerdos de \u201cdescr\u00e9dito\u201d ni tomen represalias contra quienes expresan preocupaciones relacionadas con el riesgo. &#171;Las protecciones ordinarias a los denunciantes son insuficientes porque se centran en actividades ilegales, mientras que muchos de los riesgos que nos preocupan a\u00fan no est\u00e1n regulados&#187;, escribi\u00f3 el grupo.<\/p>\n<p>Empleados actuales y anteriores de OpenAI hablan sobre la necesidad de que la empresa y otros similares sean m\u00e1s transparentes sobre la tecnolog\u00eda que est\u00e1n desarrollando.. Cr\u00e9dito: Didem Mente\/Anadolu\/Getty Images<\/p>\n<p>Su carta llega en un momento en que las empresas se apresuran a implementar herramientas de IA generativa en sus productos, mientras los reguladores gubernamentales, las empresas y los consumidores luchan por un uso responsable. Mientras tanto, muchos expertos en tecnolog\u00eda, investigadores y l\u00edderes han pedido una pausa temporal en la carrera de la IA, o que el gobierno intervenga y cree una moratoria.<\/p>\n<p>La respuesta de OpenAI<\/p>\n<p>En respuesta a la carta, el portavoz de OpenAI dijo a CNN que est\u00e1 &#171;orgulloso de nuestro historial proporcionando los sistemas de IA m\u00e1s capaces y seguros y cree en nuestro enfoque cient\u00edfico para abordar el riesgo\u201d, y agreg\u00f3 que la compa\u00f1\u00eda est\u00e1 de acuerdo en que &#171;un debate riguroso es crucial dada la importancia de esta tecnolog\u00eda\u201d.<\/p>\n<p>OpenAI se\u00f1al\u00f3 que tiene una l\u00ednea directa de integridad an\u00f3nima y un Comit\u00e9 de Seguridad dirigido por miembros de su junta directiva y l\u00edderes de seguridad de la empresa. La empresa no vende informaci\u00f3n personal, no crea perfiles de usuario ni utiliza esos datos para dirigirse a nadie ni vender nada.<\/p>\n<p>Sin embargo, Daniel Ziegler, uno de los organizadores detr\u00e1s de la carta y uno de los primeros ingenieros de aprendizaje autom\u00e1tico que trabaj\u00f3 en OpenAI entre 2018 y 2021, dijo a CNN que es importante permanecer esc\u00e9ptico sobre el compromiso de la empresa con la transparencia.<\/p>\n<p>&#171;Es realmente dif\u00edcil decir desde fuera qu\u00e9 tan en serio est\u00e1n tomando sus compromisos de aumentar la seguridad y determinar los da\u00f1os sociales, especialmente porque existen fuertes presiones comerciales para actuar muy r\u00e1pido&#187;, dijo. &#171;Es realmente importante tener la cultura y los procesos adecuados para que los empleados puedan expresarse de manera espec\u00edfica cuando tengan inquietudes&#187;.<\/p>\n<p>Espera que m\u00e1s profesionales de la industria de la IA hagan p\u00fablicas sus preocupaciones como resultado de la carta.<\/p>\n<p>Mientras tanto, se espera que Apple anuncie una asociaci\u00f3n con OpenAI en su Conferencia Mundial de Desarrolladores anual para llevar la IA generativa al iPhone.<\/p>\n<p>&#171;Vemos la IA generativa como una oportunidad clave en todos nuestros productos y creemos que tenemos ventajas que nos diferencian en eso&#187;, dijo el director ejecutivo de Apple, Tim Cook, en la conferencia telef\u00f3nica sobre resultados m\u00e1s reciente de la compa\u00f1\u00eda a principios de mayo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un grupo de expertos de OpenAI exige que las empresas de inteligencia artificial sean mucho m\u00e1s transparentes sobre los \u201cgraves riesgos\u201d de la IA y que protejan a los empleados que expresen preocupaciones sobre la tecnolog\u00eda que est\u00e1n desarrollando. \u201cLas empresas de inteligencia artificial tienen fuertes incentivos financieros para evitar una supervisi\u00f3n efectiva\u201d, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450020","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un grupo de expertos de OpenAI exige que las empresas de inteligencia artificial sean mucho m\u00e1s transparentes sobre los \u201cgraves riesgos\u201d de la IA y que protejan a los empleados que expresen preocupaciones sobre la tecnolog\u00eda que est\u00e1n desarrollando. \u201cLas empresas de inteligencia artificial tienen fuertes incentivos financieros para evitar una supervisi\u00f3n efectiva\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes\",\"datePublished\":\"2024-06-04T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\"},\"wordCount\":752,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\",\"name\":\"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-04T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes - Noticias","og_description":"(CNN) &#8212; Un grupo de expertos de OpenAI exige que las empresas de inteligencia artificial sean mucho m\u00e1s transparentes sobre los \u201cgraves riesgos\u201d de la IA y que protejan a los empleados que expresen preocupaciones sobre la tecnolog\u00eda que est\u00e1n desarrollando. \u201cLas empresas de inteligencia artificial tienen fuertes incentivos financieros para evitar una supervisi\u00f3n efectiva\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-04T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/"},"author":{"name":"","@id":""},"headline":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes","datePublished":"2024-06-04T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/"},"wordCount":752,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","name":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-04T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-04T18:03:50Z","datePublished":"2024-06-04T18:03:50Z","dateModified":"2024-06-04T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Carta abierta de los expertos de OpenAI advierte sobre \\u201criesgos graves\\u201d y pide protecci\\u00f3n para los denunciantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/06\\\/04\\\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/06\\\/04\\\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-04T18:03:50Z\",\"datePublished\":\"2024-06-04T18:03:50Z\",\"dateModified\":\"2024-06-04T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451429,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/25\/openai-google-motor-busqueda-inteligencia-artifical-trax\/","url_meta":{"origin":1450020,"position":0},"title":"OpenAI le compite a Google con un nuevo motor de b\u00fasqueda de inteligencia artificial","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- OpenAI anunci\u00f3 este jueves su amenaza m\u00e1s directa hasta el momento para sus incondicionales rivales de las grandes tecnol\u00f3gicas: un motor de b\u00fasqueda que utiliza inteligencia artificial incorporada desde el principio.La empresa est\u00e1 probando SearchGPT, que combinar\u00e1 su tecnolog\u00eda de inteligencia artificial con informaci\u00f3n en tiempo real de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469677,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/30\/inteligencia-artificial-sacudio-mundo-que-viene-trax\/","url_meta":{"origin":1450020,"position":1},"title":"C\u00f3mo la IA sacudi\u00f3 el mundo en 2025 y qu\u00e9 viene despu\u00e9s","author":"","date":"diciembre 30, 2025","format":false,"excerpt":"Cientos de miles de millones de d\u00f3lares gastados, un aumento en las preocupaciones de salud mental y miles de empleos perdidos.\u00bfEl v\u00ednculo entre todo esto? La inteligencia artificial, la tecnolog\u00eda de moda pero controvertida que se presenta como el futuro o la pr\u00f3xima burbuja del mercado de valores, dependiendo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468023,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/04\/studio-ghibli-openai-contenidos-ia-orix\/","url_meta":{"origin":1450020,"position":2},"title":"Studio Ghibli y otras empresas japonesas le piden a OpenAI que deje de usar sus contenidos para entrenar su IA","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Los principales creadores de anime y manga de Jap\u00f3n se han unido para hacer frente a la inteligencia artificial.La Asociaci\u00f3n para la Distribuci\u00f3n de Contenidos en el Extranjero (CODA, por sus siglas en ingl\u00e9s), que promueve los contenidos japoneses en el exterior y los protege de la pirater\u00eda \u2013y que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469204,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/12\/disney-openai-apuesta-futuro-contenido-baja-calidad-trax\/","url_meta":{"origin":1450020,"position":3},"title":"El acuerdo de Disney con OpenAI es una apuesta de US$ 1.000 millones sobre el futuro del contenido de baja calidad","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"A simple vista, el plan de Disney para invertir US$ 1.000 millones en OpenAI y licenciar sus personajes a Sora parece como si un gigante se rindiera ante un peque\u00f1o rival. \u00bfPor qu\u00e9 Disney abrir\u00eda su valiosa propiedad intelectual al p\u00fablico para que hagan lo que quieran? Es la misma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462670,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/22\/acuerdos-masivos-golfo-liderazgo-ee-uu-dominio-global-ia-trax\/","url_meta":{"origin":1450020,"position":4},"title":"\u00bfLos acuerdos &#171;masivos&#187; con el Golfo consolidar\u00e1n el liderazgo de EE.UU. en la carrera por el dominio global de la IA?","author":"","date":"mayo 22, 2025","format":false,"excerpt":"La visita rel\u00e1mpago del presidente de Estados Unidos Donald Trump la semana pasada a Medio Oriente gener\u00f3 una ola de acuerdos en inteligencia artificial que podr\u00edan transformar el panorama tecnol\u00f3gico mundial.El 12 de mayo, el fondo soberano de inversi\u00f3n p\u00fablica de Arabia Saudita anunci\u00f3 la creaci\u00f3n de la startup de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458240,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/04\/google-elimina-tecnologia-ia-armas-vigilancia-trax\/","url_meta":{"origin":1450020,"position":5},"title":"Google elimina su promesa de no usar tecnolog\u00eda de inteligencia artificial para armas o vigilancia","author":"","date":"febrero 4, 2025","format":false,"excerpt":"La pol\u00edtica de \u00e9tica e inteligencia artificial actualizada de Google elimina su anterior promesa de no usar la tecnolog\u00eda para desarrollar armas y vigilancia.En una versi\u00f3n anterior de los principios vista por CNN en el archivo de internet Wayback Machine, la compa\u00f1\u00eda inclu\u00eda aplicaciones que no perseguir\u00eda. Una de esas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1450020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1450020"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1450020\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1450020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1450020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1450020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}