{"id":1450669,"date":"2024-06-24T15:03:48","date_gmt":"2024-06-24T22:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/"},"modified":"2024-06-24T15:03:48","modified_gmt":"2024-06-24T22:03:48","slug":"mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","title":{"rendered":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, anunci\u00f3 este lunes que llegaron a un acuerdo con las autoridades de Estados Unidos para implementar un modelo para proteger la labor de los inspectores de sanidad agr\u00edcola que certifican el aguacate y mango de exportaci\u00f3n a ese pa\u00eds, suspendida durante algunos d\u00edas de la semana pasada por un incidente de seguridad.<\/p>\n<p>Desde Morelia, la capital del estado, y en compa\u00f1\u00eda del embajador de Estados Unidos en M\u00e9xico, Ken Salazar, el mandatario estatal explic\u00f3 \u2015sin dar detalles\u2015 que el modelo de seguridad para los funcionarios estadounidenses ser\u00e1 permanente.<\/p>\n<p>EE.UU. reanuda inspecci\u00f3n en Michoac\u00e1n para exportar aguacate y mango tras incidente<\/p>\n<p>&#171;Comentarles que ya se ha logrado un acuerdo, un modelo de seguridad para los inspectores USDA-APHIS (Departamento de Agricultura de EE.UU.-Servicio de Inspecci\u00f3n Sanitaria de Animales y Plantas, por sus siglas en ingl\u00e9s) que desde el s\u00e1bado paulatinamente se ha venido recuperando la actividad de estos inspectores de la embajada norteamericana, tan importantes para la agroexportaci\u00f3n del aguacate michoacano, mango y otros productos. Hemos estado en comunicaci\u00f3n constante con la embajada norteamericana, agradezco esa apertura y di\u00e1logo permanente que nos ha permitido llegar a este gran acuerdo para reestablecer el trabajo de los inspectores y con ello restablecer la exportaci\u00f3n de mango y aguacate&#187;, abund\u00f3 Ram\u00edrez Bedolla.<\/p>\n<p>Salazar dijo que adem\u00e1s se abord\u00f3 el tema ambiental y el de seguridad laboral de los trabajadores relacionados con la producci\u00f3n, empaque y exportaci\u00f3n de estos productos michoacanos.<\/p>\n<p>En la reuni\u00f3n estuvieron tambi\u00e9n el secretario de Agricultura, V\u00edctor Manuel Villalobos, y Roberto Velasco, jefe de Unidad para Am\u00e9rica del Norte de la Secretar\u00eda de Relaciones Exteriores.<\/p>\n<p>Salazar anunci\u00f3 este viernes que los inspectores de sanidad animal y vegetal del Departamento de Agricultura, que certifican los productos con destino comercial hacia EE.UU., regresar\u00edan paulatinamente a las plantas de empaque de aguacate y mango en Michoac\u00e1n para as\u00ed poder reanudar la exportaci\u00f3n, luego de que a inicios de semana la revisi\u00f3n fue suspendida por una agresi\u00f3n a sus empleados. Entonces, la Asociaci\u00f3n de Productores y Empacadores Exportadores de Aguacate de M\u00e9xico (APEAM) se\u00f1al\u00f3 que el incidente hab\u00eda sido \u201cajeno a la industria aguacatera\u201d. La Fiscal\u00eda de Michoac\u00e1n dijo a CNN que abri\u00f3 una carpeta de investigaci\u00f3n y se recuper\u00f3 la unidad de la que los empleados fueron despojados, as\u00ed como sus pertenencias.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, anunci\u00f3 este lunes que llegaron a un acuerdo con las autoridades de Estados Unidos para implementar un modelo para proteger la labor de los inspectores de sanidad agr\u00edcola que certifican el aguacate y mango de exportaci\u00f3n a ese pa\u00eds, suspendida durante algunos d\u00edas de la semana [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450669","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0El gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, anunci\u00f3 este lunes que llegaron a un acuerdo con las autoridades de Estados Unidos para implementar un modelo para proteger la labor de los inspectores de sanidad agr\u00edcola que certifican el aguacate y mango de exportaci\u00f3n a ese pa\u00eds, suspendida durante algunos d\u00edas de la semana [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T22:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas\",\"datePublished\":\"2024-06-24T22:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\"},\"wordCount\":459,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\",\"name\":\"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-24T22:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0El gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, anunci\u00f3 este lunes que llegaron a un acuerdo con las autoridades de Estados Unidos para implementar un modelo para proteger la labor de los inspectores de sanidad agr\u00edcola que certifican el aguacate y mango de exportaci\u00f3n a ese pa\u00eds, suspendida durante algunos d\u00edas de la semana [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-24T22:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/"},"author":{"name":"","@id":""},"headline":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas","datePublished":"2024-06-24T22:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","name":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-24T22:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\u00edcolas","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/06\/24\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-24T22:03:48Z","datePublished":"2024-06-24T22:03:48Z","dateModified":"2024-06-24T22:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9xico y EE.UU. anuncian modelo de seguridad para inspectores agr\\u00edcolas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/06\\\/24\\\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/06\\\/24\\\/mexico-estados-unidos-modelo-seguridad-inspectores-agricolas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-24T22:03:48Z\",\"datePublished\":\"2024-06-24T22:03:48Z\",\"dateModified\":\"2024-06-24T22:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450474,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/18\/eeuu-suspende-importacion-de-aguacates-de-michoacan-orix\/","url_meta":{"origin":1450669,"position":0},"title":"Gobierno de EE.UU. suspende la importaci\u00f3n de aguacates de Michoac\u00e1n","author":"","date":"junio 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La exportaci\u00f3n de aguacate procedente del estado mexicano de Michoac\u00e1n a Estados Unidos fue suspendida este fin de semana, inform\u00f3 este lunes la Asociaci\u00f3n de Productores y Empacadores Exportadores de Aguacate de M\u00e9xico (APEAM).En un comunicado difundido este lunes, la APEAM indica que \"la interrupci\u00f3n de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465921,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/27\/inspectores-nucleares-onu-regresan-iran-conflicto-israel-trax\/","url_meta":{"origin":1450669,"position":1},"title":"Inspectores nucleares de la ONU regresan a Ir\u00e1n por primera vez desde el conflicto con Israel","author":"","date":"agosto 27, 2025","format":false,"excerpt":"Inspectores del organismo nuclear de las Naciones Unidas regresaron a Ir\u00e1n, seg\u00fan confirmaron el jefe de la agencia y funcionarios iran\u00edes, a pesar de la negativa iran\u00ed de cooperar con ese organismo.\u201cEstamos a punto de reiniciar\u2026 hay muchas instalaciones (nucleares), algunas fueron atacadas y otras no. Estamos discutiendo qu\u00e9 tipo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460907,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/07\/sobornos-inspectores-personas-sin-documentos-ap\/","url_meta":{"origin":1450669,"position":2},"title":"Acusan a dos inspectores fronterizos de EE.UU. \u200b\u200bde aceptar sobornos para dejar entrar a personas sin documentos","author":"","date":"abril 7, 2025","format":false,"excerpt":"Dos inspectores fronterizos de Estados Unidos en el sur de California fueron acusados \u200b\u200bde aceptar miles de d\u00f3lares en sobornos para permitir que personas ingresaran al pa\u00eds a trav\u00e9s del puerto de entrada m\u00e1s transitado del pa\u00eds sin mostrar documentos, dijeron los fiscales.Los oficiales de Aduanas y Protecci\u00f3n Fronteriza de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465509,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/14\/ee-uu-sanciona-presuntos-lideres-carteles-unidos-los-viagras-orix\/","url_meta":{"origin":1450669,"position":3},"title":"EE.UU. sanciona a siete presuntos l\u00edderes de las organizaciones criminales mexicanas C\u00e1rteles Unidos y Los Viagras","author":"","date":"agosto 14, 2025","format":false,"excerpt":"El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a siete personas que considera presuntos l\u00edderes de las organizaciones criminales mexicanas C\u00e1rteles Unidos y Los Viagras, a las que atribuy\u00f3 la producci\u00f3n y el env\u00edo de drogas a territorio estadounidense y la generaci\u00f3n de violencia en M\u00e9xico, entre otros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471705,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/26\/pentagono-derriba-dron-cbp-sistema-laser-trax\/","url_meta":{"origin":1450669,"position":4},"title":"El Pent\u00e1gono derriba un dron de la CBP de EE.UU. con un sistema l\u00e1ser, dicen legisladores","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Las Fuerzas Armadas de Estados Unidos utilizaron un controvertido sistema l\u00e1ser antidrones para derribar una aeronave no tripulada operada por la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP, por sus siglas en ingl\u00e9s) en Texas, seg\u00fan representantes del Congreso.\u201cNos explota la cabeza con la noticia de que, seg\u00fan se informa,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472422,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/21\/aeropuertos-sin-tsa-demoras-retrasos-trax\/","url_meta":{"origin":1450669,"position":5},"title":"\u00bfPor qu\u00e9 solo los pasajeros de 20 aeropuertos de EE.UU. no sufren largas filas ni retrasos?","author":"","date":"marzo 21, 2026","format":false,"excerpt":"En 20 aeropuertos de Estados Unidos, la inspecci\u00f3n de seguridad no est\u00e1 a cargo de la Administraci\u00f3n de Seguridad del Transporte (TSA), sino de empresas privadas, y sus puntos de control no presentan largas filas.Aeropuertos como el Internacional de San Francisco, el Internacional de Kansas City, el de Orlando Sanford\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1450669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1450669"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1450669\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1450669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1450669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1450669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}