{"id":1452182,"date":"2024-08-26T17:03:53","date_gmt":"2024-08-27T00:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/"},"modified":"2024-08-26T17:03:53","modified_gmt":"2024-08-27T00:03:53","slug":"maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","title":{"rendered":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La l\u00edder opositora venezolana Mar\u00eda Corina Machado convoc\u00f3 este lunes a una nueva jornada de protestas en el pa\u00eds y el mundo para este mi\u00e9rcoles, cuando se cumple un mes de las elecciones presidenciales del 28 de julio, en las que la oposici\u00f3n asegura que triunf\u00f3 en las urnas con su candidato Edmundo Gonz\u00e1lez, al contrario que los resultados anunciados por las autoridades.<\/p>\n<p>&#171;Acta mata sentencia&#187;, dice Machado al inicio de un video publicado en sus cuentas de redes sociales y en el que alude a la decisi\u00f3n de la Sala Electoral del Tribunal Supremo de Justicia (TSJ), que la semana pasada valid\u00f3 los resultados del Consejo Nacional Electoral (CNE) que dieron por ganador de los comicios al presidente Nicol\u00e1s Maduro. Ambas entidades est\u00e1n encabezadas por funcionarios que obedecen al chavismo.<\/p>\n<p>&#171;Por eso nos vemos este mi\u00e9rcoles 28 de agosto en las calles. A un mes de nuestra gloriosa victoria del 28 de julio, cuando votamos, ganamos y recogimos nuestras actas que demuestran la victoria apabullante de Edmundo Gonz\u00e1lez&#187;, indic\u00f3 Machado en su video.<\/p>\n<p>\u201c(Las autoridades) no presentaron ning\u00fan papelito y salieron corriendo a esconderse detr\u00e1s de su TSJ, sometido a la tiran\u00eda, que no tiene vela en este entierro, para lavarle la cara a su CNE fraudulento&#187;, dijo.<\/p>\n<p>Simpatizantes ondean banderas venezolanas el 17 de agosto de 2024 en Caracas, Venezuela. Cr\u00e9dito: Jes\u00fas Vargas\/Getty Images<\/p>\n<p>Hasta este lunes, ni el CNE ni el TSJ se hab\u00edan pronunciado p\u00fablicamente sobre los se\u00f1alamientos de Machado. CNN trabaja para obtener comentarios al respecto.<\/p>\n<p>La convocatoria de Machado se da a dos d\u00edas de que se cumpla un mes luego de las elecciones presidenciales y sin que hasta la fecha el CNE haya publicado en detalle los resultados electorales de la contienda. Sin presentar pruebas ni detallar en qu\u00e9 consisti\u00f3 su peritaje, el TSJ declar\u00f3 v\u00e1lidos sus resultados, algo que ha sido criticado por la oposici\u00f3n que alega fraude, y por gran parte de la comunidad internacional que pide la publicaci\u00f3n en detalle de los resultados.<\/p>\n<p>Este lunes, la p\u00e1gina web del CNE, que hab\u00eda estado ca\u00edda desde el d\u00eda de la elecci\u00f3n, volvi\u00f3 a estar en l\u00ednea, sin publicar los resultados detallados de los comicios por centros y mesas de votaci\u00f3n. La entidad dijo en un comunicado que lo har\u00eda &#171;en el lapso de ley&#187;, tal y como se lo solicit\u00f3 el TSJ en su resoluci\u00f3n que valid\u00f3 el controvertido triunfo de Maduro.<\/p>\n<p>Oficialismo dice que saldr\u00e1 a marchar el mismo d\u00eda<\/p>\n<p>El primer vicepresidente del Partido Socialista Unido de Venezuela, Diosdado Cabello, inform\u00f3 este lunes en conferencia de prensa que el chavismo saldr\u00e1 a las calles este mi\u00e9rcoles para celebrar el primer mes de lo que llam\u00f3 &#171;la gran victoria popular del 28 de julio&#187;, cuando el pa\u00eds celebr\u00f3 elecciones presidenciales en las que el Consejo Nacional Electoral (CNE) dio por ganador al presidente Nicol\u00e1s Maduro, sin que hasta la fecha se conozcan los resultados detallados de los comicios por centros y mesas de votaci\u00f3n.<\/p>\n<p>La declaratoria de triunfo del mandatario ha sido criticada por la oposici\u00f3n, que alega fraude, y por gran parte de la comunidad internacional que pide la publicaci\u00f3n en detalle de los resultados.<\/p>\n<p>-Osmary Hern\u00e1ndez colabor\u00f3 en este reporte<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La l\u00edder opositora venezolana Mar\u00eda Corina Machado convoc\u00f3 este lunes a una nueva jornada de protestas en el pa\u00eds y el mundo para este mi\u00e9rcoles, cuando se cumple un mes de las elecciones presidenciales del 28 de julio, en las que la oposici\u00f3n asegura que triunf\u00f3 en las urnas con su candidato [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452182","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La l\u00edder opositora venezolana Mar\u00eda Corina Machado convoc\u00f3 este lunes a una nueva jornada de protestas en el pa\u00eds y el mundo para este mi\u00e9rcoles, cuando se cumple un mes de las elecciones presidenciales del 28 de julio, en las que la oposici\u00f3n asegura que triunf\u00f3 en las urnas con su candidato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T00:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio\",\"datePublished\":\"2024-08-27T00:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\",\"name\":\"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-27T00:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La l\u00edder opositora venezolana Mar\u00eda Corina Machado convoc\u00f3 este lunes a una nueva jornada de protestas en el pa\u00eds y el mundo para este mi\u00e9rcoles, cuando se cumple un mes de las elecciones presidenciales del 28 de julio, en las que la oposici\u00f3n asegura que triunf\u00f3 en las urnas con su candidato [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2024-08-27T00:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio","datePublished":"2024-08-27T00:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","name":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-27T00:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-27T00:03:53Z","datePublished":"2024-08-27T00:03:53Z","dateModified":"2024-08-27T00:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mar\\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/08\\\/26\\\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/08\\\/26\\\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-27T00:03:53Z\",\"datePublished\":\"2024-08-27T00:03:53Z\",\"dateModified\":\"2024-08-27T00:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452219,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/27\/protestas-elecciones-venezuela-un-mes-oposicion-oficialismo-orix\/","url_meta":{"origin":1452182,"position":0},"title":"Oposici\u00f3n y oficialismo vuelven a las calles de Venezuela un mes despu\u00e9s de las elecciones: as\u00ed llegan las protestas","author":"","date":"agosto 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este mi\u00e9rcoles se cumple un mes de las elecciones presidenciales en Venezuela, en las que el Consejo Nacional Electoral (CNE) dio por ganador al presidente Nicol\u00e1s Maduro, sin que hasta la fecha se conozcan los resultados detallados de los comicios por centros y mesas de votaci\u00f3n. Han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451552,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/01\/maria-corina-machado-limita-apariciones-publicas-persecucion-maduro-orix\/","url_meta":{"origin":1452182,"position":1},"title":"Mar\u00eda Corina Machado limita sus apariciones p\u00fablicas ante persecuci\u00f3n del Gobierno de Maduro","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La l\u00edder opositora Maria Corina Machado decidi\u00f3 limitar sus apariciones p\u00fablicas en vista de la persecuci\u00f3n iniciada por el Gobierno de Venezuela tras los controvertidos resultados de las elecciones presidenciales del domingo, confirm\u00f3 a CNN una fuente del equipo de campa\u00f1a de la exdiputada y fundadora del movimiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453181,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/28\/maduro-venezuela-critica-edmundo-gonzalez-maria-corina-machado-orix\/","url_meta":{"origin":1452182,"position":2},"title":"Dos meses despu\u00e9s de las controversiales elecciones, Nicol\u00e1s Maduro critica la salida de Edmundo Gonz\u00e1lez y sugiere sin pruebas que Mar\u00eda Corina Machado abandonar\u00e1 Venezuela","author":"","date":"septiembre 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Venezuela, Nicol\u00e1s Maduro, critic\u00f3 este s\u00e1bado la salida a Espa\u00f1a del candidato presidencial opositor Edmundo Gonz\u00e1lez Urrutia y sugiri\u00f3, sin mayores explicaciones o pruebas, que Mar\u00eda Corina Machado podr\u00eda dejar el pa\u00eds.\"Y el cobarde de Edmundo Gonz\u00e1lez Urrutia huy\u00f3, se fue, claudic\u00f3, capitul\u00f3, abandon\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451919,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/16\/maduro-machado-rechazan-propuesta-repetir-elecciones-venezuela-orix\/","url_meta":{"origin":1452182,"position":3},"title":"Tanto Nicol\u00e1s Maduro como Mar\u00eda Corina Machado rechazan la propuesta de nuevas elecciones en Venezuela","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Una propuesta para celebrar nuevas elecciones en Venezuela, originalmente planteada por el principal asesor de pol\u00edtica internacional de Lula da Silva y posteriormente respaldada por Colombia, parece ser rechazada en el pa\u00eds, tanto por el Gobierno de Nicolc\u00e1s Maduro como por la oposici\u00f3n, encabezada por Mar\u00eda Corina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451524,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/31\/carter-center-eleccion-presidencial-venezuela-no-considerada-democratica-orix\/","url_meta":{"origin":1452182,"position":4},"title":"Elecci\u00f3n presidencial de Venezuela &#171;no puede ser considerada democr\u00e1tica&#187;, dice Centro Carter","author":"","date":"julio 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Centro Carter, una de las pocas instituciones independientes autorizadas a monitorear las elecciones venezolanas, dijo este martes que la elecci\u00f3n presidencial de Venezuela \"no se adecu\u00f3 a par\u00e1metros y est\u00e1ndares internacionales de integridad electoral y no puede ser considerada como democr\u00e1tica\".En un comunicado publicado a \u00faltima\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464901,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/27\/maria-corina-machado-mapa-electoral-orix\/","url_meta":{"origin":1452182,"position":5},"title":"Mar\u00eda Corina Machado dice que el mapa electoral de Venezuela &#171;no refleja la realidad del pa\u00eds&#187;","author":"","date":"julio 27, 2025","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo que el mapa electoral de la naci\u00f3n sudamericana, donde el oficialista Partido Socialista Unido de Venezuela (PSUV) ha ganado la mayor\u00eda de los cargos en disputa en los \u00faltimos a\u00f1os, \u201cno refleja la realidad del pa\u00eds\u201d.Machado hizo estas declaraciones en un encuentro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1452182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1452182"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1452182\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1452182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1452182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1452182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}