{"id":1456432,"date":"2024-12-10T11:03:48","date_gmt":"2024-12-10T19:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/"},"modified":"2024-12-10T11:03:48","modified_gmt":"2024-12-10T19:03:48","slug":"agua-vida-marte-meteorito-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","title":{"rendered":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011"},"content":{"rendered":"<p>Un mineral atrapado en un meteorito marciano que cay\u00f3 a la Tierra ha revelado rastros de agua en Marte que datan de hace 4.450 millones de a\u00f1os, seg\u00fan una nueva investigaci\u00f3n. El grano de circ\u00f3n puede contener la evidencia directa m\u00e1s antigua de <a href=\"https:\/\/www.cnn.com\/2024\/07\/20\/science\/nasa-curiosity-rover-mars-sulfur-rocks\/index.html\">agua caliente en el planeta rojo<\/a>, que puede haber proporcionado entornos como fuentes termales que est\u00e1n asociados con la vida en la Tierra.<\/p>\n<p>El descubrimiento abre nuevas formas de entender si <a href=\"https:\/\/cnnespanol.cnn.com\/ciencia\">Marte<\/a> alguna vez fue habitable en su pasado remoto. Tambi\u00e9n agrega m\u00e1s respaldo a las observaciones ya recopiladas por la flota de naves espaciales que orbitan y recorren el planeta rojo, que han descubierto evidencia de d\u00f3nde alguna vez existieron r\u00edos y lagos en la superficie marciana.<\/p>\n<p>Pero quedan preguntas clave sobre cu\u00e1ndo exactamente apareci\u00f3 el agua por primera vez en Marte y c\u00f3mo evolucion\u00f3 -y desapareci\u00f3- con el tiempo.<\/p>\n<p>Los cient\u00edficos analizaron una muestra del meteorito \u201cBlack Beauty\u201d, tambi\u00e9n conocido como NWA 7034, que se encontr\u00f3 en el desierto del Sahara en 2011. El meteorito fue expulsado de la superficie marciana despu\u00e9s de que otro objeto celeste impactara el planeta hace entre 5 y 10 millones de a\u00f1os, y sus fragmentos han servido como una fuente clave para estudiar el antiguo Marte durante a\u00f1os.<\/p>\n<p>El nuevo estudio, publicado en la <a href=\"https:\/\/www.science.org\/doi\/10.1126\/sciadv.adq3694#con1\">revista Science Advances<\/a> el 22 de noviembre, se enfoc\u00f3 en un solo grano del mineral circ\u00f3n detectado dentro del meteorito. El an\u00e1lisis del equipo muestra que el agua estaba presente solo 100 millones de a\u00f1os despu\u00e9s de que se formara el planeta, lo que sugiere que Marte pudo haber sido capaz de albergar vida en alg\u00fan momento de su historia.<\/p>\n<p>\u201cNuestros datos sugieren la presencia de agua en la corteza de Marte en un momento comparable a la <a href=\"https:\/\/www.cnn.com\/2024\/06\/03\/science\/earliest-evidence-fresh-water-dry-land-earth-scn\/index.html\">evidencia m\u00e1s temprana de agua<\/a> en la superficie de la Tierra, hace unos 4.400 millones de a\u00f1os\u201d, dijo el autor principal del estudio, Jack Gillespie, investigador de la Facultad de Geociencias y Medio Ambiente de la Universidad de Lausana en Suiza, en un comunicado. \u201cEste descubrimiento aporta nuevas pruebas para entender la evoluci\u00f3n planetaria de Marte, los procesos que tuvieron lugar en \u00e9l y su potencial para haber albergado vida\u201d.<\/p>\n<p>Las rocas pueden contener las respuestas a algunas de las preguntas m\u00e1s importantes que quedan sobre Marte, como cu\u00e1nta agua hab\u00eda y si alguna vez existi\u00f3 vida en el planeta. Por eso los meteoritos como Black Beauty son de tanto inter\u00e9s para los cient\u00edficos. Carl Agee, profesor y director del Instituto de Meteor\u00edtica de la Universidad de Nuevo M\u00e9xico, present\u00f3 por primera vez la roca espacial a la comunidad cient\u00edfica en 2013.<\/p>\n<p>\u201c(El meteorito Black Beauty) contiene cientos de fragmentos de rocas y minerales, cada uno con una parte diferente de los 4.500 millones de a\u00f1os de historia marciana\u201d, dijo el coautor del estudio, el Dr. Aaron Cavosie, cient\u00edfico planetario y profesor titular del Centro de Ciencia y Tecnolog\u00eda Espacial de la Universidad de Curtin, en un correo electr\u00f3nico. \u201c(Es) la \u00fanica fuente de piezas para el rompecabezas geol\u00f3gico del Marte pre-No\u00e9ico\u201d.<\/p>\n<p>El per\u00edodo No\u00e9ico se produjo hace entre 4.100 y 3.700 millones de a\u00f1os, y se sabe poco a partir de mediciones directas que datan del per\u00edodo pre-No\u00e9ico en Marte, entre 4.500 y 4.100 millones de a\u00f1os atr\u00e1s, aunque es crucial comprenderlo porque sirve como la primera p\u00e1gina en el libro de historia de Marte, dijo Cavosie.<\/p>\n<p>Pero el Black Beauty revel\u00f3 algunos de sus secretos. Muchos de los fragmentos de roca que contiene el meteorito muestran que la corteza marciana soport\u00f3 una serie de impactos, lo que caus\u00f3 una enorme cantidad de trastornos en la superficie del planeta, dijo.<\/p>\n<p>La roca espacial tambi\u00e9n contiene las piezas m\u00e1s antiguas conocidas de Marte, incluidos los circones m\u00e1s antiguos, indic\u00f3 Cavosie.<\/p>\n<p>El circ\u00f3n, utilizado en productos como joyas, baldosas de cer\u00e1mica e implantes m\u00e9dicos, es un mineral resistente que puede ayudar a los cient\u00edficos a escudri\u00f1ar el pasado y determinar las condiciones presentes cuando cristaliz\u00f3, incluida la temperatura en ese momento y si el mineral interactu\u00f3 con el agua.<\/p>\n<p>\u201cEl circ\u00f3n contiene trazas de uranio, un elemento que act\u00faa como un reloj natural\u201d, dijo Gillespie, quien era investigador asociado postdoctoral en la Escuela de Ciencias de la Tierra y Planetarias de la Universidad de Curtin en el momento del estudio. \u201cEste elemento se desintegra en plomo con el tiempo a un ritmo conocido con precisi\u00f3n. Al comparar la proporci\u00f3n de uranio y plomo, podemos calcular la edad de formaci\u00f3n del cristal\u201d.<\/p>\n<p>El circ\u00f3n del Black Beauty no sufri\u00f3 alteraciones durante su viaje a la Tierra y su ardiente entrada en la atm\u00f3sfera de nuestro planeta antes de estrellarse en el Sahara porque estaba protegido por su ubicaci\u00f3n dentro del interior del meteorito, dijo Cavosie.<\/p>\n<p>Durante el an\u00e1lisis del grano de circ\u00f3n, el equipo de estudio detect\u00f3 cantidades inusuales de hierro, sodio y aluminio, lo que sugiere que los fluidos ricos en agua dejaron estos rastros en el circ\u00f3n cuando se form\u00f3 hace 4.450 millones de a\u00f1os.<br \/>Dichos elementos no suelen encontrarse en el circ\u00f3n cristalino, pero los estudios a escala at\u00f3mica del circ\u00f3n realizados por los investigadores mostraron que los elementos se incorporaron a la estructura cristalina y se alinearon como puestos de frutas en un mercado, dijo Cavosie.<\/p>\n<p>\u201cPodr\u00edamos decir por los patrones de c\u00f3mo se encuentran (el hierro, el aluminio y el sodio) dentro del circ\u00f3n que se incorporaron al grano a medida que crec\u00eda, como capas en una cebolla\u201d, explic\u00f3 Cavosie.<\/p>\n<p>En la Tierra, los circones de los sistemas hidrotermales, que se forman cuando el agua se calienta por la actividad volc\u00e1nica del subsuelo como el flujo ascendente de magma caliente, tienen patrones similares a los encontrados en el Black Beauty.<\/p>\n<p>Si hace 4.450 millones de a\u00f1os exist\u00edan sistemas hidrotermales en la corteza marciana, es probable que el agua l\u00edquida llegara a la superficie.<\/p>\n<p>\u201cNuestra experiencia en la Tierra demuestra que el agua es fundamental para los h\u00e1bitats capaces de sustentar la vida\u201d, afirm\u00f3 Cavosie. \u201cMuchos entornos de la Tierra albergan vida en sistemas de agua caliente, incluidas fuentes termales y respiraderos hidrotermales. Dichos entornos pueden haber dado lugar a las primeras formas de vida en la Tierra. Nuestro nuevo estudio demuestra que la corteza de Marte era c\u00e1lida y h\u00fameda en el per\u00edodo anterior al No\u00e9, lo que significa que es posible que existieran entornos habitables en esa \u00e9poca\u201d.<\/p>\n<p>Cavosie siente curiosidad por determinar si los sistemas hidrotermales como las fuentes termales eran frecuentes cuando el magma ayudaba a formar la corteza del planeta rojo entre hace 4.480 millones y 4.430 millones de a\u00f1os o si eran m\u00e1s epis\u00f3dicos.<\/p>\n<p>\u201cSi los sistemas hidrotermales eran una caracter\u00edstica estable en el Marte primitivo, indicar\u00eda que las condiciones habitables pueden haber persistido durante un per\u00edodo considerable de tiempo\u201d, afirm\u00f3 Cavosie. \u201cEsta es ahora una hip\u00f3tesis comprobable que se puede abordar mediante la recopilaci\u00f3n de m\u00e1s datos de los circones marcianos\u201d.<\/p>\n<p>Hasta que se puedan traer muestras directamente de Marte, el meteorito Black Beauty es una de las mejores ventanas para ver c\u00f3mo se form\u00f3 la corteza marciana y c\u00f3mo era la superficie primitiva de Marte, dijo Briony Horgan, coinvestigadora de la misi\u00f3n del rover Perseverance y profesora de ciencias planetarias en la Universidad de Purdue en West Lafayette, Indiana. Horgan no particip\u00f3 en este estudio.<\/p>\n<p>Encontrar evidencia de sistemas hidrotermales dentro del subsuelo a partir de un peque\u00f1o grano de circ\u00f3n se alinea con las teor\u00edas cient\u00edficas sobre la cantidad de agua y actividad volc\u00e1nica que exist\u00edan en el antiguo Marte, indic\u00f3. Y estos primeros entornos potencialmente habitables habr\u00edan estado protegidos de la radiaci\u00f3n por un fuerte campo magn\u00e9tico planetario, del que Marte carece actualmente, agreg\u00f3 Horgan. Los cient\u00edficos todav\u00eda tratan de explicar c\u00f3mo el planeta rojo perdi\u00f3 su campo magn\u00e9tico protector.<\/p>\n<p>Actualmente, el rover Perseverance escala el borde del <a href=\"https:\/\/www.cnn.com\/2024\/08\/24\/science\/perseverance-rover-crater-rim-climb\/index.html\">cr\u00e1ter Jezero en Marte<\/a>, un antiguo lago que estuvo lleno de agua hace 3.700 millones de a\u00f1os. Algunas de las rocas que ha encontrado el rover pueden haberse formado por sistemas hidrotermales, seg\u00fan Horgan.<\/p>\n<p>El rover tomar\u00e1 muestras de las rocas porque podr\u00edan preservar evidencia de vida microbiana antigua.<\/p>\n<p>\u201cPor mucho que los meteoritos nos puedan decir, podemos hacerlo a\u00fan mejor con una muestra de roca cuidadosamente seleccionada e intacta de una ubicaci\u00f3n conocida en Marte con un buen contexto geol\u00f3gico\u201d, afirm\u00f3 Horgan. \u201cPor lo tanto, este art\u00edculo es una gran motivaci\u00f3n para traer nuestras muestras de Marte de regreso a la Tierra para estudiarlas con el mismo nivel de detalle en los pr\u00f3ximos a\u00f1os\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mineral atrapado en un meteorito marciano que cay\u00f3 a la Tierra ha revelado rastros de agua en Marte que datan de hace 4.450 millones de a\u00f1os, seg\u00fan una nueva investigaci\u00f3n. El grano de circ\u00f3n puede contener la evidencia directa m\u00e1s antigua de agua caliente en el planeta rojo, que puede haber proporcionado entornos como [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456432","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un mineral atrapado en un meteorito marciano que cay\u00f3 a la Tierra ha revelado rastros de agua en Marte que datan de hace 4.450 millones de a\u00f1os, seg\u00fan una nueva investigaci\u00f3n. El grano de circ\u00f3n puede contener la evidencia directa m\u00e1s antigua de agua caliente en el planeta rojo, que puede haber proporcionado entornos como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T19:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011\",\"datePublished\":\"2024-12-10T19:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\"},\"wordCount\":1544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\",\"name\":\"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T19:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011 - Noticias","og_description":"Un mineral atrapado en un meteorito marciano que cay\u00f3 a la Tierra ha revelado rastros de agua en Marte que datan de hace 4.450 millones de a\u00f1os, seg\u00fan una nueva investigaci\u00f3n. El grano de circ\u00f3n puede contener la evidencia directa m\u00e1s antigua de agua caliente en el planeta rojo, que puede haber proporcionado entornos como [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-10T19:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/"},"author":{"name":"","@id":""},"headline":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011","datePublished":"2024-12-10T19:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/"},"wordCount":1544,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","name":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T19:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cient\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/10\/agua-vida-marte-meteorito-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T19:03:48Z","datePublished":"2024-12-10T19:03:48Z","dateModified":"2024-12-10T19:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cient\\u00edficos hallan una nueva pista sobre la vida en Marte con un meteorito marciano encontrado en la Tierra en 2011\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/10\\\/agua-vida-marte-meteorito-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/10\\\/agua-vida-marte-meteorito-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T19:03:48Z\",\"datePublished\":\"2024-12-10T19:03:48Z\",\"dateModified\":\"2024-12-10T19:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464582,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/16\/roca-marte-grande-subasta-trax\/","url_meta":{"origin":1456432,"position":0},"title":"La roca m\u00e1s grande de Marte se vende por US$ 4,3 millones en una subasta","author":"","date":"julio 16, 2025","format":false,"excerpt":"Un meteorito, que es el trozo m\u00e1s grande conocido de Marte en la Tierra, se vendi\u00f3 por un precio de US$ 4,3 millones a un postor an\u00f3nimo en una subasta de Sotheby\u2019s en Nueva York este mi\u00e9rcoles.El meteorito, conocido como NWA 16788, pesa 24,5 kilogramos, un peso enorme comparado con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459179,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/25\/por-que-marte-es-rojo-trax\/","url_meta":{"origin":1456432,"position":1},"title":"Nueva investigaci\u00f3n desmiente la teor\u00eda sobre por qu\u00e9 Marte es rojo, dicen los cient\u00edficos","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Marte, con su ic\u00f3nico tono oxidado, ha sido llamado durante mucho tiempo el planeta rojo.Ahora, los cient\u00edficos pueden haber descubierto la fuente potencial de esa coloraci\u00f3n distintiva, echando por tierra una teor\u00eda popular en el proceso.Marte es uno de los planetas m\u00e1s estudiados de nuestro sistema solar debido a su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473492,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/24\/curiosity-componentes-vida-experimento-marte-trax\/","url_meta":{"origin":1456432,"position":2},"title":"El rover Curiosity detecta los componentes b\u00e1sicos de la vida en el primer experimento realizado en Marte","author":"","date":"abril 24, 2026","format":false,"excerpt":"El rover Curiosity descubri\u00f3 el conjunto m\u00e1s diverso de mol\u00e9culas org\u00e1nicas jam\u00e1s encontrado en Marte, incluidas siete que no se hab\u00edan detectado en el planeta rojo.Estos compuestos que contienen carbono son los mismos componentes b\u00e1sicos que permitieron que la vida surgiera en la Tierra.Los resultados, publicados el martes en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451770,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/12\/deposito-subterraneo-marte-agua-oceanos-trax\/","url_meta":{"origin":1456432,"position":3},"title":"Un dep\u00f3sito subterr\u00e1neo en Marte podr\u00eda llenar oc\u00e9anos en la superficie del planeta, seg\u00fan un estudio","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN) -- Los datos de una misi\u00f3n retirada de la NASA revelaron evidencia de un dep\u00f3sito subterr\u00e1neo de agua en las profundidades de la superficie de Marte, seg\u00fan una nueva investigaci\u00f3n.Un equipo de cient\u00edficos estima que podr\u00eda haber suficiente agua atrapada en peque\u00f1as grietas y poros de la roca en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450240,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/11\/agua-congelada-volcanes-marte-primera-vez-trax\/","url_meta":{"origin":1456432,"position":4},"title":"Cient\u00edficos detectan agua congelada en los volcanes de Marte por primera vez","author":"","date":"junio 11, 2024","format":false,"excerpt":"(CNN) -- La regi\u00f3n ecuatorial de Marte alberga los volcanes m\u00e1s altos del sistema solar que, adem\u00e1s de alcanzar la altura de tres montes Everest en algunos casos, probablemente ocultan un fen\u00f3meno helado inesperado, seg\u00fan descubri\u00f3 un nuevo estudio.El m\u00e1s grande, Olympus Mons, tiene 26 kil\u00f3metros (16 millas) de altura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445812,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/21\/marciano-nueva-mision-nasa-chapea-voluntarios-experiencia-simulada-marte-trax\/","url_meta":{"origin":1456432,"position":5},"title":"\u00bfQuieres vivir como un marciano? Nueva misi\u00f3n de la NASA busca voluntarios para simular la experiencia en el planeta rojo","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Para cualquiera que haya so\u00f1ado alguna vez con vivir en Marte, la NASA est\u00e1 buscando posibles \"marcianos\" para simular una misi\u00f3n al planeta rojo.La agencia espacial lanz\u00f3 una convocatoria que busca voluntarios para su segunda misi\u00f3n Chapea (Crew Health and Performance Exploration Analog), que comenzar\u00e1 en la primavera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456432"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456432\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}