{"id":1456582,"date":"2024-12-13T16:03:43","date_gmt":"2024-12-14T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/"},"modified":"2024-12-13T16:03:43","modified_gmt":"2024-12-14T00:03:43","slug":"derechos-humanos-onu-preocupacion-saab-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","title":{"rendered":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela"},"content":{"rendered":"<p>El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de un nuevo per\u00edodo de Gobierno. Estas declaraciones fueron rechazadas por el fiscal general de Venezuela, Tarek William Saab.<\/p>\n<p>T\u00fcrk habl\u00f3 del tema este viernes durante una sesi\u00f3n del Consejo de Derechos Humanos de la ONU, ante el que expuso lo que \u00e9l y su equipo han observado en el pa\u00eds sudamericano despu\u00e9s de los comicios del 28 de julio, cuando el Consejo Nacional Electoral y luego el Tribunal Supremo de Justicia dieron a Maduro como el ganador sin mostrar los resultados detallados por centro y mesa.<\/p>\n<p>\u201cSigo profundamente preocupado por el uso desproporcionado de la fuerza y la violencia durante las protestas poselectorales de julio y agosto, incluyendo a los individuos armados en respaldo del Gobierno\u201d, dijo T\u00fcrk.<\/p>\n<p>T\u00fcrk tambi\u00e9n llam\u00f3 a que se investiguen las 28 muertes registradas durante las manifestaciones y record\u00f3 que unas <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/12\/venezuela\/gobierno-103-personas-excarceladas-foro-penal-25-orix\">2.000 personas fueron detenidas <\/a>en ese contexto.<\/p>\n<p>Agreg\u00f3 que aunque las autoridades venezolanas han dado \u201cun paso importante\u201d con las recientes excarcelaciones de algunos manifestantes, consider\u00f3 que deben revisar los casos de quienes siguen encerrados.<\/p>\n<p>\u201cEl uso continuo de legislaci\u00f3n antiterrorista contra manifestantes, incluyendo adolescentes, y reportes de desapariciones forzadas y malos tratos son preocupantes\u201d, dijo el alto comisionado, y consider\u00f3 que normas como la <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/29\/maduro-promulga-ley-castigo-sanciones-extranjeras-bolivar-orix\">Ley Sim\u00f3n Bol\u00edvar<\/a>, recientemente aprobada por la Asamblea Nacional y que establece, entre otros, duras penas de prisi\u00f3n a quienes promuevan sanciones contra la econom\u00eda de Venezuela y una inhabilitaci\u00f3n pol\u00edtica de hasta 60 a\u00f1os, ponen en riesgo el ejercicio de las libertades de expresi\u00f3n, reuni\u00f3n, asamblea y participaci\u00f3n pol\u00edtica.<\/p>\n<p>Horas despu\u00e9s del mensaje del Alto Comisionado, el fiscal Tarek William Saab emiti\u00f3 un comunicado en el que rechaz\u00f3 las declaraciones de T\u00fcrk.<\/p>\n<p>Saab consider\u00f3 que T\u00fcrk hizo \u201cafirmaciones irresponsables que lo alejan de la que deber\u00eda ser una posici\u00f3n de equilibrio y di\u00e1logo cooperativo\u201d con Venezuela, y que responsabiliza al Gobierno de actos de violencia que, seg\u00fan el funcionario, fueron realizados por grupos de la oposici\u00f3n.<\/p>\n<p>En contraste, la oposici\u00f3n rechaza que haya sido as\u00ed.<\/p>\n<p>El fiscal tambi\u00e9n dijo que T\u00fcrk no habla de las sanciones internacionales impuestas a Venezuela, \u201cdestinadas a destruir su econom\u00eda y generar dolor y sufrimiento a su poblaci\u00f3n\u201d.<\/p>\n<p>\u201cLe hacemos un llamado, desde nuestra dignidad y soberan\u00eda, a que rectifique en su trato hacia Venezuela y a que recupere el equilibrio y no se deje manipular por quienes hablan de derechos humanos y borran pa\u00edses del mapa en nombre de la democracia\u201d, concluy\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de un nuevo per\u00edodo de Gobierno. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456582","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de un nuevo per\u00edodo de Gobierno. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela\",\"datePublished\":\"2024-12-14T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\"},\"wordCount\":521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\",\"name\":\"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela - Noticias","og_description":"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de un nuevo per\u00edodo de Gobierno. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-14T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/"},"author":{"name":"","@id":""},"headline":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","datePublished":"2024-12-14T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/"},"wordCount":521,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","name":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T00:03:43Z","datePublished":"2024-12-14T00:03:43Z","dateModified":"2024-12-14T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\\u00f3n por la situaci\\u00f3n pol\\u00edtica en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/13\\\/derechos-humanos-onu-preocupacion-saab-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/13\\\/derechos-humanos-onu-preocupacion-saab-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T00:03:43Z\",\"datePublished\":\"2024-12-14T00:03:43Z\",\"dateModified\":\"2024-12-14T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1446054,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/27\/venezuela-alto-comisionado-reunion-orix\/","url_meta":{"origin":1456582,"position":0},"title":"Canciller de Venezuela se re\u00fane con el alto comisionado de DD.HH. de la ONU a 12 d\u00edas de haber expulsado a su personal en Caracas","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN) -- El canciller de Venezuela, Yvan Gil, se reuni\u00f3 este martes con el alto comisionado de las Naciones Unidas para los Derechos Humanos, Volker Turk, para \u201creafirmar su firme disposici\u00f3n a seguir colaborando con esa oficina\u201d, de acuerdo con \u201cel principio de no interferencia y respeto mutuo\u201d, seg\u00fan una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464020,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/27\/alto-comisionado-onu-expresa-preocupacion-derechos-humanos-orix\/","url_meta":{"origin":1456582,"position":1},"title":"Alto Comisionado de la ONU expresa preocupaci\u00f3n por el &#171;deterioro de la situaci\u00f3n de los derechos humanos&#187; en Venezuela","author":"","date":"junio 27, 2025","format":false,"excerpt":"El Alto Comisionado de la ONU para los derechos humanos, Volker T\u00fcrk, dijo este viernes estar preocupado porque \u201cla situaci\u00f3n de los derechos humanos en Venezuela se ha deteriorado\u201d desde mayo de 2024.A\u00f1adi\u00f3 que durante este lapso el organismo que representa ha registrado \u201cdetenciones arbitrarias, violaciones al debido proceso y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448451,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/23\/maduro-acepta-la-reapertura-en-venezuela-de-la-oficina-del-alto-comisionado-de-la-onu-para-los-dd-hh\/","url_meta":{"origin":1456582,"position":2},"title":"Maduro acepta la reapertura en Venezuela de la Oficina del Alto Comisionado de la ONU para los DD.HH.","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En una presentaci\u00f3n p\u00fablica desde el Palacio de Miraflores y junto al fiscal de la Corte Penal Internacional, Karim Kham, el presidente de Venezuela, Nicol\u00e1s Maduro, afirm\u00f3 que recibi\u00f3 la propuesta del funcionario internacional para reabrir en Caracas la oficina del Alto Comisionado de la ONU para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451828,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/13\/venezuela-onu-derechos-humanos-detenciones-fuerza-miedo-orix\/","url_meta":{"origin":1456582,"position":3},"title":"\u201cDetenciones arbitrarias y uso desproporcionado de la fuerza alimentan clima de miedo\u201d en Venezuela, advierte la ONU","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La tensi\u00f3n en Venezuela sigue en aumento tras las elecciones presidenciales del 28 de julio, cuyos resultados a\u00fan se disputan entre el oficialismo y la oposici\u00f3n mayoritaria, mientras crecen las denuncias de violaciones a los derechos humanos. Ante este contexto, la Oficina del Alto Comisionado para los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451753,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/12\/onu-cipe-venezuela-violaciones-derechos-humanos-orix\/","url_meta":{"origin":1456582,"position":4},"title":"La ONU y la CPI monitorean denuncias de violaciones a los derechos humanos en Venezuela","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Tanto la ONU como la Corte Penal Internacional (CPI) est\u00e1n siguiendo muy de cerca la situaci\u00f3n de los derechos humanos en Venezuela, de acuerdo con sendos comunicados publicados este lunes.La Misi\u00f3n de Determinaci\u00f3n de los Hechos de la ONU exigi\u00f3 al Gobierno de Nicol\u00e1s Maduro \u201cdetenga inmediatamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472249,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/16\/onu-persisten-denuncias-detenidos-venezuela-lista-presos-liberados-orix\/","url_meta":{"origin":1456582,"position":5},"title":"Alto comisionado de la ONU dice que persisten las denuncias y pide transparencia sobre la liberaci\u00f3n de presos en Venezuela","author":"","date":"marzo 16, 2026","format":false,"excerpt":"El alto comisionado de la ONU para los derechos humanos, Volker T\u00fcrk, dijo este lunes que su oficina contin\u00faa recibiendo informaci\u00f3n sobre torturas y malos tratos contra detenidos en Venezuela tras la captura de Nicol\u00e1s Maduro por parte de fuerzas militares estadounidenses en Caracas el pasado 3 de enero.\u201cLas preocupaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456582"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456582\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}