{"id":1456644,"date":"2024-12-16T02:03:38","date_gmt":"2024-12-16T10:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/"},"modified":"2024-12-16T02:03:38","modified_gmt":"2024-12-16T10:03:38","slug":"xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","title":{"rendered":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres"},"content":{"rendered":"<p>En los primeros a\u00f1os de la guerra de Xi Jinping contra la corrupci\u00f3n, el l\u00edder chino consolid\u00f3 el control sobre el Ej\u00e9rcito m\u00e1s grande del mundo derrocando a generales poderosos de facciones rivales y reemplaz\u00e1ndolos por aliados y protegidos leales.<\/p>\n<p>Una d\u00e9cada despu\u00e9s, despu\u00e9s de haber reformado la estructura del Ej\u00e9rcito Popular de Liberaci\u00f3n (EPL) y de llenar sus filas con sus propios hombres, el l\u00edder supremo todav\u00eda est\u00e1 hundido hasta las rodillas en su lucha aparentemente interminable contra la corrupci\u00f3n y la deslealtad.<\/p>\n<p>Y, como muchos l\u00edderes autoritarios de la historia, cada vez se vuelve m\u00e1s contra sus propios leales elegidos a dedo.<\/p>\n<p>A fines del mes pasado, Xi purg\u00f3 a uno de sus protegidos m\u00e1s cercanos en el ej\u00e9rcito: un antiguo colaborador encargado de inculcar lealtad pol\u00edtica en el EPL y de examinar los ascensos de alto rango.<\/p>\n<p>El almirante Miao Hua, miembro de la Comisi\u00f3n Militar Central (CMC), el m\u00e1ximo \u00f3rgano de mando presidido por Xi, fue <a href=\"https:\/\/www.cnn.com\/2024\/11\/28\/china\/china-military-general-investigation-intl-hnk\/index.html\">suspendido bajo investigaci\u00f3n<\/a> por \u201cgraves violaciones de la disciplina\u201d, anunci\u00f3 el Ministerio de Defensa, utilizando un eufemismo com\u00fan para la corrupci\u00f3n y la deslealtad.<\/p>\n<p>Como jefe del departamento de trabajo pol\u00edtico de la CMC, que supervisa el adoctrinamiento pol\u00edtico y los nombramientos de personal, Miao es el principal responsable de la \u00faltima purga militar de Xi. Desde el verano pasado, m\u00e1s de una decena de figuras de alto rango del estamento de defensa de China fueron destituidos, incluidos los dos \u00faltimos ministros de defensa promovidos por Xi a la CMC.<\/p>\n<p>Pero ninguno de ellos puede presumir del tipo de relaci\u00f3n de larga data que Miao comparti\u00f3 con el m\u00e1ximo l\u00edder, que se remonta a d\u00e9cadas de la temprana carrera pol\u00edtica de Xi en la provincia costera de Fujian.<\/p>\n<p>La investigaci\u00f3n sobre Miao abre un nuevo frente en una purga cada vez mayor que suscit\u00f3 <a href=\"https:\/\/www.cnn.com\/2024\/07\/01\/china\/china-defense-ministers-downfall-analysis-intl-hnk\/index.html\">dudas<\/a> sobre la capacidad de Xi para poner fin a la corrupci\u00f3n sistem\u00e1tica en el ej\u00e9rcito y mejorar su preparaci\u00f3n para el combate en un momento de mayores tensiones geopol\u00edticas.<\/p>\n<p>En la \u00faltima d\u00e9cada, Xi supervis\u00f3 una ambiciosa transformaci\u00f3n del EPL en una fuerza de combate de \u201cclase mundial\u201d capaz de rivalizar con el Ej\u00e9rcito estadounidense. Un objetivo clave de esa campa\u00f1a de modernizaci\u00f3n es asegurar que China est\u00e9 preparada para luchar y ganar una guerra por Taiw\u00e1n, la isla democr\u00e1tica aut\u00f3noma que Beijing reclama como suya.<\/p>\n<p>Pero la ca\u00edda de Miao renueva las preguntas \u2013surgidas durante las purgas del verano pasado\u2013 sobre cu\u00e1nta confianza tiene Xi en sus principales generales que ser\u00edan responsables de liderar una guerra, dijo Joel Wuthnow, investigador principal de la Universidad de Defensa Nacional financiada por el Pent\u00e1gono.<\/p>\n<p>\u201cSi teme haber tra\u00eddo a personas que no son incuestionablemente leales a \u00e9l o a su agenda, eso ser\u00eda un gran problema\u201d.<\/p>\n<p>Los expertos dicen que la purga de Xi de un antiguo ac\u00f3lito apunta a un dilema familiar para los aut\u00f3cratas, incluido su predecesor Mao Zedong: despu\u00e9s de eliminar a sus rivales pol\u00edticos, el l\u00edder supremo nunca deja de buscar nuevas amenazas a su control absoluto del poder, incluso entre su propio c\u00edrculo cercano.<\/p>\n<p>La relaci\u00f3n de Miao con Xi se remonta a tres d\u00e9cadas. El nativo de Fujian sirvi\u00f3 como oficial pol\u00edtico en el antiguo 31\u00ba Grupo del Ej\u00e9rcito desde la d\u00e9cada de 1980 hasta principios de la d\u00e9cada de 2000, cuando Xi ascend\u00eda de rango como funcionario local hasta convertirse en gobernador provincial de Fujian.<\/p>\n<p>\u201cSeg\u00fan fuentes cre\u00edbles, Xi visitaba regularmente al 31\u00ba Grupo del Ej\u00e9rcito en ese momento\u201d y se sabe que tuvo contactos personales con Miao, dijo James Char, un observador del EPL de larga data e investigador de la Escuela de Estudios Internacionales S. Rajaratnam en Singapur.<\/p>\n<p>La carrera militar de Miao despeg\u00f3 poco despu\u00e9s de que Xi llegara al poder. En 2014, recibi\u00f3 un importante ascenso y se convirti\u00f3 en comisario pol\u00edtico de la Armada del EPL, lo que supuso un cambio poco habitual con respecto a su carrera en la Fuerza Terrestre. Tres a\u00f1os despu\u00e9s, fue ascendido de nuevo a la CMC, la c\u00faspide del poder militar.<\/p>\n<p>\u201cNo podemos encontrar un ac\u00f3lito m\u00e1s apod\u00edctico de Xi que Miao\u201d, dijo Char. \u201cSi Miao es finalmente acusado de corrupci\u00f3n, es evidente que el propio Xi no hab\u00eda previsto el nivel obsceno de corrupci\u00f3n que existe entre las \u00e9lites del EPL\u201d.<\/p>\n<p>Durante los \u00faltimos 18 meses, la campa\u00f1a de limpieza de Xi se hab\u00eda dirigido principalmente contra funcionarios vinculados con la adquisici\u00f3n de armas y la Fuerza de Cohetes, que supervisa los misiles nucleares y convencionales de China. Pero la ca\u00edda de Miao indica una ampliaci\u00f3n de esa campa\u00f1a a nuevos sectores, como el trabajo pol\u00edtico \u2013que Xi ha descrito como el \u201csalvavidas\u201d del ej\u00e9rcito\u2013 y la Armada.<\/p>\n<p>\u201cEstoy seguro de que all\u00ed donde miren encontrar\u00e1n problemas y casos. Es solo cuesti\u00f3n de qu\u00e9 sector elijan\u201d, dijo Char.<\/p>\n<p>El Ministerio de Defensa no ha ofrecido detalles sobre las acusaciones contra Miao.<\/p>\n<p>Como comisario pol\u00edtico jefe del EPL, Miao tiene la tarea de garantizar su lealtad al Partido Comunista gobernante. Supervisa los ascensos en el ej\u00e9rcito y examina a los candidatos clave para determinar su lealtad pol\u00edtica, un papel que tambi\u00e9n desempe\u00f1\u00f3 en la Marina.<\/p>\n<p>En el pasado, esos cargos han sido terreno f\u00e9rtil para la corrupci\u00f3n, especialmente los sobornos para ascensos. El predecesor de Miao, el general Zhang Yang, <a href=\"https:\/\/www.cnn.com\/2017\/11\/28\/asia\/china-corruption-zhang-yang-suicide\/index.html\">se suicid\u00f3<\/a> mientras estaba siendo investigado disciplinariamente por soborno.<\/p>\n<p>A medida que se intensifica la rivalidad geopol\u00edtica entre Estados Unidos y China, la Armada del EPL tambi\u00e9n ha visto un aumento dr\u00e1stico en la adquisici\u00f3n de buques de guerra y otras armas, lo que proporciona amplias oportunidades para la corrupci\u00f3n, dijo Victor Shih, profesor de ciencias pol\u00edticas en la Universidad de San Diego.<\/p>\n<p><strong>Art\u00edculo relacionado<\/strong>\u00bfQu\u00e9 tan preparada est\u00e1 la milicia china? La dram\u00e1tica ca\u00edda de dos ministros de Defensa plantea interrogantes<\/p>\n<p>Pero podr\u00eda haber otra raz\u00f3n potencial detr\u00e1s de la ca\u00edda de Miao, dijo Shih, por \u201cser demasiado obvio en su intento de fomentar una facci\u00f3n en el ej\u00e9rcito\u201d.<\/p>\n<p>Xi ha advertido en repetidas ocasiones contra la formaci\u00f3n de facciones tanto en el partido como en el ej\u00e9rcito. \u201cPor supuesto, la \u00fanica persona a la que se le permite hacer eso es el propio Xi\u201d, a\u00f1adi\u00f3 Shih.<\/p>\n<p>Algunos analistas consideran que Miao recomend\u00f3 a varios asociados de la Armada para ascensos a puestos clave, incluido el comandante de la Fuerza de Cohetes, Wang Houbin, y el ministro de Defensa, Dong Jun.<\/p>\n<p>El anuncio de la investigaci\u00f3n de Miao se produjo un d\u00eda despu\u00e9s de que el Financial Times informara que Dong hab\u00eda sido puesto bajo investigaci\u00f3n por corrupci\u00f3n, citando a funcionarios estadounidenses actuales y anteriores. El Ministerio de Defensa desestim\u00f3 el informe como \u201cpura invenci\u00f3n\u201d y d\u00edas despu\u00e9s, Dong hizo una aparici\u00f3n p\u00fablica en un foro de seguridad.<\/p>\n<p>Wuthnow, el experto de la Universidad de Defensa Nacional, dijo que lo que llev\u00f3 a la ca\u00edda de Miao fue una \u201cp\u00e9rdida de confianza\u201d, pero las razones de eso siguen siendo esquivas.<\/p>\n<p>En un escenario, dijo Wuthnow, Xi podr\u00eda haber considerado que Miao se estaba volviendo demasiado poderoso e independiente y quer\u00eda erradicar lo que ve\u00eda como un basti\u00f3n de influencia que no pod\u00eda controlar por completo.<\/p>\n<p>\u201cNo creo que as\u00ed se comporten los l\u00edderes que conf\u00edan en su propio poder y en su capacidad para controlar a la burocracia. En realidad, me parece un signo de debilidad, por no decir de paranoia, que sienta que necesita constantemente poner patas arriba el carro de las manzanas\u201d, afirm\u00f3.<\/p>\n<p>La ca\u00edda de Miao se produce menos de un a\u00f1o despu\u00e9s de que el exministro de Defensa Li Shangfu fuera expulsado de la CMC.<\/p>\n<p>El poderoso organismo contaba con seis miembros \u2013todos considerados leales a Xi\u2013 que prestaban servicios bajo el mando del m\u00e1ximo l\u00edder cuando comenz\u00f3 su tercer mandato sin precedentes hace dos a\u00f1os. Si tambi\u00e9n destituyen a Miao, quedar\u00edan dos puestos vacantes.<\/p>\n<p>Shih, el experto en pol\u00edtica de \u00e9lite china, dijo que muchos dictadores, desde el exl\u00edder sovi\u00e9tico Joseph Stalin hasta Mao, eventualmente se han vuelto contra sus propios protegidos.<\/p>\n<p>\u201cUna vez que todos sus verdaderos competidores han desaparecido, un dictador nunca puede pensar: \u2018Bueno, ya no hay amenazas, puedo relajarme\u2019, porque siempre piensa que pueden surgir nuevas amenazas, incluso de personas que alguna vez fueron muy cercanas. Esto sucede una y otra vez\u201d, afirm\u00f3.<\/p>\n<p><strong>Art\u00edculo relacionado<\/strong>La \u00faltima purga de Xi apunta a los militares. \u00bfPor qu\u00e9 generales poderosos cayeron en desgracia?<\/p>\n<p>Como resultado, el dictador siempre est\u00e1 buscando se\u00f1ales cada vez m\u00e1s sutiles de que alguien est\u00e1 conspirando contra \u00e9l, dijo Shih, autor de \u201cCoaliciones de los d\u00e9biles\u201d, que examina el control de Mao sobre el poder en la \u00faltima etapa de su vida.<\/p>\n<p>Durante los \u00faltimos a\u00f1os de Mao, se volvi\u00f3 contra Lin Biao, su protegido de mucho tiempo, exministro de Defensa y aparente heredero, acus\u00e1ndolo de planear un golpe de Estado.<\/p>\n<p>\u201cEste tipo de din\u00e1mica se tornar\u00e1 cada vez m\u00e1s severa a medida que Xi Jinping envejezca, ya que su salud no es tan robusta como antes. Su sensibilidad a las se\u00f1ales de un posible desaf\u00edo a su poder tambi\u00e9n se agudizar\u00e1 con el tiempo\u201d, afirm\u00f3 Shih.<\/p>\n<p>Por ahora, el m\u00e1ximo l\u00edder parece decidido a continuar su cruzada contra la corrupci\u00f3n y la deslealtad.<\/p>\n<p>A principios de este mes, Xi inspeccion\u00f3 la Fuerza de Apoyo de Informaci\u00f3n del EPL con sus cuatro leales restantes en el CMC.<\/p>\n<p>\u201cDebemos garantizar que las tropas permanezcan absolutamente leales, absolutamente puras y absolutamente confiables\u201d, dijo Xi a una audiencia de oficiales que tomaban notas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los primeros a\u00f1os de la guerra de Xi Jinping contra la corrupci\u00f3n, el l\u00edder chino consolid\u00f3 el control sobre el Ej\u00e9rcito m\u00e1s grande del mundo derrocando a generales poderosos de facciones rivales y reemplaz\u00e1ndolos por aliados y protegidos leales. Una d\u00e9cada despu\u00e9s, despu\u00e9s de haber reformado la estructura del Ej\u00e9rcito Popular de Liberaci\u00f3n (EPL) [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456644","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres - Noticias\" \/>\n<meta property=\"og:description\" content=\"En los primeros a\u00f1os de la guerra de Xi Jinping contra la corrupci\u00f3n, el l\u00edder chino consolid\u00f3 el control sobre el Ej\u00e9rcito m\u00e1s grande del mundo derrocando a generales poderosos de facciones rivales y reemplaz\u00e1ndolos por aliados y protegidos leales. Una d\u00e9cada despu\u00e9s, despu\u00e9s de haber reformado la estructura del Ej\u00e9rcito Popular de Liberaci\u00f3n (EPL) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T10:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres\",\"datePublished\":\"2024-12-16T10:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\"},\"wordCount\":1758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\",\"name\":\"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T10:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres - Noticias","og_description":"En los primeros a\u00f1os de la guerra de Xi Jinping contra la corrupci\u00f3n, el l\u00edder chino consolid\u00f3 el control sobre el Ej\u00e9rcito m\u00e1s grande del mundo derrocando a generales poderosos de facciones rivales y reemplaz\u00e1ndolos por aliados y protegidos leales. Una d\u00e9cada despu\u00e9s, despu\u00e9s de haber reformado la estructura del Ej\u00e9rcito Popular de Liberaci\u00f3n (EPL) [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-16T10:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres","datePublished":"2024-12-16T10:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/"},"wordCount":1758,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","name":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T10:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Xi derrot\u00f3 a poderosos rivales en el Ej\u00e9rcito. Ahora va tras sus propios hombres","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T10:03:38Z","datePublished":"2024-12-16T10:03:38Z","dateModified":"2024-12-16T10:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Xi derrot\\u00f3 a poderosos rivales en el Ej\\u00e9rcito. Ahora va tras sus propios hombres\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/16\\\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/16\\\/xi-derroto-rivales-en-ejercito-ahora-va-tras-sus-hombres-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T10:03:38Z\",\"datePublished\":\"2024-12-16T10:03:38Z\",\"dateModified\":\"2024-12-16T10:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450818,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/01\/analisis-ejercito-china-combate-caida-ministros-defensa-interrogantes-trax\/","url_meta":{"origin":1456644,"position":0},"title":"AN\u00c1LISIS | \u00bfQu\u00e9 tan listo est\u00e1 el Ej\u00e9rcito de China para un combate? La dram\u00e1tica ca\u00edda de dos ministros de Defensa plantea interrogantes","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN) -- Tras meses de intensas especulaciones y reticencias oficiales, China confirm\u00f3 finalmente que sus dos exministros de Defensa, que desaparecieron de la escena p\u00fablica el a\u00f1o pasado, hab\u00edan sido investigados por corrupci\u00f3n.Su dram\u00e1tica ca\u00edda ha sacado a la luz presuntos enga\u00f1os profundamente arraigados en sectores clave de la modernizaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460861,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/05\/china-ejercito-general-he-weidong-ausencia-trax\/","url_meta":{"origin":1456644,"position":1},"title":"Por qu\u00e9 la ausencia del segundo general de m\u00e1s alto rango en China ha desatado especulaciones","author":"","date":"abril 5, 2025","format":false,"excerpt":"Los oficiales militares chinos, con uniformes marrones, se despliegan entre hileras de \u00e1rboles j\u00f3venes, echando tierra en fosas reci\u00e9n cavadas. La c\u00e1mara enfoca a los l\u00edderes de mayor rango, uno por uno, por orden de rango. Pero un rostro prominente brilla por su ausencia.El segmento de noticias, emitido el mi\u00e9rcoles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456132,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/11\/28\/china-militar-general-investigacion-trax\/","url_meta":{"origin":1456644,"position":2},"title":"China investiga a un alto cargo militar mientras se ampl\u00eda la purga de Xi","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN) -- China suspendi\u00f3 a un alto cargo militar y lo puso bajo investigaci\u00f3n por corrupci\u00f3n, seg\u00fan inform\u00f3 el Ministerio de Defensa, mientras el l\u00edder Xi Jinping ampl\u00eda una amplia purga en los rangos superiores del mayor Ej\u00e9rcito del mundo.El almirante Miao Hua, miembro de la poderosa Comisi\u00f3n Militar Central\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456734,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/pentagono-anticorrupcion-china-expansion-militar-trax\/","url_meta":{"origin":1456644,"position":3},"title":"La campa\u00f1a anticorrupci\u00f3n de China dificulta sus planes de expansi\u00f3n militar, dice el Pent\u00e1gono","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Una campa\u00f1a anticorrupci\u00f3n generalizada dentro de los niveles m\u00e1s altos del Ej\u00e9rcito y el Gobierno de China est\u00e1 obstaculizando el esfuerzo del pa\u00eds por desarrollar su Ej\u00e9rcito para 2027, dijo el Pent\u00e1gono en un nuevo informe publicado este mi\u00e9rcoles.\u201cSolo en la segunda mitad de 2023, al menos 15 altos funcionarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470507,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/26\/analisis-xi-jinping-control-absoluto-ejercito-china-trax\/","url_meta":{"origin":1456644,"position":4},"title":"Xi tiene control absoluto sobre el Ej\u00e9rcito de China. Ahora quiere m\u00e1s","author":"","date":"enero 26, 2026","format":false,"excerpt":"La decisi\u00f3n del l\u00edder de China Xi Jinping de poner bajo investigaci\u00f3n al general de m\u00e1s alto rango del pa\u00eds es un movimiento sorprendente que deja a Xi pr\u00e1cticamente solo en la cima de la jerarqu\u00eda militar, lo que plantea profundas interrogantes sobre las implicaciones para las fuerzas armadas m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443414,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/09\/xi-jinping-intensifica-su-campana-anti-corrupcion-y-apuntara-a-las-industrias-como-finanzas-energia-e-infraestructura\/","url_meta":{"origin":1456644,"position":5},"title":"Xi Jinping intensifica su campa\u00f1a anti-corrupci\u00f3n y apuntar\u00e1 a las industrias como finanzas, energ\u00eda e infraestructura","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) --El l\u00edder chino Xi Jinping prometi\u00f3 perseguir \u201cmoscas y hormigas\u201d como parte de una intensificaci\u00f3n de la campa\u00f1a anti-corrupci\u00f3n que apuntar\u00e1 a industrias como las finanzas, la energ\u00eda y la infraestructura.China abordar\u00e1 los \u201criesgos ocultos\u201d y aumentar\u00e1 el castigo para las personas que ofrecen sobornos, dijo Xi en una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456644"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456644\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}