{"id":1456660,"date":"2024-12-16T11:03:43","date_gmt":"2024-12-16T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/"},"modified":"2024-12-16T11:03:43","modified_gmt":"2024-12-16T19:03:43","slug":"trump-biden-muro-venezuela-teletrabajo-conferencia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","title":{"rendered":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales"},"content":{"rendered":"<p>El presidente electo de EE.UU. Donald Trump critic\u00f3 al presidente Joe Biden luego de un par de acciones que la administraci\u00f3n de Biden tom\u00f3 despu\u00e9s de la elecci\u00f3n de Trump en noviembre, incluidos informes de que la administraci\u00f3n vendi\u00f3 materiales de construcci\u00f3n del muro fronterizo entre Estados Unidos y M\u00e9xico y un acuerdo para permitir que algunos trabajadores federales contin\u00faen trabajando de forma remota hasta 2029.<\/p>\n<p>En su primera conferencia de prensa desde ganar las elecciones, Trump respondi\u00f3 a una amplia gama de preguntas y detall\u00f3 algunos asuntos sobre el tema fronterizo y de inmigraci\u00f3n.<\/p>\n<p>Trump cit\u00f3 informes de que la administraci\u00f3n Biden vendi\u00f3 partes que se asignaron para construir secciones adicionales del muro fronterizo que comenz\u00f3 a construirse durante el primer mandato de Trump. Acus\u00f3 a Biden de intentar socavar intencionalmente los esfuerzos de Trump para completar el proyecto.<\/p>\n<p>\u201cPedimos 200 millas adicionales de muro. Es muy caro, y ahora cuesta aproximadamente el doble de lo que habr\u00eda costado hace seis a\u00f1os, y la administraci\u00f3n est\u00e1 tratando de venderlo a cinco centavos por d\u00f3lar, sabiendo que nos estamos preparando para levantarlo\u201d, dijo.<\/p>\n<p>\u201cLe pido hoy a Joe Biden que deje de vender el muro, vamos a usarlo para crear una barrera fuerte\u201d, continu\u00f3. \u201cY funcion\u00f3 bien, y es muy costoso de hacer, y le pido a Joe Biden que impida que su gente lo regale. Es algo que la gente ni siquiera puede creer que est\u00e9 sucediendo. As\u00ed que espero que Joe pueda detenerlo\u201d.<\/p>\n<p>Trump tambi\u00e9n critic\u00f3 a la administraci\u00f3n Biden luego de un acuerdo entre la Administraci\u00f3n del Seguro Social y el sindicato que representa a sus trabajadores que les permitir\u00eda continuar con el teletrabajo hasta 2029. Trump y sus aliados, incluidos los empresarios tecnol\u00f3gicos y los jefes de la iniciativa de eficiencia gubernamental de Trump Elon Musk y Vivek Ramaswamy, han sugerido que eliminar\u00edan el teletrabajo para los empleados federales.<\/p>\n<p>\u201cSi la gente no regresa al trabajo, si no regresa a la oficina, los van a despedir. Y alguien en la administraci\u00f3n Biden dio una exenci\u00f3n de cinco a\u00f1os de eso, de modo que durante cinco a\u00f1os, la gente no tenga que volver a la oficina. \u201cInvolucr\u00f3 a 49.000 personas durante cinco a\u00f1os, no tienen por qu\u00e9 ir. Simplemente firmaron esta cosa. Eso es rid\u00edculo. As\u00ed que fue como un regalo a un sindicato\u201d, dijo.<\/p>\n<p>Trump dijo que est\u00e1 considerando emprender acciones legales para bloquear ambas acciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente electo de EE.UU. Donald Trump critic\u00f3 al presidente Joe Biden luego de un par de acciones que la administraci\u00f3n de Biden tom\u00f3 despu\u00e9s de la elecci\u00f3n de Trump en noviembre, incluidos informes de que la administraci\u00f3n vendi\u00f3 materiales de construcci\u00f3n del muro fronterizo entre Estados Unidos y M\u00e9xico y un acuerdo para permitir [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456660","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente electo de EE.UU. Donald Trump critic\u00f3 al presidente Joe Biden luego de un par de acciones que la administraci\u00f3n de Biden tom\u00f3 despu\u00e9s de la elecci\u00f3n de Trump en noviembre, incluidos informes de que la administraci\u00f3n vendi\u00f3 materiales de construcci\u00f3n del muro fronterizo entre Estados Unidos y M\u00e9xico y un acuerdo para permitir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales\",\"datePublished\":\"2024-12-16T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\"},\"wordCount\":455,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\",\"name\":\"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales - Noticias","og_description":"El presidente electo de EE.UU. Donald Trump critic\u00f3 al presidente Joe Biden luego de un par de acciones que la administraci\u00f3n de Biden tom\u00f3 despu\u00e9s de la elecci\u00f3n de Trump en noviembre, incluidos informes de que la administraci\u00f3n vendi\u00f3 materiales de construcci\u00f3n del muro fronterizo entre Estados Unidos y M\u00e9xico y un acuerdo para permitir [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-16T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/"},"author":{"name":"","@id":""},"headline":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales","datePublished":"2024-12-16T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/"},"wordCount":455,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","name":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T19:03:43Z","datePublished":"2024-12-16T19:03:43Z","dateModified":"2024-12-16T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump critica a Biden por vender partes del muro fronterizo y extender el teletrabajo para funcionarios federales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/16\\\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/16\\\/trump-biden-muro-venezuela-teletrabajo-conferencia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T19:03:43Z\",\"datePublished\":\"2024-12-16T19:03:43Z\",\"dateModified\":\"2024-12-16T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452433,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/04\/cambio-harris-centro-muro-fronterizo-asilo-inmigracion-trax\/","url_meta":{"origin":1456660,"position":0},"title":"El cambio de Harris hacia el centro sobre el muro fronterizo y el asilo contradice sus a\u00f1os de posiciones progresistas sobre inmigraci\u00f3n","author":"","date":"septiembre 4, 2024","format":false,"excerpt":"(CNN) -- A la vicepresidenta Kamala Harris le gusta presentarse como dura con la frontera y la inmigraci\u00f3n.Anuncios de televisi\u00f3n recientes destacan su etapa como \"fiscal del estado fronterizo\" que persigui\u00f3 agresivamente a los c\u00e1rteles criminales y a los contrabandistas de drogas, as\u00ed como su apoyo al \"proyecto de ley\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465685,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","url_meta":{"origin":1456660,"position":1},"title":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido","author":"","date":"agosto 20, 2025","format":false,"excerpt":"El muro a lo largo de la frontera sur ser\u00e1 pintado de negro en un esfuerzo por hacer que la estructura sea demasiado caliente para escalarla, anunci\u00f3 este martes la secretaria del Departamento de Seguridad Nacional, Kristi Noem, diciendo que la sugerencia vino del presidente Donald Trump.\u201cEs alto, lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447296,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","url_meta":{"origin":1456660,"position":2},"title":"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;","author":"","date":"marzo 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que el expresidente de Estados Unidos Donald Trump no construir\u00e1 el muro en caso de ganar un segundo mandato en las elecciones de noviembre.En una entrevista con el programa \"60 Minutes\" de CBS, que se emite la noche\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1417877,"url":"https:\/\/noticiasya.com\/midland-odessa\/2022\/08\/04\/cbp-anuncia-pausa-en-la-construccion-de-muro-fronterizo-en-el-parque-de-la-amistad\/","url_meta":{"origin":1456660,"position":3},"title":"CBP anuncia pausa en la construcci\u00f3n de muro fronterizo en el Parque de la Amistad","author":"agomez","date":"agosto 4, 2022","format":false,"excerpt":"La agencia fronteriza destac\u00f3 estar comprometida con preservar el acceso al Parque de la Amistad.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1436564,"url":"https:\/\/noticiasya.com\/midland-odessa\/2023\/01\/24\/activistas-protestan-contra-construccion-de-muro-fronterizo-en-el-parque-de-la-amistad\/","url_meta":{"origin":1456660,"position":4},"title":"Activistas protestan contra construcci\u00f3n de muro fronterizo en el parque de la amistad","author":"","date":"enero 24, 2023","format":false,"excerpt":"Activistas y organizaciones locales seguir\u00e1n protestando durante los pr\u00f3ximos d\u00edas con el fin de ser escuchados.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461587,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/24\/abinader-expansion-muro-fronterizo-reforestacion-indocumentado-orix\/","url_meta":{"origin":1456660,"position":5},"title":"Abinader anuncia expansi\u00f3n del muro fronterizo y plan de reforestaci\u00f3n: &#171;Dejar pasar a un indocumentado es inaceptable&#187;","author":"","date":"abril 24, 2025","format":false,"excerpt":"El presidente de Rep\u00fablica Dominicana, Luis Abinader, lanz\u00f3 este jueves un firme llamado a las tropas, en la frontera con Hait\u00ed, inst\u00e1ndolas a ser \u201clos ojos de la patria\u201d y a duplicar los esfuerzos para resguardar la soberan\u00eda nacional ante el aumento de los flujos migratorios irregulares.\u201cDejar pasar a un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456660"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456660\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}