{"id":1456677,"date":"2024-12-17T09:03:52","date_gmt":"2024-12-17T17:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/"},"modified":"2024-12-17T09:03:52","modified_gmt":"2024-12-17T17:03:52","slug":"indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","title":{"rendered":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia"},"content":{"rendered":"<p>El estado de Indiana tiene la intenci\u00f3n de llevar a cabo su primera ejecuci\u00f3n en 15 a\u00f1os antes del amanecer de este mi\u00e9rcoles, aunque los abogados del recluso condenado est\u00e1n luchando para detener la inyecci\u00f3n letal alegando una enfermedad mental.<\/p>\n<p>Los abogados de Joseph Corcoran \u2014condenado a muerte por los asesinatos de cuatro hombres en 1997, incluidos su hermano y el prometido de su hermana\u2014 han argumentado en documentos judiciales que condenarlo a muerte violar\u00eda las enmiendas Octava y Decimocuarta porque ha sufrido durante mucho tiempo de esquizofrenia paranoide.<\/p>\n<p>El hombre de 49 a\u00f1os experimenta alucinaciones auditivas y delirios, que le hacen creer err\u00f3neamente que los guardias de la prisi\u00f3n lo torturan con ondas sonoras, se\u00f1alan. Corcoran no tiene un entendimiento racional de su situaci\u00f3n, argumentan, a pesar de las propias declaraciones escritas del recluso que indican que desea que su ejecuci\u00f3n proceda.<\/p>\n<p>Ni la Corte Suprema de Indiana ni un juez del tribunal de distrito de EE.UU. en el norte de Indiana han sido convencidos por los argumentos de los abogados, y los tribunales hasta ahora han rechazado detener la ejecuci\u00f3n. Corcoran fue condenado por el asesinato de su hermano, James Corcoran; el prometido de su hermana, Robert Scott Turner; as\u00ed como de Timothy Bricker y Douglas Stillwell.<\/p>\n<p>La ejecuci\u00f3n programada se produce aproximadamente seis meses despu\u00e9s de que el gobernador republicano Eric Holcomb anunciara que el estado hab\u00eda \u201c(despu\u00e9s de a\u00f1os) obtenido el f\u00e1rmaco pentobarbital\u201d, lo que permite reanudar la pena capital por primera vez desde 2009.<\/p>\n<p>Varios organismos han recurrido al sedante para llevar a cabo inyecciones letales en los \u00faltimos a\u00f1os (\u2026). Las compa\u00f1\u00edas farmac\u00e9uticas que se oponen a la pena de muerte han prohibido el uso de sus productos para ejecuciones.<\/p>\n<p>\u201cEn consecuencia, estoy cumpliendo con mis deberes como gobernador siguiendo la ley para avanzar adecuadamente en este asunto\u201d, dijo el gobernador Holcomb en <a href=\"https:\/\/archive.ph\/o\/R4gv2\/https:\/\/events.in.gov\/event\/governor-eric-j-holcomb-and-attorney-general-todd-rokita-seek-execution-date-for-convicted-murderer-3092\">una declaraci\u00f3n <\/a>en el verano boreal.<\/p>\n<p>El fiscal general de Indiana, Todd Rokita, present\u00f3 la pena de muerte \u201ccomo un medio para proporcionar justicia a las v\u00edctimas de los cr\u00edmenes m\u00e1s atroces de la sociedad y hacer responsables a los perpetradores\u201d.<\/p>\n<p>\u201cAhora que el Departamento Correccional de Indiana est\u00e1 listo para cumplir la sentencia impuesta legalmente\u201d, dijo Rokita, \u201ccorresponde a nuestro sistema de justicia permitir inmediatamente que las ejecuciones se reanuden en nuestras prisiones\u201d.<\/p>\n<p>La hermana de Corcoran, Kelly Ernst, quien tambi\u00e9n era hermana de la v\u00edctima James Corcoran y quien estaba comprometida con Turner, se opone a la ejecuci\u00f3n de su hermano y a la pena de muerte de manera m\u00e1s amplia. Le dijo a Associated Press que cree que la grave enfermedad mental de Corcoran es \u201cbastante obvia\u201d.<\/p>\n<p>\u201cSimplemente siento que no hay tal cosa como un cierre\u201d, dijo Ernst, de 56 a\u00f1os, a AP. \u201cSimplemente no s\u00e9 qu\u00e9 m\u00e1s decir. No he dormido en semanas\u201d.<\/p>\n<p>CNN se ha comunicado con Ernst para que hiciera comentarios sobre lo ocurrido.<\/p>\n<p>Adam Bricker, el hermano de la v\u00edctima Timothy Bricker, le dijo a CNN que no est\u00e1 convencido sobre si Corcoran debe ser ejecutado o pasar el resto de su vida en prisi\u00f3n. Pero quiere que el asunto concluya despu\u00e9s de soportar tantos a\u00f1os de cobertura intermitente, lo que reaviva el dolor de su familia.<\/p>\n<p>\u201cNo es justo para mi mam\u00e1, sus hijos que a\u00fan viven, ni para nadie. No es justo y no es correcto\u201d, dijo Adam Bricker.<\/p>\n<p>\u201cComo cristiano, no deseo que nadie muera\u201d, agreg\u00f3. \u201cTampoco deseaba que mi hermano muriera. Pero creo que las leyes deben ser seguidas\u201d.<\/p>\n<p>Indiana es uno de solo dos estados con pena de muerte que no permite a los reporteros presenciar las ejecuciones, seg\u00fan el Centro de Informaci\u00f3n sobre la Pena de Muerte. La ley estatal indica que los presentes pueden incluir a funcionarios de correccionales, el asesor espiritual del condenado, hasta cinco amigos o familiares del recluso y hasta ocho miembros de las familias inmediatas de la v\u00edctima o v\u00edctimas.<\/p>\n<p>En otros estados, los testigos de los medios generalmente act\u00faan como monitores p\u00fablicos neutrales, informando al p\u00fablico sobre los detalles de una ejecuci\u00f3n. Esto puede implicar informar sobre ejecuciones que violan el protocolo de un estado, una responsabilidad particularmente importante cuando contradicen la caracterizaci\u00f3n de los eventos por parte de los funcionarios.<\/p>\n<p>En el momento de los asesinatos, Corcoran estaba estresado porque el matrimonio de su hermana lo hab\u00eda obligado a mudarse de su casa, seg\u00fan un resumen del caso incluido en la decisi\u00f3n de la Corte Suprema de Indiana este mes. Corcoran, quien seg\u00fan AP hab\u00eda sido acusado pero absuelto por el asesinato de sus padres en 1992, se despert\u00f3 una tarde y supuestamente escuch\u00f3 a su hermano y a otros hombres hablando de \u00e9l, dice ese resumen, y dispar\u00f3 fatalmente a los cuatro con un rifle.<\/p>\n<p>Hay pruebas de la enfermedad mental de Corcoran incluso previas a los asesinatos, dijeron sus abogados en una apelaci\u00f3n en la corte federal este mes, citando testigos que lo recordaban hablando con personas que no estaban presentes o instancias en las que insisti\u00f3 err\u00f3neamente que la gente hablaba de \u00e9l.<\/p>\n<p>Los abogados de Corcoran sostienen que nunca debi\u00f3 ser juzgado. Pero sus dos abogados en ese momento no se dieron cuenta de la magnitud de su enfermedad mental, escribieron en nuevas declaraciones juradas, y no solicitaron una audiencia de competencia.<\/p>\n<p>Cuando sus abogados intentaron presentar una apelaci\u00f3n posterior a la condena, Corcoran al principio se neg\u00f3 a firmarla, una decisi\u00f3n que en ese momento impidi\u00f3 su revisi\u00f3n. Sus abogados argumentaron en una audiencia de 2003 que Corcoran era incompetente y presentaron el testimonio de tres expertos en salud mental, cada uno de los cuales diagnostic\u00f3 a Corcoran con esquizofrenia paranoide.<\/p>\n<p>La corte finalmente determin\u00f3 que Corcoran era competente para renunciar a sus apelaciones, y aunque el recluso cambiar\u00eda de opini\u00f3n despu\u00e9s de eso, ya era demasiado tarde. Su petici\u00f3n fue desestimada.<\/p>\n<p>La enfermedad de Corcoran no ha mejorado en las \u00faltimas dos d\u00e9cadas y ha demostrado ser resistente a los intentos de medicaci\u00f3n del Departamento de Correcciones de Indiana, dicen sus abogados.<\/p>\n<p>Aun as\u00ed, la corte suprema del estado dictamin\u00f3 este mes que sus abogados no hab\u00edan logrado demostrar que algo hab\u00eda cambiado desde que se consider\u00f3 al recluso competente. Un juez federal igualmente determin\u00f3 que la afirmaci\u00f3n de que Corcoran era incompetente para la ejecuci\u00f3n carec\u00eda de fundamento.<\/p>\n<p>Ambas cortes se\u00f1alaron en parte a una declaraci\u00f3n jurada reciente presentada ante la corte alta del estado, en la que Corcoran escribi\u00f3 que quer\u00eda abandonar sus apelaciones y afirm\u00f3 que entend\u00eda las consecuencias de ser ejecutado. Pero los abogados de Corcoran argumentaron que esta declaraci\u00f3n jurada no era cre\u00edble, citando a otro psiquiatra que determin\u00f3 que los escritos del recluso \u2014aunque parec\u00edan l\u00f3gicos\u2014 est\u00e1n ligados a sus delirios.<\/p>\n<p>\u201cEs irracional permitir que los insanos determinen su propia competencia\u201d, escribieron los abogados.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estado de Indiana tiene la intenci\u00f3n de llevar a cabo su primera ejecuci\u00f3n en 15 a\u00f1os antes del amanecer de este mi\u00e9rcoles, aunque los abogados del recluso condenado est\u00e1n luchando para detener la inyecci\u00f3n letal alegando una enfermedad mental. Los abogados de Joseph Corcoran \u2014condenado a muerte por los asesinatos de cuatro hombres en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456677","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia - Noticias\" \/>\n<meta property=\"og:description\" content=\"El estado de Indiana tiene la intenci\u00f3n de llevar a cabo su primera ejecuci\u00f3n en 15 a\u00f1os antes del amanecer de este mi\u00e9rcoles, aunque los abogados del recluso condenado est\u00e1n luchando para detener la inyecci\u00f3n letal alegando una enfermedad mental. Los abogados de Joseph Corcoran \u2014condenado a muerte por los asesinatos de cuatro hombres en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-17T17:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia\",\"datePublished\":\"2024-12-17T17:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\"},\"wordCount\":1233,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\",\"name\":\"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-17T17:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia - Noticias","og_description":"El estado de Indiana tiene la intenci\u00f3n de llevar a cabo su primera ejecuci\u00f3n en 15 a\u00f1os antes del amanecer de este mi\u00e9rcoles, aunque los abogados del recluso condenado est\u00e1n luchando para detener la inyecci\u00f3n letal alegando una enfermedad mental. Los abogados de Joseph Corcoran \u2014condenado a muerte por los asesinatos de cuatro hombres en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-17T17:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/"},"author":{"name":"","@id":""},"headline":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia","datePublished":"2024-12-17T17:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/"},"wordCount":1233,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","name":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-17T17:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Indiana planea su primera ejecuci\u00f3n en 15 a\u00f1os contra un acusado por cu\u00e1druple asesinato, a pesar de su esquizofrenia","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-17T17:03:52Z","datePublished":"2024-12-17T17:03:52Z","dateModified":"2024-12-17T17:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Indiana planea su primera ejecuci\\u00f3n en 15 a\\u00f1os contra un acusado por cu\\u00e1druple asesinato, a pesar de su esquizofrenia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/17\\\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/17\\\/indiana-ejecucion-cuadruple-asesinato-esquizofrenia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-17T17:03:52Z\",\"datePublished\":\"2024-12-17T17:03:52Z\",\"dateModified\":\"2024-12-17T17:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464001,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/27\/japon-ejecuta-asesino-twitter-trax\/","url_meta":{"origin":1456677,"position":0},"title":"Jap\u00f3n ejecuta al &#171;asesino de Twitter&#187; que mat\u00f3 y desmembr\u00f3 a nueve personas","author":"","date":"junio 27, 2025","format":false,"excerpt":"Jap\u00f3n ejecut\u00f3 a un hombre conocido como el \u201casesino de Twitter\u201d, condenado por matar y desmembrar a nueve personas, en su mayor\u00eda mujeres, en la primera aplicaci\u00f3n de la pena capital en el pa\u00eds en casi tres a\u00f1os.Takahiro Shiraishi, de 34 a\u00f1os, fue ahorcado el viernes en el Centro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455846,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/11\/15\/corte-suprema-texas-fecha-ejecucion-robert-robertson-bebe-sacudido-trax\/","url_meta":{"origin":1456677,"position":1},"title":"Corte Suprema de Texas allana el camino para una nueva fecha de ejecuci\u00f3n de Robert Roberson en caso de &#171;beb\u00e9 sacudido&#187;","author":"","date":"noviembre 15, 2024","format":false,"excerpt":"(CNN) -- La Corte Suprema de Texas deneg\u00f3 este viernes el intento de una comisi\u00f3n de la c\u00e1mara estatal de retrasar la ejecuci\u00f3n de un hombre condenado por homicidio por la muerte en 2002 de su hija de 2 a\u00f1os, con lo que allan\u00f3 el camino para una nueva fecha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447876,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/09\/misuri-ejecutara-brian-dorsey-doble-asesinato-2006-trax\/","url_meta":{"origin":1456677,"position":2},"title":"El estado de Misuri ejecutar\u00e1 a Brian Dorsey por el doble asesinato de 2006 despu\u00e9s de que el gobernador denegara el indulto","author":"","date":"abril 9, 2024","format":false,"excerpt":"(CNN) -- El estado de Misuri tiene planeado ejecutar a Brian Dorsey este martes por la tarde por los asesinatos de su prima y el marido de \u00e9sta en 2006, despu\u00e9s de que el gobernador denegara el indulto un d\u00eda antes, a pesar del apoyo de m\u00e1s de 70 funcionarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459625,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/07\/brad-singmon-peloton-fusilamiento-carolina-del-sur-trax\/","url_meta":{"origin":1456677,"position":3},"title":"\u00bfQui\u00e9n es Brad Sigmon y por qu\u00e9 ser\u00e1 ejecutado por un pelot\u00f3n de fusilamiento en Carolina del Sur?","author":"","date":"marzo 7, 2025","format":false,"excerpt":"Un hombre condenado por un doble homicidio ser\u00e1 ejecutado en Carolina del Sur el viernes por la noche por un pelot\u00f3n de fusilamiento, un m\u00e9todo que no se ha utilizado en Estados Unidos en casi 15 a\u00f1os y nunca en el estado.Brad Sigmon, de 67 a\u00f1os, eligi\u00f3 el pelot\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447863,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/08\/defensores-brian-dorsey-muerte-missouri-ejecucion-trax\/","url_meta":{"origin":1456677,"position":4},"title":"Defensores de Brian Dorsey, condenado a muerte en Missouri, piden clemencia a pocos d\u00edas de su ejecuci\u00f3n","author":"","date":"abril 8, 2024","format":false,"excerpt":"(CNN) -- Missouri planea ejecutar esta semana a Brian Dorsey, condenado a muerte por los homicidios de su prima y su marido en 2006, pero una petici\u00f3n de clemencia muestra que decenas de personas han pedido al gobernador Mike Parsons que le perdone la vida, citando la rehabilitaci\u00f3n de Dorsey\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447906,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/09\/missouri-ejecuta-brian-dorsey-trax\/","url_meta":{"origin":1456677,"position":5},"title":"Missouri ejecuta a Brian Dorsey por un asesinato doble en 2006 tras un pedido de clemencia que respaldaron 72 funcionarios penitenciarios","author":"","date":"abril 9, 2024","format":false,"excerpt":"(CNN) -- El estado de Missouri ejecut\u00f3 a Brian Dorsey quien, tras ser condenado a muerte por asesinar a su prima y al marido de su prima, obtuvo el apoyo de m\u00e1s de 70 funcionarios penitenciarios y otras personas que hab\u00edan respaldado salvarle la vida.Dorsey, de 52 a\u00f1os, fue ejecutado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456677"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456677\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}