{"id":1456684,"date":"2024-12-17T15:03:46","date_gmt":"2024-12-17T23:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/"},"modified":"2024-12-17T15:03:46","modified_gmt":"2024-12-17T23:03:46","slug":"color-buho-dificultar-caza-util-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","title":{"rendered":"El color &#171;impactante&#187; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil?"},"content":{"rendered":"<p>Los b\u00fahos comunes, que vuelan lenta y silenciosamente por el cielo nocturno, son majestuosos cazadores nocturnos que atrapan con \u00e9xito a los roedores que corretean por el suelo.<\/p>\n<p>Los cient\u00edficos llevan mucho tiempo debatiendo sobre una caracter\u00edstica que parecer\u00eda perjudicar a esta ave durante sus cacer\u00edas nocturnas. El plumaje de su vientre y de sus alas es de un blanco brillante, un rasgo inusual que, en teor\u00eda, deber\u00eda dificultarle acercarse a su presa sin ser detectado.<\/p>\n<p>A diferencia del b\u00faho nival, el b\u00faho com\u00fan vive en latitudes donde no nieva con regularidad. El plumaje parad\u00f3jicamente brillante del b\u00faho com\u00fan desconcert\u00f3 al bi\u00f3logo Juanjo Negro y a sus colegas, quienes pensaron que el intrigante fen\u00f3meno biol\u00f3gico ameritaba una investigaci\u00f3n m\u00e1s profunda.<\/p>\n<p>\u201cPartimos de la intuici\u00f3n de que la blancura tan llamativa del b\u00faho com\u00fan es tan impactante que deber\u00eda implicar alguna ventaja adaptativa\u201d, dijo Negro, profesor de investigaci\u00f3n de la Estaci\u00f3n Biol\u00f3gica de Do\u00f1ana y del Consejo Superior de Investigaciones Cient\u00edficas en Sevilla, Espa\u00f1a, por correo electr\u00f3nico.<\/p>\n<p><a href=\"https:\/\/www.nature.com\/articles\/s41559-019-0967-2\">Investigaciones anteriores de septiembre de 2019<\/a> hab\u00edan sugerido que la coloraci\u00f3n blanca brillante era esencialmente una forma de conmoci\u00f3n y asombro, que explotaba la aversi\u00f3n de los roedores a la luz brillante. Al hacer que el depredador fuera m\u00e1s visible para las presas roedoras, que se quedaban paralizadas de miedo, la blancura de los b\u00fahos hizo que los ratones fueran m\u00e1s f\u00e1ciles de matar, seg\u00fan el estudio anterior.<\/p>\n<p>Las \u00faltimas investigaciones de Negro y su equipo sugieren, en cambio, que el brillante plumaje blanco del b\u00faho es en realidad una forma de camuflaje nocturno o contrailuminaci\u00f3n que proporciona al cazador un elemento de sorpresa.<\/p>\n<p>De acuerdo con el nuevo estudio que describe los hallazgos del equipo y que se public\u00f3 el lunes en la revista <a href=\"https:\/\/www.pnas.org\/doi\/10.1073\/pnas.2406808121\">PNAS<\/a>, la parte inferior blanca reflectante del ave imita eficazmente la luz de la luna. El plumaje brillante permite que su silueta se mimetice con el cielo nocturno y hace que sea m\u00e1s dif\u00edcil para los ratones u otros roedores detectar al b\u00faho.<\/p>\n<p>\u201cCuando la luna es visible, el cielo tiene un brillo que var\u00eda seg\u00fan la direcci\u00f3n de observaci\u00f3n. En estas condiciones, un p\u00e1jaro oscuro ser\u00eda visto por su presa potencial como una silueta negra contra el cielo\u201d, dijo Negro, autor principal del estudio. \u201cPero, si la parte ventral del p\u00e1jaro es lo suficientemente reflectante, en otras palabras, si es lo suficientemente \u2018blanca\u2019, reflejar\u00eda una buena parte de la luna\u201d.<\/p>\n<p>Seg\u00fan los c\u00e1lculos de los investigadores, el contraste entre las partes inferiores blancas y reflectantes de los b\u00fahos y amplias \u00e1reas del cielo nocturno iluminado cae por debajo del umbral de detecci\u00f3n de la agudeza visual de los roedores, lo que permite a los b\u00fahos acercarse a sus presas a pocos metros desde una amplia gama de direcciones sin ser detectadas.<\/p>\n<p>\u201cEsta explicaci\u00f3n no se hab\u00eda propuesto antes para justificar la blancura de los b\u00fahos\u201d, a\u00f1adi\u00f3 Negro.<\/p>\n<p>Un fen\u00f3meno similar existe en el oc\u00e9ano, donde los peces a menudo tienen la parte inferior de color claro para combinar con el agua iluminada por el sol y hacerlos menos visibles para los depredadores que rondan en las profundidades.<\/p>\n<p>Sin embargo, no todos los b\u00fahos tienen el vientre blanco; algunos tienen en cambio un plumaje de color marr\u00f3n rojizo.<\/p>\n<p>Negro dijo que el estudio no investig\u00f3 la eficacia de la caza en relaci\u00f3n con el color del plumaje, pero investigaciones anteriores hab\u00edan sugerido que los b\u00fahos m\u00e1s blancos eran cazadores m\u00e1s eficientes que sus contrapartes m\u00e1s oscuras durante la luna llena.<\/p>\n<p><a href=\"https:\/\/barnowl-research.ch\/en\">Alexandre Roulin<\/a>, experto en b\u00fahos comunes y profesor de biolog\u00eda en el departamento de ecolog\u00eda y evoluci\u00f3n de la Universidad de Lausana, quien dirigi\u00f3 la investigaci\u00f3n anterior que suger\u00eda que la coloraci\u00f3n blanca de la especie conmocionaba e inmovilizaba a sus presas, dijo que no estaba completamente convencido por la nueva explicaci\u00f3n. Sin embargo, dijo que no pod\u00eda descartarla.<\/p>\n<p>\u201cNo queremos descartar por completo la hip\u00f3tesis de los autores. De hecho, puede que sea complementaria a la nuestra. Tal vez a grandes distancias el plumaje blanco ayude al camuflaje, mientras que a distancias m\u00e1s cortas, puede servir para hacer al b\u00faho m\u00e1s visible\u201d, dijo por correo electr\u00f3nico.<\/p>\n<p>Un aspecto clave que, seg\u00fan Roulin, necesita mayor explicaci\u00f3n es el comportamiento de los ratones bajo la luz de la luna.<\/p>\n<p>\u201cObservamos que los topillos permanec\u00edan inm\u00f3viles durante m\u00e1s tiempo cuando el b\u00faho que se acercaba era blanco en lugar de rojizo. Investigaciones anteriores han demostrado que esta inmovilizaci\u00f3n es una respuesta antidepredadora\u201d, dijo Roulin. \u201cBas\u00e1ndonos en esto, podr\u00edamos afirmar que los topillos reconocieron al b\u00faho blanco como un depredador, lo que sugiere que el b\u00faho era visible, en lugar de estar camuflado\u201d.<\/p>\n<p>Negro dijo que la capacidad del b\u00faho de volar en completo silencio, una caracter\u00edstica que le permite acercarse sigilosamente a sus presas, no concuerda con la idea de que el depredador quiera hacerse m\u00e1s visible. No obstante, estuvo de acuerdo en que la nueva hip\u00f3tesis no desmiente por completo la teor\u00eda anterior.<\/p>\n<p>El camuflaje suele considerarse un fen\u00f3meno diurno basado en la luz y la sombra. Negro dijo que es probable que existan otras formas de coloraci\u00f3n animal que sirvieron como camuflaje nocturno, que no han sido tan bien estudiadas como las t\u00e1cticas de ocultamiento diurnas.<\/p>\n<p>\u201cLa ecolog\u00eda nocturna es un campo emergente y, considerando que la mitad de los animales del planeta son esencialmente nocturnos, las adaptaciones a los ciclos naturales de la Luna seguramente est\u00e1n muy extendidas\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los b\u00fahos comunes, que vuelan lenta y silenciosamente por el cielo nocturno, son majestuosos cazadores nocturnos que atrapan con \u00e9xito a los roedores que corretean por el suelo. Los cient\u00edficos llevan mucho tiempo debatiendo sobre una caracter\u00edstica que parecer\u00eda perjudicar a esta ave durante sus cacer\u00edas nocturnas. El plumaje de su vientre y de sus [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456684","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El color &quot;impactante&quot; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El color &quot;impactante&quot; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los b\u00fahos comunes, que vuelan lenta y silenciosamente por el cielo nocturno, son majestuosos cazadores nocturnos que atrapan con \u00e9xito a los roedores que corretean por el suelo. Los cient\u00edficos llevan mucho tiempo debatiendo sobre una caracter\u00edstica que parecer\u00eda perjudicar a esta ave durante sus cacer\u00edas nocturnas. El plumaje de su vientre y de sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-17T23:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El color &#171;impactante&#187; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil?\",\"datePublished\":\"2024-12-17T23:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\"},\"wordCount\":1039,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\",\"name\":\"El color \\\"impactante\\\" de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-17T23:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El color &#171;impactante&#187; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El color \"impactante\" de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El color \"impactante\" de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil? - Noticias","og_description":"Los b\u00fahos comunes, que vuelan lenta y silenciosamente por el cielo nocturno, son majestuosos cazadores nocturnos que atrapan con \u00e9xito a los roedores que corretean por el suelo. Los cient\u00edficos llevan mucho tiempo debatiendo sobre una caracter\u00edstica que parecer\u00eda perjudicar a esta ave durante sus cacer\u00edas nocturnas. El plumaje de su vientre y de sus [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-17T23:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/"},"author":{"name":"","@id":""},"headline":"El color &#171;impactante&#187; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil?","datePublished":"2024-12-17T23:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/"},"wordCount":1039,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","name":"El color \"impactante\" de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-17T23:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El color &#171;impactante&#187; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El color &#171;impactante&#187; de un b\u00faho deber\u00eda dificultar la caza. \u00bfPor qu\u00e9 en realidad es \u00fatil?","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/color-buho-dificultar-caza-util-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-17T23:03:46Z","datePublished":"2024-12-17T23:03:46Z","dateModified":"2024-12-17T23:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El color &#171;impactante&#187; de un b\\u00faho deber\\u00eda dificultar la caza. \\u00bfPor qu\\u00e9 en realidad es \\u00fatil?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/17\\\/color-buho-dificultar-caza-util-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/17\\\/color-buho-dificultar-caza-util-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-17T23:03:46Z\",\"datePublished\":\"2024-12-17T23:03:46Z\",\"dateModified\":\"2024-12-17T23:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458624,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/buho-duolingo-ha-muerto-exbuho-trax\/","url_meta":{"origin":1456684,"position":0},"title":"La simp\u00e1tica mascota b\u00faho de Duolingo ha muerto. Es un exb\u00faho","author":"","date":"febrero 12, 2025","format":false,"excerpt":"El b\u00faho verde que era el logo de la aplicaci\u00f3n de aprendizaje de idiomas Duolingo ya no existe.La compa\u00f1\u00eda estadounidense detr\u00e1s de la aplicaci\u00f3n, que se convirti\u00f3 en un nombre familiar durante la pandemia de Covid-19, emiti\u00f3 un anuncio revelando que su simp\u00e1tico b\u00faho de dibujos animados ha muerto.Siguiendo los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456855,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/22\/fosa-edad-bronce-masacre-trax\/","url_meta":{"origin":1456684,"position":1},"title":"Una fosa com\u00fan de la Edad de Bronce revela una masacre espantosa en la que las v\u00edctimas probablemente fueron devoradas","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"Hoy en d\u00eda, la meseta de piedra caliza de Mendip Hills, en el Reino Unido, es famosa por su belleza natural. Pero hace unos 4.000 a\u00f1os, en la Edad del Bronce Temprano, all\u00ed se desarroll\u00f3 un cap\u00edtulo espeluznante de la prehistoria brit\u00e1nica.Miles de huesos humanos excavados en las d\u00e9cadas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470624,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/29\/descubren-tumba-oaxaca-buho-mexico-trax\/","url_meta":{"origin":1456684,"position":2},"title":"Descubren en M\u00e9xico asombrosa tumba zapoteca de 1.400 a\u00f1os con s\u00edmbolos en piedra, un mural y una escultura gigante de b\u00faho","author":"","date":"enero 29, 2026","format":false,"excerpt":"Arque\u00f3logos descubrieron una tumba zapoteca de 1.400 a\u00f1os en el sur de M\u00e9xico, adornada con complejos relieves, la cual ha sido calificada como \u201cel descubrimiento arqueol\u00f3gico m\u00e1s importante de la \u00faltima d\u00e9cada\u201d.Ubicada en San Pablo Huitzo, en el estado de Oaxaca, la tumba fue construida por la cultura zapoteca alrededor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462690,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/22\/venezolano-cecot-abogado-tras-orden-judicial-ee-uu-trax\/","url_meta":{"origin":1456684,"position":3},"title":"Venezolano en el Cecot espera contacto con su abogado tras orden judicial de EE.UU. para que restablezca comunicaci\u00f3n","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Un ciudadano venezolano que hab\u00eda sido aprobado para ingresar a Estados Unidos bajo el Programa de Reasentamiento de Refugiados de las Naciones Unidas aparentemente termin\u00f3 en una prisi\u00f3n de El Salvador y ahora espera saber si tendr\u00e1 la oportunidad de hablar con su abogado, despu\u00e9s de que un juez ordenara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470648,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/30\/5-cosas-30-de-enero-orix\/","url_meta":{"origin":1456684,"position":4},"title":"Las 5 cosas que debes saber este 30 de enero","author":"","date":"enero 30, 2026","format":false,"excerpt":"Trump 2.0 ve terrorismo por todas partes. Corte de apelaciones de EE.UU. dice que el fin del TPS para los venezolanos fue ilegal. Caracas aprueba reforma a ley de hidrocarburos. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463812,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/21\/senales-hielo-antartico-fisica-buscan-respuesta-trax\/","url_meta":{"origin":1456684,"position":5},"title":"Detectan se\u00f1ales extra\u00f1as en el hielo ant\u00e1rtico que parecen desafiar las leyes de la f\u00edsica. Cient\u00edficos buscan una respuesta","author":"","date":"junio 21, 2025","format":false,"excerpt":"Los cient\u00edficos intentan resolver un misterio de una d\u00e9cada al determinar la identidad de se\u00f1ales an\u00f3malas detectadas bajo el hielo de la Ant\u00e1rtida.Las extra\u00f1as ondas de radio surgieron durante la b\u00fasqueda de otro fen\u00f3meno inusual: part\u00edculas c\u00f3smicas de alta energ\u00eda conocidas como neutrinos. Al llegar a la Tierra desde los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456684"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456684\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}