{"id":1456686,"date":"2024-12-17T16:03:52","date_gmt":"2024-12-18T00:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/"},"modified":"2024-12-17T16:03:52","modified_gmt":"2024-12-18T00:03:52","slug":"abuela-alabama-rinon-cerdo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","title":{"rendered":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente"},"content":{"rendered":"<p>Towana Looney es la \u00fanica persona del mundo que vive con un ri\u00f1\u00f3n funcional de cerdo. Pero su m\u00e9dico predice que, en menos de una d\u00e9cada, los trasplantes de \u00f3rganos de cerdo a humanos como el suyo podr\u00edan convertirse en rutinarios.<\/p>\n<p>Looney, de 53 a\u00f1os, es de Alabama y se someti\u00f3 al trasplante en el Instituto de Trasplantes Langone de la NYU de Nueva York el 25 de noviembre. Once d\u00edas despu\u00e9s, pudo salir por la puerta mientras el personal del hospital aplaud\u00eda en el vest\u00edbulo. Con mascarilla y sudadera del NYU Langone Health, Looney alz\u00f3 los pulgares al aire.<\/p>\n<p>Los m\u00e9dicos anunciaron el martes que Looney se encuentra bien y que el ri\u00f1\u00f3n parece funcionar seg\u00fan lo previsto.<\/p>\n<p>\u201cEstoy encantada. Me siento bendecida por haber recibido este regalo, una segunda oportunidad en la vida\u201d, dijo Looney en una rueda de prensa el martes. \u201cEstoy llena de energ\u00eda. Tengo un apetito que nunca hab\u00eda tenido en ocho a\u00f1os. Y por supuesto, ya saben, puedo ir al ba\u00f1o. No he ido en ocho a\u00f1os. No puedo acostumbrarme a eso\u201d.<\/p>\n<p>Al preguntarle qu\u00e9 quiere hacer ahora, respondi\u00f3: \u201cQuiero ir a Disney World\u201d.<\/p>\n<p>Por ahora, vive en un apartamento cerca del hospital para poder hacerse chequeos todos los d\u00edas. El equipo de m\u00e9dicos tambi\u00e9n controla su salud mediante inteligencia artificial y equipos port\u00e1tiles que pueden realizar un seguimiento constante de sus signos vitales e, incluso, detectar potencialmente un problema como una infecci\u00f3n antes de que pueda enfermar.<\/p>\n<p>Looney no estar\u00e1 de vuelta en Alabama a tiempo para las fiestas, pero sus m\u00e9dicos dicen que, si todo va bien, podr\u00eda volver a casa en tres meses, donde tendr\u00e1 muchas ganas de reanudar una vida normal y pasar tiempo de calidad con su familia y sus nietos.<\/p>\n<p>Looney no ha tenido una vida normal desde hace tiempo. Era una de las m\u00e1s de 90.000 personas que actualmente est\u00e1n en <a href=\"https:\/\/www.kidneyregistry.com\/for-donors\/kidney-donation-blog\/is-there-a-living-kidney-donor-waiting-list-for-kidney-transplants\/\">lista de espera<\/a> para un trasplante de ri\u00f1\u00f3n en Estados Unidos.<\/p>\n<p>\u201cSi hiciera caso a lo negativo y no siguiera lo positivo, no estar\u00eda aqu\u00ed\u201d, dijo Looney. \u201cMe gu\u00edo por la fe. Conoce d\u00f3nde est\u00e1 tu fe y el resto llegar\u00e1\u201d.<\/p>\n<p>Incluso antes de esta operaci\u00f3n, Looney no era ajena a los trasplantes. En 1999 don\u00f3 un ri\u00f1\u00f3n a su madre para salvarle la vida. Pero tiempo despu\u00e9s, se convirti\u00f3 en una de las menos del 1% de donantes vivos de ri\u00f1\u00f3n que desarrollan insuficiencia renal, seg\u00fan la <a href=\"https:\/\/www.kidney.org\/kidney-topics\/what-to-expect-after-donation#:~:text=Does%20living%20donation%20affect%20life,the%20risks%20of%20living%20donation.\">Fundaci\u00f3n Nacional del Ri\u00f1\u00f3n<\/a>.<\/p>\n<p>En el \u00faltimo trimestre de su embarazo, Looney sufri\u00f3 preeclampsia, una grave afecci\u00f3n cuyos s\u00edntomas son la hipertensi\u00f3n, que da\u00f1\u00f3 el ri\u00f1\u00f3n que le quedaba. Tambi\u00e9n tuvo que someterse a una transfusi\u00f3n de sangre, y ambos factores dificultaron encontrar un donante de ri\u00f1\u00f3n compatible.<\/p>\n<p>En 2016, Looney se someti\u00f3 a di\u00e1lisis, un procedimiento que ayuda a eliminar los residuos y el exceso de l\u00edquido de la sangre. La di\u00e1lisis puede ser \u00fatil a corto plazo, pero solo puede hacer entre el 10% y el 15% de lo que hace un<a href=\"https:\/\/www.kidneyfund.org\/treatments\/dialysis#:~:text=It%20helps%20your%20body%20remove,what%20a%20normal%20kidney%20does.\"> ri\u00f1\u00f3n sano<\/a>, y las personas en di\u00e1lisis se enfrentan a un 50% de probabilidades de morir en cinco a\u00f1os despu\u00e9s de comenzar el tratamiento, <a href=\"https:\/\/pharm.ucsf.edu\/kidney\/need\/statistics#:~:text=After%20one%20year%20of%20treatment,about%2080%25%20after%205%20years.\">seg\u00fan muestran los estudios<\/a>.<\/p>\n<p>\u201cSe ha sensibilizado a casi todos los tipos de tejido de la poblaci\u00f3n, lo que hace casi imposible encontrar un ri\u00f1\u00f3n compatible\u201d, explica uno de sus m\u00e9dicos, el Dr. Robert Montgomery, director del Instituto de Trasplantes Langone de la NYU. \u201cLanguideci\u00f3 durante ocho a\u00f1os en di\u00e1lisis a la espera de un ri\u00f1\u00f3n compatible entre un mill\u00f3n. Empez\u00f3 a desarrollar problemas asociados a la dependencia cr\u00f3nica de la di\u00e1lisis. Sin una v\u00eda para recibir un ri\u00f1\u00f3n humano, decidi\u00f3 que merec\u00eda la pena probar un ri\u00f1\u00f3n de cerdo modificado gen\u00e9ticamente, y mucha gente apoy\u00f3 su decisi\u00f3n, incluidos su marido y su familia\u201d.<\/p>\n<p>Looney entr\u00f3 en la lista de espera para recibir un ri\u00f1\u00f3n en 2017. Sus m\u00e9dicos dijeron que estaba perdiendo lentamente vasos sangu\u00edneos accesibles para continuar con la di\u00e1lisis y que eventualmente dejar\u00eda de ser \u00fatil. Sin un donante compatible, fallecer\u00eda.<\/p>\n<p>Looney oy\u00f3 hablar por primera vez de la opci\u00f3n de un trasplante de ri\u00f1\u00f3n porcino gracias a la doctora Jayme Locke, entonces profesora de Cirug\u00eda y directora de la Divisi\u00f3n de Trasplantes de la Facultad de Medicina Heersink de la Universidad de Alabama en Birmingham. Locke fue nombrada recientemente para un nuevo puesto de direcci\u00f3n de trasplantes en la Administraci\u00f3n de Recursos y Servicios Sanitarios de Estados Unidos.<\/p>\n<p>Locke explic\u00f3 el trabajo que realiz\u00f3 con xenotrasplantes, t\u00e9rmino con el que los m\u00e9dicos denominan el trasplante de \u00f3rganos de animales a humanos. A pesar de los a\u00f1os de estudio, este campo est\u00e1 a\u00fan en sus primeras fases.<\/p>\n<p>Looney es la <a href=\"https:\/\/archive.ph\/9teig\">tercera persona<\/a> que recibe en vida un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente. Pero Looney no dej\u00f3 pasar la oportunidad de probarlo, y Locke ni siquiera hab\u00eda terminado de plantearle la cuesti\u00f3n antes de que aceptara.<\/p>\n<p>Locke explic\u00f3 las probabilidades y pregunt\u00f3 a Looney por qu\u00e9 aceptaba participar en un procedimiento experimental. Looney respondi\u00f3 que quer\u00eda ayudar a la gente.<\/p>\n<p>Locke dijo el martes que la energ\u00eda de Looney, incluso inmediatamente despu\u00e9s del trasplante, dec\u00eda mucho de lo que el xenotrasplante puede hacer por la gente.<\/p>\n<p>\u201cEstar en su habitaci\u00f3n inmediatamente despu\u00e9s del trasplante y ver a su marido mirarla y describirla como si tuviera una vida en ella que \u00e9l no hab\u00eda visto, este color rosado en sus mejillas, verla tener llamadas FaceTime con su familia, y luego ver un cambio inmediato, ese es el milagro del trasplante\u201d, dijo Locke. \u201cLiteralmente, devuelve a las personas la salud que ten\u00edan antes de someterse a di\u00e1lisis. Y ella lo sinti\u00f3 al instante. Su familia lo sinti\u00f3, y su comunidad lo ha sentido, y creo que ustedes lo vieron hoy\u201d.<\/p>\n<p>La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) permite a los m\u00e9dicos trasplantar \u00f3rganos de cerdos a humanos en virtud de lo que se conoce como \u201cuso compasivo\u201d, que permite utilizar una terapia o procedimiento experimental si no se dispone de opciones \u201ccomparables o satisfactorias\u201d.<\/p>\n<p>Los \u00f3rganos de los cerdos son similares a los de los humanos, y la velocidad de reproducci\u00f3n de los cerdos permite obtenerlos r\u00e1pidamente. Los cient\u00edficos pueden editar los genes del cerdo para reducir el riesgo de que el cuerpo humano rechace su \u00f3rgano.<\/p>\n<p>De las tres personas que han recibido en vida un ri\u00f1\u00f3n de un cerdo editado gen\u00e9ticamente, ella es la primera en recibir un ri\u00f1\u00f3n con 10 genes editados. Las modificaciones gen\u00e9ticas deben hacer que el \u00f3rgano del cerdo sea m\u00e1s compatible con el ser humano para que el cuerpo no lo rechace. United Therapeutics, la empresa que desarroll\u00f3 el ri\u00f1\u00f3n porcino modificado, dijo el martes que planea presentarlo a la FDA \u00abmuy, muy pronto\u00bb para que los estudios cl\u00ednicos puedan comenzar con el ri\u00f1\u00f3n con 10 ediciones ya el a\u00f1o que viene.<\/p>\n<p>\u201cCreo que el pr\u00f3ximo objetivo es prolongar la vida de estos ri\u00f1ones, y parte de ello consiste en colocarlos en personas m\u00e1s sanas que tengan m\u00e1s posibilidades de vivir m\u00e1s tiempo\u201d, declar\u00f3 Montgomery.<\/p>\n<p>Seg\u00fan los m\u00e9dicos, Looney goza de mejor salud que los dem\u00e1s pacientes que se sometieron a un trasplante de ri\u00f1\u00f3n de cerdo a principios de a\u00f1o, lo que deber\u00eda suponer una ventaja para ella.<\/p>\n<p>En marzo, Rick Slayman, de 52 a\u00f1os, con <a href=\"https:\/\/archive.ph\/LXrih\">insuficiencia renal terminal<\/a>, recibi\u00f3 un trasplante de ri\u00f1\u00f3n de cerdo en el Hospital General de Massachusetts. El ri\u00f1\u00f3n funcion\u00f3 al principio y pudo irse a casa a las dos semanas, pero muri\u00f3 unos dos meses despu\u00e9s.<\/p>\n<p>En abril, la NYU realiz\u00f3 un trasplante de ri\u00f1\u00f3n de cerdo con bomba card\u00edaca mec\u00e1nica a Lisa Pisano, de 54 a\u00f1os, que vivi\u00f3 casi tres meses m\u00e1s.<\/p>\n<p>En el caso de Looney, seg\u00fan Locke, el ri\u00f1\u00f3n empez\u00f3 a funcionar de inmediato, como lo har\u00eda un ri\u00f1\u00f3n de un donante humano. Despu\u00e9s de tres semanas, sigue en buena forma.<\/p>\n<p>\u201cEste ri\u00f1\u00f3n es extraordinario\u201d, afirma Locke.<\/p>\n<p>El equipo m\u00e9dico de Looney espera que el ri\u00f1\u00f3n siga funcionando para que pueda tener una vida larga y sana. En la rueda de prensa, Looney ten\u00eda una v\u00eda intravenosa que le suministraba medicamentos adicionales para asegurarse de que su cuerpo no rechazara el ri\u00f1\u00f3n de cerdo.<\/p>\n<p>\u201cS\u00e9 que ahora puede pasar cualquier cosa, como en la di\u00e1lisis, pero quiero saber que lo he intentado. Intent\u00e9 marcar la diferencia\u201d, dijo Looney en un video realizado por la NYU.<\/p>\n<p>En general, Montgomery se muestra optimista ante los recientes avances en este campo. Los cient\u00edficos llevan d\u00e9cadas estudiando los <a href=\"https:\/\/www.nature.com\/articles\/s41586-023-06594-4\">xenotrasplantes<\/a>, pero en los dos \u00faltimos a\u00f1os han aprendido r\u00e1pidamente qu\u00e9 puede hacer que el organismo del receptor rechace el \u00f3rgano y c\u00f3mo tratar los problemas que puedan surgir.<\/p>\n<p>\u201cHemos aprendido much\u00edsimo de cada trasplante\u201d, afirma Montgomery. \u201cNo tenemos todas las respuestas. Este campo est\u00e1 a\u00fan en pa\u00f1ales, pero nuestra curva de aprendizaje ha sido empinada y r\u00e1pida\u201d.<\/p>\n<p>Todav\u00eda hay muchas preguntas sobre los xenotrasplantes. Entre ellas: Los cient\u00edficos no saben cu\u00e1nto tiempo puede funcionar un \u00f3rgano porcino. Pero Montgomery se atreve a pronosticar que los xenotrasplantes ser\u00e1n rutinarios en menos de 10 a\u00f1os.<\/p>\n<p>Montgomery afirma que el reto en el futuro ser\u00e1 aprender a mantener los ri\u00f1ones durante periodos m\u00e1s largos para que puedan convertirse en \u201cuna alternativa razonable a este suministro escaso y muy racionado de \u00f3rganos humanos\u201d.<\/p>\n<p>\u201cPacientes como Towana son nuestros pioneros que, con su valent\u00eda, nos mostrar\u00e1n el camino\u201d, dijo Montgomery.<\/p>\n<p>Tener esa opci\u00f3n podr\u00eda ser transformador: cada d\u00eda mueren en EE.UU. <a href=\"https:\/\/unos.org\/media-resources\/releases\/over-30-kidney-donors-and-advocates-to-celebrate-world-kidney-day-from-the-top-of-mount-kilimanjaro\/#:~:text=Roughly%2013%20people%20die%20each,as%2075%20through%20tissue%20donation.\">unas 13 personas<\/a> esperando un trasplante de ri\u00f1\u00f3n.<\/p>\n<p>Looney dijo que ha sido maravilloso vivir sin la necesidad de ir a di\u00e1lisis todo el d\u00eda.<\/p>\n<p>\u201cEs como si pudiera sentir la sangre bombeando por mis venas. Puedes poner la mano en mi f\u00edstula y sentir c\u00f3mo zumba. Puedo poner la mano en este ri\u00f1\u00f3n y sentirlo zumbar. Es tan fuerte\u201d, dijo Looney. \u201cEmocionalmente, estoy radiante\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Towana Looney es la \u00fanica persona del mundo que vive con un ri\u00f1\u00f3n funcional de cerdo. Pero su m\u00e9dico predice que, en menos de una d\u00e9cada, los trasplantes de \u00f3rganos de cerdo a humanos como el suyo podr\u00edan convertirse en rutinarios. Looney, de 53 a\u00f1os, es de Alabama y se someti\u00f3 al trasplante en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456686","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Towana Looney es la \u00fanica persona del mundo que vive con un ri\u00f1\u00f3n funcional de cerdo. Pero su m\u00e9dico predice que, en menos de una d\u00e9cada, los trasplantes de \u00f3rganos de cerdo a humanos como el suyo podr\u00edan convertirse en rutinarios. Looney, de 53 a\u00f1os, es de Alabama y se someti\u00f3 al trasplante en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T00:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente\",\"datePublished\":\"2024-12-18T00:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\"},\"wordCount\":1824,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\",\"name\":\"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T00:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente - Noticias","og_description":"Towana Looney es la \u00fanica persona del mundo que vive con un ri\u00f1\u00f3n funcional de cerdo. Pero su m\u00e9dico predice que, en menos de una d\u00e9cada, los trasplantes de \u00f3rganos de cerdo a humanos como el suyo podr\u00edan convertirse en rutinarios. Looney, de 53 a\u00f1os, es de Alabama y se someti\u00f3 al trasplante en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-18T00:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/"},"author":{"name":"","@id":""},"headline":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente","datePublished":"2024-12-18T00:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/"},"wordCount":1824,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","name":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T00:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tras a\u00f1os en lista de espera, una abuela de Alabama recibe un ri\u00f1\u00f3n de un cerdo modificado gen\u00e9ticamente","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/abuela-alabama-rinon-cerdo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T00:03:52Z","datePublished":"2024-12-18T00:03:52Z","dateModified":"2024-12-18T00:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tras a\\u00f1os en lista de espera, una abuela de Alabama recibe un ri\\u00f1\\u00f3n de un cerdo modificado gen\\u00e9ticamente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/17\\\/abuela-alabama-rinon-cerdo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/17\\\/abuela-alabama-rinon-cerdo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T00:03:52Z\",\"datePublished\":\"2024-12-18T00:03:52Z\",\"dateModified\":\"2024-12-18T00:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450996,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/09\/muere-mujer-trasplante-rinon-cerdo-trax\/","url_meta":{"origin":1456686,"position":0},"title":"Muere la mujer que recibi\u00f3 un trasplante de una bomba card\u00edaca y un ri\u00f1\u00f3n de cerdo","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN) -- Lisa Pisano, la primera persona en recibir una bomba card\u00edaca mec\u00e1nica y un ri\u00f1\u00f3n de cerdo editado gen\u00e9ticamente, muri\u00f3 este domingo, seg\u00fan el centro NYU Langone Health, donde se realiz\u00f3 la cirug\u00eda.Pisano recibi\u00f3 el trasplante el 12 de abril, pero el \u00f3rgano fall\u00f3 debido al flujo sangu\u00edneo limitado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447195,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/21\/trasplante-rinon-cerdo-persona-trax\/","url_meta":{"origin":1456686,"position":1},"title":"Trasplantan por primera vez un ri\u00f1\u00f3n de cerdo a una persona viva","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN) -- Los m\u00e9dicos del Hospital General de Massachusetts aseguran que completaron con \u00e9xito el primer trasplante del mundo de un ri\u00f1\u00f3n gen\u00e9ticamente modificado de un cerdo a un ser humano vivo.El paciente es Rick Slayman, un hombre de 62 a\u00f1os, de Weymouth, Massachusetts, a quien le diagnosticaron una enfermedad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449420,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/12\/primer-receptor-vivo-rinon-cerdo-muere-meses-despues-trasplante-trax\/","url_meta":{"origin":1456686,"position":2},"title":"Muri\u00f3 la primera persona que recibi\u00f3 un ri\u00f1\u00f3n de cerdo meses despu\u00e9s del trasplante","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN) -- Un hombre de 62 a\u00f1os falleci\u00f3 meses despu\u00e9s de convertirse en el primer receptor vivo de un trasplante de ri\u00f1\u00f3n de cerdo editado gen\u00e9ticamente, lo que fue considerado como un hito m\u00e9dico.Rick Slayman recibi\u00f3 el ri\u00f1\u00f3n en el Hospital General de Massachusetts en marzo, tras hab\u00e9rsele diagnosticado una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465851,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/25\/primer-trasplante-pulmon-cerdo-humano-trax\/","url_meta":{"origin":1456686,"position":3},"title":"Se trasplanta por primera vez un pulm\u00f3n de cerdo gen\u00e9ticamente modificado a un hombre con muerte cerebral","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Un pulm\u00f3n de cerdo gen\u00e9ticamente modificado fue trasplantado a un hombre con muerte cerebral y funcion\u00f3 durante nueve d\u00edas, seg\u00fan un informe reci\u00e9n publicado.Ha habido algunos \u00e9xitos recientes en el trasplante de ri\u00f1ones y corazones de cerdo a personas, pero se cree que este es el primer intento de trasplantar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460771,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/03\/venezolano-donar-rinon-deportacion-estados-unidos-trax\/","url_meta":{"origin":1456686,"position":4},"title":"Un venezolano que quiere donar un ri\u00f1\u00f3n a su hermano enfrenta la deportaci\u00f3n. ICE lo liber\u00f3 temporalmente","author":"","date":"abril 3, 2025","format":false,"excerpt":"Un venezolano que lleg\u00f3 a Estados Unidos para donar un ri\u00f1\u00f3n a su hermano se enter\u00f3 esta semana de que ser\u00eda deportado, lo que gener\u00f3 s\u00faplicas desesperadas para que lo liberaran de la custodia migratoria por razones humanitarias. D\u00edas despu\u00e9s, Jos\u00e9 Gregorio Gonz\u00e1lez recibi\u00f3 una suspensi\u00f3n de la deportaci\u00f3n, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447228,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/22\/5-cosas-22-marzo-ley-texas-orix\/","url_meta":{"origin":1456686,"position":5},"title":"Las 5 cosas que debes saber este\u00a022 marzo: \u00bfPor qu\u00e9 es dif\u00edcil implementar la ley de inmigraci\u00f3n de Texas?","author":"","date":"marzo 22, 2024","format":false,"excerpt":"P\u00e1nico en Kyiv por ataque de Rusia con misiles. EE.UU. demanda a Apple en hist\u00f3rico caso antimonopolio. EE.UU. necesita m\u00e1s trabajadores migrantes para la construcci\u00f3n.\u00a0Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo1. \u00bfPor qu\u00e9 es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456686"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456686\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}