{"id":1456697,"date":"2024-12-18T00:03:48","date_gmt":"2024-12-18T08:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/"},"modified":"2024-12-18T00:03:48","modified_gmt":"2024-12-18T08:03:48","slug":"rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","title":{"rendered":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango"},"content":{"rendered":"<p>Un ciudadano uzbeko de 29 a\u00f1os fue detenido por presuntamente colocar la <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/17\/mundo\/rusia-bomba-mata-jefe-proteccion-nuclear-reux\">bomba que mat\u00f3<\/a> a un alto general ruso y a su asistente, inform\u00f3 este mi\u00e9rcoles el Comit\u00e9 de Investigaci\u00f3n Ruso.<\/p>\n<p>El teniente general Igor Kirillov, que dirig\u00eda las fuerzas de protecci\u00f3n radiol\u00f3gica, biol\u00f3gica y qu\u00edmica de Rusia, muri\u00f3 al ser <a href=\"https:\/\/www.cnn.com\/2024\/12\/17\/europe\/russia-bomb-kills-nuclear-protection-chief-intl-hnk\/index.html\">detonado a distancia una bomba<\/a> colocada en un scooter el\u00e9ctrico en el exterior de un edificio de apartamentos a unos 7 kil\u00f3metros al sureste del Kremlin.<\/p>\n<p>La explosi\u00f3n se produjo un d\u00eda despu\u00e9s de que los fiscales ucranianos condenaran a Kirillov en ausencia por el uso de armas qu\u00edmicas prohibidas por parte de Rusia durante su invasi\u00f3n. Una fuente con conocimiento de la operaci\u00f3n dijo m\u00e1s tarde a CNN que el servicio de seguridad de Ucrania, el SBU, estaba detr\u00e1s del ataque.<\/p>\n<p>El sospechoso uzbeko fue supuestamente reclutado por los servicios especiales de Ucrania y lleg\u00f3 a Mosc\u00fa bajo sus instrucciones, dijo el comit\u00e9 en su canal oficial de Telegram.<\/p>\n<p>\u201cEl detenido recibi\u00f3 un artefacto explosivo casero y lo coloc\u00f3 en un patinete el\u00e9ctrico que estacion\u00f3 a la entrada del edificio residencial donde viv\u00eda Igor Kirillov\u201d, seg\u00fan el comunicado del comit\u00e9.<\/p>\n<p>Para vigilar la residencia de Kirillov, el sospechoso alquil\u00f3 un autom\u00f3vil y lo equip\u00f3 con una c\u00e1mara de vigilancia, a\u00f1adi\u00f3 el comit\u00e9.<\/p>\n<p>\u201cLas im\u00e1genes de esta c\u00e1mara fueron transmitidas por Internet a los organizadores del ataque terrorista en la ciudad de Dnipro. Despu\u00e9s de recibir una se\u00f1al de v\u00edideo sobre los militares que sal\u00edan de la entrada, el artefacto explosivo fue activado a distancia por ellos\u201d, dijo el comit\u00e9, y agreg\u00f3 que \u201cse est\u00e1 identificando a otras personas involucradas en la organizaci\u00f3n de este crimen\u201d.<\/p>\n<p>Al ciudadano uzbeko detenido se le garantiz\u00f3 una recompensa monetaria de US$ 100.000 y la residencia en un pa\u00eds europeo no especificado, seg\u00fan el comit\u00e9.<\/p>\n<p>Los funcionarios rusos han reaccionado con furia a la muerte del general, prometiendo un castigo \u201csin duda y sin piedad\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ciudadano uzbeko de 29 a\u00f1os fue detenido por presuntamente colocar la bomba que mat\u00f3 a un alto general ruso y a su asistente, inform\u00f3 este mi\u00e9rcoles el Comit\u00e9 de Investigaci\u00f3n Ruso. El teniente general Igor Kirillov, que dirig\u00eda las fuerzas de protecci\u00f3n radiol\u00f3gica, biol\u00f3gica y qu\u00edmica de Rusia, muri\u00f3 al ser detonado a distancia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456697","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un ciudadano uzbeko de 29 a\u00f1os fue detenido por presuntamente colocar la bomba que mat\u00f3 a un alto general ruso y a su asistente, inform\u00f3 este mi\u00e9rcoles el Comit\u00e9 de Investigaci\u00f3n Ruso. El teniente general Igor Kirillov, que dirig\u00eda las fuerzas de protecci\u00f3n radiol\u00f3gica, biol\u00f3gica y qu\u00edmica de Rusia, muri\u00f3 al ser detonado a distancia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T08:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango\",\"datePublished\":\"2024-12-18T08:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\",\"name\":\"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T08:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango - Noticias","og_description":"Un ciudadano uzbeko de 29 a\u00f1os fue detenido por presuntamente colocar la bomba que mat\u00f3 a un alto general ruso y a su asistente, inform\u00f3 este mi\u00e9rcoles el Comit\u00e9 de Investigaci\u00f3n Ruso. El teniente general Igor Kirillov, que dirig\u00eda las fuerzas de protecci\u00f3n radiol\u00f3gica, biol\u00f3gica y qu\u00edmica de Rusia, muri\u00f3 al ser detonado a distancia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-18T08:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/"},"author":{"name":"","@id":""},"headline":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango","datePublished":"2024-12-18T08:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","name":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T08:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\u00f3 a general de alto rango","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T08:03:48Z","datePublished":"2024-12-18T08:03:48Z","dateModified":"2024-12-18T08:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Rusia detiene a un ciudadano uzbeko por el atentado con bomba que mat\\u00f3 a general de alto rango\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/18\\\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/18\\\/rusia-detiene-ciudadano-uzbeko-muerte-bomba-general-ruso-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T08:03:48Z\",\"datePublished\":\"2024-12-18T08:03:48Z\",\"dateModified\":\"2024-12-18T08:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469483,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/22\/ucrania-rusia-general-ruso-muerto-trax\/","url_meta":{"origin":1456697,"position":0},"title":"General ruso muere en un atentado con coche bomba en Mosc\u00fa, seg\u00fan las autoridades","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"Un general ruso muri\u00f3 en un aparente atentado con coche bomba en Mosc\u00fa, y las autoridades culpan a Ucrania por el \u00faltimo asesinato de un alto oficial militar.El teniente general Fanil Sarvarov, que dirig\u00eda el departamento de entrenamiento operativo de las fuerzas armadas, muri\u00f3 despu\u00e9s de que un artefacto explosivo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473689,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/30\/carnicero-bucha-rusia-bomba-trax\/","url_meta":{"origin":1456697,"position":1},"title":"Bomba que mat\u00f3 a un militar ruso podr\u00eda haber tenido como objetivo al &#171;Carnicero de Bucha&#187;","author":"","date":"abril 30, 2026","format":false,"excerpt":"Una bomba que mat\u00f3 a un militar en una remota ciudad de Rusia probablemente ten\u00eda como objetivo a un notorio comandante ruso conocido como el \u201cCarnicero de Bucha\u201d, seg\u00fan medios rusos y ucranianos, as\u00ed como blogueros militares.Las autoridades rusas dijeron que el ataque con bomba ocurrido el martes en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467843,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/29\/ucrania-mata-veniamin-mazzherin-carro-bomba-rusia-trax\/","url_meta":{"origin":1456697,"position":2},"title":"Ucrania reporta que mat\u00f3 a un oficial ruso en Siberia usando un carro bomba","author":"","date":"octubre 29, 2025","format":false,"excerpt":"Ucrania afirm\u00f3 el mi\u00e9rcoles que mat\u00f3 a un oficial ruso responsable de cr\u00edmenes de guerra, atac\u00e1ndolo con un carro bomba dentro de Rusia.Veniamin Mazzherin, quien muri\u00f3 el fin de semana, era el subcomandante de una unidad de la polic\u00eda militar rusa en Kemerovo, en el suroeste de Siberia, seg\u00fan la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469535,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/24\/explosion-moscu-mata-dos-policias-trax\/","url_meta":{"origin":1456697,"position":3},"title":"Una explosi\u00f3n en Mosc\u00fa mata a dos polic\u00edas, d\u00edas despu\u00e9s del aparente homicidio de un general","author":"","date":"diciembre 24, 2025","format":false,"excerpt":"Dos polic\u00edas y una tercera persona murieron la madrugada del mi\u00e9rcoles por una bomba en Mosc\u00fa, cerca del lugar donde hace dos d\u00edas ocurri\u00f3 un atentado con veh\u00edculo con explosivos que mat\u00f3 a un alto general ruso.Dos agentes se acercaron a una persona sospechosa que deton\u00f3 un dispositivo explosivo cerca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468334,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","url_meta":{"origin":1456697,"position":4},"title":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"El servicio de seguridad ruso afirm\u00f3 haber frustrado un complot de Ucrania para asesinar a un alto funcionario del Kremlin dentro de Rusia, mientras el supuesto objetivo visitaba un cementerio.La afirmaci\u00f3n del Servicio Federal de Seguridad de Rusia (FSB, por sus siglas) se produjo mientras los residentes de Kyiv sufr\u00edan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447580,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/31\/como-isis-tiene-a-europa-y-estados-unidos-en-la-mira-trax\/","url_meta":{"origin":1456697,"position":5},"title":"C\u00f3mo ISIS tiene a Europa y Estados Unidos en la mira despu\u00e9s del mortal ataque en Mosc\u00fa","author":"","date":"marzo 31, 2024","format":false,"excerpt":"(CNN) -- Pod\u00eda parecer que la amenaza del ISIS, tambi\u00e9n conocido como Estado Isl\u00e1mico, estaba menguando a medida que los titulares se centraban en Ucrania, Gaza y las pr\u00f3ximas elecciones estadounidenses. Pero el atentado de la semana pasada en una sala de conciertos de Mosc\u00fa record\u00f3 al mundo el peligro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456697"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456697\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}