{"id":1456703,"date":"2024-12-18T03:03:40","date_gmt":"2024-12-18T11:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/"},"modified":"2024-12-18T03:03:40","modified_gmt":"2024-12-18T11:03:40","slug":"wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","title":{"rendered":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas"},"content":{"rendered":"<p>Cientos de personas se reunieron afuera del Capitolio del Estado de Wisconsin este martes por la noche a pesar de las g\u00e9lidas temperaturas para recordar a las v\u00edctimas de un <a href=\"https:\/\/www.cnn.com\/2024\/12\/17\/us\/natalie-rupnow-madison-school\/index.html\">tiroteo en una escuela privada<\/a> que dej\u00f3 un maestro y un estudiante muertos y otros seis heridos.<\/p>\n<p>Un \u00e1rbol de Navidad decorado para la temporada festiva brillaba mientras los dolientes se reun\u00edan para llorar, sosteniendo velas y abrazando perros de terapia.<\/p>\n<p>Los investigadores todav\u00eda est\u00e1n tratando de reconstruir c\u00f3mo y por qu\u00e9 Natalie Rupnow, de 15 a\u00f1os, conocida con el nombre de \u201cSamantha\u201d, sac\u00f3 un arma y abri\u00f3 fuego contra sus compa\u00f1eros y maestros en la Escuela Cristiana Abundant Life el lunes.<\/p>\n<p>El jefe de Polic\u00eda de Madison, Shon Barnes, dijo el martes que identificar el motivo de Rupnow es prioridad m\u00e1xima y que parece ser una \u201ccombinaci\u00f3n de factores\u201d, pero se neg\u00f3 a dar m\u00e1s detalles.<\/p>\n<p>La Polic\u00eda est\u00e1 hablando con los estudiantes para determinar si el acoso fue uno de los factores, dijo, y los investigadores est\u00e1n revisando la presencia en l\u00ednea del tirador para tratar de obtener nueva informaci\u00f3n.<\/p>\n<p>Esto es lo que hemos aprendido hasta ahora:<\/p>\n<ul>\n<li><strong>V\u00edctimas:<\/strong> la Polic\u00eda a\u00fan no revel\u00f3 p\u00fablicamente los nombres de las v\u00edctimas del tiroteo. Barnes dijo que la maestra que recibi\u00f3 el disparo fatal era miembro del personal a tiempo completo. En una entrevista con CNN, Angel Brube, un estudiante de s\u00e9ptimo grado de la Escuela Cristiana Abundant Life, dijo que conoc\u00eda bien a la maestra y la describi\u00f3 como \u201camable y cari\u00f1osa\u201d y \u201cuna persona realmente buena\u201d. Dos personas que resultaron heridas en el tiroteo se encuentran en estado cr\u00edtico con \u201cheridas que ponen en peligro su vida\u201d, mientras que dos est\u00e1n estables y permanecen en el hospital y otras dos fueron dadas de alta, seg\u00fan los funcionarios de la ciudad.<\/li>\n<li><strong>Arma:<\/strong> la Polic\u00eda dijo que Rupnow us\u00f3 una pistola para llevar a cabo el ataque. La Oficina de Alcohol, Tabaco, Armas de Fuego y Explosivos de Estados Unidos est\u00e1 rastreando el arma, lo que ayudar\u00e1 a responder preguntas como \u201cel origen de esa arma, qui\u00e9n la compr\u00f3 y c\u00f3mo lleg\u00f3 desde un fabricante hasta las manos de una ni\u00f1a de 15 a\u00f1os\u201d, dijo Barnes.<\/li>\n<li><strong>Familia del tirador:<\/strong> Los registros judiciales obtenidos por <a href=\"https:\/\/www.washingtonpost.com\/nation\/2024\/12\/17\/madison-wisconsin-school-shooter-natalie-rupnow\/\">The Washington Post<\/a> muestran que Rupnow ten\u00eda \u201cuna vida familiar turbulenta\u201d y que hab\u00eda estado inscribi\u00e9ndose en terapia. Los documentos revelan que sus padres \u201cse divorciaron y se volvieron a casar varias veces\u201d y que sus acuerdos de custodia \u201ca veces la obligaban a mudarse entre sus hogares cada dos o tres d\u00edas\u201d. Los padres de Rupnow \u2013Jeff y Mellissa Rupnow\u2013 no han respondido a las reiteradas solicitudes de comentarios por parte del Washington Post o CNN.<\/li>\n<li><strong>Posibilidad de cargos criminales:<\/strong> el alcalde de Madison dijo que es <a href=\"https:\/\/www.cnn.com\/us\/live-news\/madison-wisconsin-school-shooting-12-17-24#cm4sezu290000356m7k4atrds\">demasiado pronto para comentar<\/a> si los padres del tirador <a href=\"https:\/\/www.cnn.com\/us\/live-news\/madison-wisconsin-school-shooting-12-17-24#cm4sezu290000356m7k4atrds\">enfrentar\u00e1n cargos criminales<\/a> . Barnes dijo anteriormente que los investigadores est\u00e1n analizando \u201csi los padres pueden haber sido negligentes\u201d. Tambi\u00e9n dijo que los padres est\u00e1n cooperando y hasta el lunes por la noche, los investigadores \u201cno tienen motivos para creer que hayan cometido un delito en este momento\u201d.<\/li>\n<li><strong>Enlaces a club de tiro:<\/strong> Jeff Rupnow, el padre de Natalie, hab\u00eda publicado una foto en Facebook de su hija en un campo de tiro en agosto. En la foto, se puede ver a la adolescente con una camiseta negra con el nombre de la banda KMFDM, cuyas letras de canciones tambi\u00e9n han sido citadas por los estudiantes que llevaron a cabo la masacre de 1999 en Columbine High School en Colorado, donde murieron 13 personas, seg\u00fan inform\u00f3 CNN. KMFDM emiti\u00f3 un comunicado condenando el ataque de 1999 y expres\u00f3 su simpat\u00eda por las v\u00edctimas, a\u00f1adiendo que su m\u00fasica ten\u00eda la intenci\u00f3n de oponerse a la violencia, seg\u00fan <a href=\"https:\/\/www.reuters.com\/world\/us\/police-search-motive-wisconsin-school-shooting-2024-12-17\/#:~:text=At%20the%20time%2C%20KMFDM%20issued,intended%20to%20stand%20against%20violence.\">Reuters<\/a>.<\/li>\n<li><strong>Documentos:<\/strong> las autoridades tienen conocimiento de <a href=\"https:\/\/www.cnn.com\/us\/live-news\/abundant-life-christian-school-shooting-madison-12-16-24#cm4rusx09001z356nm3j6t0dh\">escritos publicados<\/a> por alguien que afirma ser amigo del tirador, pero esos documentos no han sido verificados. Barnes pidi\u00f3 a la gente que no comparta los documentos en l\u00ednea porque <a href=\"https:\/\/www.cnn.com\/us\/live-news\/madison-wisconsin-school-shooting-12-17-24#cm4suedxx0000356n63140ua2\">\u201cno pueden verificar su autenticidad\u201d,<\/a> y agreg\u00f3 que los detectives est\u00e1n trabajando para averiguar de d\u00f3nde provienen.<\/li>\n<\/ul>\n<p><em>Taylor Romine, Sarah Dewberry, Elise Hammond, Holly Yan, Steve Almasy, Jillian Sykes, Caroll Alvarado y Taylor Galgano de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cientos de personas se reunieron afuera del Capitolio del Estado de Wisconsin este martes por la noche a pesar de las g\u00e9lidas temperaturas para recordar a las v\u00edctimas de un tiroteo en una escuela privada que dej\u00f3 un maestro y un estudiante muertos y otros seis heridos. Un \u00e1rbol de Navidad decorado para la temporada [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456703","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cientos de personas se reunieron afuera del Capitolio del Estado de Wisconsin este martes por la noche a pesar de las g\u00e9lidas temperaturas para recordar a las v\u00edctimas de un tiroteo en una escuela privada que dej\u00f3 un maestro y un estudiante muertos y otros seis heridos. Un \u00e1rbol de Navidad decorado para la temporada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T11:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas\",\"datePublished\":\"2024-12-18T11:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\"},\"wordCount\":786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\",\"name\":\"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T11:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas - Noticias","og_description":"Cientos de personas se reunieron afuera del Capitolio del Estado de Wisconsin este martes por la noche a pesar de las g\u00e9lidas temperaturas para recordar a las v\u00edctimas de un tiroteo en una escuela privada que dej\u00f3 un maestro y un estudiante muertos y otros seis heridos. Un \u00e1rbol de Navidad decorado para la temporada [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-18T11:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/"},"author":{"name":"","@id":""},"headline":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas","datePublished":"2024-12-18T11:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/"},"wordCount":786,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","name":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T11:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una comunidad peque\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T11:03:40Z","datePublished":"2024-12-18T11:03:40Z","dateModified":"2024-12-18T11:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una comunidad peque\\u00f1a y unida en Wisconsin se recupera del tiroteo en la escuela mientras autoridades buscan respuestas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/18\\\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/18\\\/wisconsin-recupera-tiroteo-escuela-autoridades-buscan-respuestas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T11:03:40Z\",\"datePublished\":\"2024-12-18T11:03:40Z\",\"dateModified\":\"2024-12-18T11:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456676,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/17\/quien-es-natalie-rupnow-tiroteo-wisconsin-orix\/","url_meta":{"origin":1456703,"position":0},"title":"\u00bfQui\u00e9n es Natalie \u2018Samantha\u2019 Rupnow, la sospechosa del tiroteo en escuela de Wisconsin?","author":"","date":"diciembre 17, 2024","format":false,"excerpt":"La Polic\u00eda de Madison, Wisconsin, identific\u00f3 a Natalie Rupnow, de 15 a\u00f1os, como la sospechosa del tiroteo en la Abundant Life Christian School de Madison, Wisconsin, en el que murieron dos personas el lunes.La sospechosa ingres\u00f3 a la escuela al comienzo del d\u00eda junto con el resto de los estudiantes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458789,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/15\/esto-ayudo-frustrar-potencial-tiroteo-escuela-indiana-dia-san-valentin-trax\/","url_meta":{"origin":1456703,"position":1},"title":"Esto es lo que ayud\u00f3 a frustrar un potencial tiroteo en una escuela de Indiana el d\u00eda de San Valent\u00edn","author":"","date":"febrero 15, 2025","format":false,"excerpt":"Una llamada a una l\u00ednea de denuncia an\u00f3nima creada despu\u00e9s del tiroteo de 2012 en la escuela primaria Sandy Hook en Newtown, Connecticut, desencaden\u00f3 una serie de eventos que ayudaron a frustrar un potencial tiroteo masivo en el d\u00eda de San Valent\u00edn en Indiana, dicen las autoridades.Trinity Shockley, de 18\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456661,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/16\/tiroteo-escuela-madison-wisconsin-trax\/","url_meta":{"origin":1456703,"position":2},"title":"Mueren al menos 4 personas tras tiroteo en una escuela en Madison, Wisconsin, dice la Polic\u00eda","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"Al menos cuatro personas murieron y otras cinco resultaron heridas tras un tiroteo en la escuela Abundant Life Christian School de Madison, Wisconsin, este lunes, seg\u00fan la Polic\u00eda.La actualizaci\u00f3n lleg\u00f3 durante una rueda de prensa con la polic\u00eda. Al principio de esta conferencia con medios de comunicaci\u00f3n, se hab\u00eda informado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448766,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/02\/policias-dispararon-estudiante-armado-escuela-secundaria-wisconsin-trax\/","url_meta":{"origin":1456703,"position":3},"title":"Polic\u00edas dispararon y mataron a un estudiante que portaba un arma en una escuela secundaria, dice el fiscal general de Wisconsin","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN) -- Agentes de Polic\u00eda en un pueblo de Wisconsin dispararon y mataron a un estudiante que llev\u00f3 un arma cerca de una escuela secundaria este mi\u00e9rcoles por la ma\u00f1ana, seg\u00fan el fiscal general de Wisconsin Josh Kaul.El estudiante del Distrito Escolar del \u00c1rea de Mount Horeb, que era menor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471093,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/10\/tiroteo-escolar-canada-muertos-dicen-autoridades-trax\/","url_meta":{"origin":1456703,"position":4},"title":"Mueren al menos nueve personas tras tiroteo masivo en una escuela y una vivienda de Canad\u00e1, dice la Polic\u00eda","author":"","date":"febrero 10, 2026","format":false,"excerpt":"Al menos nueve personas murieron en un tiroteo masivo en una escuela secundaria y una propiedad residencial en la parte noreste de la provincia de Columbia Brit\u00e1nica, inform\u00f3 la Polic\u00eda canadiense el martes.La Polic\u00eda respondi\u00f3 a informes de un atacante activo en la Escuela Secundaria Tumbler Ridge alrededor de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456748,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/19\/victimas-tiroteo-escuela-madison-trax\/","url_meta":{"origin":1456703,"position":5},"title":"Una profesora cari\u00f1osa y una alumna rebosante de ambici\u00f3n art\u00edstica son las v\u00edctimas del tiroteo en una escuela de Wisconsin","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Rubi Patricia Vergara era una \u201c\u00e1vida lectora\u201d y llena de promesas art\u00edsticas, seg\u00fan su obituario en l\u00ednea.Pero la estudiante de noveno curso y la profesora Erin Michelle West murieron en un tiroteo ocurrido este lunes por la ma\u00f1ana en la Abundant Life Christian School de Madison, Wisconsin, seg\u00fan anunci\u00f3 este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456703"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456703\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}