{"id":1456738,"date":"2024-12-18T17:03:47","date_gmt":"2024-12-19T01:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/"},"modified":"2024-12-18T17:03:47","modified_gmt":"2024-12-19T01:03:47","slug":"secuestro-pandillas-colorado-inmigrantes-venezolanos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","title":{"rendered":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos"},"content":{"rendered":"<p>La ciudad de Aurora, Colorado, volvi\u00f3 a entrar en el debate nacional sobre inmigraci\u00f3n despu\u00e9s de que un hombre y una mujer fueran sacados a rastras de una unidad en un complejo de departamentos el lunes por la noche para luego ser atados, golpeados y azotados con pistolas hasta que pudieron rogar por su liberaci\u00f3n, dijo la Polic\u00eda.<\/p>\n<p>Al menos 19 sospechosos fueron detenidos en relaci\u00f3n con el allanamiento a mano armada y el secuestro en el complejo de departamentos The Edge on Lowry, que seg\u00fan el jefe de polic\u00eda de Aurora, Todd Chamberlain, es \u201csin lugar a dudas un incidente de pandillas\u201d. Dijo que tanto los perpetradores como las v\u00edctimas del crimen probablemente eran inmigrantes venezolanos, algunos de los cuales podr\u00edan ser indocumentados.<\/p>\n<p>La Polic\u00eda est\u00e1 trabajando con funcionarios federales de inmigraci\u00f3n y seguridad nacional para identificar a los sospechosos y determinar qu\u00e9 organizaci\u00f3n delictiva<strong> <\/strong>pertenecen, si es que pertenecen a alguna, dijo Chamberlain durante una conferencia de prensa el martes. Eso incluye investigar si pueden estar conectados con el <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/18\/tren-de-aragua-expansion-america-orix\">Tren de Aragua<\/a>, cuyos miembros han sido identificados previamente en la ciudad. Chamberlain dijo el martes que hab\u00eda una \u201calta sospecha\u201d de que esa organizaci\u00f3n estuviera involucrada.<\/p>\n<p>No se presentaron cargos y los nombres de los sospechosos no se hicieron p\u00fablicos.<\/p>\n<p>Las v\u00edctimas denunciaron el ataque a la Polic\u00eda y estaban siendo atendidas en un hospital por lesiones que no pon\u00edan en peligro su vida, dijo el jefe de polic\u00eda.<\/p>\n<p>El ataque volvi\u00f3 a poner el foco sobre el complejo de edificios de departamentos de ladrillo sobre la ciudad de Aurora, que hace apenas unos meses <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/09\/12\/apartamentos-colorado-convirtio-campo-batalla-nacional-sobre-inmigracion-trax\">se convirti\u00f3 en un punto \u00e1lgido<\/a> del conflicto nacional sobre la inmigraci\u00f3n.<\/p>\n<p>Durante la campa\u00f1a electoral, el presidente electo Donald Trump compar\u00f3 repetidamente al suburbio de Denver con una \u201czona de guerra\u201d, y se repiti\u00f3 rumores infundados de que bandas venezolanas estaban asumiendo violentamente el control de partes de la ciudad en medio de una afluencia de inmigrantes a las \u00e1reas de Aurora y Denver.<\/p>\n<p>Sin embargo, los funcionarios locales argumentan que si bien la actividad criminal organizada est\u00e1 presente en Aurora, el problema se exager\u00f3 enormemente ya que en realidad se limita a un pu\u00f1ado de edificios de departamentos en una ciudad que alberga a m\u00e1s de 400.000 residentes.<\/p>\n<p>\u201cComo todo el mundo sabe aqu\u00ed, y como lo sabe el pa\u00eds, este complejo es incre\u00edblemente problem\u00e1tico\u201d, dijo Chamberlain el martes. \u201cEs un complejo incre\u00edblemente plagado de delitos en el que creo que nos hemos estado centrando, la ciudad de Aurora se ha estado centrando. Y sin duda, la atenci\u00f3n no se detendr\u00e1 hasta que cada individuo que victimice a otra persona rinda cuentas o sea expulsado de ese complejo\u201d.<strong><\/strong><\/p>\n<p>Chamberlain dijo que The Edge se convirti\u00f3 en el centro de atenci\u00f3n de su unidad policial, que estuvo trabajando \u201cde manera proactiva\u201d para abordar la delincuencia en la propiedad y realiza patrullas \u201cininterrumpidas\u201d en la zona. Pero el problema se extiende m\u00e1s all\u00e1 de esa propiedad, dijo.<\/p>\n<p>\u201cTenemos un problema de pandillas en Aurora sin lugar a dudas\u201d, dijo Chamberlain. \u201cTenemos unas 25 pandillas como en cualquier ciudad importante. Tenemos varios miembros de pandillas y no se trata solo de esa zona, ni solo de ese complejo, sino de toda la ciudad de Aurora\u201d.<\/p>\n<p>El alcalde de Aurora, Mike Coffman, replic\u00f3 las preocupaciones del jefe de la Polic\u00eda en una declaraci\u00f3n el mi\u00e9rcoles, pero insisti\u00f3 en que la ciudad no deber\u00eda definirse por sus recientes problemas criminales.<\/p>\n<p>\u201cComo dijo el jefe Chamberlain, Aurora, como cualquier otra ciudad importante del pa\u00eds, debe combatir la delincuencia, especialmente los focos de delincuencia concentrados, de manera agresiva. Pero, como he dicho en repetidas ocasiones, los malos actores espec\u00edficos y las propiedades problem\u00e1ticas no reflejan a esta ciudad en su conjunto\u201d, dijo Coffman.<\/p>\n<p>Y agreg\u00f3: \u201cHemos protegido y seguiremos protegiendo a los miembros de nuestra comunidad y perseguiremos agresivamente a cualquiera que intente victimizarlos, sin importar qui\u00e9nes sean o de d\u00f3nde vengan\u201d.<\/p>\n<p>Los investigadores afirman que el allanamiento a la vivienda comenz\u00f3 alrededor de las 8:45 p.m. (hora local) en un departamento de The Edge at Lowry. Las v\u00edctimas, un hombre y una mujer, fueron abordadas por m\u00e1s de una decena de personas armadas y llevadas contra su voluntad a otra unidad dentro del mismo complejo, dijo Chamberlain.<\/p>\n<p>Las v\u00edctimas fueron atadas y \u201caterrorizadas\u201d mientras algunos de los sospechosos regresaban a su departamento, saqueaban y robaban sus pertenencias, dijo el jefe de polic\u00eda. El hombre fue apu\u00f1alado y ambos fueron atados y golpeados con pistolas, dijo.<\/p>\n<p>Poco antes de las dos de la madrugada, las v\u00edctimas pidieron su liberaci\u00f3n y dijeron a sus presuntos secuestradores que no denunciar\u00edan el ataque a la polic\u00eda, dijo Chamberlain. La pareja fue liberada y se dirigi\u00f3 a la casa de un amigo, donde inmediatamente llamaron a la polic\u00eda.<\/p>\n<p>Los agentes acudieron al complejo de departamentos y cerraron la propiedad, donde encontraron a 15 personas en una de las unidades, muchas de las cuales son sospechosas del ataque, dijo Chamberlain. Hasta el mi\u00e9rcoles por la tarde, 19 sospechosos hab\u00edan sido detenidos, seg\u00fan el portavoz de la Polic\u00eda de Aurora, Joe Moylan.<\/p>\n<p>\u201cLa mayor\u00eda de ellos son, sin lugar a dudas o muy probablemente (\u2026) indocumentados o inmigrantes en la ciudad de Aurora\u201d, dijo Chamberlain.<\/p>\n<p>La Polic\u00eda est\u00e1 buscando \u00f3rdenes de allanamiento para varios lugares que se cree est\u00e1n relacionados con el secuestro, dijo.<\/p>\n<p>El Departamento de Seguridad Nacional de Estados Unidos, el Servicio de Inmigraci\u00f3n y Control de Aduanas y la Divisi\u00f3n de Investigaciones de Seguridad Nacional est\u00e1n colaborando en el caso. CNN ha solicitado comentarios de las agencias.<\/p>\n<p>Se cree que las v\u00edctimas del ataque del lunes son inmigrantes venezolanos y Chamberlain aplaudi\u00f3 su \u201cincre\u00edble coraje\u201d por dar un paso adelante y denunciar el crimen, a pesar de los temores de que su estatus migratorio pueda tener repercusiones en su contra.<\/p>\n<p>Chamberlain dijo que los sospechosos probablemente atacaron a las v\u00edctimas porque cre\u00edan que no denunciar\u00edan el crimen a la polic\u00eda.<\/p>\n<p>\u201cEstos individuos, como muchas bandas y muchas personas involucradas en este tipo de actividades, victimizan a personas de su propia raza y etnia\u201d, dijo el jefe de Polic\u00eda. \u201cLo hacen porque son v\u00edctimas f\u00e1ciles porque saben que, debido a su estatus, no se presentar\u00e1n ante la polic\u00eda\u201d.<\/p>\n<p>Chamberlain alent\u00f3 a que cualquier persona, independientemente de su estatus migratorio, se sienta c\u00f3moda al comunicarse con la Polic\u00eda de Aurora si fue v\u00edctima de un delito.<\/p>\n<p>\u201cNo hay ning\u00fan lugar en este pa\u00eds, no hay ning\u00fan lugar en esta ciudad donde alguien pueda ser victimizado o maltratado por su estatus migratorio\u201d, agreg\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de Aurora, Colorado, volvi\u00f3 a entrar en el debate nacional sobre inmigraci\u00f3n despu\u00e9s de que un hombre y una mujer fueran sacados a rastras de una unidad en un complejo de departamentos el lunes por la noche para luego ser atados, golpeados y azotados con pistolas hasta que pudieron rogar por su liberaci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456738","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La ciudad de Aurora, Colorado, volvi\u00f3 a entrar en el debate nacional sobre inmigraci\u00f3n despu\u00e9s de que un hombre y una mujer fueran sacados a rastras de una unidad en un complejo de departamentos el lunes por la noche para luego ser atados, golpeados y azotados con pistolas hasta que pudieron rogar por su liberaci\u00f3n, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-19T01:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos\",\"datePublished\":\"2024-12-19T01:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\"},\"wordCount\":1195,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\",\"name\":\"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-19T01:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos - Noticias","og_description":"La ciudad de Aurora, Colorado, volvi\u00f3 a entrar en el debate nacional sobre inmigraci\u00f3n despu\u00e9s de que un hombre y una mujer fueran sacados a rastras de una unidad en un complejo de departamentos el lunes por la noche para luego ser atados, golpeados y azotados con pistolas hasta que pudieron rogar por su liberaci\u00f3n, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-19T01:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/"},"author":{"name":"","@id":""},"headline":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos","datePublished":"2024-12-19T01:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/"},"wordCount":1195,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","name":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-19T01:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Detienen a 19 por secuestro en Colorado, seg\u00fan la Polic\u00eda; las v\u00edctimas y sospechosos ser\u00edan inmigrantes venezolanos","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-19T01:03:47Z","datePublished":"2024-12-19T01:03:47Z","dateModified":"2024-12-19T01:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Detienen a 19 por secuestro en Colorado, seg\\u00fan la Polic\\u00eda; las v\\u00edctimas y sospechosos ser\\u00edan inmigrantes venezolanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/18\\\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/18\\\/secuestro-pandillas-colorado-inmigrantes-venezolanos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-19T01:03:47Z\",\"datePublished\":\"2024-12-19T01:03:47Z\",\"dateModified\":\"2024-12-19T01:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458000,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/29\/tren-de-aragua-objetivo-trump-trax\/","url_meta":{"origin":1456738,"position":0},"title":"La pandilla Tren de Aragua, surgida en una prisi\u00f3n venezolana, es el primer objetivo de las redadas de Trump","author":"","date":"enero 29, 2025","format":false,"excerpt":"Un objetivo central de la oleada de redadas de del Gobierno de Trump es un grupo del crimen organizado de Venezuela.Una serie de decretos en materia de inmigraci\u00f3n tomados por el presidente Donald Trump en el primer d\u00eda de su segundo mandato incluyeron una recomendaci\u00f3n para que el Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444975,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/05\/arrestan-a-siete-inmigrantes-sospechosos-despues-de-mas-de-60-incidentes-de-robo-en-nueva-york\/","url_meta":{"origin":1456738,"position":1},"title":"Arrestan a siete inmigrantes sospechosos despu\u00e9s de m\u00e1s de 60 incidentes de robo en Nueva York","author":"","date":"febrero 5, 2024","format":false,"excerpt":"(CNN) -- Al menos siete inmigrantes fueron arrestados el lunes despu\u00e9s de que una orden de registro en una casa en el Bronx revelara una conexi\u00f3n con un patr\u00f3n de robo que ocurr\u00eda en cuatro distritos de la ciudad de Nueva York, dijeron funcionarios el lunes.Los sospechosos son parte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444985,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/06\/arrestan-a-siete-inmigrantes-sospechosos-despues-de-mas-de-60-incidentes-de-robo-en-nueva-york-2\/","url_meta":{"origin":1456738,"position":2},"title":"Arrestan a siete inmigrantes sospechosos despu\u00e9s de m\u00e1s de 60 incidentes de robo en Nueva York","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN) -- Al menos siete inmigrantes fueron arrestados el lunes despu\u00e9s de que una orden de registro en una casa en el Bronx revelara una conexi\u00f3n con un patr\u00f3n de robo que ocurr\u00eda en cuatro distritos de la ciudad de Nueva York, dijeron funcionarios el lunes.Los sospechosos son parte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458282,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/05\/tren-aragua-operacion-denver-trax\/","url_meta":{"origin":1456738,"position":3},"title":"Agencias federales lanzan operaci\u00f3n coordinada en Denver contra la pandilla venezolana Tren de Aragua","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Agentes federales de inmigraci\u00f3n de EE.UU. realizaron una redada en la ma\u00f1ana de este mi\u00e9rcoles en un complejo de apartamentos en el \u00e1rea metropolitana de Denver, Colorado. La ICE dijo que el objetivo eran \u201cm\u00e1s de 100 miembros de la violenta pandilla venezolana Tren de Aragua\u201d.Se trata de una operaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1423123,"url":"https:\/\/noticiasya.com\/midland-odessa\/2022\/08\/29\/tiktok-te-dice-como-robar-autos-kia-o-hyundai-ya-hay-victimas-en-colorado\/","url_meta":{"origin":1456738,"position":4},"title":"TikTok te dice c\u00f3mo robar autos Kia o Hyundai; ya hay v\u00edctimas en Colorado","author":"agomez","date":"agosto 29, 2022","format":false,"excerpt":"Las automotrices est\u00e1n al tanto de la desconcertante tendencia e intentan ofrecer soluciones a los preocupados automovilistas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459113,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/23\/estafadora-aurora-phelps-aplicaciones-citas-victimas-eeuu-mexico-trax\/","url_meta":{"origin":1456738,"position":5},"title":"Estafadora us\u00f3 aplicaciones de citas para atraer y drogar a sus v\u00edctimas en EE.UU. y M\u00e9xico","author":"agomez","date":"febrero 23, 2025","format":false,"excerpt":"Un anciano de Nevada fue supuestamente drogado y empujado a trav\u00e9s de la frontera de Estados Unidos hacia M\u00e9xico en una silla de ruedas por una estafadora \u201csiniestra\u201d antes de ser encontrado muerto en una habitaci\u00f3n de un hotel de la Ciudad de M\u00e9xico, una de las casi una docena\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456738"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456738\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}