{"id":1456759,"date":"2024-12-19T10:04:00","date_gmt":"2024-12-19T18:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/"},"modified":"2024-12-19T10:04:00","modified_gmt":"2024-12-19T18:04:00","slug":"2023-458-asesinatos-en-trabajo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","title":{"rendered":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes"},"content":{"rendered":"<p> Al d\u00eda siguiente de Pascua de 2023, Dana Mitchell fue a trabajar, tom\u00f3 un caf\u00e9 y camin\u00f3 hacia la sala de conferencias para la reuni\u00f3n regular del lunes por la ma\u00f1ana. Estaba hablando con un compa\u00f1ero de trabajo sobre su bronceado de unas vacaciones.<\/p>\n<p>Mir\u00f3 hacia arriba y vio a otro compa\u00f1ero de trabajo, Connor Sturgeon, en la puerta. \u00c9l sosten\u00eda un arma.<\/p>\n<p>El caos estall\u00f3 cuando comenz\u00f3 a disparar contra Mitchell y sus colegas en Old National Bank, en Louisville. En pocos minutos, Sturgeon hab\u00eda matado a cinco empleados del banco y herido a otros ocho compa\u00f1eros de trabajo, incluida Mitchell, antes de que la Polic\u00eda de Louisville que atend\u00eda la emergencia lo matara en el lugar.<\/p>\n<p>En Estados Unidos, no fue un evento \u00fanico.<\/p>\n<p>Cientos de personas son asesinadas en el trabajo cada a\u00f1o en Estados Unidos. Seg\u00fan un informe publicado el jueves por la Oficina de Estad\u00edsticas Laborales, hubo 458 homicidios en centros laborales en 2023. Eso es un promedio de casi nueve por semana. La cifra fue inferior a las 524 que fueron asesinadas en el trabajo en 2022. Entre 2018 y 2023 ha habido 2.762 homicidios laborales en los Estados Unidos.<\/p>\n<p>La amenaza de ser asesinado en el trabajo no es, por supuesto, el \u00fanico riesgo que enfrentan los trabajadores. El informe muestra que un total de 5.283 murieron en el trabajo en 2023, siendo los accidentes de transporte la forma m\u00e1s com\u00fan de muerte, con 1.942 fallecidos de esa manera el a\u00f1o pasado, seguidos por las muertes por ca\u00eddas, tropiezos o resbalones, que mataron a 885 trabajadores. Pero esas fueron muertes no intencionales.<\/p>\n<p>El tema de los homicidios en el trabajo ha recibido m\u00e1s atenci\u00f3n en las \u00faltimas semanas tras el <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/19\/estados-unidos\/luigi-mangione-jueves-audiencia-extradicion-trax\">ataque fatal <\/a>al CEO de UnitedHealthcare, Brian Thompson, mientras se preparaba para entrar en un hotel de la ciudad de Nueva York para una reuni\u00f3n de inversores. La muerte de Thompson y la b\u00fasqueda y captura de su presunto agresor han sido un tema destacado. Pero muchos homicidios en el lugar de trabajo pasan relativamente desapercibidos. Los tiroteos masivos, como el de Old National Bank, se han vuelto comunes y pueden recibir unos pocos d\u00edas de cobertura nacional, a veces porque otro tiroteo masivo ha tomado su lugar. Muchos otros incidentes en los que solo se mata a una sola persona pueden recibir solo cobertura de noticias locales, si acaso.<\/p>\n<p>Y la mayor\u00eda de las personas que llegan a trabajar est\u00e1n tan ajenas a las cifras como lo estaban Mitchell y sus compa\u00f1eros de trabajo cuando fueron a una reuni\u00f3n esa ma\u00f1ana para charlar sobre c\u00f3mo hab\u00eda sido su fin de semana de Pascua, o sobre las vacaciones de las que uno de ellos acababa de regresar.<\/p>\n<p>Mitchell hab\u00eda trabajado en bancos durante casi 40 a\u00f1os, desde que ten\u00eda 19 a\u00f1os. Nunca consider\u00f3 la seguridad como un problema en su trabajo. Su empresa requer\u00eda que viera un video de capacitaci\u00f3n sobre atacantes armados activos, pero apenas lo registraba. La \u00fanica raz\u00f3n por la que lo estaba viendo era porque ten\u00eda que hacerlo, pens\u00f3. No pod\u00eda suceder en Old National.<\/p>\n<p>Incluso cuando Sturgeon estaba all\u00ed con el rifle estilo asalto, no ten\u00eda sentido en su mente.<\/p>\n<p>\u201cRealmente pens\u00e9 que hab\u00eda comprado un arma durante el fin de semana y la hab\u00eda tra\u00eddo para mostrarnos. Nunca asum\u00ed que iba a usarla\u201d, dijo.<\/p>\n<p>\u201cLas personas estaban saliendo corriendo de la sala de conferencias. Uno lo logr\u00f3, otros no\u201d, record\u00f3. \u201cMe lanc\u00e9 al suelo y trat\u00e9 de arrastrarme tan lejos como pudiera. Me dispararon en la espalda mientras estaba en el suelo\u201d.<\/p>\n<p>Sturgeon vaci\u00f3 su primer cargador justo all\u00ed, en la sala de conferencias. Luego, el tiroteo se detuvo por un momento. Los compa\u00f1eros de trabajo sentados a cada lado de Mitchell en la mesa de la conferencia estaban muertos. Afortunadamente, la herida de bala de Mitchell era relativamente superficial. Ella yac\u00eda en el suelo, tratando de no respirar, por si acaso \u00e9l estaba buscando signos de vida en sus v\u00edctimas.<\/p>\n<p>\u201cNo sab\u00eda d\u00f3nde estaba, si todav\u00eda estaba de pie all\u00ed\u201d, dijo. \u201cRecuerdo estar tirada en el suelo, pensando: \u2018\u00bfRealmente est\u00e1 ocurriendo esto? \u00bfAs\u00ed es como voy a morir?\u2019\u201d.<\/p>\n<p>Pero, por aterrador que fuera el incidente para las v\u00edctimas que sobrevivieron y los familiares de los fallecidos, los asesinatos tienen lugar en alg\u00fan lugar de trabajo estadounidense un promedio de unas tres veces por semana, o m\u00e1s.<\/p>\n<p>Solo alrededor de una cuarta parte de los adultos dijo que se sent\u00eda estresada por la posibilidad de un tiroteo masivo en el trabajo o en una oficina, seg\u00fan una encuesta de 2019 realizada para la Asociaci\u00f3n Estadounidense de Psicolog\u00eda. Aproximadamente el doble de personas estaban nerviosas por la posibilidad de un tiroteo en eventos p\u00fablicos como un desfile, un evento deportivo, un centro comercial o una escuela o universidad.<\/p>\n<p>Pero un estudio del Proyecto de Prevenci\u00f3n de la Violencia, un centro de investigaci\u00f3n sin fines de lucro y no partidista financiado por el Instituto Nacional de Justicia, encontr\u00f3 que los lugares de trabajo actuales o anteriores de los perpetradores eran los sitios m\u00e1s comunes para que ocurrieran tiroteos masivos. Y el 30% de la base de datos del proyecto de 200 tiroteos masivos desde 1966 se clasifica como \u201ctiroteos en el lugar de trabajo\u201d.<\/p>\n<p>\u201cLos homicidios en el lugar de trabajo a menudo surgen de agravios personales que se desbordan en entornos profesionales\u201d, dijo el Dr. James Dempsey, director adjunto del Proyecto de Prevenci\u00f3n de la Violencia y presidente del Departamento de Criminolog\u00eda y Justicia Penal de la Universidad Estatal de Metro, en Minessota. \u201cPara algunos perpetradores, los lugares de trabajo representan s\u00edmbolos de autoridad o rechazo, especialmente en casos de p\u00e9rdida de empleo o acci\u00f3n disciplinaria. Al mismo tiempo, los humanos son criaturas de h\u00e1bito, y los perpetradores suelen atacar lo que conocen. La familiaridad genera oportunidades. Cuando alguien est\u00e1 enojado o desesperado, act\u00faa dentro de entornos que entiende mejor\u201d.<\/p>\n<p>Sin embargo, muchos trabajadores no ten\u00edan ni siquiera la capacitaci\u00f3n rudimentaria que Mitchell y otros empleados del banco hab\u00edan recibido en sus <em>laptops <\/em>sobre qu\u00e9 hacer en caso de un atacante armado activo.<\/p>\n<p>\u201cEl estudiante promedio de tercer grado recibe m\u00e1s capacitaci\u00f3n sobre qu\u00e9 hacer (con un atacante armado activo) que la mayor\u00eda de los trabajadores\u201d, dijo Jessica Martinez, directora ejecutiva del Consejo Nacional de Seguridad y Salud Ocupacional, un grupo de inter\u00e9s p\u00fablico. Muchos estados exigen que los estudiantes pasen por simulacros de cierre de seguridad varias veces al a\u00f1o.<\/p>\n<p>Martinez dijo que desde el homicidio de Thompson \u201chay mayor seguridad para los CEO, pero todos los trabajadores merecen llegar a casa al final del d\u00eda, no solo los CEO\u201d.<\/p>\n<p>Mitchell dijo que apoya el derecho a portar armas y posee un arma ella misma. Pero dijo que le gustar\u00eda ver l\u00edmites en la propiedad p\u00fablica de rifles de estilo de asalto, como el que us\u00f3 Sturgeon esa ma\u00f1ana.<\/p>\n<p>\u201cPor falta de una mejor palabra, esas armas son excesivas\u201d, dijo. Y tambi\u00e9n le gustar\u00eda que hubiera mejores controles para asegurarse de que las personas con problemas de salud mental no puedan comprar armas. Desde el tiroteo, se ha activado para trabajar para que Kentucky apruebe el proyecto de ley de Aversion a Crisis y Mantenimiento de Derechos, que permitir\u00eda la transferencia temporal de armas de fuego de personas si un tribunal determina que el propietario del arma representa un peligro de causar da\u00f1o a s\u00ed mismo o a otros.<\/p>\n<p>Tres meses despu\u00e9s del tiroteo, Mitchell volvi\u00f3 al trabajo, pero dej\u00f3 el empleo a principios de este a\u00f1o para cuidar a un familiar. Era dif\u00edcil estar en el banco, dijo. Sufri\u00f3 culpa del sobreviviente.<\/p>\n<p>\u201cIncluso ahora, lo m\u00e1s dif\u00edcil con lo que he lidiado es la p\u00e9rdida de esas cinco personas. Dos de ellas estaban muy muy cercanas a m\u00ed\u201d, dijo. \u201cHasta el d\u00eda de hoy, cuando pienso en el hecho de que todav\u00eda estoy aqu\u00ed y ellos no, me hace sentir extremadamente triste, extremadamente enojada. No s\u00e9 por qu\u00e9 sobreviv\u00ed y las personas a cada lado de m\u00ed se han ido\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al d\u00eda siguiente de Pascua de 2023, Dana Mitchell fue a trabajar, tom\u00f3 un caf\u00e9 y camin\u00f3 hacia la sala de conferencias para la reuni\u00f3n regular del lunes por la ma\u00f1ana. Estaba hablando con un compa\u00f1ero de trabajo sobre su bronceado de unas vacaciones. Mir\u00f3 hacia arriba y vio a otro compa\u00f1ero de trabajo, Connor [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456759","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al d\u00eda siguiente de Pascua de 2023, Dana Mitchell fue a trabajar, tom\u00f3 un caf\u00e9 y camin\u00f3 hacia la sala de conferencias para la reuni\u00f3n regular del lunes por la ma\u00f1ana. Estaba hablando con un compa\u00f1ero de trabajo sobre su bronceado de unas vacaciones. Mir\u00f3 hacia arriba y vio a otro compa\u00f1ero de trabajo, Connor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-19T18:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes\",\"datePublished\":\"2024-12-19T18:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\"},\"wordCount\":1438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\",\"name\":\"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-19T18:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes - Noticias","og_description":"Al d\u00eda siguiente de Pascua de 2023, Dana Mitchell fue a trabajar, tom\u00f3 un caf\u00e9 y camin\u00f3 hacia la sala de conferencias para la reuni\u00f3n regular del lunes por la ma\u00f1ana. Estaba hablando con un compa\u00f1ero de trabajo sobre su bronceado de unas vacaciones. Mir\u00f3 hacia arriba y vio a otro compa\u00f1ero de trabajo, Connor [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-19T18:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/"},"author":{"name":"","@id":""},"headline":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes","datePublished":"2024-12-19T18:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/"},"wordCount":1438,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","name":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-19T18:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/19\/2023-458-asesinatos-en-trabajo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-19T18:04:00Z","datePublished":"2024-12-19T18:04:00Z","dateModified":"2024-12-19T18:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"En 2023, hubo 458 homicidios en el lugar de trabajo y se han vuelto inquietantemente frecuentes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/19\\\/2023-458-asesinatos-en-trabajo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/19\\\/2023-458-asesinatos-en-trabajo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-19T18:04:00Z\",\"datePublished\":\"2024-12-19T18:04:00Z\",\"dateModified\":\"2024-12-19T18:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447593,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/01\/puente-baltimore-sobreviviente-colapso-larry-desantis-trax\/","url_meta":{"origin":1456759,"position":0},"title":"&#171;Me considero muy afortunado&#187;: habla una de las \u00faltimas personas en salir del puente de Baltimore antes de su derrumbe","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) -- Eran poco m\u00e1s de la 1:00 a.m. del 26 de marzo y Larry DeSantis se dirig\u00eda a su segundo trabajo en Herman's Bakery, en la zona de Baltimore: la mitad de otra larga, pero normal, jornada laboral.Cuando un barco colision\u00f3 con el puente Francis Scott Key, provocando su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465265,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/08\/tiroteo-fort-stewart-sospechoso-envio-mensaje-familia-trax\/","url_meta":{"origin":1456759,"position":1},"title":"Minutos antes del tiroteo en Fort Stewart, el sospechoso envi\u00f3 un mensaje a su familia diciendo &#171;Los quiero&#187;, seg\u00fan su t\u00edo","author":"","date":"agosto 8, 2025","format":false,"excerpt":"\u201cSolo quiero que sepan que los quiero y que me esforc\u00e9 al m\u00e1ximo para ser lo mejor posible\u201d, escribi\u00f3 el sargento Quornelius Samentrio Radford a sus familiares al menos 20 minutos antes de comenzar a disparar contra otros soldados a inicios de esta semana en su base militar en Georgia.\u201cMi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470456,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/24\/quien-era-alex-pretti-baleado-patrulla-fronteriza-minneapolis-trax\/","url_meta":{"origin":1456759,"position":2},"title":"\u00bfQui\u00e9n era Alex Pretti, el hombre que muri\u00f3 baleado por un agente de la Patrulla Fronteriza en Minneapolis?","author":"","date":"enero 24, 2026","format":false,"excerpt":"Alex Pretti, el hombre de 37 a\u00f1os que muri\u00f3 baleado por agentes federales de inmigraci\u00f3n este s\u00e1bado, trabajaba como enfermero atendiendo a veteranos enfermos, de acuerdo con familiares, amigos y colegas, quienes dijeron que esto reflejaba su profundo deseo de ayudar a los dem\u00e1s.Pretti trabaj\u00f3 como enfermero en la Unidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472507,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/24\/quien-es-matt-floca-centro-kennedy-trax\/","url_meta":{"origin":1456759,"position":3},"title":"Qui\u00e9n es Matt Floca, el encargado de &#171;la climatizaci\u00f3n y los ba\u00f1os&#187; que ahora dirige el Centro Kennedy","author":"","date":"marzo 24, 2026","format":false,"excerpt":"El nuevo director del Centro Kennedy es un joven y apreciado gerente de instalaciones que, hasta hace poco, estaba \u201ca cargo de la climatizaci\u00f3n y los ba\u00f1os\u201d, como lo describi\u00f3 un antiguo compa\u00f1ero, en la prestigiosa instituci\u00f3n dedicada a las artes esc\u00e9nicas.Momentos despu\u00e9s de que la junta del Centro Kennedy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463657,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/17\/sospechoso-minnesota-vance-boelter-giro-trax\/","url_meta":{"origin":1456759,"position":4},"title":"Sermones y funerarias: la vida del sospechoso de Minnesota Vance Boelter dio un giro extra\u00f1o en los \u00faltimos a\u00f1os","author":"","date":"junio 17, 2025","format":false,"excerpt":"Durante d\u00e9cadas, Vance Boelter parec\u00eda llevar una vida t\u00edpica del medio oeste estadounidense. Su curr\u00edculum lo mostraba ascendiendo en la escala corporativa de empresas de servicios de alimentaci\u00f3n como Gerber y 7-Eleven, mientras criaba a una familia con cinco hijos y dos pastores alemanes y compraba varias casas cada vez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460786,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/03\/alejandro-kim-candidato-a-legislador-la-lista-de-leandro-santoro-no-se-que-es-pero-no-es-peronista\/","url_meta":{"origin":1456759,"position":5},"title":"Alejandro Kim, candidato a legislador: &#171;La lista de Leandro Santoro no s\u00e9 qu\u00e9 es, pero no es peronista&#187;","author":"","date":"abril 3, 2025","format":false,"excerpt":"Alejandro Kim, candidato a legislador porte\u00f1o por \u201cPrincipios y Valores\u201d, habl\u00f3 este jueves en CNN Radio sobre su identificaci\u00f3n con el peronismo, Guillermo Moreno, Cristina Kirchner y Alberto Fern\u00e1ndez y las diferencias con los candidatos Leandro Santoro y Juan Abal Medina para la Ciudad de Buenos Aires.En La Ma\u00f1ana de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456759"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456759\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}