{"id":1456835,"date":"2024-12-21T11:03:45","date_gmt":"2024-12-21T19:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/"},"modified":"2024-12-21T11:03:45","modified_gmt":"2024-12-21T19:03:45","slug":"rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","title":{"rendered":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria"},"content":{"rendered":"<p>La secretaria de Gobernaci\u00f3n de M\u00e9xico, Rosa Icela Rodr\u00edguez, <a href=\"https:\/\/x.com\/rosaicela_\/status\/1870290892931916181\">se reuni\u00f3 este viernes<\/a> con los cinco gobernadores de los estados mexicanos fronterizos con Estados Unidos para hablar sobre la estrategia migratoria del pa\u00eds a un mes de la investidura del presidente electo de Estados Unidos, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/12\/estados-unidos\/trump-ejercito-deportaciones-masivas-trax\">Donald Trump<\/a>.<\/p>\n<p>Los gobernadores que participaron en la reuni\u00f3n fueron: Marina del Pilar \u00c1vila, de Baja California; Manolo Jim\u00e9nez Salinas, de Coahuila; Alfonso Durazo, de Sonora; Am\u00e9rico Villarreal, de Tamaulipas, y Samuel Garc\u00eda, de Nuevo Le\u00f3n.<\/p>\n<p>\u201cJunto a mis compa\u00f1eros gobernadores de la frontera, estamos priorizando el trato humano y bienestar de los migrantes que pasan por nuestro pa\u00eds\u201d, <a href=\"https:\/\/x.com\/MarinadelPilar\/status\/1870235452445470768\">se\u00f1al\u00f3 \u00c1vila en una publicaci\u00f3n en X<\/a>.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo el 5 de diciembre que espera alcanzar <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/05\/mexico\/sheinbaum-trump-migrantes-deportados-no-mexicanos-orix\">un acuerdo con Trump<\/a> para que los deportados que no sean de nacionalidad mexicana sean enviados directamente a sus pa\u00edses de origen. La mandataria ha reiterado en varias ocasiones que la estrategia de su gobierno es \u201chumanitaria\u201d con los migrantes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria de Gobernaci\u00f3n de M\u00e9xico, Rosa Icela Rodr\u00edguez, se reuni\u00f3 este viernes con los cinco gobernadores de los estados mexicanos fronterizos con Estados Unidos para hablar sobre la estrategia migratoria del pa\u00eds a un mes de la investidura del presidente electo de Estados Unidos, Donald Trump. Los gobernadores que participaron en la reuni\u00f3n fueron: [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1456835","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria - Noticias\" \/>\n<meta property=\"og:description\" content=\"La secretaria de Gobernaci\u00f3n de M\u00e9xico, Rosa Icela Rodr\u00edguez, se reuni\u00f3 este viernes con los cinco gobernadores de los estados mexicanos fronterizos con Estados Unidos para hablar sobre la estrategia migratoria del pa\u00eds a un mes de la investidura del presidente electo de Estados Unidos, Donald Trump. Los gobernadores que participaron en la reuni\u00f3n fueron: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-21T19:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria\",\"datePublished\":\"2024-12-21T19:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\",\"name\":\"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-21T19:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria - Noticias","og_description":"La secretaria de Gobernaci\u00f3n de M\u00e9xico, Rosa Icela Rodr\u00edguez, se reuni\u00f3 este viernes con los cinco gobernadores de los estados mexicanos fronterizos con Estados Unidos para hablar sobre la estrategia migratoria del pa\u00eds a un mes de la investidura del presidente electo de Estados Unidos, Donald Trump. Los gobernadores que participaron en la reuni\u00f3n fueron: [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-21T19:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/"},"author":{"name":"","@id":""},"headline":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria","datePublished":"2024-12-21T19:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","name":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-21T19:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Secretaria de Gobernaci\u00f3n de M\u00e9xico se re\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/12\/21\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-21T19:03:45Z","datePublished":"2024-12-21T19:03:45Z","dateModified":"2024-12-21T19:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Secretaria de Gobernaci\\u00f3n de M\\u00e9xico se re\\u00fane con gobernadores de estados fronterizos para trazar estrategia migratoria\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/21\\\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/12\\\/21\\\/rosa-icela-rodriguez-gobernadores-estrategia-migratoria-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-21T19:03:45Z\",\"datePublished\":\"2024-12-21T19:03:45Z\",\"dateModified\":\"2024-12-21T19:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456940,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/24\/mexico-albergues-deportados-ciudadania-mexicana-orix\/","url_meta":{"origin":1456835,"position":0},"title":"M\u00e9xico prepara 25 nuevos albergues para recibir a deportados con ciudadan\u00eda mexicana, informa gobernadora de Baja California","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"M\u00e9xico prepara 25 nuevos albergues para recibir a ciudadanos mexicanos que sean deportados de Estados Unidos, inform\u00f3 este lunes la gobernadora del estado fronterizo de Baja California, Marina del Pilar \u00c1vila.\u201cHemos sostenido ya dos reuniones con la Secretar\u00eda de Gobernaci\u00f3n\u201d, se\u00f1al\u00f3 \u00c1vila. \u201cTodos los gobernadores de la frontera norte (de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445998,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/25\/crisis-migratoria-reunion-gobernadores-casa-blanca-trax\/","url_meta":{"origin":1456835,"position":1},"title":"La crisis migratoria domin\u00f3 la conversaci\u00f3n en la reuni\u00f3n de gobernadores en la Casa Blanca","author":"","date":"febrero 25, 2024","format":false,"excerpt":"(CNN) -- La cifra r\u00e9cord de migrantes que llegan a la frontera entre Estados Unidos y M\u00e9xico fue el principal tema de conversaci\u00f3n en la reuni\u00f3n de gobernadores en la Casa Blanca este fin de semana, lo cual revel\u00f3 c\u00f3mo el asunto se ha vuelto relevante en los estados de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445953,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/23\/biden-acuerdo-fronterizo-mas-fuerte-de-la-historia-trax\/","url_meta":{"origin":1456835,"position":2},"title":"Biden califica el acuerdo fronterizo como &#171;el m\u00e1s fuerte&#187; de la historia","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) --\u00a0El presidente Joe Biden pidi\u00f3 a los republicanos de la C\u00e1mara de Representantes que aceptaran el acuerdo fronterizo bipartidista, calific\u00e1ndolo como \"el acuerdo fronterizo m\u00e1s s\u00f3lido que el pa\u00eds haya visto jam\u00e1s\", e inst\u00f3 a los gobernadores a presionar al Congreso para que apruebe el proyecto de ley.En una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466077,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/02\/mayo-zambada-culpable-sobornos-funcionarios-orix\/","url_meta":{"origin":1456835,"position":3},"title":"El Mayo Zambada se declar\u00f3 culpable y admiti\u00f3 haber sobornado a funcionarios: \u00bfsabr\u00e1n los mexicanos alguna vez a qui\u00e9nes?","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"Durante d\u00e9cadas, Ismael \u201cEl Mayo\u201d Zambada dirigi\u00f3 el C\u00e1rtel de Sinaloa desde las sombras \u2014nunca fue arrestado y rara vez se le vio en p\u00fablico\u2014 pero, seg\u00fan los fisclaes estadounidenses, estuvo al mando de una de las organizaciones criminales m\u00e1s poderosas y violentas del mundo.La semana pasada, rompi\u00f3 el silencio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450998,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/09\/mexico-triplica-migrantes-irregulares-detenidos-2024-orix\/","url_meta":{"origin":1456835,"position":4},"title":"M\u00e9xico triplica la cantidad de migrantes &#171;irregulares&#187; detenidos en lo que va de 2024","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El gobierno de M\u00e9xico triplic\u00f3 el n\u00famero de migrantes \"irregulares\" detenidos en los primeros cinco meses de este a\u00f1o, al pasar de 185.038 en el periodo enero-mayo de 2023 a 590.401 en el mismo lapso de 2024, seg\u00fan cifras oficiales difundidas por la Secretar\u00eda de Gobernaci\u00f3n.De acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446041,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","url_meta":{"origin":1456835,"position":5},"title":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0En apenas una d\u00e9cada, el mapa electoral de M\u00e9xico ha pasado de la hegemon\u00eda del Partido Revolucionario Institucional (PRI) al dominio de Morena, el partido fundado por el actual presidente, Andr\u00e9s Manuel L\u00f3pez Obrador.En seis a\u00f1os, Morena logr\u00f3 posicionarse como la primera fuerza pol\u00edtica. Los datos hablan por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1456835"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1456835\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1456835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1456835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1456835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}