{"id":1458376,"date":"2025-02-06T18:03:45","date_gmt":"2025-02-07T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/"},"modified":"2025-02-06T18:03:45","modified_gmt":"2025-02-07T02:03:45","slug":"petro-embajada-ee-uu-migrantes-deportados-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","title":{"rendered":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados"},"content":{"rendered":"<p>El presidente de Colombia, Gustavo Petro, y encargado de negocios de la Embajada de Estados Unidos, John McNamara, se reunieron en privado este jueves para hablar de temas como la migraci\u00f3n y la lucha contra el narcotr\u00e1fico, dijo la canciller colombiana, Laura Sarabia, en un mensaje en video difundido a los medios.<\/p>\n<p>La ministra asegur\u00f3 que la reuni\u00f3n tuvo el objetivo de mostrar que \u201ca pesar de cualquier tensi\u00f3n o cualquier diferencia, el di\u00e1logo y la diplomacia ser\u00e1n el camino para superar cualquier diferencia y construir la agenda bilateral que potenciar\u00e1 a ambas naciones\u201d.<\/p>\n<p>El encuentro se realiz\u00f3 casi dos semanas despu\u00e9s del diferendo diplom\u00e1tico que a finales de enero tuvieron los gobiernos de Petro y del presidente de EE.UU., Donald Trump, luego de que el mandatario colombiano rechaz\u00f3 recibir vuelos procedentes de EE.UU. con migrantes deportados.<\/p>\n<p>Petro reclam\u00f3 que los migrantes viajaran en aviones militares y esposados, mientras que EE.UU. argument\u00f3 que Colombia ya hab\u00eda aceptado recibir esos traslados y amenaz\u00f3 con imponer aranceles a los productos colombianos. Finalmente, la noche del 26 de enero, el entonces canciller colombiano, Luis Gilberto Murillo, inform\u00f3 a medios que las aeronaves ser\u00edan recibidas y dio por superado lo que llam\u00f3 un \u201cimpasse\u201d.<\/p>\n<p>Acerca de la deportaci\u00f3n de migrantes, Sarabia dijo este jueves que Petro y McNamara hablaron sobre que Colombia recibir\u00e1 a todos sus connacionales retornados. \u201cVamos a recibir y no vamos a dejar solos a nuestros ciudadanos colombianos, pero manteniendo un trato digno y, sobre todo, velando por la protecci\u00f3n de sus derechos\u201d, agreg\u00f3.<\/p>\n<p>En cuanto al combate al narcotr\u00e1fico, la canciller se\u00f1al\u00f3 que en la reuni\u00f3n se habl\u00f3 sobre construir \u201cestrategias conjuntas\u201d que abarquen tanto el uso de la fuerza p\u00fablica como medidas para sustituir econom\u00edas ilegales.<\/p>\n<p>CNN contact\u00f3 al Departamento de Estado de EE.UU. para pedir comentarios sobre el encuentro y est\u00e1 en espera de respuesta.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Colombia, Gustavo Petro, y encargado de negocios de la Embajada de Estados Unidos, John McNamara, se reunieron en privado este jueves para hablar de temas como la migraci\u00f3n y la lucha contra el narcotr\u00e1fico, dijo la canciller colombiana, Laura Sarabia, en un mensaje en video difundido a los medios. La ministra asegur\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458376","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Colombia, Gustavo Petro, y encargado de negocios de la Embajada de Estados Unidos, John McNamara, se reunieron en privado este jueves para hablar de temas como la migraci\u00f3n y la lucha contra el narcotr\u00e1fico, dijo la canciller colombiana, Laura Sarabia, en un mensaje en video difundido a los medios. La ministra asegur\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-07T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados\",\"datePublished\":\"2025-02-07T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\",\"name\":\"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-07T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados - Noticias","og_description":"El presidente de Colombia, Gustavo Petro, y encargado de negocios de la Embajada de Estados Unidos, John McNamara, se reunieron en privado este jueves para hablar de temas como la migraci\u00f3n y la lucha contra el narcotr\u00e1fico, dijo la canciller colombiana, Laura Sarabia, en un mensaje en video difundido a los medios. La ministra asegur\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-07T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/"},"author":{"name":"","@id":""},"headline":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados","datePublished":"2025-02-07T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","name":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-07T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Petro se re\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/06\/petro-embajada-ee-uu-migrantes-deportados-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-07T02:03:45Z","datePublished":"2025-02-07T02:03:45Z","dateModified":"2025-02-07T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Petro se re\\u00fane con el encargado de la embajada de EE.UU. en Colombia tras diferendo por migrantes deportados\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/06\\\/petro-embajada-ee-uu-migrantes-deportados-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/06\\\/petro-embajada-ee-uu-migrantes-deportados-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-07T02:03:45Z\",\"datePublished\":\"2025-02-07T02:03:45Z\",\"dateModified\":\"2025-02-07T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464380,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/09\/petro-nombra-rosa-villavicencio-canciller-cargo-menos-3-anos-orix\/","url_meta":{"origin":1458376,"position":0},"title":"Petro nombra a Rosa Villavicencio como canciller, es la cuarta persona que ocupa el cargo en menos de 3 a\u00f1os de mandato","author":"","date":"julio 9, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, nombr\u00f3 este mi\u00e9rcoles a Rosa Yolanda Villavicencio como nueva ministra de Relaciones Exteriores, un cargo que asume tras la renuncia de la anterior canciller, Laura Sarabia, la semana pasada.La canciller\u00eda de Colombia dio a conocer el nombramiento en un comunicado, en el que se\u00f1al\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464193,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/03\/ee-uu-consultas-negocios-colombia-petro-responde-orix\/","url_meta":{"origin":1458376,"position":1},"title":"EE.UU. llama a consultas a su encargado de negocios en Colombia. Petro responde con la misma medida","author":"","date":"julio 3, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos llam\u00f3 este jueves a consultas a su encargado de negocios en Colombia, John McNamara, en represalia por lo que consider\u00f3 \u201cdeclaraciones infundadas y reprobables de los m\u00e1s altos niveles del Gobierno de Colombia\u201d.El secretario de Estado de Estados Unidos, Marco Rubio, dijo en un comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472404,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/20\/petro-niega-vinculos-narcotrafico-ninguna-notificacion-formal-eeuu-orix\/","url_meta":{"origin":1458376,"position":2},"title":"Petro niega v\u00ednculos con el narcotr\u00e1fico y su gobierno dice que no ha sido notificado de posibles investigaciones en EE.UU.","author":"","date":"marzo 20, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, neg\u00f3 este viernes tener alg\u00fan v\u00ednculo con grupos del narcotr\u00e1fico, luego de que se difundieran reportes de medios sobre posibles investigaciones de Estados Unidos contra el mandatario por este motivo, al tiempo que la Embajada de Colombia en Washington dijo que no ha recibido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458018,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/29\/laura-sarabia-asume-canciller-colombia-orix\/","url_meta":{"origin":1458376,"position":3},"title":"Laura Sarabia asume como canciller de Colombia; es la tercera en el cargo en menos de un a\u00f1o","author":"","date":"enero 29, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, nombr\u00f3 este mi\u00e9rcoles a Laura Sarabia como nueva canciller en sustituci\u00f3n de Luis Gilberto Murillo. El nombramiento tuvo lugar durante una ceremonia en el Palacio de Nari\u00f1o, donde se oficializaron tambi\u00e9n otras designaciones.La llegada de Sarabia a la Canciller\u00eda se dio a conocer la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467646,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/22\/trump-confirma-suspension-pagos-subsidios-colombia-trax\/","url_meta":{"origin":1458376,"position":4},"title":"Trump confirm\u00f3 la suspensi\u00f3n de pagos y subsidios de EE.UU. a Colombia","author":"","date":"octubre 22, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 el mi\u00e9rcoles que EE.UU. suspendi\u00f3 todos los pagos y subsidios a Colombia, cumpliendo as\u00ed una amenaza hecha el fin de semana durante un intercambio con el presidente del pa\u00eds, Gustavo Petro.\u201cAcabamos de \u2013 a partir de hoy \u2013 detener todos los pagos que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460880,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/05\/petro-secretaria-seguridad-ee-uu-comentarios-tren-aragua-orix\/","url_meta":{"origin":1458376,"position":5},"title":"Petro dice que la secretaria de Seguridad de EE.UU. malinterpret\u00f3 sus comentarios sobre integrantes del Tren de Aragua","author":"","date":"abril 5, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, rechaz\u00f3 este s\u00e1bado declaraciones que la secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, dio el viernes en una entrevista, en la que habl\u00f3 de la reuni\u00f3n que tuvo con el mandatario en Bogot\u00e1 a finales marzo y en la cual, seg\u00fan la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1458376"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458376\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1458376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1458376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1458376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}