{"id":1458534,"date":"2025-02-10T14:03:45","date_gmt":"2025-02-10T22:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/"},"modified":"2025-02-10T14:03:45","modified_gmt":"2025-02-10T22:03:45","slug":"venezuela-reanudacion-vuelos-deportados-ee-uu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","title":{"rendered":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU."},"content":{"rendered":"<p>A partir de este lunes Venezuela recibir\u00e1 nuevamente vuelos con venezolanos deportados de Estados Unidos, inform\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro en un comunicado.<\/p>\n<p>En el documento se agrega que los primeros dos vuelos con repatriados desde Estados Unidos son operados por la aerol\u00ednea estatal venezolana Conviasa.<\/p>\n<p>El Gobierno de Estados Unidos, agreg\u00f3 el comunicado y notific\u00f3 que algunas de las personas deportadas ser\u00edan posibles integrantes del grupo criminal \u201cTren de Aragua\u201d, por lo que afirma Caracas que ser\u00e1n sometidos \u201ca una rigurosa investigaci\u00f3n\u201d y sujetos de \u201clas acciones previstas en nuestro sistema de justicia\u201d.<\/p>\n<p>El Gobierno de Venezuela destac\u00f3 que las deportaciones se producen en el marco de la reciente visita a Caracas del asesor de pol\u00edtica exterior del presidente Donald Trump, Richard Grenell, a quien se le propuso que los repatriados regresen en aviones enviados por Venezuela \u201ccon absoluto respeto de su dignidad y derechos humanos\u201d.<\/p>\n<p>CNN est\u00e1 tratando de averiguar con el Departamento de Seguridad Nacional de Estados Unidos los detalles del reinicio de las deportaciones a Venezuela.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de este lunes Venezuela recibir\u00e1 nuevamente vuelos con venezolanos deportados de Estados Unidos, inform\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro en un comunicado. En el documento se agrega que los primeros dos vuelos con repatriados desde Estados Unidos son operados por la aerol\u00ednea estatal venezolana Conviasa. El Gobierno de Estados Unidos, agreg\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458534","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"A partir de este lunes Venezuela recibir\u00e1 nuevamente vuelos con venezolanos deportados de Estados Unidos, inform\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro en un comunicado. En el documento se agrega que los primeros dos vuelos con repatriados desde Estados Unidos son operados por la aerol\u00ednea estatal venezolana Conviasa. El Gobierno de Estados Unidos, agreg\u00f3 el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T22:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU.\",\"datePublished\":\"2025-02-10T22:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\"},\"wordCount\":206,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\",\"name\":\"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-10T22:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU. - Noticias","og_description":"A partir de este lunes Venezuela recibir\u00e1 nuevamente vuelos con venezolanos deportados de Estados Unidos, inform\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro en un comunicado. En el documento se agrega que los primeros dos vuelos con repatriados desde Estados Unidos son operados por la aerol\u00ednea estatal venezolana Conviasa. El Gobierno de Estados Unidos, agreg\u00f3 el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-10T22:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/"},"author":{"name":"","@id":""},"headline":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU.","datePublished":"2025-02-10T22:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/"},"wordCount":206,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","name":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-10T22:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Venezuela anuncia la reanudaci\u00f3n de vuelos de deportados desde EE.UU.","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-10T22:03:45Z","datePublished":"2025-02-10T22:03:45Z","dateModified":"2025-02-10T22:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Venezuela anuncia la reanudaci\\u00f3n de vuelos de deportados desde EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/10\\\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/10\\\/venezuela-reanudacion-vuelos-deportados-ee-uu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-10T22:03:45Z\",\"datePublished\":\"2025-02-10T22:03:45Z\",\"dateModified\":\"2025-02-10T22:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460502,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/27\/se-espera-que-venezuela-reciba-este-jueves-un-segundo-vuelo-con-deportados-de-estados-unidos-segun-fuentes\/","url_meta":{"origin":1458534,"position":0},"title":"Se espera que Venezuela reciba este jueves un segundo vuelo con deportados de Estados Unidos, seg\u00fan fuentes","author":"","date":"marzo 27, 2025","format":false,"excerpt":"Se espera que Venezuela reciba un vuelo de deportaci\u00f3n desde Estados Unidos este jueves, el segundo de esta semana desde que se reanudaron los vuelos de deportaci\u00f3n directa el lunes, seg\u00fan anunci\u00f3 el Ministerio del Interior venezolano.El Gobierno de Trump ha priorizado las deportaciones directas a Caracas desde que asumi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460615,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/30\/vuelo-inmigrantes-deportados-eeuu-caracas-venezuela-trax\/","url_meta":{"origin":1458534,"position":1},"title":"Llega a Venezuela un nuevo vuelo con 175 inmigrantes deportados de EE.UU.","author":"","date":"marzo 30, 2025","format":false,"excerpt":"Un avi\u00f3n que transportaba inmigrantes deportados de Estados Unidos aterriz\u00f3 en Venezuela este domingo, el tercer vuelo de este tipo desde que ambas naciones acordaron reanudar los vuelos de repatriaci\u00f3n a principios de este mes, seg\u00fan un equipo de CNN en el lugar.El vuelo, que despeg\u00f3 de Texas, aterriz\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458104,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/01\/trump-venezuela-acepto-recibir-venezolanos-deportados-trax\/","url_meta":{"origin":1458534,"position":2},"title":"Trump dice que Venezuela &#171;acept\u00f3 recibir&#187; a venezolanos deportados de EE.UU.","author":"","date":"febrero 1, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dijo en una publicaci\u00f3n en la red social Truth Social la ma\u00f1ana de este s\u00e1bado que Venezuela \u201cacept\u00f3 recibir\u201d a los ciudadanos venezolanos que sean deportados de Estados Unidos.\u201cVenezuela acept\u00f3 recibir, de regreso a su pa\u00eds, a todos los extranjeros ilegales venezolanos que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460819,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/04\/vuelos-repatriacion-500-migrantes-venezuela-trax\/","url_meta":{"origin":1458534,"position":3},"title":"Vuelos de repatriaci\u00f3n con m\u00e1s de 500 migrantes retornados aterrizan en Venezuela","author":"","date":"abril 4, 2025","format":false,"excerpt":"Las autoridades venezolanas recibieron el jueves a m\u00e1s de 500 migrantes que regresaban de Estados Unidos y M\u00e9xico, lo que indica una intensificaci\u00f3n de las deportaciones y repatriaciones entre Washington y Caracas a pesar de las renovadas tensiones geopol\u00edticas.El jueves por la ma\u00f1ana, un vuelo venezolano con 313 migrantes provenientes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468823,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/29\/eeuu-venezuela-crisis-aerea-tension-mas-aislada-orix\/","url_meta":{"origin":1458534,"position":4},"title":"Por la tensi\u00f3n con EE.UU., Venezuela enfrenta una crisis a\u00e9rea y queda a\u00fan m\u00e1s aislada","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Mientras recrudece la tensi\u00f3n por el despliegue militar de Estados Unidos en el Caribe, se complica cada vez m\u00e1s la situaci\u00f3n relacionada con el espacio a\u00e9reo de Venezuela.Este s\u00e1bado, el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a aerol\u00edneas, pilotos y redes criminales que consideraran el \u201cespacio a\u00e9reo sobre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459879,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/13\/venezuela-vuelos-repatriacion-inmigrantes-eeuu-trax\/","url_meta":{"origin":1458534,"position":5},"title":"Venezuela reanudar\u00e1 vuelos de repatriaci\u00f3n de inmigrantes desde EE.UU., dice enviado de Trump","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Venezuela accedi\u00f3 a reanudar los vuelos para recoger y llevar a casa a sus propios ciudadanos que entraron ilegalmente en Estados Unidos, seg\u00fan Ric Grenell, enviado del presidente Donald Trump para misiones especiales.\u201cMe complace anunciar que Venezuela ha acordado reanudar los vuelos para recoger a sus ciudadanos que violaron las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1458534"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458534\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1458534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1458534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1458534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}