{"id":1458548,"date":"2025-02-10T19:03:51","date_gmt":"2025-02-11T03:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/"},"modified":"2025-02-10T19:03:51","modified_gmt":"2025-02-11T03:03:51","slug":"cientificos-forma-nucleo-interno-tierra-cambiando-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","title":{"rendered":"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando"},"content":{"rendered":"<p>Cient\u00edficos que hace solo unos meses confirmaron que el n\u00facleo interno de la Tierra recientemente invirti\u00f3 su giro tienen una nueva revelaci\u00f3n sobre los secretos m\u00e1s profundos de nuestro planeta: identificaron cambios en la forma del n\u00facleo interno.<\/p>\n<p>La capa m\u00e1s interna de la Tierra es una bola de metal caliente y s\u00f3lida rodeada por un n\u00facleo externo de metal l\u00edquido. Durante d\u00e9cadas, los cient\u00edficos planetarios sospecharon que el n\u00facleo interno s\u00f3lido se deformaba con el tiempo a medida que giraba. Ahora, los investigadores han encontrado la primera evidencia de cambios que han tenido lugar en los \u00faltimos 20 a\u00f1os en la forma del n\u00facleo interno. Los signos de la deformaci\u00f3n del n\u00facleo aparecieron en ondas de terremotos lo suficientemente fuertes como para alcanzar el centro de la Tierra.<\/p>\n<p>El equipo de investigaci\u00f3n utiliz\u00f3 esos mismos datos s\u00edsmicos para un estudio de 2024 con el fin de resolver un debate de larga data sobre la rotaci\u00f3n del n\u00facleo interno. Encontraron que el n\u00facleo interno una vez gir\u00f3 m\u00e1s r\u00e1pido que la propia Tierra. Pero a partir de 2010, la rotaci\u00f3n del n\u00facleo interno s\u00f3lido se ralentiz\u00f3. Ahora est\u00e1 <a href=\"https:\/\/www.nature.com\/articles\/s41586-024-07536-4\">girando hacia atr\u00e1s<\/a>, en relaci\u00f3n con el resto del planeta.<\/p>\n<p>Su nuevo estudio, publicado este lunes en la <a href=\"https:\/\/www.nature.com\/articles\/s41561-025-01642-2\">revista Nature Geoscience<\/a>, se basa en ese descubrimiento, utilizando datos s\u00edsmicos recopilados desde 1991 hasta 2023. El trabajo previo de los cient\u00edficos sobre la rotaci\u00f3n del n\u00facleo les ayud\u00f3 a interpretar variaciones en la altura de las ondas s\u00edsmicas, defini\u00e9ndolas como indicadores de cambios en la superficie del n\u00facleo interno, dijo el Dr. John Vidale, coautor del estudio previo y autor principal del nuevo estudio.<\/p>\n<p>\u201cPodemos comparar las se\u00f1ales que vemos cuando el n\u00facleo interno vuelve a la misma posici\u00f3n que ten\u00eda en alg\u00fan otro momento y ver si hay diferencias que no se pueden explicar por la rotaci\u00f3n\u201d, dijo a CNN Vidale, profesor decano de Ciencias de la Tierra en la Universidad del Sur de California en el Colegio Dornsife de Letras, Artes y Ciencias. Los cambios de forma en el n\u00facleo podr\u00edan contener pistas sobre las fuerzas en el interior de la Tierra que alimentan nuestra magnetosfera, las l\u00edneas invisibles de energ\u00eda magn\u00e9tica que protegen nuestro planeta del clima solar y la radiaci\u00f3n mortal, informaron los investigadores.<\/p>\n<p>\u201cLa Tierra evoluciona en una escala de tiempo geol\u00f3gica, por lo que observar cambios en una escala de tiempo anual es siempre intrigante, debido a que mejora nuestra comprensi\u00f3n de la din\u00e1mica del n\u00facleo interno\u201d, dijo el <a href=\"https:\/\/geology.rutgers.edu\/people\/faculty\/faculty-member\/1570-miyazaki-yoshi\">Dr. Yoshi Miyazaki<\/a>, profesor asociado en el departamento de ciencias de la Tierra y planetarias en la Universidad de Rutgers en Nueva Jersey.<\/p>\n<p>\u201cEstudios previos ya han discutido c\u00f3mo ha cambiado la rotaci\u00f3n del n\u00facleo interno en la \u00faltima d\u00e9cada, y este estudio introduce una nueva perspectiva: cambios no rotacionales, a\u00f1adiendo otra dimensi\u00f3n a la discusi\u00f3n. Creo que esto avivar\u00e1 a\u00fan m\u00e1s esos debates\u201d, coment\u00f3 Miyazaki, quien no particip\u00f3 en la nueva investigaci\u00f3n, a CNN en un correo electr\u00f3nico.<\/p>\n<p>De todas las capas de la Tierra, el n\u00facleo interno es el m\u00e1s remoto y misterioso. Esta esfera s\u00f3lida de hierro y n\u00edquel es aproximadamente el 70% del tama\u00f1o de la luna, con un radio de aproximadamente 1.221 kil\u00f3metros.<\/p>\n<p>Las temperaturas en el n\u00facleo interno alcanzan hasta 5.400 grados Celsius, y las presiones pueden llegar a 365 gigapascales (GPa), m\u00e1s de 3 millones de veces mayor que <a href=\"https:\/\/www.ndbc.noaa.gov\/education\/pressure.shtml\">la presi\u00f3n atmosf\u00e9rica promedio en la superficie terrestre<\/a>. Si bien la observaci\u00f3n directa del n\u00facleo es imposible, los cient\u00edficos lo estudian analizando cambios en el tama\u00f1o y la forma de las ondas s\u00edsmicas a medida que atraviesan el n\u00facleo.<\/p>\n<p>Los terremotos generan dos tipos de ondas. Las ondas primarias, u ondas P, son las primeras ondas producidas por un temblor, y mueven el suelo en la misma direcci\u00f3n en que se mueve la onda. Las ondas de corte, u ondas S, son m\u00e1s lentas que las ondas P y mueven el suelo de manera perpendicular a la direcci\u00f3n de la onda.<\/p>\n<p>Los cambios de amplitud en un tipo de onda P que penetra el n\u00facleo \u2014ondas PKIKP\u2014 indicaron deformaciones en el nivel m\u00e1s superficial del n\u00facleo interno, seg\u00fan el nuevo estudio. En el l\u00edmite donde el n\u00facleo interno s\u00f3lido se encuentra con el l\u00edquido del n\u00facleo externo, la superficie de la esfera podr\u00eda ser m\u00e1s maleable de lo que es a niveles m\u00e1s profundos.<\/p>\n<p>\u201cEs casi ciencia ficci\u00f3n visualizar lo que est\u00e1 sucediendo en la superficie del n\u00facleo interno\u201d, dijo Vidale. \u201cEs un lugar que es tan diferente de nuestras vidas diarias, con escalas de tiempo diferentes, materiales diferentes e incre\u00edbles fuerzas. Y, sin embargo, podemos llegar hasta all\u00ed y aprender m\u00e1s sobre ello simplemente al examinar algunas de las \u00faltimas observaciones\u201d.<\/p>\n<p>Los cient\u00edficos analizaron 168 ondas emparejadas de terremotos en 42 ubicaciones cerca de las Islas Sandwich del Sur, una cadena de islas volc\u00e1nicas en el oc\u00e9ano Atl\u00e1ntico Sur. Rastrear la velocidad y direcci\u00f3n de la rotaci\u00f3n del n\u00facleo brind\u00f3 a los investigadores una forma de detectar cambios en la forma del n\u00facleo. Una vez que conocieron la velocidad de rotaci\u00f3n del n\u00facleo, pudieron modelar su posici\u00f3n y luego comparar diferentes ondas PKIKP que llegaron al n\u00facleo mientras este se giraba hacia el mismo punto.<\/p>\n<p>Los cambios de amplitud en esas ondas emparejadas podr\u00edan asignarse a cambios de forma en el n\u00facleo, en lugar de cambios de rotaci\u00f3n, seg\u00fan el estudio. Sin embargo, lo que esa deformaci\u00f3n del n\u00facleo interno podr\u00eda parecer es m\u00e1s dif\u00edcil de precisar.<\/p>\n<p>\u201cQuiz\u00e1s la topograf\u00eda est\u00e1 subiendo y bajando. Tal vez se est\u00e9 deslizando como deslizamientos de tierra\u201d, dijo Vidale. \u201cLo m\u00e1s probable es que el n\u00facleo externo simplemente est\u00e9 empujando al n\u00facleo interno y movi\u00e9ndolo un poco\u201d.<\/p>\n<p>Si bien solo una ubicaci\u00f3n del n\u00facleo interno mostr\u00f3 signos de deformaci\u00f3n entre 2004 y 2008, puede haber m\u00e1s que a\u00fan no se han detectado, informaron los investigadores.<\/p>\n<p>\u201cEs dif\u00edcil saber si estamos observando una ubicaci\u00f3n an\u00f3mala o una normal\u201d, afirm\u00f3 Vidale. \u201cPero una suposici\u00f3n ser\u00eda que alguna cantidad de deformaci\u00f3n ocurre con bastante frecuencia en muchos lugares\u201d.<\/p>\n<p>A medida que el n\u00facleo interno s\u00f3lido de la Tierra gira, el n\u00facleo externo fundido hierve y se agita. Sus interacciones generan energ\u00eda magn\u00e9tica, que se despliega para envolver a nuestro planeta en la magnetosfera. Pero el n\u00facleo externo l\u00edquido se est\u00e1 encogiendo. Mil\u00edmetro a mil\u00edmetro, el n\u00facleo interno ha extra\u00eddo con sif\u00f3n metal fundido del n\u00facleo l\u00edquido que lo rodea, dijo Vidale. Probablemente tom\u00f3 miles de millones de a\u00f1os para que el n\u00facleo interno se enfriara y solidificara, y durante los pr\u00f3ximos pocos miles de millones de a\u00f1os, el n\u00facleo interno continuar\u00e1 enfri\u00e1ndose, absorbiendo gotas de metal l\u00edquido del n\u00facleo externo, hasta que todo el n\u00facleo de la Tierra sea una esfera de metal s\u00f3lido, agreg\u00f3.<\/p>\n<p>\u201cEso matar\u00e1 el campo magn\u00e9tico\u201d, dijo Vidale. \u201cYa no habr\u00e1 hierro en movimiento all\u00ed abajo\u201d.<\/p>\n<p>Sin embargo, tal evento est\u00e1 a miles de millones de a\u00f1os en nuestro futuro. Y antes de que eso pueda suceder, la Tierra probablemente ser\u00e1 destruida cuando nuestro sol se expanda en una gigante roja y devore los planetas interiores del sistema solar, dijo Vidale. Hasta entonces, los cient\u00edficos deber\u00edan tener tiempo suficiente para investigar los mecanismos invisibles en el coraz\u00f3n de nuestro planeta y descubrir qu\u00e9 podr\u00eda deparar el giro, la agitaci\u00f3n y la transformaci\u00f3n de la forma interna de la Tierra para el planeta.<\/p>\n<p>\u201cCon respecto al impacto en la vida, como se mencion\u00f3 en la introducci\u00f3n del art\u00edculo, el crecimiento del n\u00facleo interno juega un papel crucial en la generaci\u00f3n del campo magn\u00e9tico de la Tierra, que nos protege de la da\u00f1ina radiaci\u00f3n solar\u201d, dijo Miyazaki. \u201cSi bien una conexi\u00f3n directa entre la vida en la superficie de la Tierra y el ICB (l\u00edmite entre el n\u00facleo interno y el n\u00facleo externo) sigue siendo lejana, lo que sucede en el ICB a\u00fan tiene algunas implicaciones para la evoluci\u00f3n a largo plazo de la Tierra\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cient\u00edficos que hace solo unos meses confirmaron que el n\u00facleo interno de la Tierra recientemente invirti\u00f3 su giro tienen una nueva revelaci\u00f3n sobre los secretos m\u00e1s profundos de nuestro planeta: identificaron cambios en la forma del n\u00facleo interno. La capa m\u00e1s interna de la Tierra es una bola de metal caliente y s\u00f3lida rodeada por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458548","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Es casi ciencia ficci\u00f3n&quot;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Es casi ciencia ficci\u00f3n&quot;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cient\u00edficos que hace solo unos meses confirmaron que el n\u00facleo interno de la Tierra recientemente invirti\u00f3 su giro tienen una nueva revelaci\u00f3n sobre los secretos m\u00e1s profundos de nuestro planeta: identificaron cambios en la forma del n\u00facleo interno. La capa m\u00e1s interna de la Tierra es una bola de metal caliente y s\u00f3lida rodeada por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-11T03:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando\",\"datePublished\":\"2025-02-11T03:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\"},\"wordCount\":1512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\",\"name\":\"\\\"Es casi ciencia ficci\u00f3n\\\": cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-11T03:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Es casi ciencia ficci\u00f3n\": cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Es casi ciencia ficci\u00f3n\": cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando - Noticias","og_description":"Cient\u00edficos que hace solo unos meses confirmaron que el n\u00facleo interno de la Tierra recientemente invirti\u00f3 su giro tienen una nueva revelaci\u00f3n sobre los secretos m\u00e1s profundos de nuestro planeta: identificaron cambios en la forma del n\u00facleo interno. La capa m\u00e1s interna de la Tierra es una bola de metal caliente y s\u00f3lida rodeada por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","og_site_name":"Noticias","article_published_time":"2025-02-11T03:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando","datePublished":"2025-02-11T03:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/"},"wordCount":1512,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","url":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","name":"\"Es casi ciencia ficci\u00f3n\": cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-11T03:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Es casi ciencia ficci\u00f3n&#187;: cient\u00edficos dicen que la forma del n\u00facleo interno de la Tierra est\u00e1 cambiando","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/10\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-11T03:03:51Z","datePublished":"2025-02-11T03:03:51Z","dateModified":"2025-02-11T03:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Es casi ciencia ficci\\u00f3n&#187;: cient\\u00edficos dicen que la forma del n\\u00facleo interno de la Tierra est\\u00e1 cambiando\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/10\\\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/10\\\/cientificos-forma-nucleo-interno-tierra-cambiando-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-11T03:03:51Z\",\"datePublished\":\"2025-02-11T03:03:51Z\",\"dateModified\":\"2025-02-11T03:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450905,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/05\/nucleo-tierra-desacelerado-retrocediendo-trax\/","url_meta":{"origin":1458548,"position":0},"title":"El n\u00facleo de la Tierra se ha desacelerado tanto que est\u00e1 retrocediendo, confirman los cient\u00edficos. Esto es lo que podr\u00eda significar","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN) -- En las profundidades de la Tierra hay una bola de metal s\u00f3lido que gira independientemente de nuestro planeta, como una peonza que gira dentro de otra peonza m\u00e1s grande, envuelta en el misterio.Este n\u00facleo interno ha intrigado a los investigadores desde su descubrimiento por la sism\u00f3loga danesa Inge\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471094,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/10\/nucleo-tierra-deposito-descubrimiento-hidrogeno-elemento-vida-trax\/","url_meta":{"origin":1458548,"position":1},"title":"El gran secreto del centro de la Tierra: encuentran dep\u00f3sito de un elemento vital que supera 45 veces a los oc\u00e9anos","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El n\u00facleo de la Tierra podr\u00eda ser el dep\u00f3sito de hidr\u00f3geno m\u00e1s grande jam\u00e1s imaginado. Investigaciones recientes estiman que el centro de nuestro planeta alberga hasta nueve veces m\u00e1s hidr\u00f3geno que todos los oc\u00e9anos de la superficie combinados. Este hallazgo redefine la estructura interna de la Tierra, sugiriendo que las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451543,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/01\/mercurio-capa-subterranea-diamantes-trax\/","url_meta":{"origin":1458548,"position":2},"title":"Mercurio podr\u00eda tener una capa subterr\u00e1nea de diamantes de 18 kil\u00f3metros, seg\u00fan los investigadores","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN) --\u00a0Mercurio, el planeta m\u00e1s peque\u00f1o del Sistema Solar y el m\u00e1s cercano al Sol, podr\u00eda esconder bajo su superficie una capa de diamantes de hasta 18 kil\u00f3metros de espesor, seg\u00fan una nueva investigaci\u00f3n.Los diamantes podr\u00edan haberse formado poco despu\u00e9s de que Mercurio se convirtiera en planeta, hace unos 4.500\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462780,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/25\/pablo-minini-querian-asegurarse-que-la-ciencia-que-iban-a-usar-en-la-actualizacion-fuera-correcta\/","url_meta":{"origin":1458548,"position":3},"title":"Pablo Minini: &#171;Quer\u00edan asegurarse que la ciencia que iban a usar en la actualizaci\u00f3n fuera correcta&#187;","author":"","date":"mayo 25, 2025","format":false,"excerpt":"Pablo Minini, profesor, habl\u00f3 este domingo con CNN Radio sobre la asesor\u00eda que realizaron los graduados y docentes de la Facultad de Ciencias Exactas y Naturales en el Eternauta.En Mundo UBA con Ricardo Bragisnki indic\u00f3: \u201dHace varios a\u00f1os, cuando empezaron a escribir el gui\u00f3n Bruno Stagnaro, que es el director\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457705,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/21\/nueva-posicion-polo-norte-magnetico-tierra-trax\/","url_meta":{"origin":1458548,"position":4},"title":"El polo norte magn\u00e9tico de la Tierra se est\u00e1 moviendo y los cient\u00edficos acaban de actualizar su posici\u00f3n","author":"","date":"enero 21, 2025","format":false,"excerpt":"Si usas tu tel\u00e9fono inteligente para navegar, tu sistema acaba de recibir una actualizaci\u00f3n importante. Los cient\u00edficos han publicado un nuevo modelo que rastrea la posici\u00f3n del polo norte magn\u00e9tico, y revela que el polo ahora est\u00e1 m\u00e1s cerca de Siberia que hace cinco a\u00f1os y contin\u00faa desplaz\u00e1ndose hacia Rusia.A\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455043,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/10\/11\/gran-mancha-roja-jupiter-mueve-manera-inesperada-trax\/","url_meta":{"origin":1458548,"position":5},"title":"La Gran Mancha Roja de J\u00fapiter se mueve de manera inesperada, dicen los cient\u00edficos","author":"","date":"octubre 11, 2024","format":false,"excerpt":"(CNN) -- Nuevas observaciones de la Gran Mancha Roja de J\u00fapiter capturadas por el Telescopio Espacial Hubble muestran que la tormenta de 190 a\u00f1os se mueve como gelatina y cambia de forma como una bola antiestr\u00e9s cuando se aprieta.Las observaciones inesperadas, que Hubble tom\u00f3 durante 90 d\u00edas de diciembre a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1458548"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458548\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1458548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1458548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1458548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}