{"id":1458599,"date":"2025-02-11T16:03:43","date_gmt":"2025-02-12T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/"},"modified":"2025-02-11T16:03:43","modified_gmt":"2025-02-12T00:03:43","slug":"primer-caviar-africa-sorprende-us-10000-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","title":{"rendered":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo"},"content":{"rendered":"<p>Cuando Delphyne Dabezies anunci\u00f3 por primera vez sus planes de lanzar el primer fabricante de caviar de \u00c1frica, algunos en la industria de alimentos de lujo se mostraron incr\u00e9dulos.<\/p>\n<p>Sin embargo, ahora, 15 a\u00f1os despu\u00e9s de fundar su empresa, Acipenser, con sus marcas Rova y Kasnodar Caviar, los productos de Dabezies han llegado a algunas de las cocinas m\u00e1s prestigiosas del mundo.<\/p>\n<p>En lo alto de las monta\u00f1as de Madagascar, justo al este de la capital Antananarivo, el lago Mantasoa ha surgido como una fuente inesperada de este opulento ingrediente. \u201cTodos los expertos dec\u00edan que era imposible\u201d, dijo Dabezies a CNN.<\/p>\n<p>El caviar es un manjar elaborado a partir de huevas saladas del esturi\u00f3n. Procedente tradicionalmente del mar Caspio de Rusia, alcanz\u00f3 la categor\u00eda de producto de lujo en el siglo XVII, despu\u00e9s de que el zar Alexei Mikhailovich I convirtiera el caviar en un monopolio estatal.<\/p>\n<p>La producci\u00f3n pronto se extendi\u00f3 por todo el mundo. Con el establecimiento de Acipenser en Madagascar, el caviar ahora se produce en todos los continentes habitados, excepto Australia.<\/p>\n<p>Debido tanto a su significado cultural como al largo per\u00edodo de maduraci\u00f3n del pez esturi\u00f3n, que es de entre ocho y 20 a\u00f1os, el caviar puede alcanzar precios de hasta US$ 27.000 por cucharadita.<\/p>\n<p>Y luego est\u00e1 el codiciado sabor. \u201cSimplemente lo presionas contra tu paladar,\u201d dijo Nichola Fletcher, autora de \u201cCaviar: A Global History\u201d, a CNN, \u201cy los peque\u00f1os huevos se disuelven en una delicia\u201d.<\/p>\n<p>Inspirados por un programa de televisi\u00f3n sobre la cr\u00eda de esturiones en Francia, el tr\u00edo compuesto por Dabezies, su esposo Christophe y su amigo Alexandre Guerrier, decidieron emprender un proyecto similar en su hogar adoptivo de Madagascar, donde ya trabajaban en el comercio textil.<\/p>\n<p>Dabezies dijo que comenzaron \u201csin ning\u00fan conocimiento\u201d de la producci\u00f3n de caviar.<\/p>\n<p>\u201cNadie al principio pens\u00f3 que era posible, y nadie quer\u00eda ayudarnos,\u201d dijo Dabezies. Fue la llegada de un experto retirado en cr\u00eda de esturiones, Francoise Rennes, de vacaciones en Madagascar, lo que les ayud\u00f3 a poner en marcha su proyecto. Y luego, un d\u00eda, mientras conduc\u00edan hacia su casa de fin de semana, vieron el lago.<\/p>\n<p>El lago Mantasoa est\u00e1 situado a una altitud de aproximadamente 1.400 metros en las tierras altas de Madagascar, una zona templada at\u00edpica para los tr\u00f3picos. Result\u00f3 ser \u201cabsolutamente el entorno perfecto para criar el esturi\u00f3n,\u201d dijo Dabezies. A diferencia del hemisferio norte, donde las bajas temperaturas del agua pueden hacer que los peces dejen de crecer, el Lago Mantasoa var\u00eda entre 13 y 23\u00b0C, lo que permite que los peces crezcan durante todo el a\u00f1o. Como resultado, los peces de Dabezies maduran alrededor de dos a\u00f1os m\u00e1s r\u00e1pido.<\/p>\n<p>Pronto, el sue\u00f1o de tres novatos criadores de esturiones se hizo realidad. Hoy, su producci\u00f3n de caviar se realiza tanto en tierra como en estanques lacustres en Madagascar, donde se cr\u00edan seis especies de esturi\u00f3n.<\/p>\n<p>El mundo culinario fue cauteloso cuando Acipenser produjo el primer lote de su caviar premium Rova, nombrado as\u00ed por el hist\u00f3rico Palacio de la Reina de Madagascar en Antananarivo, en 2017. Madagascar es conocido por su vainilla, no por sus huevos de pescado.<\/p>\n<p>\u201cAl principio fue dif\u00edcil,\u201d dijo Dabezies. \u201cTodos se re\u00edan, era una broma. Pero la \u00fanica manera de demostrar que el caviar es excelente es probarlo\u201d.<\/p>\n<p>La oportunidad lleg\u00f3 cuando los mejores chefs de Europa probaron el producto en la prestigiosa exposici\u00f3n culinaria Sirha Lyon en 2019. Desde entonces, el caviar Rova ha aparecido en men\u00fas de alta gama en todo el mundo, incluyendo el H\u00f4tel de Crillon, de cinco estrellas en Par\u00eds, y el H\u00f4tel du Palais en Biarritz.<\/p>\n<p>\u201cAqu\u00ed tenemos un caviar que est\u00e1 lleno de indulgencia,\u201d dijo Julia Sedefjian, quien fue la chef m\u00e1s joven en dirigir una cocina con estrella Michelin en Francia, y quien cre\u00f3 un plato con caviar Rova para La Grande Tabl\u00e9e en Par\u00eds el pasado diciembre, una cena de gala presentada por la organizaci\u00f3n sin fines de lucro La Tabl\u00e9e des Chefs. \u201cUn caviar que podr\u00eda adaptarse a todos los paladares, con un sabor a mantequilla, similar al brioche y un toque final de avellana\u201d.<\/p>\n<p>El caviar tambi\u00e9n ha demostrado ser popular en \u00c1frica; el Hotel Le Saint-Ger\u00e1n en Mauricio, y el Constance Lemuria y Constance Ephelia en las Seychelles lo han servido.<\/p>\n<p>\u201cPara los chefs actuales, tener caviar de Madagascar en el plato es un atractivo\u201d, afirm\u00f3 Dabezies.<\/p>\n<p>El producto m\u00e1s caro de Rova se vende por 11.670 euros (alrededor de US$ 11.960) por kilogramo.<\/p>\n<p>Madagascar es uno de los pa\u00edses m\u00e1s biodiversos del mundo y alberga miles de especies que no se encuentran en ning\u00fan otro lugar. Dabezies, junto con Christophe y Guerrier, ha vivido all\u00ed durante casi 30 a\u00f1os.<\/p>\n<p>\u201cNos ha dado mucho\u201d, dijo, y por eso \u201clo m\u00e1s importante es que el negocio proporcione un beneficio a la gente local y al pa\u00eds\u201d.<\/p>\n<p>Acipenser emplea a alrededor de 300 personas, el 80% de las cuales son del municipio local de Ambatolaona. La empresa ofrece capacitaci\u00f3n en piscicultura y producci\u00f3n de caviar, y brinda cobertura m\u00e9dica, cursos de alfabetizaci\u00f3n y educaci\u00f3n en planificaci\u00f3n familiar.<\/p>\n<p>Recientemente, el Gobierno le otorg\u00f3 un arrendamiento que le permitir\u00e1 reforestar y proteger 200 hect\u00e1reas de colinas alrededor del lago Mantasoa.<\/p>\n<p>Acipenser afirma que est\u00e1 tomando medidas para garantizar la sostenibilidad del lago, incluyendo el repoblamiento para apoyar las pesquer\u00edas locales, la instalaci\u00f3n de un sistema de monitoreo del agua y facilidades para prevenir la contaminaci\u00f3n del agua.<\/p>\n<p>El objetivo final para muchos productores de caviar es producir caviar de Beluga, la forma m\u00e1s cara y lujosa de caviar, hecho del esturi\u00f3n Beluga, la especie que tarda m\u00e1s en madurar y que produce los huevos m\u00e1s grandes.<\/p>\n<p>El a\u00f1o pasado, Acipenser obtuvo su primer pez Beluga en Madagascar. Este a\u00f1o, su objetivo es producir caviar beluga por primera vez.<\/p>\n<p>\u201cMadagascar es un lugar \u00fanico con un potencial incre\u00edble\u201d, dijo Dabezies, \u201cEstamos orgullosos de ser parte de su historia y de compartir sus tesoros con el mundo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando Delphyne Dabezies anunci\u00f3 por primera vez sus planes de lanzar el primer fabricante de caviar de \u00c1frica, algunos en la industria de alimentos de lujo se mostraron incr\u00e9dulos. Sin embargo, ahora, 15 a\u00f1os despu\u00e9s de fundar su empresa, Acipenser, con sus marcas Rova y Kasnodar Caviar, los productos de Dabezies han llegado a algunas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458599","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando Delphyne Dabezies anunci\u00f3 por primera vez sus planes de lanzar el primer fabricante de caviar de \u00c1frica, algunos en la industria de alimentos de lujo se mostraron incr\u00e9dulos. Sin embargo, ahora, 15 a\u00f1os despu\u00e9s de fundar su empresa, Acipenser, con sus marcas Rova y Kasnodar Caviar, los productos de Dabezies han llegado a algunas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo\",\"datePublished\":\"2025-02-12T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\"},\"wordCount\":1088,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\",\"name\":\"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-12T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","og_locale":"es_ES","og_type":"article","og_title":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo - Noticias","og_description":"Cuando Delphyne Dabezies anunci\u00f3 por primera vez sus planes de lanzar el primer fabricante de caviar de \u00c1frica, algunos en la industria de alimentos de lujo se mostraron incr\u00e9dulos. Sin embargo, ahora, 15 a\u00f1os despu\u00e9s de fundar su empresa, Acipenser, con sus marcas Rova y Kasnodar Caviar, los productos de Dabezies han llegado a algunas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","og_site_name":"Noticias","article_published_time":"2025-02-12T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/"},"author":{"name":"","@id":""},"headline":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo","datePublished":"2025-02-12T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/"},"wordCount":1088,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","url":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","name":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-12T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"A m\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \u00c1frica sorprende a la industria de alimentos de lujo","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/primer-caviar-africa-sorprende-us-10000-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-12T00:03:43Z","datePublished":"2025-02-12T00:03:43Z","dateModified":"2025-02-12T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"A m\\u00e1s de US$ 10.000 por kilogramo, el primer caviar de \\u00c1frica sorprende a la industria de alimentos de lujo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/11\\\/primer-caviar-africa-sorprende-us-10000-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/11\\\/primer-caviar-africa-sorprende-us-10000-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-12T00:03:43Z\",\"datePublished\":\"2025-02-12T00:03:43Z\",\"dateModified\":\"2025-02-12T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471100,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/11\/5-cosas-11-de-febrero-orix\/","url_meta":{"origin":1458599,"position":0},"title":"Las 5 cosas que debes saber este 11 de febrero","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Cuba despliega plan para sobrevivir a una de sus peores crisis. Miles de hondure\u00f1os y nicarag\u00fcenses est\u00e1n en riesgo de deportaci\u00f3n tras fallo sobre el TPS. El FBI publica im\u00e1genes de la casa de Nancy Guthrie mientras sigue su b\u00fasqueda. Esto es lo que debes saber para comenzar el d\u00eda.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449449,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/14\/nueva-ruta-tren-de-lujo-vietnam-impresionantes-vistas-costa-y-te-de-la-tarde-trax\/","url_meta":{"origin":1458599,"position":1},"title":"La nueva ruta de tren de lujo en Vietnam ofrece impresionantes vistas de la costa y t\u00e9 de la tarde","author":"","date":"mayo 14, 2024","format":false,"excerpt":"(CNN) -- No hay nada como recostarse en el asiento del tren y ver el horizonte urbano a trav\u00e9s de la ventanilla desvaneci\u00e9ndose en exuberantes paisajes naturales a medida que avanza hacia su pr\u00f3ximo destino.Seg\u00fan los expertos ferroviarios , un n\u00famero cada vez mayor de viajeros de lujo busca experimentar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458620,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/5-cosas-12-febrero-ebrard-aranceles-papa-francisco-golfo-de-america-orix\/","url_meta":{"origin":1458599,"position":2},"title":"Las 5 cosas que debes saber este 12 de febrero: Ebrard sobre aranceles, papa Francisco y &#171;golfo de Am\u00e9rica&#187; en Google Maps","author":"","date":"febrero 12, 2025","format":false,"excerpt":"El papa Francisco critic\u00f3 el programa de deportaciones de inmigrantes. Trump dice que \u201cse desatar\u00e1 el infierno\u201d si Hamas no libera a los rehenes. Noboa alega, sin pruebas, irregularidades en resultados electorales en Ecuador. Sam Altman responde a Elon Musk tras su intento de comprar OpenAI. Esto es lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461512,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/22\/fda-eliminara-colorantes-alimentarios-petroleo-trax\/","url_meta":{"origin":1458599,"position":3},"title":"La FDA eliminar\u00e1 gradualmente los colorantes alimentarios a base de petr\u00f3leo; autorizar\u00e1 cuatro aditivos de color naturales","author":"","date":"abril 22, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s) de EE.UU. planea eliminar gradualmente el uso de colorantes sint\u00e9ticos a base de petr\u00f3leo en el suministro de alimentos del pa\u00eds debido a preocupaciones de salud, anunci\u00f3 este martes el comisionado Dr. Marty Makary.\u201cDurante los \u00faltimos 50 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460812,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/03\/significan-aranceles-trump-para-moda-trax\/","url_meta":{"origin":1458599,"position":4},"title":"As\u00ed pueden impactar los aranceles de Trump a la ropa y la industria de la moda","author":"","date":"abril 3, 2025","format":false,"excerpt":"La industria mundial de la moda qued\u00f3 at\u00f3nita el mi\u00e9rcoles despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, anunciara los aranceles m\u00e1s altos y completos en casi un siglo, con los grav\u00e1menes m\u00e1s severos reservados para algunos de los mayores centros de fabricaci\u00f3n de prendas de vestir.En un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466640,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/20\/aranceles-deportaciones-trump-cambio-climatico-alimentos-trax\/","url_meta":{"origin":1458599,"position":5},"title":"Los aranceles, las deportaciones de Trump y el cambio clim\u00e1tico encarecen los alimentos","author":"","date":"septiembre 20, 2025","format":false,"excerpt":"El presidente Donald Trump se comprometi\u00f3 a reducir los precios de los alimentos. Sin embargo, las pol\u00edticas de su administraci\u00f3n est\u00e1n contribuyendo a una aceleraci\u00f3n de los costes, seg\u00fan economistas y empresas alimentarias. Los comestibles se encarecieron el mes pasado a su ritmo m\u00e1s r\u00e1pido en tres a\u00f1os, impulsados \u200b\u200bpor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1458599"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458599\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1458599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1458599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1458599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}