{"id":1458606,"date":"2025-02-11T17:03:42","date_gmt":"2025-02-12T01:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/"},"modified":"2025-02-11T17:03:42","modified_gmt":"2025-02-12T01:03:42","slug":"panama-costa-rica-mecanismos-atencion-migrantes-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","title":{"rendered":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;"},"content":{"rendered":"<p>El Ministerio de Seguridad P\u00fablica de Panam\u00e1 anunci\u00f3 este martes que las autoridades paname\u00f1as y costarricenses han establecido mecanismos conjuntos para \u201canalizar y optimizar\u201d lo que describieron <a href=\"https:\/\/www.minseg.gob.pa\/2025\/02\/autoridades-de-panama-y-costa-rica-establecen-protocolos-para-el-flujo-migratorio-inverso\/\">como \u201cflujo de retorno inverso de norte a sur\u201d<\/a> de migrantes irregulares.<\/p>\n<p>Frank Alexis \u00c1brego, ministro de Seguridad P\u00fablica de Panam\u00e1, sostuvo una reuni\u00f3n en territorio costarricense con su hom\u00f3logo de Costa Rica, Mario Zamora Cordero, tras la cual, seg\u00fan el comunicado difundido por las autoridades paname\u00f1as, el ministro \u00c1brego indic\u00f3 que se logr\u00f3 \u201cestablecer un protocolo inicial para gestionar el retorno de migrantes irregulares\u201d.<\/p>\n<p>\u201cQueremos garantizar un flujo migratorio ordenado, legal, humanitario y seguro. Esta reuni\u00f3n marca el inicio de una coordinaci\u00f3n que busca asegurar el regreso de los migrantes a sus pa\u00edses de origen en condiciones adecuadas\u201d, agreg\u00f3 Zamora, de acuerdo con el comunicado.<\/p>\n<p>Seg\u00fan la informaci\u00f3n publicada por las autoridades paname\u00f1as, \u201cel retorno de migrantes ha sido lento, pero muestra una tendencia al aumento\u201d y, ante esa situaci\u00f3n, los ministros de ambos pa\u00edses se reunieron con el objetivo de \u201cevitar que (los migrantes) permanezcan en situaci\u00f3n de calle en Costa Rica y Panam\u00e1\u201d.<\/p>\n<p>El acuerdo entre ambos pa\u00edses se produce en coordinaci\u00f3n con el memorando de entendimiento con EE.UU. que Panam\u00e1 <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/07\/01\/panama-estados-unidos-acuerdo-inmigracion-darien-orix\">firm\u00f3 en julio de 2024<\/a> y que fue ampliado durante la visita que el secretario de Estado de EE.UU., Marco Rubio, hiciera a Panam\u00e1 <a href=\"https:\/\/www.minseg.gob.pa\/2025\/02\/panama-y-estados-unidos-ampliaran-memorandum-de-entendimiento-para-repatriacion-y-deportacion-de-migrantes-irregulares\/\">el 2 de febrero.<\/a><\/p>\n<p>Las cifras oficiales m\u00e1s recientes muestran una pronunciada ca\u00edda en la cantidad de migrantes que han ingresado a Panam\u00e1 <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/24\/latinoamerica\/migrantes-indocumentados-panama-disminuyo-orix\" rel=\"noopener noreferrer\" target=\"_blank\">en los primeros d\u00edas de 2025<\/a>. Un comunicado del ministerio de Seguridad P\u00fablica de Panam\u00e1, difundido el 24 de enero, muestra que en los primeros 23 d\u00edas de enero de 2025 el ingreso de migrantes irregulares al pa\u00eds disminuy\u00f3 un 93% <a href=\"https:\/\/www.minseg.gob.pa\/2025\/01\/cierre-de-trochas-en-darien-reduce-el-flujo-migratorio-en-un-93\/\" rel=\"noopener noreferrer\" target=\"_blank\">con respecto al mismo periodo de 2024<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Seguridad P\u00fablica de Panam\u00e1 anunci\u00f3 este martes que las autoridades paname\u00f1as y costarricenses han establecido mecanismos conjuntos para \u201canalizar y optimizar\u201d lo que describieron como \u201cflujo de retorno inverso de norte a sur\u201d de migrantes irregulares. Frank Alexis \u00c1brego, ministro de Seguridad P\u00fablica de Panam\u00e1, sostuvo una reuni\u00f3n en territorio costarricense con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458606","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &quot;su retorno al sur&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &quot;su retorno al sur&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Seguridad P\u00fablica de Panam\u00e1 anunci\u00f3 este martes que las autoridades paname\u00f1as y costarricenses han establecido mecanismos conjuntos para \u201canalizar y optimizar\u201d lo que describieron como \u201cflujo de retorno inverso de norte a sur\u201d de migrantes irregulares. Frank Alexis \u00c1brego, ministro de Seguridad P\u00fablica de Panam\u00e1, sostuvo una reuni\u00f3n en territorio costarricense con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T01:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;\",\"datePublished\":\"2025-02-12T01:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\",\"name\":\"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en \\\"su retorno al sur\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-12T01:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en \"su retorno al sur\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en \"su retorno al sur\" - Noticias","og_description":"El Ministerio de Seguridad P\u00fablica de Panam\u00e1 anunci\u00f3 este martes que las autoridades paname\u00f1as y costarricenses han establecido mecanismos conjuntos para \u201canalizar y optimizar\u201d lo que describieron como \u201cflujo de retorno inverso de norte a sur\u201d de migrantes irregulares. Frank Alexis \u00c1brego, ministro de Seguridad P\u00fablica de Panam\u00e1, sostuvo una reuni\u00f3n en territorio costarricense con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-12T01:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/"},"author":{"name":"","@id":""},"headline":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;","datePublished":"2025-02-12T01:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","name":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en \"su retorno al sur\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-12T01:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-12T01:03:42Z","datePublished":"2025-02-12T01:03:42Z","dateModified":"2025-02-12T01:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Panam\\u00e1 y Costa Rica establecen mecanismos para la atenci\\u00f3n de los migrantes en &#171;su retorno al sur&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/11\\\/panama-costa-rica-mecanismos-atencion-migrantes-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/11\\\/panama-costa-rica-mecanismos-atencion-migrantes-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-12T01:03:42Z\",\"datePublished\":\"2025-02-12T01:03:42Z\",\"dateModified\":\"2025-02-12T01:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459307,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/27\/migrantes-indocumentados-panama-colombia-eeuu-orix\/","url_meta":{"origin":1458606,"position":0},"title":"300 migrantes indocumentados viajar\u00e1n desde Panam\u00e1 hacia Colombia tras desistir de llegar a EE.UU., informa una fuente","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Unos 300 migrantes indocumentados que se encuentran en las costas de Miramar, Col\u00f3n, en el norte de Panam\u00e1, se preparan para regresar a Necocl\u00ed, en el oeste de Colombia, en una traves\u00eda a la inversa de que pretend\u00edan seguir hacia el norte del continente, confirm\u00f3 a CNN una fuente oficial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459459,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","url_meta":{"origin":1458606,"position":1},"title":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Los ministros de Seguridad de Costa Rica y Panam\u00e1 anunciaron este lunes la implementaci\u00f3n de rutas de autobuses como estrategia \u201chumanitaria y regulada\u201d para atender en sus pa\u00edses el regreso de migrantes, ante las pol\u00edticas implementadas por el Gobierno de Estados Unidos.Al inaugurar una aduana en Pe\u00f1as Blancas, Costa Rica,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451043,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/11\/panama-pasos-darien-protesta-colombia-orix\/","url_meta":{"origin":1458606,"position":2},"title":"Panam\u00e1 despliega patrullaje en el mar Caribe y cierra m\u00e1s pasos en el Dari\u00e9n a pesar de protesta de Colombia","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) -- El ministro de Seguridad Publica de Panam\u00e1, Frank \u00c1brego, inform\u00f3 a trav\u00e9s de un comunicado que se cerraron entre cuatro y cinco pasos de la frontera con Colombia en la zona del Dari\u00e9n.\u00c1brego dijo que los sitios que se han cerrado son por donde ingresaban migrantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459169,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/25\/pueblo-panama-advierte-migracion-inversa-orix\/","url_meta":{"origin":1458606,"position":3},"title":"Pueblo Gunayala en Panam\u00e1 advierte de creciente migraci\u00f3n inversa de sudamericanos","author":"","date":"febrero 25, 2025","format":false,"excerpt":"El pueblo Gunayala denunci\u00f3 que la creciente migraci\u00f3n inversa de sudamericanos por la regi\u00f3n de la costa atl\u00e1ntica de Panam\u00e1 podr\u00eda representar un problema para su comunidad debido a la falta de servicios e infraestructura para atender las demandas del paso migratorio.Anelio Merry, vocero del pueblo Gunayala, dijo a CNN\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458935,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/19\/reubican-deportados-eeuu-nyt-migrantes-hotel-panama-orix\/","url_meta":{"origin":1458606,"position":4},"title":"Reubican a deportados de EE.UU. tras reportaje de NYT que mostr\u00f3 la angustia de los migrantes retenidos en un hotel de Panam\u00e1","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Un grupo de 100 migrantes que permanec\u00eda en un hotel de la ciudad de Panam\u00e1 fue trasladado a un centro de detenci\u00f3n, seg\u00fan report\u00f3 The New York Times este mi\u00e9rcoles, al igual que varios medios paname\u00f1os.Periodistas locales publicaron videos que muestran a personas saliendo del hotel y subiendo a autobuses.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461010,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/09\/ministro-seguridad-panama-pais-no-puede-aceptar-base-militar-estadounidense-trax\/","url_meta":{"origin":1458606,"position":5},"title":"El ministro de Seguridad de Panam\u00e1 dice que el pa\u00eds &#171;no puede aceptar&#187; una base militar estadounidense","author":"","date":"abril 9, 2025","format":false,"excerpt":"Mientras que el secretario de Defensa de Estados Unidos, Pete Hegseth, dej\u00f3 la puerta abierta a una mayor presencia militar en Panam\u00e1 con comentarios vagos este mi\u00e9rcoles, Frank Abrego, ministro de Seguridad de Panam\u00e1, dijo que el pa\u00eds no aceptar\u00eda una base militar permanente de EE.UU. y reafirm\u00f3 que Hegseth\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1458606"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458606\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1458606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1458606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1458606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}