{"id":1458630,"date":"2025-02-12T08:03:44","date_gmt":"2025-02-12T16:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/"},"modified":"2025-02-12T08:03:44","modified_gmt":"2025-02-12T16:03:44","slug":"secretario-defensa-ee-uu-descarta-ucrania-otan-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","title":{"rendered":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad"},"content":{"rendered":"<p>El secretario de Defensa de Estados Unidos, Pete Hegseth, dijo este mi\u00e9rcoles que la guerra entre Ucrania y Rusia \u201cdebe terminar\u201d, que la incorporaci\u00f3n de Kyiv a la OTAN no es realista y que Estados Unidos ya no priorizar\u00e1 la seguridad europea y ucraniana, dado que la administraci\u00f3n Trump se enfoca en asegurar las fronteras de Estados Unidos y disuadir la guerra con China.<\/p>\n<p>En declaraciones previas a una reuni\u00f3n del Grupo de Contacto de Defensa de Ucrania, Hegseth tambi\u00e9n dijo que las tropas europeas deber\u00edan ser la fuerza principal para asegurar una Ucrania de posguerra, algo en lo que las tropas estadounidenses no participar\u00e1n, agreg\u00f3.<\/p>\n<p>\u201cEstados Unidos no cree que la membres\u00eda de Ucrania en la OTAN sea un resultado realista de un acuerdo negociado\u201d, dijo Hegseth. Y agreg\u00f3 que cualquier garant\u00eda de seguridad \u201cdebe estar respaldada por tropas europeas y no europeas capaces\u201d. .<\/p>\n<p>\u201cPara ser claros\u201d, agreg\u00f3, \u201ccomo parte de cualquier garant\u00eda de seguridad, no habr\u00e1 tropas estadounidenses desplegadas en Ucrania\u201d.<\/p>\n<p>Hegseth tambi\u00e9n dijo que volver a las fronteras de Ucrania anteriores a 2014 \u201ces un objetivo poco realista\u201d.<\/p>\n<p>Sin duda, los comentarios preocupar\u00e1n al presidente de Ucrania, Volodymyr Zelensky, quien dijo esta semana que Europa por s\u00ed sola no puede proporcionar garant\u00edas de seguridad significativas a Ucrania sin el liderazgo estadounidense.<\/p>\n<p>Hegseth tampoco anunci\u00f3 nueva ayuda estadounidense para Ucrania. \u201cTambi\u00e9n estamos aqu\u00ed hoy para expresar de manera directa e inequ\u00edvoca que la dura realidad estrat\u00e9gica impide que Estados Unidos se centre en la seguridad de Europa\u201d, dijo.<\/p>\n<p>Los comentarios de Hegseth no necesariamente sorprendieron a los aliados de Estados Unidos. La OTAN y la Uni\u00f3n Europea se han estado preparando para que Estados Unidos de un paso atr\u00e1s en el rol que hab\u00eda desempe\u00f1ado desde 2022 en la prestaci\u00f3n y coordinaci\u00f3n de la ayuda militar a Ucrania. Es por eso que la OTAN estableci\u00f3 su propio mecanismo de seguridad para ayudar a coordinar la ayuda militar al pa\u00eds.<\/p>\n<p>\u201cEscuchamos sus preocupaciones sobre la intensificaci\u00f3n de la ayuda a Ucrania, y escuchamos sus preocupaciones sobre la intensificaci\u00f3n de la ayuda a la seguridad europea\u201d, dijo en respuesta el secretario de Defensa del Reino Unido, John Healey.<\/p>\n<p>El secretario general de la OTAN, Mark Rutte, dijo este mi\u00e9rcoles que est\u00e1 de acuerdo con Trump en que se debe equilibrar la ayuda en seguridad que se da a Ucrania, pero a\u00f1adi\u00f3 que para modificar realmente la trayectoria del conflicto, hay a\u00fan m\u00e1s trabajo que hacer.<\/p>\n<p>Sin embargo, los comentarios del secretario de Defensa de Estados Unidos fueron la articulaci\u00f3n m\u00e1s clara hasta ahora de c\u00f3mo la administraci\u00f3n Trump buscar\u00e1 desvincularse de Europa y convertir el conflicto de Ucrania en un problema completamente europeo. Es un cambio radical respecto del enfoque de la administraci\u00f3n Biden, que hizo de la alianza transatl\u00e1ntica y el apoyo a Ucrania la pieza central de su pol\u00edtica exterior.<\/p>\n<p>Hegseth tambi\u00e9n se hizo eco de los llamados del presidente Donald Trump para que los aliados aumenten su gasto de defensa al 5% de su PIB, en lugar del 2%, diciendo que esto \u00faltimo \u201cno es suficiente\u201d.<\/p>\n<p>Hacia el final de su intervenci\u00f3n, Hegseth subray\u00f3 que Estados Unidos \u201csigue comprometido con la alianza de la OTAN y con la asociaci\u00f3n de defensa con Europa. Y punto. Pero Estados Unidos ya no tolerar\u00e1 una relaci\u00f3n desequilibrada que fomente la dependencia\u201d.<\/p>\n<p><em>Esta noticia es de \u00faltimo momento y ser\u00e1 actualizada.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Defensa de Estados Unidos, Pete Hegseth, dijo este mi\u00e9rcoles que la guerra entre Ucrania y Rusia \u201cdebe terminar\u201d, que la incorporaci\u00f3n de Kyiv a la OTAN no es realista y que Estados Unidos ya no priorizar\u00e1 la seguridad europea y ucraniana, dado que la administraci\u00f3n Trump se enfoca en asegurar las fronteras [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458630","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad - Noticias\" \/>\n<meta property=\"og:description\" content=\"El secretario de Defensa de Estados Unidos, Pete Hegseth, dijo este mi\u00e9rcoles que la guerra entre Ucrania y Rusia \u201cdebe terminar\u201d, que la incorporaci\u00f3n de Kyiv a la OTAN no es realista y que Estados Unidos ya no priorizar\u00e1 la seguridad europea y ucraniana, dado que la administraci\u00f3n Trump se enfoca en asegurar las fronteras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-12T16:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad\",\"datePublished\":\"2025-02-12T16:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\",\"name\":\"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-12T16:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad - Noticias","og_description":"El secretario de Defensa de Estados Unidos, Pete Hegseth, dijo este mi\u00e9rcoles que la guerra entre Ucrania y Rusia \u201cdebe terminar\u201d, que la incorporaci\u00f3n de Kyiv a la OTAN no es realista y que Estados Unidos ya no priorizar\u00e1 la seguridad europea y ucraniana, dado que la administraci\u00f3n Trump se enfoca en asegurar las fronteras [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","og_site_name":"Noticias","article_published_time":"2025-02-12T16:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/"},"author":{"name":"","@id":""},"headline":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad","datePublished":"2025-02-12T16:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","url":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","name":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-12T16:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-12T16:03:44Z","datePublished":"2025-02-12T16:03:44Z","dateModified":"2025-02-12T16:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Secretario de Defensa de EE.UU. descarta ingreso de Ucrania a la OTAN y dice que Europa debe ser responsable de la seguridad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/12\\\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/12\\\/secretario-defensa-ee-uu-descarta-ucrania-otan-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-12T16:03:44Z\",\"datePublished\":\"2025-02-12T16:03:44Z\",\"dateModified\":\"2025-02-12T16:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458665,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/12\/aliados-otan-direccion-trump-rusia-trax\/","url_meta":{"origin":1458630,"position":0},"title":"AN\u00c1LISIS | Los aliados de la OTAN buscan direcci\u00f3n mientras el equipo de Trump habla de concesiones con Mosc\u00fa","author":"","date":"febrero 12, 2025","format":false,"excerpt":"La reuni\u00f3n del mi\u00e9rcoles en la sede de la OTAN en Bruselas fue, en la teor\u00eda, sobre la coordinaci\u00f3n de la ayuda militar para Ucrania y la bienvenida al nuevo secretario de Defensa de EE.UU., Pete Hegseth, en el \u00e1mbito internacional. En la pr\u00e1ctica, fue un d\u00eda en que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467387,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/15\/hegseth-ucrania-armas-tomahawks-otan-trax\/","url_meta":{"origin":1458630,"position":1},"title":"Hegseth afirma que Ucrania recibir\u00e1 &#171;potencia de fuego&#187;, pero los misiles Tomahawks no figuran en la agenda de la OTAN","author":"","date":"octubre 15, 2025","format":false,"excerpt":"El secretario de Defensa de Estados Unidos, Pete Hegseth, dijo que Ucrania est\u00e1 recibiendo \u201cpoder de fuego\u201d a trav\u00e9s de las compras de armas estadounidenses por parte de las naciones europeas, pero a\u00fan no est\u00e1 claro si eso incluye misiles Tomahawk de fabricaci\u00f3n estadounidense.\u201cPoder de fuego, eso es lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455273,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/10\/21\/secretario-defensa-austin-llega-ucrania-avances-rusos-elecciones-estadounidenses-inminentes-trax\/","url_meta":{"origin":1458630,"position":2},"title":"El secretario de Defensa, Austin, llega a Ucrania en medio de avances rusos y elecciones estadounidenses inminentes","author":"","date":"octubre 21, 2024","format":false,"excerpt":"(CNN) --El secretario de Defensa, Lloyd Austin, lleg\u00f3 a Kyiv la madrugada de este lunes, mientras el futuro de la ayuda estadounidense a Ucrania pende de un hilo en las inminentes elecciones presidenciales estadounidenses y Rusia sigue logrando avances peque\u00f1os pero constantes en el campo de batalla .Austin se reunir\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458671,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/13\/eeuu-relaciones-europeas-trump-putin-analisis-trax\/","url_meta":{"origin":1458630,"position":3},"title":"AN\u00c1LISIS | Las relaciones de EE.UU. con Europa no volver\u00e1n a ser las mismas tras la llamada de Trump a Putin","author":"","date":"febrero 13, 2025","format":false,"excerpt":"El siglo estadounidense de Europa ha terminado.Este mi\u00e9rcoles, dos truenos geopol\u00edticos transformar\u00e1n las relaciones transatl\u00e1nticas.La llamada de Donald Trump a Vladimir Putin hizo que el l\u00edder ruso saliera del fr\u00edo, ya que urdieron planes para poner fin a la guerra en Ucrania y acordaron intercambiar visitas presidenciales.Por su parte, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458730,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/14\/ee-uu-tropas-ucrania-vance-trax\/","url_meta":{"origin":1458630,"position":4},"title":"EE.UU. podr\u00eda enviar tropas a Ucrania si Rusia no busca la paz con Kyiv, seg\u00fan Vance","author":"","date":"febrero 14, 2025","format":false,"excerpt":"El vicepresidente J.D. Vance advirti\u00f3 el jueves que Estados Unidos podr\u00eda enviar tropas a Ucrania y golpear a Rusia con m\u00e1s sanciones si Vladimir Putin no negocia un acuerdo de paz de buena fe.En declaraciones al Wall Street Journal, Vance afirm\u00f3 que la opci\u00f3n de enviar tropas estadounidenses a Ucrania\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459613,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/07\/europa-seguridad-ucrania-defensa-explicacion-trax\/","url_meta":{"origin":1458630,"position":5},"title":"Europa se apresura a rearmarse mientras Trump amenaza con garant\u00edas de seguridad y se cierne la amenaza rusa. Esto sabemos","author":"","date":"marzo 7, 2025","format":false,"excerpt":"Los l\u00edderes europeos han prometido rearmar el continente en unas hist\u00f3ricas conversaciones de emergencia celebradas despu\u00e9s de que Estados Unidos amenazara con romper 80 a\u00f1os de garant\u00edas de seguridad por la trayectoria de la guerra de Rusia en Ucrania.Desde que asumi\u00f3 el cargo en enero, el presidente de Estados Unidos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1458630"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1458630\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1458630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1458630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1458630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}