{"id":1459298,"date":"2025-02-27T16:03:45","date_gmt":"2025-02-28T00:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/"},"modified":"2025-02-27T16:03:45","modified_gmt":"2025-02-28T00:03:45","slug":"crucero-rescata-refugiados-deriva-cuba-mexico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","title":{"rendered":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico"},"content":{"rendered":"<p>El crucero Brilliance of the Seas rescat\u00f3 a 11 personas a la deriva en el golfo de M\u00e9xico entre Cuba y M\u00e9xico el mi\u00e9rcoles, seg\u00fan VACAYA, una compa\u00f1\u00eda de vacaciones LGBT+ que alquil\u00f3 el barco.<\/p>\n<p>El barco de la l\u00ednea de cruceros Royal Caribbean sali\u00f3 de Nueva Orleans el s\u00e1bado para un crucero de siete noches. El mi\u00e9rcoles, el capit\u00e1n divis\u00f3 un barco a lo lejos \u201cque parec\u00eda estar en peligro\u201d, dijo Randle Roper, el CEO de VACAYA, quien estaba a bordo del barco.<\/p>\n<p>\u201cEl capit\u00e1n me llama de inmediato como el arrendador del barco para informarme que van a dar la vuelta e investigar, y eso fue precisamente lo que hicieron\u201d, relat\u00f3 Roper m\u00e1s tarde en una entrevista grabada compartida con CNN Travel. \u201cEnviaron un barco piloto con miembros de la tripulaci\u00f3n del Brilliance of the Seas hacia el barco varado\u201d.<\/p>\n<p>Roper indic\u00f3 que las 11 personas eran refugiados, pero no sab\u00eda de d\u00f3nde eran.<\/p>\n<p>\u201cSolo puedo imaginar el miedo que deb\u00edan estar sintiendo al estar en el golfo abierto sin otros barcos alrededor\u201d, dijo Roper.<\/p>\n<p>Cuando los refugiados divisaron el barco, Roper dijo que \u201ccomenzaron a agitar esa bandera blanca de socorro\u201d y que los pasajeros de los cruceros alquilados fueron a las cubiertas para presenciar el rescate.<\/p>\n<p>\u201cHab\u00edan determinado desde una distancia que hab\u00eda 10 o m\u00e1s personas\u2026 en el barco. Tambi\u00e9n pod\u00edan ver que claramente estaban en apuros\u201d, dijo Roper. \u201cLos refugiados en el barco estaban literalmente achicando el agua del barco, as\u00ed que su barco claramente se hab\u00eda averiado, y estaban a la deriva en el mar y tomando agua.\u201d<\/p>\n<p>Dijo que m\u00e1s tarde se enteraron de que hab\u00edan estado all\u00ed entre uno y dos d\u00edas.<\/p>\n<p>Entre los pasajeros que vieron el rescate estaba la expresentadora de MTV, Julie Brown, que tuvo una presentaci\u00f3n en el barco. Ella fue grabada en video presenciando y comentando sobre el rescate, se\u00f1alando que las personas fueron trasladadas de tres en tres desde el bote a la deriva y que los que quedaban recibieron chalecos salvavidas.<\/p>\n<p>\u201cCuando ven\u00edan hacia el barco, les salud\u00e9 y todos me saludaron de vuelta, as\u00ed que obviamente est\u00e1n de buen \u00e1nimo tambi\u00e9n\u201d, coment\u00f3 Brown en el video.<\/p>\n<p>En cuanto a la condici\u00f3n de las personas rescatadas una vez a bordo, \u201cEstaban bastante desnutridos y exhaustos. Pero los tenemos aqu\u00ed a salvo y sanos. Les estamos alimentando, d\u00e1ndoles mucha, mucha agua para rehidratar. (\u2026) Est\u00e1n de gran \u00e1nimo\u201d, dijo Roper.<\/p>\n<p>Sobre el futuro inmediato de los refugiados, Roper dijo que la Guardia Costera de EE.UU. estaba involucrada en determinar los pr\u00f3ximos pasos. Dijo que los 11 refugiados desembarcaron en M\u00e9xico el jueves.<\/p>\n<p>CNN Travel se puso en contacto con la Guardia Costera para solicitar comentarios el jueves por la tarde. Royal Caribbean no respondi\u00f3 de inmediato a las solicitudes de comentarios el jueves.<\/p>\n<p>Roper indic\u00f3 que los invitados de VACAYA \u201cactuaron\u2026 donando ropa, proporcionando fondos\u201d.<\/p>\n<p>Roper se\u00f1al\u00f3 la conmovedora intersecci\u00f3n de su grupo de alquiler y las personas rescatadas en el mar.<\/p>\n<p>\u201cDos de los grupos m\u00e1s vulnerables en Estados Unidos en este momento son la comunidad LGBT+ y los refugiados, y el hecho de que seamos nosotros los que, voy a decir, tenemos la suerte de ayudarlos, simplemente se siente muy, muy bien\u201d, dijo Roper.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El crucero Brilliance of the Seas rescat\u00f3 a 11 personas a la deriva en el golfo de M\u00e9xico entre Cuba y M\u00e9xico el mi\u00e9rcoles, seg\u00fan VACAYA, una compa\u00f1\u00eda de vacaciones LGBT+ que alquil\u00f3 el barco. El barco de la l\u00ednea de cruceros Royal Caribbean sali\u00f3 de Nueva Orleans el s\u00e1bado para un crucero de siete [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459298","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"El crucero Brilliance of the Seas rescat\u00f3 a 11 personas a la deriva en el golfo de M\u00e9xico entre Cuba y M\u00e9xico el mi\u00e9rcoles, seg\u00fan VACAYA, una compa\u00f1\u00eda de vacaciones LGBT+ que alquil\u00f3 el barco. El barco de la l\u00ednea de cruceros Royal Caribbean sali\u00f3 de Nueva Orleans el s\u00e1bado para un crucero de siete [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T00:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico\",\"datePublished\":\"2025-02-28T00:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\",\"name\":\"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-28T00:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico - Noticias","og_description":"El crucero Brilliance of the Seas rescat\u00f3 a 11 personas a la deriva en el golfo de M\u00e9xico entre Cuba y M\u00e9xico el mi\u00e9rcoles, seg\u00fan VACAYA, una compa\u00f1\u00eda de vacaciones LGBT+ que alquil\u00f3 el barco. El barco de la l\u00ednea de cruceros Royal Caribbean sali\u00f3 de Nueva Orleans el s\u00e1bado para un crucero de siete [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","og_site_name":"Noticias","article_published_time":"2025-02-28T00:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/"},"author":{"name":"","@id":""},"headline":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico","datePublished":"2025-02-28T00:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","url":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","name":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-28T00:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Crucero rescata a 11 personas a la deriva entre Cuba y M\u00e9xico","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/27\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-28T00:03:45Z","datePublished":"2025-02-28T00:03:45Z","dateModified":"2025-02-28T00:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Crucero rescata a 11 personas a la deriva entre Cuba y M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/27\\\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/27\\\/crucero-rescata-refugiados-deriva-cuba-mexico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-28T00:03:45Z\",\"datePublished\":\"2025-02-28T00:03:45Z\",\"dateModified\":\"2025-02-28T00:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450726,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/26\/incendio-crucero-mas-grande-mundo-trax\/","url_meta":{"origin":1459298,"position":0},"title":"Se produce un incendio en el crucero m\u00e1s grande del mundo","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN) -- La tripulaci\u00f3n a bordo del crucero m\u00e1s grande del mundo, el Icon of the Seas, fue llamada a combatir un incendio esta semana mientras el gigantesco barco estaba atracado en un puerto de M\u00e9xico.El \"peque\u00f1o incendio\" se \"extingui\u00f3 r\u00e1pidamente\" despu\u00e9s de que se desatara este martes, confirm\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447303,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/24\/extinguen-incendio-crucero-carnival-freedom-impacto-rayo-trax\/","url_meta":{"origin":1459298,"position":1},"title":"Extinguen incendio en el crucero Carnival Freedom despu\u00e9s de que testigos informaran sobre el posible impacto de un rayo","author":"","date":"marzo 24, 2024","format":false,"excerpt":"(CNN) -- Heath Barnes abri\u00f3 su libro en las cubiertas superiores del crucero Carnival Freedom con destino a las Bahamas. Llov\u00eda. Pero su relajaci\u00f3n el s\u00e1bado por la tarde se vio interrumpida por \u201clos truenos y rel\u00e1mpagos m\u00e1s fuertes que jam\u00e1s haya escuchado\u201d, le dijo a CNN.Barnes, de Woodsboro, Maryland,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444020,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/17\/cualquier-cosa-puede-suceder-el-reality-show-de-la-vida-real-de-un-crucero-de-nueve-meses\/","url_meta":{"origin":1459298,"position":2},"title":"&#171;Cualquier cosa puede suceder&#187;: el &#171;reality show de la vida real&#187; de un crucero de nueve meses","author":"","date":"enero 17, 2024","format":false,"excerpt":"(CNN) -- Nueve meses. Siete continentes. Cientos de pasajeros en el mar. Millones m\u00e1s sigui\u00e9ndolo en l\u00ednea.Bienvenidos a bordo del Ultimate World Cruise de Royal Caribbean, que zarp\u00f3 hace un mes y ha cautivado inesperadamente la imaginaci\u00f3n de Internet.No, el crucero no es el primero de su clase: los viajes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448761,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/01\/compania-cruceros-norwegian-cruise-linepareja-ochenta-anos-varados-espana-trax\/","url_meta":{"origin":1459298,"position":3},"title":"Compa\u00f1\u00eda de cruceros deja a pareja de pasajeros de ochenta a\u00f1os varados en Espa\u00f1a","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- Un mes despu\u00e9s de que ocho pasajeros de Norwegian Cruise Line quedaran varados en \u00c1frica cuando su barco zarp\u00f3 sin ellos porque tardaban en regresar, una pareja estadounidense \u2014de 84 y 81 a\u00f1os\u2014 tambi\u00e9n fue abandonada por la compa\u00f1\u00eda de cruceros en Espa\u00f1a.Richard y Claudene Gordon, de Salt\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467832,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/29\/mujer-octagenaria-muerta-isla-tropical-australia-crucero-trax\/","url_meta":{"origin":1459298,"position":4},"title":"Mujer octagenaria es hallada muerta en una isla tropical despu\u00e9s de que su crucero zarpara sin ella","author":"","date":"octubre 29, 2025","format":false,"excerpt":"Una pasajera de un crucero, de unos 80 a\u00f1os, que acababa de embarcar en un viaje de lujo de 60 d\u00edas por Australia, fue hallada muerta tras ser olvidada en una isla tropical.La pasajera, cuya identidad no ha sido revelada, fue reportada como desaparecida a las autoridades en la noche\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467835,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/29\/mujer-octogenaria-muerta-isla-tropical-australia-crucero-trax\/","url_meta":{"origin":1459298,"position":5},"title":"Mujer octogenaria es hallada muerta en una isla tropical despu\u00e9s de que su crucero zarpara sin ella","author":"","date":"octubre 29, 2025","format":false,"excerpt":"Una pasajera de un crucero, de unos 80 a\u00f1os, que acababa de embarcar en un viaje de lujo de 60 d\u00edas por Australia, fue hallada muerta tras ser olvidada en una isla tropical.La pasajera, cuya identidad no ha sido revelada, fue reportada como desaparecida a las autoridades en la noche\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1459298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1459298"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1459298\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1459298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1459298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1459298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}