{"id":1459325,"date":"2025-02-28T08:03:40","date_gmt":"2025-02-28T16:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/"},"modified":"2025-02-28T08:03:40","modified_gmt":"2025-02-28T16:03:40","slug":"trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","title":{"rendered":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto"},"content":{"rendered":"<p>El presidente Donald Trump firmar\u00e1 este viernes un decreto para designar al ingl\u00e9s como idioma oficial de Estados Unidos, inform\u00f3 un funcionario de la Casa Blanca.<\/p>\n<p>Es la primera vez en la historia estadounidense que se designa un idioma oficial a nivel nacional. El objetivo es promover la unidad dentro del pa\u00eds, dijeron personas con informaci\u00f3n sobre la orden ejecutiva.<\/p>\n<p>El decreto anular\u00eda un mandato firmado por el expresidente Bill Clinton que obligaba a los organismos a prestar asistencia a las personas que no hablaran ingl\u00e9s, aunque a\u00fan se les permitir\u00eda a dichos organismos ofrecer servicios en otras lenguas.<\/p>\n<p>The Wall Street Journal fue el primero en informar sobre la acci\u00f3n prevista.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump firmar\u00e1 este viernes un decreto para designar al ingl\u00e9s como idioma oficial de Estados Unidos, inform\u00f3 un funcionario de la Casa Blanca. Es la primera vez en la historia estadounidense que se designa un idioma oficial a nivel nacional. El objetivo es promover la unidad dentro del pa\u00eds, dijeron personas con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459325","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump firmar\u00e1 este viernes un decreto para designar al ingl\u00e9s como idioma oficial de Estados Unidos, inform\u00f3 un funcionario de la Casa Blanca. Es la primera vez en la historia estadounidense que se designa un idioma oficial a nivel nacional. El objetivo es promover la unidad dentro del pa\u00eds, dijeron personas con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-28T16:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto\",\"datePublished\":\"2025-02-28T16:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\"},\"wordCount\":149,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\",\"name\":\"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-28T16:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","og_locale":"es_ES","og_type":"article","og_title":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto - Noticias","og_description":"El presidente Donald Trump firmar\u00e1 este viernes un decreto para designar al ingl\u00e9s como idioma oficial de Estados Unidos, inform\u00f3 un funcionario de la Casa Blanca. Es la primera vez en la historia estadounidense que se designa un idioma oficial a nivel nacional. El objetivo es promover la unidad dentro del pa\u00eds, dijeron personas con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","og_site_name":"Noticias","article_published_time":"2025-02-28T16:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/"},"author":{"name":"","@id":""},"headline":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto","datePublished":"2025-02-28T16:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/"},"wordCount":149,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","url":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","name":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-28T16:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump designar\u00e1 al ingl\u00e9s como idioma oficial de Estados Unidos por decreto","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/02\/28\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-28T16:03:40Z","datePublished":"2025-02-28T16:03:40Z","dateModified":"2025-02-28T16:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump designar\\u00e1 al ingl\\u00e9s como idioma oficial de Estados Unidos por decreto\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/28\\\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/02\\\/28\\\/trump-designara-el-ingles-como-idioma-oficial-de-estados-unidos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-28T16:03:40Z\",\"datePublished\":\"2025-02-28T16:03:40Z\",\"dateModified\":\"2025-02-28T16:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459378,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/01\/trump-firma-un-decreto-designando-el-ingles-como-el-idioma-oficial-de-ee-uu\/","url_meta":{"origin":1459325,"position":0},"title":"Trump firma un decreto que designa al ingl\u00e9s como el idioma oficial de EE.UU.","author":"","date":"marzo 1, 2025","format":false,"excerpt":"El presidente Donald Trump firm\u00f3 un decreto este s\u00e1bado designando el ingl\u00e9s como el idioma oficial de Estados Unidos.\u201cUn idioma designado a nivel nacional est\u00e1 en el n\u00facleo de una sociedad unificada y cohesionada, y Estados Unidos se fortalece con una ciudadan\u00eda que puede intercambiar ideas libremente en un idioma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459893,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/13\/ingles-idioma-oficial-eeuu-acceso-millones-inmigrantes-servicios-publicos-orix\/","url_meta":{"origin":1459325,"position":1},"title":"El ingl\u00e9s como idioma oficial de EE.UU.: un obst\u00e1culo para el acceso de millones de inmigrantes a servicios p\u00fablicos","author":"","date":"marzo 13, 2025","format":false,"excerpt":"La declaraci\u00f3n del ingl\u00e9s como el idioma oficial de Estados Unidos por parte del presidente Donald Trump podr\u00eda dificultar el acceso a servicios p\u00fablicos como la salud, la educaci\u00f3n, la justicia o el derecho a votar en un pa\u00eds donde casi 68 millones de personas hablan un idioma distinto en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464506,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/14\/gobierno-recorta-servicios-multilingues-ingles-idioma-oficial-trax\/","url_meta":{"origin":1459325,"position":2},"title":"El Departamento de Justicia ordena al gobierno recortar los servicios multiling\u00fces en EE.UU.","author":"","date":"julio 14, 2025","format":false,"excerpt":"El Departamento de Justicia instruy\u00f3 a todas las agencias federales a reducir la cantidad de servicios multiling\u00fces que ofrecen como parte de la iniciativa de la administraci\u00f3n de Trump para convertir el ingl\u00e9s en el idioma oficial de Estados Unidos.En un memorando, el Departamento de Justicia afirm\u00f3 que la eliminaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464382,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/09\/trump-elogia-buen-ingles-presidente-liberia-trax\/","url_meta":{"origin":1459325,"position":3},"title":"Trump elogia el &#171;buen ingl\u00e9s&#187; del presidente de Liberia, lo que genera cr\u00edticas en toda \u00c1frica","author":"","date":"julio 9, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, elogi\u00f3 el mi\u00e9rcoles al presidente de Liberia, Joseph Boakai, por su gran dominio del idioma ingl\u00e9s. Sin embargo, el l\u00edder africano fue educado en Liberia, donde el ingl\u00e9s es el idioma oficial.Mientras recib\u00eda a cinco l\u00edderes africanos en la Casa Blanca, Trump le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461731,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/28\/trump-firma-decretos-inmigracion-100-dias-gobierno-trax\/","url_meta":{"origin":1459325,"position":4},"title":"Trump firma decretos sobre inmigraci\u00f3n mientras se acerca a los 100 d\u00edas en el cargo","author":"","date":"abril 28, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump firm\u00f3 este lunes un decreto que ordena tomar medidas en\u00e9rgicas contra las \u201cjurisdicciones santuario\u201d, o estados y localidades que limitan la cooperaci\u00f3n con la aplicaci\u00f3n de las leyes federales de inmigraci\u00f3n.El decreto exige la creaci\u00f3n de una lista por parte del Departamento de Justicia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457683,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/20\/puede-trump-renombrar-golfo-mexico-orix\/","url_meta":{"origin":1459325,"position":5},"title":"\u00bfPuede Trump renombrar el golfo de M\u00e9xico como &#171;golfo de Am\u00e9rica&#187;?","author":"","date":"enero 20, 2025","format":false,"excerpt":"Donald Trump insiste en renombrar el golfo de M\u00e9xico, una de las rutas marinas m\u00e1s importantes en la historia del pa\u00eds, a \u201cgolfo de Am\u00e9rica\u201d. Apenas tom\u00f3 posesi\u00f3n, el presidente de Estados Unidos firm\u00f3 un decreto que ordena que se inicie el proceso para realizar el cambio como parte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1459325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1459325"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1459325\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1459325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1459325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1459325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}