{"id":1461683,"date":"2025-04-27T11:03:39","date_gmt":"2025-04-27T18:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/"},"modified":"2025-04-27T11:03:39","modified_gmt":"2025-04-27T18:03:39","slug":"millennials-consejos-generacion-z-primera-recesion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","title":{"rendered":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n"},"content":{"rendered":"<p>Los millennials han pasado por muchas cosas.<\/p>\n<p>Muchos de esta generaci\u00f3n eran j\u00f3venes adultos cuando comenz\u00f3 la Gran Recesi\u00f3n, y hasta el d\u00eda de hoy, luchan por comprar casas y pagar sus deudas estudiantiles. Ahora, estos millennials <a href=\"https:\/\/www.tiktok.com\/@itzettromero\/video\/7490593355634658591\">comparten su sabidur\u00eda con la generaci\u00f3n Z en TikTok<\/a>, donde publican consejos de preparaci\u00f3n y listas de cosas que no deben comprar para tranquilizar a los j\u00f3venes que podr\u00edan estar entrando en su primera gran recesi\u00f3n como adultos.<\/p>\n<p>Los dr\u00e1sticos cambios de pol\u00edtica del presidente Donald Trump han hecho que todos adviertan sobre las graves consecuencias para la econom\u00eda estadounidense, desde el presidente de la Reserva Federal, Jerome Powell, hasta los analistas de Goldman Sachs \u00a1. La escalada de represalias del Gobierno de Trump en la guerra comercial global podr\u00eda conducir a una recesi\u00f3n tanto para Estados Unidos como para el mundo este a\u00f1o, seg\u00fan declar\u00f3 JPMorgan este mes. Esto ocurre en medio de una serie de acontecimientos sin precedentes para los j\u00f3venes: los j\u00f3venes de veintitantos a\u00f1os ganan menos y tienen m\u00e1s deudas, ya que se vieron afectados por la pandemia de covid-19 y una gran inflaci\u00f3n.<\/p>\n<p>Puede que Estados Unidos no est\u00e9 en recesi\u00f3n en este momento, pero sus adultos trabajadores m\u00e1s j\u00f3venes todav\u00eda est\u00e1n ansiosos y buscan el consejo de sus pares mayores.<\/p>\n<p>Al navegar por TikTok, <a href=\"https:\/\/www.tiktok.com\/@thesashawhitney\/video\/7492091839651089695\">Sasha Whitney<\/a>, de 37 a\u00f1os, not\u00f3 que los usuarios de la generaci\u00f3n Z compart\u00edan los mismos sentimientos ante una recesi\u00f3n inminente: \u201cpisoteados, frustrados, muy sombr\u00edos y sin esperanza sobre el futuro\u201d.<\/p>\n<p>Es una marcada diferencia con respecto a cuando Whitney se gradu\u00f3 de la universidad en 2009, durante la Gran Recesi\u00f3n, antes de que las redes sociales se volvieran tan omnipresentes y cuando Barack Obama, quien bas\u00f3 su campa\u00f1a en el concepto de esperanza, acababa de asumir el cargo.<\/p>\n<p>\u201cCuando habl\u00e9 con algunos de mis amigos millennials, me dijeron: \u2018S\u00ed, est\u00e1bamos en la ruina. Lo pas\u00e1bamos mal\u2019\u201d, dijo Whitney, cuya audiencia principal en TikTok tiene entre 18 y 25 a\u00f1os. \u201cSin embargo, no intent\u00e1bamos seguir el ritmo de los dem\u00e1s. No intent\u00e1bamos mostrar un estilo de vida para las redes sociales\u201d.<\/p>\n<p>Otros millennials bromearon en redes sociales sobre el sentido de comunidad que sintieron durante la recesi\u00f3n y recordaron con nostalgia los tiempos de licores m\u00e1s baratos, ropa informal de negocios y <a href=\"https:\/\/www.cnbc.com\/2024\/07\/21\/recession-pop-explained-how-music-collides-with-economic-trends.html\">las interminables repeticiones del pop optimista de la recesi\u00f3n<\/a>. \u201cSi quieres saber c\u00f3mo sobrevivimos, b\u00e1sicamente no \u00e9ramos conscientes\u201d, brome\u00f3 un usuario millennial en <a href=\"https:\/\/www.tiktok.com\/@thisvvitch\/video\/7489600067918155051\">TikTok<\/a>.<\/p>\n<p>Pero los millennials s\u00ed compartieron sus verdaderas dificultades financieras. Tras graduarse, Whitney vivi\u00f3 un tiempo en casa, luego se mud\u00f3, pag\u00f3 el alquiler y los pr\u00e9stamos estudiantiles, y dejaba US$ 20 semanales para la compra. Trabaj\u00f3 en un comercio minorista inmediatamente despu\u00e9s de la universidad y aprendi\u00f3 a administrar sus finanzas a base de ensayo y error.<\/p>\n<p>\u201cEstaba comprando paquetes de at\u00fan, verduras congeladas, pan y guard\u00e1ndolos en el congelador. Ah\u00ed fue cuando me di cuenta de que algo estaba pasando\u201d, dijo.<\/p>\n<p><a href=\"https:\/\/www.tiktok.com\/@thesashawhitney\/video\/7492091839651089695\">El video de TikTok<\/a> de Whitney ofreci\u00f3 a los espectadores algunos consejos para afrontar la recesi\u00f3n, como aceptar cualquier trabajo posible, vivir por debajo de sus posibilidades y eliminar plataformas de pago como Klarna y After Pay. Otros videos de millennials en TikTok ofrecen gu\u00edas de preparaci\u00f3n para la recesi\u00f3n, como tener un fondo de ahorro para emergencias y curr\u00edculums actualizados.<\/p>\n<p>\u201cSi puedo darle un consejo a alguien, especialmente a los m\u00e1s j\u00f3venes, eso es lo que har\u00e9\u201d, dijo Whitney.<\/p>\n<p>Muchos TikTokers se comprometen a hacer una cosa: limitar sus gastos.<\/p>\n<p>Para Imani Smith, una joven de 29 a\u00f1os de Dallas, <a href=\"https:\/\/www.tiktok.com\/@theimaniexchange\/video\/7490617789779070250?_r=1&#038;_t=ZP-8vkX0CK5pXz\">eso significa<\/a> compartir contrase\u00f1as de suscripciones con sus amigos y reducir las salidas a comer.<em><\/em><a href=\"https:\/\/www.tiktok.com\/@theimaniexchange\/video\/7490617789779070250?_r=1&#038;_t=ZP-8vkX0CK5pXz\"><\/a><\/p>\n<p>El cuidado de la belleza tambi\u00e9n es caro, as\u00ed que compra u\u00f1as postizas en Amazon en lugar de ir a la peluquer\u00eda. Los due\u00f1os de salones de belleza reportan m\u00e1s pedidos de tintura de pelo \u201d<a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2025-04-11\/recession-indicator-us-hairstylists-report-clients-cut-spending?srnd=all\">rubio recesi\u00f3n<\/a>\u201c, peinados m\u00e1s econ\u00f3micos y de menor mantenimiento.<\/p>\n<p>Y a pesar del famoso \u00edndice del l\u00e1piz labial (la teor\u00eda de que las compras de peque\u00f1os caprichos aumentan durante las crisis econ\u00f3micas), los usuarios de las redes sociales han prometido eliminar las compras peque\u00f1as como b\u00e1lsamos labiales y velas costosas.<\/p>\n<p>\u201cQuiero ahorrar y acostumbrarme a hacerlo antes de tener que hacerlo por necesidad b\u00e1sica\u201d, declar\u00f3 a CNN Smith, quien se describi\u00f3 como una persona a medio camino entre la generaci\u00f3n Z y la generaci\u00f3n millennial. A\u00f1adi\u00f3 que usa TikTok, como muchos j\u00f3venes, como motor de b\u00fasqueda. En un video en TikTok, pregunt\u00f3 a los espectadores adultos en 2008 si su plan para la recesi\u00f3n era suficiente.<\/p>\n<p>Cuando las personas perciben que sus presupuestos se reducen, tienen que decidir en qu\u00e9 van a gastar, declar\u00f3 a CNN Simon Blanchard, profesor de la Escuela de Negocios McDonough de la Universidad de Georgetown. A\u00f1adi\u00f3 que podr\u00eda ser un buen momento para reflexionar sobre si se tienen suficientes ahorros para emergencias, independientemente de si estamos en recesi\u00f3n o no.<\/p>\n<p>Las personas tienden a recortar una categor\u00eda entera de gastos en lugar de un poco de todo, por lo que no parece que tengan que recortar en todos los aspectos de su vida, dijo Blanchard.<\/p>\n<p>\u201cY tal vez esos peque\u00f1os caprichos, como el l\u00e1piz labial, sean los primeros en desaparecer porque simplemente no son esenciales\u201d, dijo Blanchard.<\/p>\n<p>A pesar de los consejos de los millennials de dejarse llevar y vivir, <a href=\"https:\/\/time.com\/7276586\/recession-pop-benefits-essay\/\">como alentaba toda la gran m\u00fasica de mediados de la d\u00e9cada de 2000<\/a>  la ansiedad a\u00fan persiste entre muchos j\u00f3venes.<\/p>\n<p>Despu\u00e9s de hablar con personas que vivieron la crisis del 2008, Smith dijo que \u201cpodr\u00edan haber perdido sus trabajos, pero el costo de vida era tan bajo en ese entonces que podr\u00edan haber comprado algo en tiendas minoristas y haberse mantenido a flote por un tiempo\u201d, enfatizando sus preocupaciones por el mercado laboral en este momento.<\/p>\n<p>Para muchos j\u00f3venes, la ansiedad se remonta a la pandemia de covid-19. Smith acababa de empezar su primer trabajo corporativo cuando lleg\u00f3 la pandemia, que desencaden\u00f3 la recesi\u00f3n m\u00e1s corta de la historia de Estados Unidos y termin\u00f3 tras dos meses en abril de 2020.<\/p>\n<p>\u201cMe hizo pensar que debo estar preparada para cualquier cosa\u201d, dijo Smith. \u201cPorque nadie podr\u00eda haber previsto la covid-19 y sus efectos a largo plazo\u201d.<\/p>\n<p><em>Lacey Russell de CNN contribuy\u00f3 a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los millennials han pasado por muchas cosas. Muchos de esta generaci\u00f3n eran j\u00f3venes adultos cuando comenz\u00f3 la Gran Recesi\u00f3n, y hasta el d\u00eda de hoy, luchan por comprar casas y pagar sus deudas estudiantiles. Ahora, estos millennials comparten su sabidur\u00eda con la generaci\u00f3n Z en TikTok, donde publican consejos de preparaci\u00f3n y listas de cosas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461683","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los millennials han pasado por muchas cosas. Muchos de esta generaci\u00f3n eran j\u00f3venes adultos cuando comenz\u00f3 la Gran Recesi\u00f3n, y hasta el d\u00eda de hoy, luchan por comprar casas y pagar sus deudas estudiantiles. Ahora, estos millennials comparten su sabidur\u00eda con la generaci\u00f3n Z en TikTok, donde publican consejos de preparaci\u00f3n y listas de cosas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-27T18:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n\",\"datePublished\":\"2025-04-27T18:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\"},\"wordCount\":1151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\",\"name\":\"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-27T18:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n - Noticias","og_description":"Los millennials han pasado por muchas cosas. Muchos de esta generaci\u00f3n eran j\u00f3venes adultos cuando comenz\u00f3 la Gran Recesi\u00f3n, y hasta el d\u00eda de hoy, luchan por comprar casas y pagar sus deudas estudiantiles. Ahora, estos millennials comparten su sabidur\u00eda con la generaci\u00f3n Z en TikTok, donde publican consejos de preparaci\u00f3n y listas de cosas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-27T18:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/"},"author":{"name":"","@id":""},"headline":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n","datePublished":"2025-04-27T18:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/"},"wordCount":1151,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","name":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-27T18:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los millennials dan consejos a la generaci\u00f3n Z para su primera posible recesi\u00f3n","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/millennials-consejos-generacion-z-primera-recesion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-27T18:03:39Z","datePublished":"2025-04-27T18:03:39Z","dateModified":"2025-04-27T18:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los millennials dan consejos a la generaci\\u00f3n Z para su primera posible recesi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/27\\\/millennials-consejos-generacion-z-primera-recesion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/27\\\/millennials-consejos-generacion-z-primera-recesion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-27T18:03:39Z\",\"datePublished\":\"2025-04-27T18:03:39Z\",\"dateModified\":\"2025-04-27T18:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447939,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/10\/analisis-generacion-z-angustia-financiera-trax\/","url_meta":{"origin":1461683,"position":0},"title":"AN\u00c1LISIS | \u201cNo puedo costearme la vida\u201d: la generaci\u00f3n Z sufre de angustia financiera a pesar de heredar un mercado laboral pr\u00f3spero","author":"","date":"abril 10, 2024","format":false,"excerpt":"Nueva York (CNN) -- La generaci\u00f3n Z est\u00e1 entrando en el mercado laboral y, en una de las grandes tradiciones de lo que los millennials llamaban con verg\u00fcenza \"hacerse adulto\", se est\u00e1n quejando de lo mucho m\u00e1s f\u00e1cil que era para las generaciones anteriores.Antes de que todos los \"boomers\" y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459738,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/10\/dow-850-puntos-trump-recesion-trax\/","url_meta":{"origin":1461683,"position":1},"title":"El Dow cae 850 puntos tras el anuncio de Trump de no descartar una recesi\u00f3n","author":"","date":"marzo 10, 2025","format":false,"excerpt":"La huida de Wall Street continu\u00f3 el lunes por la tarde, cuando las acciones estadounidenses se desplomaron y el Dow cay\u00f3 m\u00e1s de 850 puntos, retrocediendo desde un m\u00ednimo de 1.100 puntos que alcanz\u00f3 por la tarde.La venta generalizada se debi\u00f3 principalmente a la preocupaci\u00f3n por el impacto de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460212,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/20\/analisis-funcionarios-trump-justifican-recesion-resentiran-trax\/","url_meta":{"origin":1461683,"position":2},"title":"Los funcionarios de Trump justifican la amenaza de una recesi\u00f3n, pero ellos tambi\u00e9n lo resentir\u00e1n","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Se intensifica la conversaci\u00f3n sobre una recesi\u00f3n en Estados Unidos con un giro sorprendente del Gobierno de Trump, que sugiere que los estadounidenses podr\u00edan tener que soportar algo de dolor.Los inversionistas est\u00e1n asimilando la realidad de la pol\u00edtica arancelaria del presidente Donald Trump. El crecimiento del empleo parece inestable. La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468535,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/20\/shows-tv-relanzados-buffy-scrubs-malcolm-orix\/","url_meta":{"origin":1461683,"position":3},"title":"De &#171;Buffy&#187; a &#171;Malcolm in the Middle&#187;: todos los lanzamientos de shows cl\u00e1sicos de la TV","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Pese a su juventud, los millennials tambi\u00e9n sienten nostalgia. Esa generaci\u00f3n nacida entre 1981 y 2000 tiene a\u00f1oranza por series y pel\u00edculas que vieron de peque\u00f1os, juguetes e incluso tiendas que ya no existen.Quiz\u00e1s esa nostalgia por las series de TV que eran populares al inicio del siglo XXI explique\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469456,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/20\/turning-point-jovenes-conservadores-expresan-preocupacion-trax\/","url_meta":{"origin":1461683,"position":4},"title":"En la reuni\u00f3n anual de Turning Point, j\u00f3venes conservadores expresan preocupaci\u00f3n por el futuro","author":"","date":"diciembre 20, 2025","format":false,"excerpt":"A sus 23 a\u00f1os, Caleb Gasca ya ha cumplido varios de los hitos tradicionales de la adultez. Se gradu\u00f3 de la universidad, consigui\u00f3 trabajo en una oficina de construcci\u00f3n y se cas\u00f3.No obstante, al vivir con los padres de su esposa en el Condado de San Bernardino, California, todav\u00eda siente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460914,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/07\/trump-peor-comienzo-mercado-valores-bolsa-trax\/","url_meta":{"origin":1461683,"position":5},"title":"El de Trump es el peor comienzo de un mandato presidencial en la historia moderna en cuanto al mercado de valores","author":"","date":"abril 7, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, advirti\u00f3 a los estadounidenses en 2024 que votar por la vicepresidenta Kamala Harris equivaldr\u00eda a votar por un colapso del mercado.\u201c\u00bfQuieren ver un desplome del mercado? Si perdi\u00e9ramos estas elecciones, creo que el mercado se ir\u00eda a pique\u201d, dijo Trump en un mitin en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1461683"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461683\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1461683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1461683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1461683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}