{"id":1461695,"date":"2025-04-27T21:03:40","date_gmt":"2025-04-28T04:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/"},"modified":"2025-04-27T21:03:40","modified_gmt":"2025-04-28T04:03:40","slug":"ron-casey-desantis-florida-escandalo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","title":{"rendered":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo"},"content":{"rendered":"<p>Un a\u00f1o despu\u00e9s del fracaso de sus ambiciones presidenciales, el gobernador Ron DeSantis y su esposa Casey ya no pueden atribuirse el futuro del Partido Republicano. Y en Florida, incluso su presente est\u00e1 en peligro.<\/p>\n<p>Antes firmemente a su lado, muchos republicanos del estado del Sol se han vuelto contra DeSantis \u00faltimamente, obstaculizando su agenda y frustr\u00e1ndolo enormemente. Al mismo tiempo, Casey DeSantis, considerada desde hace tiempo una fuerza pol\u00edtica por derecho propio, se enfrenta a una resistencia silenciosa pero firme mientras sienta las bases para una posible candidatura para suceder a su esposo, una campa\u00f1a que la enfrentar\u00eda al representante Byron Donalds, elegido personalmente por el presidente Donald Trump para dirigir el estado.<\/p>\n<p>Ahora, un esc\u00e1ndalo de financiaci\u00f3n que involucra una de las iniciativas emblem\u00e1ticas de Casey \u2014un programa de asistencia estatal conocido como Hope Florida\u2014 ensombrece el legado de gobernador y complica sus ambiciones pol\u00edticas. Los legisladores dedicaron la primavera a investigar por qu\u00e9 US$ 10 millones de un acuerdo estatal con Medicaid se desviaron a una organizaci\u00f3n ben\u00e9fica vinculada a Hope Florida, que a su vez transfiri\u00f3 la misma cantidad a dos grupos que financiaron una campa\u00f1a liderada por DeSantis contra la legalizaci\u00f3n de la marihuana recreativa. Legisladores destacados han sugerido p\u00fablicamente que el flujo de dinero <a href=\"https:\/\/x.com\/RAlexAndradeFL\/status\/1915496318308585855\">parece<\/a> <a href=\"https:\/\/www.tampabay.com\/news\/florida-politics\/2025\/04\/09\/hope-florida-desantis-casey-centene-settlement-donation\/\">ilegal<\/a>.<\/p>\n<p>La pareja ha defendido firmemente su labor y ha negado cualquier irregularidad. Esta semana, DeSantis calific\u00f3 las cr\u00edticas a Hope Florida de \u201cnetamente pol\u00edticas\u201d. Junto a su esposo el jueves, Casey DeSantis calific\u00f3 el programa como \u201cuna filosof\u00eda\u201d que \u201cdemuestra que podemos ayudar a quienes lo necesitan\u201d.<\/p>\n<p>Sorprendentemente, la investigaci\u00f3n sobre Hope Florida no fue realizada por dem\u00f3cratas, sino por republicanos, una clara se\u00f1al de la p\u00e9rdida de influencia de DeSantis en una capital estatal que antes controlaba con autoridad indiscutible. Fuera de Tallahassee, algunos de los aliados m\u00e1s ac\u00e9rrimos de Trump en Florida han contribuido a amplificar la controversia entre sus seguidores del movimiento MAGA.<\/p>\n<p>En medio de las consecuencias, los DeSantis se han visto cada vez m\u00e1s aislados. Donantes, recaudadores de fondos y agentes abandonan su c\u00edrculo, y por el momento, pocos en la pol\u00edtica floridana parecen dispuestos a unirse a otra campa\u00f1a con la pareja. Varias personas han rechazado candidaturas a gobernador, seg\u00fan dos fuentes que mantienen contacto con el equipo restante del gobernador.<\/p>\n<p>\u201c\u00daltimamente, no distingo entre ser su amigo y su enemigo\u201d, declar\u00f3 a CNN un veterano agente republicano, que en su momento fue cercano al gobernador.<\/p>\n<p>Incluso entre sus aliados restantes, crece la sensaci\u00f3n de que Casey no deber\u00eda anunciar su candidatura hasta que se disipe la incertidumbre que pesa sobre la pareja, aunque pocos est\u00e1n dispuestos a compartir esa opini\u00f3n directamente con ellos. A principios de este a\u00f1o, Ryan Tyson, el encuestador de la campa\u00f1a presidencial de DeSantis, ofreci\u00f3 a la pareja una evaluaci\u00f3n contundente de los obst\u00e1culos que Casey enfrentar\u00eda al intentar extender su dinast\u00eda pol\u00edtica, seg\u00fan una de las fuentes.<\/p>\n<p>\u201cNo fue bien recibido\u201d, dijo la fuente, \u201cy nadie ha intentado aconsejarlos desde entonces\u201d.<\/p>\n<p>Mientras preparan su defensa p\u00fablica, la pareja tambi\u00e9n participa en una intensa campa\u00f1a de cabildeo en privado para minimizar la participaci\u00f3n de Trump en las primarias republicanas de Florida. Casey acompa\u00f1\u00f3 a Trump a jugar al golf y DeSantis fue visto recientemente jugando con el hijo del presidente, Eric, en el Trump National Doral Miami. Tambi\u00e9n cenaron recientemente con Trump.<\/p>\n<p>Pero poco despu\u00e9s de estos encuentros, Donalds acompa\u00f1\u00f3 a Trump a un evento de la UFC en Florida, una aparici\u00f3n conjunta que indic\u00f3 a muchos que las propuestas de Ron y Casey hab\u00edan sido insuficientes.<\/p>\n<p>Visiblemente exasperado, DeSantis, al ver c\u00f3mo sus aliados de Tallahassee se distanciaban de \u00e9l y de sus prioridades legislativas, pregunt\u00f3 recientemente en voz alta durante una <a href=\"https:\/\/www.youtube.com\/watch?v=Llp_Lk_5ywc\">conferencia de prensa<\/a>: \u201c\u00bfPor qu\u00e9 rayos hacen esto?\u201d.<\/p>\n<p>Casey DeSantis lanz\u00f3 Hope Florida en 2021 con la misi\u00f3n de desvincular a las personas de la asistencia gubernamental conect\u00e1ndolas con organizaciones religiosas y otras organizaciones ben\u00e9ficas en sus comunidades. R\u00e1pidamente se convirti\u00f3 en su proyecto insignia a medida que se hac\u00eda conocido, distribuyendo regularmente cheques novedosos con el sello estatal y su firma. Con el tiempo, Casey y Ron DeSantis promocionar\u00edan el programa en otros estados durante su campa\u00f1a presidencial como un doble golpe en 2023.<\/p>\n<p>Por aquella \u00e9poca, el Departamento de Ni\u00f1os y Familias de Florida cre\u00f3 la Fundaci\u00f3n Hope Florida, una entidad independiente sin fines de lucro encargada de impulsar el programa estatal. En su primer a\u00f1o, la fundaci\u00f3n recaud\u00f3 alrededor de US$ 800.000 en donaciones y otorg\u00f3 solo US$ 40.000 en asistencia financiera, seg\u00fan una declaraci\u00f3n de impuestos publicada recientemente.<\/p>\n<p>El a\u00f1o pasado, la fundaci\u00f3n vio crecer sus arcas con US$ 10 millones. En aquel momento, pocos se percataron. Pero una comisi\u00f3n de la C\u00e1mara de Representantes de Florida que investigaba a la organizaci\u00f3n descubri\u00f3 la fuente de esta ganancia inesperada: un acuerdo estatal con Centene, un contratista de Medicaid que hab\u00eda facturado de m\u00e1s a Florida y otros estados. El acuerdo con Centene inclu\u00eda una cl\u00e1usula inusual que obligaba a la empresa a donar US$ 10 millones a la Fundaci\u00f3n Hope Florida.<\/p>\n<p>A los pocos d\u00edas de la donaci\u00f3n, la fundaci\u00f3n otorg\u00f3 dos subvenciones de US$ 5 millones a dos grupos pol\u00edticos, seg\u00fan documentos publicados inicialmente por el <a href=\"https:\/\/www.tampabay.com\/news\/florida-politics\/2025\/04\/11\/desantis-charity-hope-florida-casey-uthmeier-legislature\/\">Tampa Bay Times y el Miami Herald<\/a> y proporcionados a CNN por el abogado de la fundaci\u00f3n, Jeff Aaron. Ambas organizaciones luego enviaron US$ 8,5 millones a Keep Florida Clean, un comit\u00e9 que lider\u00f3 la exitosa lucha en noviembre pasado contra una medida electoral que habr\u00eda enmendado la constituci\u00f3n estatal para legalizar la marihuana recreativa.<\/p>\n<p>Keep Florida Clean estaba dirigido por James Uthmeier, entonces jefe de gabinete del gobernador, a quien DeSantis posteriormente nombr\u00f3 fiscal general de Florida.<br \/>Uthmeier ha negado cualquier irregularidad.<\/p>\n<p>Tras las elecciones, los <a href=\"https:\/\/floridafreedomfund.com\/wp-content\/uploads\/2025\/04\/Contributions-FFF-1.pdf\">registros de financiaci\u00f3n<\/a> de campa\u00f1as muestran que Keep Florida Clean transfiri\u00f3 US$ 1,2 millones al Fondo de Libertad de Florida, un comit\u00e9 pol\u00edtico controlado por el gobernador. Este comit\u00e9 podr\u00eda, en \u00faltima instancia, utilizarse para apoyar las ambiciones pol\u00edticas de Casey DeSantis. Un portavoz de las operaciones pol\u00edticas del gobernador no respondi\u00f3 a una solicitud de comentarios.<\/p>\n<p>El representante estatal Alex Andrade, republicano que dirigi\u00f3 la investigaci\u00f3n de la C\u00e1mara de Representantes, declar\u00f3 a CNN que el rastro del dinero \u201cme parece muy similar a un fraude electr\u00f3nico y al blanqueo de capitales\u201d. El jueves anunci\u00f3 que su comisi\u00f3n hab\u00eda concluido su trabajo, pero ha instado p\u00fablicamente a las fuerzas del orden a revisar las conclusiones de la comisi\u00f3n.<\/p>\n<p>\u201cEspero que @PamBondi est\u00e9 prestando atenci\u00f3n\u201d, escribi\u00f3 Andrade en X, etiquetando a la secretaria de Justicia de Trump y al ex fiscal principal de Florida. La oficina de Bondi declin\u00f3 hacer comentarios.<\/p>\n<p>DeSantis <a href=\"https:\/\/www.tampabay.com\/news\/florida-politics\/2025\/04\/10\/desantis-hope-florida-charity-medicaid-settlement-casey-donation\/\">sostuvo<\/a> en una comparecencia a principios de este mes que los US$ 10 millones eran independientes del acuerdo estatal y \u201cuna especie de guinda del pastel, donde acordaron hacer una contribuci\u00f3n adicional\u201d. Bryan Griffin, portavoz del gobernador, argument\u00f3 que ni Ron ni Casey DeSantis desempe\u00f1an ning\u00fan papel en la Fundaci\u00f3n Hope Florida y afirm\u00f3 que el programa estatal \u201cha tenido un gran \u00e9xito y ha ayudado a 30.000 floridanos a reducir o eliminar su dependencia de la asistencia p\u00fablica\u201d.<\/p>\n<p>Otros elementos de Hope Florida ilustran la cercan\u00eda entre la \u00f3rbita pol\u00edtica del gobernador y la principal prioridad de su esposa.<\/p>\n<p>El presidente de la Fundaci\u00f3n Hope Florida es Joshua Hay, CEO de Indelible Solutions, una empresa a la que el estado ha pagado decenas de millones de d\u00f3lares desde que se uni\u00f3 a la organizaci\u00f3n ben\u00e9fica, seg\u00fan informaron el Times and Herald. Su empresa don\u00f3 US$ 125.000 a la reelecci\u00f3n de DeSantis en 2022. Tina Vidal-Duart, miembro de la junta directiva de la fundaci\u00f3n, es vicepresidenta ejecutiva de CDR Enterprises, una consultora que don\u00f3 US$ 1 mill\u00f3n a un Super PAC que apoy\u00f3 la campa\u00f1a presidencial de DeSantis. Su esposo, Carlos Vidal, es el presidente y CEO de la empresa.<\/p>\n<p>Varios de los principales donantes de la fundaci\u00f3n tambi\u00e9n contribuyeron al comit\u00e9 pol\u00edtico de DeSantis, incluyendo a Centene, seg\u00fan documentos fiscales y registros de financiaci\u00f3n de campa\u00f1as.<\/p>\n<p>Y luego est\u00e1 Unite Us, una empresa de tecnolog\u00eda sanitaria contratada para crear el portal web que conecta a las personas necesitadas con los servicios locales.<br \/>Unite Us cont\u00f3 con un destacado equipo de cabilderos, entre ellos Dane Eagle, exsecretario del Departamento de Oportunidades Econ\u00f3micas de Florida de DeSantis; su ex jefe de gabinete, Adrian Lukis; y la ex jefa de gabinete adjunta, Courtney Coppola. Nueve d\u00edas despu\u00e9s de que el estado firmara el contrato con Unite US, la campa\u00f1a presidencial de DeSantis anunci\u00f3 que Coppola y Eagle formar\u00edan parte de su comit\u00e9 nacional de finanzas.<\/p>\n<p>El estado otorg\u00f3 el contrato de US$ 3,9 millones a Unite Us a pesar de su historial de apoyo a iniciativas que chocaban con la represi\u00f3n de DeSantis contra las prioridades progresistas, como la promoci\u00f3n de los derechos de las personas transg\u00e9nero y las iniciativas de diversidad, equidad e inclusi\u00f3n. La postura de la empresa tecnol\u00f3gica sobre estos temas podr\u00eda proporcionar a los rivales republicanos otra l\u00ednea de ataque contra Casey DeSantis, vinculado a Hope Florida.<\/p>\n<p>Anteriormente, Unite Us hab\u00eda presumido p\u00fablicamente <a href=\"https:\/\/web.archive.org\/web\/20220607132415\/https:\/\/uniteus.com\/dei\/\">en su sitio web<\/a> de su compromiso con la diversidad en la contrataci\u00f3n, ba\u00f1os neutrales en sus oficinas de Nueva York y Los \u00c1ngeles y el uso de pronombres de g\u00e9nero en sus comunicaciones internas.<br \/>D\u00edas despu\u00e9s de que Casey DeSantis recorriera Iowa en junio de 2023 luciendo una chaqueta de cuero hecha a medida bordada con el lema \u201cWhere Woke Goes to Die\u201d, Unite Us anunci\u00f3 un premio a la cultura laboral, destacando sus esfuerzos en DEI y que la mayor\u00eda de su personal estaba compuesto por mujeres, personas no binarias y pertenecientes a minor\u00edas.<\/p>\n<p>\u201cEn muchas organizaciones, \u2018diversidad\u2019, \u2018equidad\u2019 e \u2018inclusi\u00f3n\u2019 son solo palabras de moda\u201d, dec\u00eda una cita en la p\u00e1gina web archivada de Unite Us. \u201cPero en Unite Us, la diversidad, la equidad y la inclusi\u00f3n son fundamentales para nuestra misi\u00f3n\u201d. La p\u00e1gina web parece no estar en funcionamiento.<\/p>\n<p>La oficina del gobernador declar\u00f3 que no tuvo participaci\u00f3n en la adjudicaci\u00f3n del contrato de Unite Us. Miguel Nevarez, portavoz del Departamento de Ni\u00f1os y Familias de Florida, afirm\u00f3 que un equipo de negociadores del contrato seleccion\u00f3 a Unite Us por unanimidad.<\/p>\n<p>Nevarez tambi\u00e9n se\u00f1al\u00f3 que el DCF tiene disposiciones en sus contratos que restringen el uso de fondos estatales para promover, defender o brindar capacitaci\u00f3n o educaci\u00f3n sobre diversidad, equidad e inclusi\u00f3n. El contrato con Unite Us especificaba que el portal no pod\u00eda incluir categor\u00edas o subcategor\u00edas relacionadas con la diversidad, la equidad o la inclusi\u00f3n.<\/p>\n<p>Aliados cercanos de Trump observan con regocijo el desarrollo del esc\u00e1ndalo de financiaci\u00f3n. Roger Stone, asesor pol\u00edtico de Trump desde hace mucho tiempo, analiz\u00f3 recientemente el esc\u00e1ndalo en su podcast con la ayuda del l\u00edder del Partido Dem\u00f3crata de Florida. Laura Loomer, una aliada muy fiel de Trump y una asidua critica de DeSantis, ampli\u00f3 los acontecimientos desde Tallahassee a sus 1,6 millones de seguidores en X.<\/p>\n<p>El exrepresentante de Florida Matt Gaetz, quien mantiene una estrecha relaci\u00f3n con Trump y est\u00e1 considerando su propia candidatura a gobernador, tambi\u00e9n aprovech\u00f3 la controversia a trav\u00e9s de su programa One America News.<\/p>\n<p>DeSantis ha respondido con sus caracter\u00edsticos contraataques agresivos y ha acusado a los legisladores republicanos de intentar difamar a su esposa para obtener r\u00e9dito pol\u00edtico. Tambi\u00e9n ha buscado recaudar fondos a partir de la controversia, pidiendo a los donantes que env\u00eden dinero a su comit\u00e9 pol\u00edtico para luchar contra los republicanos \u201cblandos\u201d de la C\u00e1mara de Representantes, seg\u00fan un correo electr\u00f3nico obtenido por CNN.<\/p>\n<p>\u201cAlgunas personas se sienten amenazadas por la primera dama. Seamos claros al respecto \u2014dijo DeSantis en una conferencia de prensa a principios de este mes\u2014. Si piensas en 2026 y tienes un caballo, no la quieres ni cerca. Est\u00e1s muy preocupado porque les da mil vueltas a su gente.<br \/>Todo el mundo lo sabe\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o despu\u00e9s del fracaso de sus ambiciones presidenciales, el gobernador Ron DeSantis y su esposa Casey ya no pueden atribuirse el futuro del Partido Republicano. Y en Florida, incluso su presente est\u00e1 en peligro. Antes firmemente a su lado, muchos republicanos del estado del Sol se han vuelto contra DeSantis \u00faltimamente, obstaculizando su agenda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461695","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un a\u00f1o despu\u00e9s del fracaso de sus ambiciones presidenciales, el gobernador Ron DeSantis y su esposa Casey ya no pueden atribuirse el futuro del Partido Republicano. Y en Florida, incluso su presente est\u00e1 en peligro. Antes firmemente a su lado, muchos republicanos del estado del Sol se han vuelto contra DeSantis \u00faltimamente, obstaculizando su agenda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T04:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo\",\"datePublished\":\"2025-04-28T04:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\"},\"wordCount\":2159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\",\"name\":\"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-28T04:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo - Noticias","og_description":"Un a\u00f1o despu\u00e9s del fracaso de sus ambiciones presidenciales, el gobernador Ron DeSantis y su esposa Casey ya no pueden atribuirse el futuro del Partido Republicano. Y en Florida, incluso su presente est\u00e1 en peligro. Antes firmemente a su lado, muchos republicanos del estado del Sol se han vuelto contra DeSantis \u00faltimamente, obstaculizando su agenda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-28T04:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/"},"author":{"name":"","@id":""},"headline":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo","datePublished":"2025-04-28T04:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/"},"wordCount":2159,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","name":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-28T04:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ron y Casey DeSantis tramaban una dinast\u00eda pol\u00edtica en Florida, pero surgi\u00f3 un esc\u00e1ndalo","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/27\/ron-casey-desantis-florida-escandalo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-28T04:03:40Z","datePublished":"2025-04-28T04:03:40Z","dateModified":"2025-04-28T04:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ron y Casey DeSantis tramaban una dinast\\u00eda pol\\u00edtica en Florida, pero surgi\\u00f3 un esc\\u00e1ndalo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/27\\\/ron-casey-desantis-florida-escandalo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/27\\\/ron-casey-desantis-florida-escandalo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-28T04:03:40Z\",\"datePublished\":\"2025-04-28T04:03:40Z\",\"dateModified\":\"2025-04-28T04:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1444238,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/21\/ron-desantis-pone-fin-a-su-campana-por-la-candidatura-presidencial-republicana-de-2024\/","url_meta":{"origin":1461695,"position":0},"title":"Ron DeSantis pone fin a su campa\u00f1a por la candidatura presidencial republicana de 2024","author":"","date":"enero 21, 2024","format":false,"excerpt":"(CNN) -- El gobernador de Florida, Ron DeSantis, quien entr\u00f3 en las primarias presidenciales republicanas como la mayor amenaza de Donald Trump, anunci\u00f3 este domingo que pone fin a su candidatura a la Casa Blanca y respalda al expresidente.Su anuncio, realizado con un video publicado en X, se produce despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464107,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/01\/apertura-alligator-alcatraz-ron-desantis-trump-trax\/","url_meta":{"origin":1461695,"position":1},"title":"La apertura del &#8216;Alligator Alcatraz&#8217; de Florida le da a DeSantis la oportunidad de fortalecer sus v\u00ednculos con Trump","author":"","date":"julio 1, 2025","format":false,"excerpt":"Apenas unos meses despu\u00e9s de que la administraci\u00f3n del presidente Donald Trump actuara silenciosamente para socavar el impulso de l\u00ednea dura en materia de inmigraci\u00f3n del gobernador de Florida, Ron DeSantis, los dos exrivales republicanos se reunir\u00e1n este martes para la apertura de un nuevo centro de detenci\u00f3n de migrantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473703,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/05\/01\/ron-desantis-aliado-trump-candidatura-2028-trax\/","url_meta":{"origin":1461695,"position":2},"title":"Ron DeSantis se ha convertido en un aliado clave de Trump. \u00bfSe postular\u00e1 para 2028 en el futuro?","author":"","date":"mayo 1, 2026","format":false,"excerpt":"Esta semana, en cuesti\u00f3n de d\u00edas, el gobernador de Florida, Ron DeSantis, convoc\u00f3 a los legisladores a Tallahassee, les present\u00f3 un mapa de distritos electorales agresivamente manipulado, presion\u00f3 con mano dura a la legislatura controlada por los republicanos para que lo respaldara e inclin\u00f3 el campo de batalla de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464082,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/30\/trump-visitara-alcatraz-trax\/","url_meta":{"origin":1461695,"position":3},"title":"Trump visitar\u00e1 &#171;Alligator Alcatraz&#187; con DeSantis, Noem y Donalds","author":"","date":"junio 30, 2025","format":false,"excerpt":"La secretaria de prensa de la Casa Blanca, Karoline Leavitt, confirm\u00f3 que el presidente Donald Trump visitar\u00e1 los Everglades de Florida para asistir a la apertura de \u201cAlligator Alcatraz\u201d, un nuevo centro de detenci\u00f3n de inmigraci\u00f3n en la regi\u00f3n.Trump estar\u00e1 acompa\u00f1ado en el aeropuerto de entrenamiento y transici\u00f3n Dade-Collier por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443185,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/05\/conclusiones-del-foro-de-cnn-con-ron-desantis-gobernador-de-florida-y-aspirante-republicano-a-la-presidencia\/","url_meta":{"origin":1461695,"position":4},"title":"Conclusiones del foro de CNN con Ron DeSantis, gobernador de Florida y aspirante republicano a la presidencia","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN) -- El gobernador de Florida, Ron DeSantis, busc\u00f3 dejar claras sus diferencias con el expresidente Donald Trump durante un foro presidencial de CNN la noche de este jueves. En ese sentido, asegur\u00f3 a los votantes de Iowa: \u201cNo tendr\u00e1n que preocuparse por mi conducta\u201d.A una semana y media de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444242,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/22\/lo-que-dijeron-donald-trump-y-nikki-haley-sobre-el-anuncio-de-desantis-de-terminar-su-aspiracion-presidencial-de-2024\/","url_meta":{"origin":1461695,"position":5},"title":"Lo que dijeron Donald Trump y Nikki Haley sobre el anuncio de Desantis de terminar su aspiraci\u00f3n presidencial de 2024","author":"","date":"enero 22, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump dijo el domingo que se siente \"muy honrado\" de contar con el respaldo del gobernador de Florida, Ron DeSantis, luego de que anunci\u00f3 que terminaba su campa\u00f1a por la designaci\u00f3n republicana.\"Espero trabajar con \u00e9l para vencer a Joe Biden, que es el peor y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1461695"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461695\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1461695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1461695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1461695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}