{"id":1461728,"date":"2025-04-28T18:03:38","date_gmt":"2025-04-29T01:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/"},"modified":"2025-04-28T18:03:38","modified_gmt":"2025-04-29T01:03:38","slug":"trump-represion-inmigracion-entrevista-the-atlantic-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","title":{"rendered":"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic"},"content":{"rendered":"<p>El editor en jefe de The Atlantic, Jeffrey Goldberg, fue una figura central en la primera gran crisis autoinfligida del segundo mandato de Trump, cuando el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/24\/eeuu\/periodista-the-atlantic-chat-signal-planes-de-ataque-yemen-trax\">prominente periodista fue a\u00f1adido inadvertidamente a un chat de Signal<\/a> donde funcionarios del gabinete discut\u00edan ataques militares en Yemen. Semanas despu\u00e9s, Trump se sent\u00f3 para una entrevista con reporteros de The Atlantic y habl\u00f3 del secretario de Defensa Pete Hegseth, los esfuerzos de su campa\u00f1a contra la inmigraci\u00f3n ilegal y m\u00e1s.<\/p>\n<p>La controversia del chat de Signal frustr\u00f3 a Trump, quien justo una semana antes hab\u00eda cancelado una entrevista programada con los reporteros de la revista. Y el presidente destac\u00f3 la reuni\u00f3n planeada con anticipaci\u00f3n, diciendo en una publicaci\u00f3n en Truth Social la semana pasada que estaba \u201ccurioso\u201d y a la expectativa de si \u201ces posible que Atlantic sea \u2018veraz\u2019\u201d.<\/p>\n<p>Luego habl\u00f3 con los reporteros de Atlantic Ashley Parker y Michael Scherer como estaba planeado, as\u00ed como con Goldberg. Esto fue lo que aprendimos de las conversaciones de Trump con The Atlantic:<\/p>\n<p>Trump dijo que cree que Hegseth va a \u201cespabilar\u201d, despu\u00e9s de que los informes en las \u00faltimas semanas detallaran el tumulto en el Pent\u00e1gono, incluyendo despidos por supuestas divulgaciones no autorizadas y planes militares compartidos en un segundo chat grupal de Signal que inclu\u00eda a su esposa y hermano.<\/p>\n<p>Los reporteros de Atlantic mencionaron un informe de CBS que dec\u00eda que Hegseth hab\u00eda instalado un estudio de maquillaje en el Pent\u00e1gono, que cost\u00f3 miles de d\u00f3lares. Hegseth ha refutado el informe y defendido su liderazgo en el Pent\u00e1gono, pero el presidente sonri\u00f3 cuando se le pregunt\u00f3 sobre la historia, seg\u00fan The Atlantic.<\/p>\n<p>\u201cCreo que se va a espabilar,\u201d dijo Trump en la entrevista. \u201cTuve una charla con \u00e9l, una charla positiva, pero tuve una charla con \u00e9l\u201d.<\/p>\n<p>Trump agreg\u00f3 que Hegseth estaba \u201ca salvo\u201d, de acuerdo a una transcripci\u00f3n de la entrevista publicada el lunes por la tarde.<\/p>\n<p>CNN inform\u00f3 anteriormente que Trump hab\u00eda hablado con Hegseth dos veces despu\u00e9s de que se conoci\u00f3 la noticia del <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/20\/eeuu\/hegseth-segundo-chat-signal-planes-militares-trax\">segundo chat de Signal<\/a>. Trump ha solicitado comentarios sobre el desempe\u00f1o de Hegseth, pero es reacio a despedirlo o a despedir a cualquier otro funcionario del gabinete, dijeron fuentes a CNN.<\/p>\n<p>La secretaria de prensa Karoline Leavitt fue consultada m\u00e1s tarde el lunes sobre si Trump estaba insinuando que Hegseth no estaba preparado.<\/p>\n<p>\u201cMira, el presidente ha dejado muy clara su posici\u00f3n sobre el secretario Hegseth. \u00c9l tiene absoluta confianza en la capacidad del secretario para liderar el Pent\u00e1gono\u201d, dijo Leavitt.<\/p>\n<p>Trump tambi\u00e9n le dijo a The Atlantic que Waltz estaba \u201cbien\u201d despu\u00e9s de haber sido \u201catacado\u201d.<\/p>\n<p>Cuando se le pregunt\u00f3 cu\u00e1l ser\u00eda su mensaje al personal tras las repercusiones, Trump dijo: \u201cQuiz\u00e1s no usen Signal, \u00bfde acuerdo?\u201d<\/p>\n<p>Parker y Scherer preguntaron al presidente qu\u00e9 pasar\u00eda si su administraci\u00f3n accidentalmente deportara a la persona equivocada, cuestionando la posibilidad de deportar a un residente legal o a un ciudadano estadounidense.<\/p>\n<p>\u201cD\u00e9jame decirte que nunca nada es perfecto en este mundo\u201d, dijo.<\/p>\n<p>Esos comentarios llegan d\u00edas despu\u00e9s de que CNN informara que <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/27\/eeuu\/ninos-ciudadanos-estadounidenses-cancer-deportados-trax\">tres menores estadounidenses<\/a>, incluido un ni\u00f1o de 4 a\u00f1os que sufre de c\u00e1ncer metast\u00e1sico, fueron deportados con sus madres indocumentadas a Honduras por parte de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s).<\/p>\n<p>El \u201cZar de las Fronteras\u201d Tom Homan dijo el lunes que se les pregunt\u00f3 a las madres si prefer\u00edan que sus hijos fueran con ellas o se quedaran en EE.UU., y que los funcionarios de inmigraci\u00f3n se ajustaron a esa decisi\u00f3n.<\/p>\n<p>Trump tambi\u00e9n le dijo a The Atlantic que no est\u00e1 \u201cinvolucrado\u201d en deportaciones individuales cuando se le pregunt\u00f3 si le preocupaba haber deportado err\u00f3neamente a personas inocentes.<\/p>\n<p>\u201cTengo muchas personas, muchas capas de personas que hacen eso,\u201d le dijo Trump a The Atlantic.<\/p>\n<p>Trump continu\u00f3, \u201cDir\u00eda que todos ellos son personas extremadamente duras y peligrosas. Dir\u00eda eso. Y, no olvides, ellos entraron al pa\u00eds ilegalmente\u201d.<\/p>\n<p>La opini\u00f3n p\u00fablica sobre el manejo de la inmigraci\u00f3n por parte de Trump, un tema clave para el presidente, ha disminuido en las \u00faltimas semanas. Alrededor del 45 % de los estadounidenses aprueban sus esfuerzos en inmigraci\u00f3n, seg\u00fan una nueva encuesta de CNN realizada por SSRS, bajando seis puntos desde marzo.<\/p>\n<p>Trump dijo que pensaba que Ucrania ser\u00eda \u201caplastada muy pronto\u201d sin \u00e9l, seg\u00fan la transcripci\u00f3n de la entrevista con The Atlantic.<\/p>\n<p>Cuando se le pregunt\u00f3 si hab\u00eda algo que el presidente de Rusia, Vladimir Putin, podr\u00eda hacer para que Trump estuviera del lado del presidente de Ucrania, Volodymyr Zelensky, Trump dijo: \u201cNo necesariamente del lado de Zelensky, pero del lado de Ucrania, s\u00ed\u201d.<\/p>\n<p>\u201cMe ha costado mucho con Zelensky. Lo vieron aqu\u00ed cuando estaba sentado justo en esa silla, cuando simplemente no pod\u00eda entenderlo,\u201d agreg\u00f3 Trump, refiri\u00e9ndose a <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/28\/mundo\/reunion-zelensky-trump-trax\">una tensa entrevista en la Oficina Oval<\/a> entre los dos l\u00edderes y el vicepresidente J.D. Vance.<\/p>\n<p>La entrevista se llev\u00f3 a cabo antes de que Trump y Zelensky <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/26\/mundo\/video\/reunion-trump-zelensky-funeral-papa-francisco-tv-fast\">se encontraran dentro de la Bas\u00edlica de San Pedro<\/a> antes del funeral del papa Francisco, despu\u00e9s del cual Trump dijo en Truth Social que Putin podr\u00eda estar \u201cmaniobrando\u201d con \u00e9l y mencion\u00f3 sanciones bancarias o secundarias. Trump tambi\u00e9n mencion\u00f3 la posibilidad de sanciones en la entrevista con The Atlantic, cuando se le pregunt\u00f3 si hab\u00eda un punto en el que apoyar\u00eda a Ucrania con m\u00e1s armamento.<\/p>\n<p>\u201cNo tienen que ser armas. Hay muchos tipos de armamento. No tiene que ser armas con balas. Puede ser armas con sanciones. Puede ser armas con bancos. Puede ser muchas otras armas\u201d, dijo Trump.<\/p>\n<p>Sobre la contenciosa reuni\u00f3n en la Oficina Oval con Zelensky, Trump dijo: \u201cTodo lo que ten\u00eda que hacer era estar callado, \u00bfsabes? Gan\u00f3 su punto. Gan\u00f3 su punto. Pero en lugar de decir \u2018Est\u00e1 bien\u2019 cuando hice la declaraci\u00f3n, dije, \u2018Bueno, estamos trabajando para resolverlo. Estamos tratando de ayudar.\u2019 \u00c9l dijo, \u2018No, no, tambi\u00e9n necesitamos seguridad.\u2019 Yo dije, \u2018\u00bfSeguridad?\u2019\u201d.<\/p>\n<p>Trump ha pasado los primeros 100 d\u00edas de su segundo mandato en el cargo probando los l\u00edmites de su autoridad ejecutiva, reimaginando el papel de Estados Unidos en el mundo, recortando dr\u00e1sticamente el gobierno federal y trabajando para reformar el sistema econ\u00f3mico de Estados Unidos y a nivel global. En la entrevista, consider\u00f3 que su segundo mandato en el cargo es muy diferente de su primero.<\/p>\n<p>\u201cLa primera vez, ten\u00eda dos cosas que hacer: dirigir el pa\u00eds y sobrevivir; ten\u00eda todos estos tipos corruptos,\u201d dijo el presidente para el art\u00edculo, que tiene como titular: \u201cDonald Trump est\u00e1 disfrutando de esto\u201d.<\/p>\n<p>\u201cY la segunda vez,\u201d agreg\u00f3 el presidente, \u201cyo dirijo el pa\u00eds y el mundo.\u201d<\/p>\n<p>Trump ha expresado arrepentimiento por algunas de las elecciones que hizo para roles importantes en su primera administraci\u00f3n. Designar personas leales en esos roles fue una prioridad para Trump en su segundo mandato.<\/p>\n<p>The Atlantic inform\u00f3 que las personas tanto dentro como fuera de la Casa Blanca sienten que Trump est\u00e1 teniendo \u201cm\u00e1s diversi\u00f3n de la que tuvo en su primer mandato\u201d. El presidente les dijo a los periodistas que estaba de acuerdo con esa evaluaci\u00f3n.<\/p>\n<p>\u201cMe estoy divirtiendo mucho, considerando lo que hago\u201d, dijo el presidente. \u201cSabes, lo que hago es algo muy serio.\u201d<\/p>\n<p>Los reporteros de The Atlantic dijeron que la semana de su entrevista programada, que fue \u201cprometida tentativamente\u201d, Trump los atac\u00f3 por nombre en Truth Social.<\/p>\n<p>\u201cAshley Parker no es capaz de hacer una entrevista justa e imparcial. Es una lun\u00e1tica y radical izquierdista, y ha sido tan terrible como sea posible desde que la conozco\u201d, dijo Trump, llamando a The Atlantic una \u201crevista de tercera\u201d.<\/p>\n<p>\u201cIgualmente, Michael Scherer nunca ha escrito una historia justa sobre m\u00ed, solo negativas, y pr\u00e1cticamente siempre MIENTE,\u201d continu\u00f3.<\/p>\n<p>La entrevista fue descartada, lo que llev\u00f3 a los reporteros a llamarlo directamente a finales de marzo.<\/p>\n<p>\u201cNo pregunten c\u00f3mo conseguimos su n\u00famero\u201d, escribieron.<\/p>\n<p>Cuando Trump respondi\u00f3, dijeron, estaba emocionado de hablar sobre sus logros, aparentemente dejando de lado sus opiniones negativas sobre los reporteros.<\/p>\n<p>Cuando llamaron unas semanas despu\u00e9s para hacer algunas preguntas de seguimiento, la llamada fue a la contestadora. El presidente parec\u00eda devolverles la llamada despu\u00e9s de la 1 a.m. mientras regresaba de una pelea de UFC en Miami.<\/p>\n<p>\u201c\u00bfNos llam\u00f3 para preguntar si hab\u00edamos visto la pelea? \u00bfO fue simplemente una llamada accidental de medianoche? Su equipo se neg\u00f3 a aclarar\u201d, escribieron.<\/p>\n<p>Trump finalmente accedi\u00f3 a la reuni\u00f3n posterior en la Oficina Oval junto a Goldberg la semana pasada.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El editor en jefe de The Atlantic, Jeffrey Goldberg, fue una figura central en la primera gran crisis autoinfligida del segundo mandato de Trump, cuando el prominente periodista fue a\u00f1adido inadvertidamente a un chat de Signal donde funcionarios del gabinete discut\u00edan ataques militares en Yemen. Semanas despu\u00e9s, Trump se sent\u00f3 para una entrevista con reporteros [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461728","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Nunca nada es perfecto&quot;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Nunca nada es perfecto&quot;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic - Noticias\" \/>\n<meta property=\"og:description\" content=\"El editor en jefe de The Atlantic, Jeffrey Goldberg, fue una figura central en la primera gran crisis autoinfligida del segundo mandato de Trump, cuando el prominente periodista fue a\u00f1adido inadvertidamente a un chat de Signal donde funcionarios del gabinete discut\u00edan ataques militares en Yemen. Semanas despu\u00e9s, Trump se sent\u00f3 para una entrevista con reporteros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T01:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic\",\"datePublished\":\"2025-04-29T01:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\"},\"wordCount\":1521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\",\"name\":\"\\\"Nunca nada es perfecto\\\": Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-29T01:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Nunca nada es perfecto\": Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Nunca nada es perfecto\": Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic - Noticias","og_description":"El editor en jefe de The Atlantic, Jeffrey Goldberg, fue una figura central en la primera gran crisis autoinfligida del segundo mandato de Trump, cuando el prominente periodista fue a\u00f1adido inadvertidamente a un chat de Signal donde funcionarios del gabinete discut\u00edan ataques militares en Yemen. Semanas despu\u00e9s, Trump se sent\u00f3 para una entrevista con reporteros [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-29T01:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic","datePublished":"2025-04-29T01:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/"},"wordCount":1521,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","name":"\"Nunca nada es perfecto\": Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-29T01:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\u00f1a contra la inmigraci\u00f3n ilegal y de Hegseth en entrevista con The Atlantic","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/28\/trump-represion-inmigracion-entrevista-the-atlantic-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-29T01:03:38Z","datePublished":"2025-04-29T01:03:38Z","dateModified":"2025-04-29T01:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Nunca nada es perfecto&#187;: Trump habla de su campa\\u00f1a contra la inmigraci\\u00f3n ilegal y de Hegseth en entrevista con The Atlantic\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/28\\\/trump-represion-inmigracion-entrevista-the-atlantic-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/28\\\/trump-represion-inmigracion-entrevista-the-atlantic-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-29T01:03:38Z\",\"datePublished\":\"2025-04-29T01:03:38Z\",\"dateModified\":\"2025-04-29T01:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460461,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/26\/yemen-chat-signal-hegseth-orix\/","url_meta":{"origin":1461728,"position":0},"title":"Qu\u00e9 informaci\u00f3n se revel\u00f3 en el chat grupal de Signal entre funcionarios de EE.UU. y por qu\u00e9 es importante: esto debes saber","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Hablaban de bombardear un pa\u00eds extranjero, detallando informaci\u00f3n clasificada, como si se tratara de una conversaci\u00f3n cotidiana de la vida diaria. Y no lo hac\u00edan en una red segura del Pent\u00e1gono, sino en una aplicaci\u00f3n de mensajer\u00eda disponible para el gran p\u00fablico. Con un periodista cr\u00edtico dentro del grupo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460515,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/27\/resurgen-preocupaciones-juicio-hegseth-chat-signal-trax\/","url_meta":{"origin":1461728,"position":1},"title":"Resurgen las preocupaciones sobre el criterio de Hegseth tras el esc\u00e1ndalo del chat de Signal","author":"","date":"marzo 27, 2025","format":false,"excerpt":"Desde que se conoci\u00f3 este lunes que altos funcionarios del Gobierno de Trump discutieron planes de ataque militar de Estados Unidos en un chat grupal que inadvertidamente incluy\u00f3 a un periodista, el secretario de Defensa, Pete Hegseth, ha proyectado una confianza inquebrantable.\u201cS\u00e9 exactamente lo que estoy haciendo\u201d, dijo Hegseth a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468936,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/03\/hegseth-riesgo-militares-guerra-signal-trax\/","url_meta":{"origin":1461728,"position":2},"title":"Exclusivo: \u00f3rgano de control concluye que Hegseth arriesg\u00f3 a militares al compartir planes de guerra en Signal, dicen fuentes","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"El secretario de Defensa Pete Hegseth puso en riesgo informaci\u00f3n militar confidencial, lo que podr\u00eda haber representado un peligro para las fuerzas militares de EE.UU. y los objetivos de la misi\u00f3n, cuando us\u00f3 Signal en marzo de este a\u00f1o para compartir planes de ataque altamente sensibles dirigidos contra los rebeldes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460369,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/25\/administracion-trump-waltz-hegseth-vance-yemen-trax\/","url_meta":{"origin":1461728,"position":3},"title":"El condenatorio chat grupal sobre Yemen refleja una administraci\u00f3n indiferente al estado de derecho","author":"","date":"marzo 25, 2025","format":false,"excerpt":"Es una de las indiscreciones de seguridad nacional m\u00e1s impactantes en a\u00f1os.La revelaci\u00f3n de que el equipo de seguridad nacional del presidente Donald Trump discuti\u00f3 los ataques militares en Yemen en un chat de grupo no clasificado sugiere una actitud arrogante hacia los secretos de Estados Unidos y la seguridad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460441,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/26\/the-atlantic-mas-mensajes-chat-yemen-trax\/","url_meta":{"origin":1461728,"position":4},"title":"The Atlantic publica m\u00e1s mensajes del chat grupal de funcionarios de EE.UU. que revel\u00f3 detalles sensibles del ataque en Yemen","author":"","date":"marzo 26, 2025","format":false,"excerpt":"The Atlantic public\u00f3 este mi\u00e9rcoles nuevos mensajes de texto del chat grupal en Signal de los principales funcionarios de Seguridad Nacional de Trump, lo que deja en evidencia una violaci\u00f3n a gran escala de la seguridad operativa, ya que informaci\u00f3n confidencial espec\u00edfica sobre el ataque contra los hut\u00edes en Yemen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461428,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/20\/hegseth-segundo-chat-signal-planes-militares-trax\/","url_meta":{"origin":1461728,"position":5},"title":"Hegseth comparti\u00f3 planes militares detallados en un segundo chat de Signal en el que estaban su esposa y su hermano","author":"","date":"abril 20, 2025","format":false,"excerpt":"El secretario de Defensa Pete Hegseth comparti\u00f3 planes detallados sobre una operaci\u00f3n militar contra los hut\u00edes en Yemen en un segundo chat grupal de Signal, en el que estaban su esposa, su abogado y su hermano, seg\u00fan informaron a CNN tres personas familiarizadas con el chat.La revelaci\u00f3n se produce cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1461728"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461728\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1461728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1461728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1461728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}