{"id":1461743,"date":"2025-04-29T07:03:55","date_gmt":"2025-04-29T14:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/"},"modified":"2025-04-29T07:03:55","modified_gmt":"2025-04-29T14:03:55","slug":"jefe-seguridad-israel-renunciara-presion-netanyahu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","title":{"rendered":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu"},"content":{"rendered":"<p>El jefe de la agencia de inteligencia Shin Bet, Ronen Bar, dijo que renunciar\u00e1 el 15 de junio, casi tres meses despu\u00e9s de que el Gobierno de Israel votara por primera vez para destituirlo.<\/p>\n<p>\u201cMi amor por la patria y mi lealtad al Estado son la base de cada decisi\u00f3n que he tomado en mi vida profesional\u201d, dijo Bar en un evento en memoria de los agentes ca\u00eddos del Shin Bet. \u201cY lo mismo ocurre esta noche\u201d.<\/p>\n<p>En su discurso, Bar acept\u00f3 la responsabilidad por los fallos del Shin Bet el 7 de octubre de 2023. \u201cTras a\u00f1os en muchos frentes, en una sola noche, en el frente sur, se derrumb\u00f3 el cielo. Todos los sistemas colapsaron. El Shin Bet tampoco dio una advertencia\u201d, declar\u00f3 en su discurso en Tel Aviv. Bar explic\u00f3 que parte de su raz\u00f3n para dimitir fue \u201cpermitir un proceso ordenado\u201d de elecci\u00f3n de un sucesor.<\/p>\n<p>Pero no est\u00e1 claro si el mandato de Bar durar\u00e1 tanto. El 21 de marzo, el gabinete israel\u00ed vot\u00f3 un\u00e1nimemente a favor de destituir a Bar de su cargo como director de la Agencia de Seguridad de Israel, conocida com\u00fanmente como Shin Bet.<\/p>\n<p>El despido de Bar deb\u00eda entrar en vigor el 10 de abril, pero el Tribunal Supremo de Israel congel\u00f3 el despido, lo que enfureci\u00f3 a Netanyahu y sus aliados de derecha, que a\u00fan pueden realizar un esfuerzo para despedir a Bar antes de la fecha de retiro autoanunciada.<\/p>\n<p>Bar se ha visto envuelto en una amarga disputa con Netanyahu y miembros de su Gobierno de derecha. Los ministros lo acusan de realizar investigaciones con motivaciones pol\u00edticas dise\u00f1adas para desacreditar al Gobierno. La acritud se dispar\u00f3 tras el caso QatarGate, a principios de este a\u00f1o, en el que una investigaci\u00f3n del Shin Bet atrap\u00f3 a dos allegados del veterano l\u00edder de Israel.<\/p>\n<p>La semana pasada, Bar dijo en una declaraci\u00f3n jurada que Netanyahu esperaba \u201clealtad personal\u201d.<\/p>\n<p>\u201cMe dejaron claro que, en caso de una crisis constitucional, se esperar\u00eda que obedeciera al primer ministro y no a la Corte Suprema\u201d, dijo Bar.<\/p>\n<p>En respuesta, Netanyahu acus\u00f3 a Bar de presentar una \u201cdeclaraci\u00f3n jurada falsa\u201d, y afirm\u00f3 que fue despedido porque no cumpli\u00f3 con su deber.<\/p>\n<p>Itamar Ben Gvir, el ministro de Seguridad Nacional -de extrema derecha, que desde hace tiempo pide el despido de Bar-, dijo <a href=\"https:\/\/x.com\/itamarbengvir\/status\/1916912757384921529\">en las redes sociales<\/a>: \u201cBuena suerte\u201d.<\/p>\n<p>Bar recibi\u00f3 muestras de apoyo de la oposici\u00f3n. Yair Lapid, l\u00edder de la oposici\u00f3n, emiti\u00f3 un comunicado en el que dec\u00eda: \u201cRonen Bar tom\u00f3 la decisi\u00f3n correcta y honorable. As\u00ed es como se ve asumir la responsabilidad\u201d.<\/p>\n<p>El l\u00edder del partido Dem\u00f3crata, Yair Golan, dijo en las redes sociales: \u201cNetanyahu, ahora es tu turno\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jefe de la agencia de inteligencia Shin Bet, Ronen Bar, dijo que renunciar\u00e1 el 15 de junio, casi tres meses despu\u00e9s de que el Gobierno de Israel votara por primera vez para destituirlo. \u201cMi amor por la patria y mi lealtad al Estado son la base de cada decisi\u00f3n que he tomado en mi [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461743","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu - Noticias\" \/>\n<meta property=\"og:description\" content=\"El jefe de la agencia de inteligencia Shin Bet, Ronen Bar, dijo que renunciar\u00e1 el 15 de junio, casi tres meses despu\u00e9s de que el Gobierno de Israel votara por primera vez para destituirlo. \u201cMi amor por la patria y mi lealtad al Estado son la base de cada decisi\u00f3n que he tomado en mi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T14:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu\",\"datePublished\":\"2025-04-29T14:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\",\"name\":\"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-29T14:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu - Noticias","og_description":"El jefe de la agencia de inteligencia Shin Bet, Ronen Bar, dijo que renunciar\u00e1 el 15 de junio, casi tres meses despu\u00e9s de que el Gobierno de Israel votara por primera vez para destituirlo. \u201cMi amor por la patria y mi lealtad al Estado son la base de cada decisi\u00f3n que he tomado en mi [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-29T14:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/"},"author":{"name":"","@id":""},"headline":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu","datePublished":"2025-04-29T14:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","name":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-29T14:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El jefe de Seguridad de Israel dice que renunciar\u00e1 el 15 de junio ante la presi\u00f3n de Netanyahu","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-29T14:03:55Z","datePublished":"2025-04-29T14:03:55Z","dateModified":"2025-04-29T14:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El jefe de Seguridad de Israel dice que renunciar\\u00e1 el 15 de junio ante la presi\\u00f3n de Netanyahu\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/29\\\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/29\\\/jefe-seguridad-israel-renunciara-presion-netanyahu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-29T14:03:55Z\",\"datePublished\":\"2025-04-29T14:03:55Z\",\"dateModified\":\"2025-04-29T14:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460000,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/16\/netanyahu-busca-destituir-ronen-bar-jefe-shin-bet-israel-trax\/","url_meta":{"origin":1461743,"position":0},"title":"Netanyahu busca destituir a Ronen Bar, jefe de la agencia de inteligencia Shin Bet de Israel","author":"","date":"marzo 16, 2025","format":false,"excerpt":"Tras meses de tensi\u00f3n, el primer ministro de Israel Benjamin Netanyahu anunci\u00f3 que buscar\u00e1 destituir a Ronen Bar, jefe de la agencia de inteligencia israel\u00ed Shin Bet.Netanyahu se reuni\u00f3 con Bar y le inform\u00f3 que propondr\u00e1 su destituci\u00f3n al gobierno esta semana, seg\u00fan inform\u00f3 la oficina del primer ministro el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462763,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/24\/familias-rehenes-israel-critican-jefe-seguridad-trax\/","url_meta":{"origin":1461743,"position":1},"title":"Familias de rehenes israel\u00edes critican al candidato a jefe de seguridad por su supuesta oposici\u00f3n a un acuerdo de liberaci\u00f3n","author":"","date":"mayo 24, 2025","format":false,"excerpt":"Las familias de los rehenes israel\u00edes retenidos en Gaza arremetieron contra el reci\u00e9n elegido jefe de la agencia de seguridad Shin Bet, que supuestamente se opuso a los acuerdos de rehenes.De acuerdo con el Canal 12 de noticias de Israel, el general de divisi\u00f3n David Zini dijo en las reuniones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460226,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/21\/ronen-bar-tribunal-supremo-israel-suspende-destitucion-trax\/","url_meta":{"origin":1461743,"position":2},"title":"Tribunal Supremo de Israel suspende la destituci\u00f3n del jefe de la agencia de seguridad interna por parte de Netanyahu","author":"","date":"marzo 21, 2025","format":false,"excerpt":"El Tribunal Supremo de Israel congel\u00f3 la destituci\u00f3n de Ronen Bar, jefe del servicio de seguridad interna del pa\u00eds, el Shin Bet, por parte del Gobierno, lo que ha generado la ira de altos funcionarios.Algunos ministros condenaron inmediatamente la decisi\u00f3n. El ministro de Comunicaciones, Shlomo Kari, declar\u00f3 que el tribunal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455883,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/11\/17\/policia-israel-servicios-inteligencia-inician-investigacion-lanzamiento-bengalas-contra-casa-netanyahu-trax\/","url_meta":{"origin":1461743,"position":3},"title":"La Polic\u00eda de Israel y los servicios de inteligencia inician una investigaci\u00f3n tras el lanzamiento de bengalas contra la casa de Netanyahu","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN) -- La casa privada del primer ministro de Israel, Benjamin Netanyahu, fue atacada este s\u00e1bado por la noche cuando tres individuos dispararon bengalas en direcci\u00f3n a la propiedad en la ciudad costera de Cesarea.La Polic\u00eda de Israel y los servicios de inteligencia, el Shin Bet, abrieron una investigaci\u00f3n sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462792,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/26\/ex-rehen-fdi-temores-ataques-israelies-trax\/","url_meta":{"origin":1461743,"position":4},"title":"&#171;Una y otra vez, estaba segura de que era el final&#187;: soldado israel\u00ed cautiva en Gaza tem\u00eda por ataques de Israel","author":"","date":"mayo 26, 2025","format":false,"excerpt":"Una soldado de las Fuerzas de Defensa de Israel (FDI) liberada durante un acuerdo de alto el fuego e intercambio de rehenes dijo que uno de sus mayores temores durante su cautiverio eran los ataques llevados a cabo por Israel.Na\u2019ama Levy, una de las cinco mujeres soldados de las FDI\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457450,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/11\/israel-qatar-negociaciones-avanzar-trax\/","url_meta":{"origin":1461743,"position":5},"title":"Israel enviar\u00e1 al jefe del Mossad a Qatar: las negociaciones sobre posible alto el fuego a cambio de rehenes podr\u00edan avanzar","author":"","date":"enero 11, 2025","format":false,"excerpt":"Israel enviar\u00e1 a a Qatar al jefe de su agencia de inteligencia, el Mossad, para continuar las conversaciones sobre un posible acuerdo de alto el fuego a cambio de rehenes en Gaza, en una posible se\u00f1al de que las negociaciones podr\u00edan avanzar en los pr\u00f3ximos d\u00edas.La oficina del primer ministro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1461743"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461743\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1461743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1461743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1461743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}