{"id":1461767,"date":"2025-04-29T19:03:45","date_gmt":"2025-04-30T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/"},"modified":"2025-04-29T19:03:45","modified_gmt":"2025-04-30T02:03:45","slug":"tribunal-supremo-wisconsin-suspende-jueza-dugan-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","title":{"rendered":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n"},"content":{"rendered":"<p>El Tribunal Supremo de Wisconsin dictamin\u00f3 este martes que a Hannah Dugan, una jueza de Milwaukee acusada de obstruir a los agentes de inmigraci\u00f3n, se le \u201cprohibir\u00e1 temporalmente ejercer las facultades de juez de un tribunal de circuito\u201d mientras el caso avanza en el sistema judicial, seg\u00fan muestran los registros judiciales.<\/p>\n<p>La jueza Hannah Dugan fue detenida la semana pasada en el Palacio de Justicia del condado de Milwaukee y se enfrenta a dos cargos federales por obstrucci\u00f3n y por ocultar la detenci\u00f3n de una persona. Hizo su primera aparici\u00f3n el viernes por la ma\u00f1ana y fue puesta en libertad bajo fianza.<\/p>\n<p>\u201cEs de inter\u00e9s p\u00fablico que sea relevada temporalmente de sus funciones oficiales\u201d, dice la orden de dos p\u00e1ginas, se\u00f1alando que el propio Tribunal Supremo del estado se hizo cargo del asunto \u201cpara mantener la confianza del p\u00fablico\u201d.<\/p>\n<p>CNN se ha puesto en contacto con sus abogados para que comenten la decisi\u00f3n del Tribunal Supremo estatal.<\/p>\n<p>En el tribunal el viernes, el abogado de Dugan dijo: \u201cLa jueza Dugan lamenta de todo coraz\u00f3n y protesta por su detenci\u00f3n. No se hizo en inter\u00e9s de la seguridad p\u00fablica\u201d, seg\u00fan AP.<\/p>\n<p>Dugan est\u00e1 acusada de ayudar a un acusado en su sala el 18 de abril a eludir a los funcionarios de inmigraci\u00f3n que lo detendr\u00edan en el pasillo exterior.<\/p>\n<p>La declaraci\u00f3n jurada afirma que Dugan \u201cse enfad\u00f3 visiblemente, coment\u00f3 que la situaci\u00f3n era \u201cabsurda\u201d, abandon\u00f3 el estrado y entr\u00f3 en la sala\u201d, tras enterarse de que hab\u00eda agentes en el tribunal.<\/p>\n<p>Los testigos afirman que se enfrent\u00f3 a los agentes federales en un pasillo p\u00fablico, les exigi\u00f3 repetidamente que se marcharan y les dijo que necesitaban otro tipo de orden para efectuar la detenci\u00f3n, seg\u00fan los documentos judiciales. Al parecer, tambi\u00e9n implic\u00f3 en el asunto al juez en jefe del tribunal.<\/p>\n<p>Cuando regres\u00f3 a su sala, los testigos dijeron a los investigadores que impidi\u00f3 que el hombre y su abogado salieran por las puertas principales al vest\u00edbulo y, en su lugar, los escolt\u00f3 a trav\u00e9s de una puerta del jurado. Los agentes alcanzaron al hombre fuera y fue detenido tras una breve persecuci\u00f3n a pie, dice el documento.<\/p>\n<p>La pr\u00f3xima comparecencia de Dugan ante el tribunal est\u00e1 prevista para el 15 de mayo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tribunal Supremo de Wisconsin dictamin\u00f3 este martes que a Hannah Dugan, una jueza de Milwaukee acusada de obstruir a los agentes de inmigraci\u00f3n, se le \u201cprohibir\u00e1 temporalmente ejercer las facultades de juez de un tribunal de circuito\u201d mientras el caso avanza en el sistema judicial, seg\u00fan muestran los registros judiciales. La jueza Hannah Dugan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1461767","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Tribunal Supremo de Wisconsin dictamin\u00f3 este martes que a Hannah Dugan, una jueza de Milwaukee acusada de obstruir a los agentes de inmigraci\u00f3n, se le \u201cprohibir\u00e1 temporalmente ejercer las facultades de juez de un tribunal de circuito\u201d mientras el caso avanza en el sistema judicial, seg\u00fan muestran los registros judiciales. La jueza Hannah Dugan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-30T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n\",\"datePublished\":\"2025-04-30T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\"},\"wordCount\":435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\",\"name\":\"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-04-30T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n - Noticias","og_description":"El Tribunal Supremo de Wisconsin dictamin\u00f3 este martes que a Hannah Dugan, una jueza de Milwaukee acusada de obstruir a los agentes de inmigraci\u00f3n, se le \u201cprohibir\u00e1 temporalmente ejercer las facultades de juez de un tribunal de circuito\u201d mientras el caso avanza en el sistema judicial, seg\u00fan muestran los registros judiciales. La jueza Hannah Dugan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","og_site_name":"Noticias","article_published_time":"2025-04-30T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/"},"author":{"name":"","@id":""},"headline":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n","datePublished":"2025-04-30T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/"},"wordCount":435,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","url":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","name":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-04-30T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\u00f3n","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/04\/29\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-04-30T02:03:45Z","datePublished":"2025-04-30T02:03:45Z","dateModified":"2025-04-30T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Tribunal Supremo de Wisconsin suspende a la jueza Dugan, acusada de obstruir a agentes de inmigraci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/29\\\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/04\\\/29\\\/tribunal-supremo-wisconsin-suspende-jueza-dugan-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-04-30T02:03:45Z\",\"datePublished\":\"2025-04-30T02:03:45Z\",\"dateModified\":\"2025-04-30T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462319,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/13\/imputan-tribunal-federal-jueza-wisconsin-obstruir-agentes-inmigracion-trax\/","url_meta":{"origin":1461767,"position":0},"title":"Imputan en un tribunal federal a la jueza de Wisconsin tras ser acusada de obstruir a agentes de inmigraci\u00f3n","author":"","date":"mayo 13, 2025","format":false,"excerpt":"Una jueza del Tribunal de Circuito del condado de Milwaukee fue imputada en un tribunal federal este martes, tras ser acusada de haber ayudado a un inmigrante indocumentado a evadir a agentes federales el mes pasado.La jueza Hannah Dugan fue imputada por cargos de obstrucci\u00f3n y encubrimiento de una persona\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461638,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/25\/quien-hannah-dugan-jueza-de-wisconsin-arrestada-fbi-trax\/","url_meta":{"origin":1461767,"position":1},"title":"\u00bfQui\u00e9n es Hannah Dugan, la jueza de Wisconsin arrestada por el FBI por presunta obstrucci\u00f3n a agentes del ICE?","author":"","date":"abril 25, 2025","format":false,"excerpt":"La jueza de Wisconsin que fue arrestada por el FBI el viernes y acusada de interferir en el arresto de un inmigrante indocumentado tiene una larga historia de d\u00e9cadas abogando por los pobres y vulnerables.La jueza del Tribunal de Circuito del Condado de Milwaukee, Hannah Dugan, enfrenta dos cargos por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462382,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/15\/manifestantes-apoyo-jueza-acusada-trax\/","url_meta":{"origin":1461767,"position":2},"title":"Manifestantes se concentran en apoyo a jueza acusada de ayudar a un hombre a huir de los agentes de inmigraci\u00f3n","author":"","date":"mayo 15, 2025","format":false,"excerpt":"Alrededor de 100 manifestantes se concentraron este jueves por la ma\u00f1ana frente al tribunal y edificio federal del centro de Milwaukee antes de la lectura de cargos contra una jueza de Wisconsin acusada de ayudar a un hombre que est\u00e1 en el pa\u00eds ilegalmente a evadir a los agentes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461619,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/25\/fbi-detencion-jueza-wisconsin-trax\/","url_meta":{"origin":1461767,"position":3},"title":"Director del FBI dice que detuvieron a jueza de Wisconsin por presunta obstrucci\u00f3n a ICE","author":"","date":"abril 25, 2025","format":false,"excerpt":"El FBI arrest\u00f3 el viernes a una jueza de circuito del condado de Milwaukee, seg\u00fan inform\u00f3 en redes sociales el director del FBI, Kash Patel, acus\u00e1ndola de ayudar a un inmigrante indocumentado a evitar el arresto.La juez Hannah Dugan se enfrenta a dos cargos por obstrucci\u00f3n a la justicia y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461667,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/26\/director-fbi-foto-jueza-de-wisconsin-departamento-justicia-trax\/","url_meta":{"origin":1461767,"position":4},"title":"Director del FBI publica foto del arresto de jueza de Wisconsin, posiblemente violando pol\u00edtica del Departamento de Justicia","author":"","date":"abril 26, 2025","format":false,"excerpt":"El director del FBI, Kash Patel, public\u00f3 una foto en X el viernes por la noche de la jueza de Wisconsin que fue arrestada por presuntamente obstruir a agentes de inmigraci\u00f3n, mientras estaba esposada y era escoltada a un veh\u00edculo por agentes.La foto de la jueza del Circuito del Condado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461640,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/25\/acusacion-jueza-wisconsin-enfoque-agresivo-trump-ley-inmigracion-trax\/","url_meta":{"origin":1461767,"position":5},"title":"La acusaci\u00f3n contra la jueza de Wisconsin subraya el enfoque agresivo del Gobierno de Trump para aplicar ley de inmigraci\u00f3n","author":"","date":"abril 25, 2025","format":false,"excerpt":"El arresto de una jueza estatal de Wisconsin por supuestamente ayudar a un inmigrante indocumentado a evitar su arresto abri\u00f3 un nuevo frente en el intento agresivo del Gobierno de Trump de llevar a cabo una campa\u00f1a de deportaci\u00f3n hist\u00f3rica.La decisi\u00f3n del Departamento de Justicia de acusar a la jueza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1461767"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1461767\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1461767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1461767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1461767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}