{"id":1465942,"date":"2025-08-28T11:03:47","date_gmt":"2025-08-28T18:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/"},"modified":"2025-08-28T11:03:47","modified_gmt":"2025-08-28T18:03:47","slug":"putin-kim-xi-desfile-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","title":{"rendered":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad"},"content":{"rendered":"<p>El l\u00edder norcoreano Kim Jong Un y el presidente ruso, Vladimir Putin, estar\u00e1n entre m\u00e1s de dos docenas de jefes de Estado extranjeros que asistir\u00e1n la pr\u00f3xima semana al enorme desfile militar de China, anunci\u00f3 este jueves el Ministerio de Relaciones Exteriores de ese pa\u00eds.<\/p>\n<p>El desfile, que se celebrar\u00e1 el 3 de septiembre en la plaza de Tiananmen de Beijing, forma parte de las conmemoraciones por el 80\u00b0 aniversario del final de la Segunda Guerra Mundial tras la rendici\u00f3n formal de Jap\u00f3n.<\/p>\n<p>El anuncio, que coloca a Putin y Kim a la cabeza de la lista de invitados de Xi, prepara el escenario para una extraordinaria foto de los tres l\u00edderes autocr\u00e1ticos de pie, uno al lado del otro, en lo alto de la Puerta de la Paz Celestial en Beijing, en una inequ\u00edvoca demostraci\u00f3n de unidad.<\/p>\n<p>La agencia estatal norcoreana KCNA confirm\u00f3 la asistencia de Kim, en lo que ser\u00eda su primer viaje a China desde 2019. Kim, que solo ha realizado 10 viajes al extranjero desde que asumi\u00f3 el poder en 2011, sali\u00f3 por \u00faltima vez de su aislado pa\u00eds en 2023 para reunirse con Putin en un remoto puerto espacial del extremo oriente de Rusia.<\/p>\n<p>El desfile ofrece al reservado jefe del r\u00e9gimen m\u00e1s sancionado del mundo una rara oportunidad de aparecer junto a otros l\u00edderes mundiales que se inclinan hacia un orden alternativo que Xi y Putin han promovido.<\/p>\n<p>La confirmaci\u00f3n de la asistencia de Kim al desfile llega apenas unos d\u00edas despu\u00e9s de que el presidente de EE.UU., Donald Trump, dijera que le gustar\u00eda reunirse con el l\u00edder norcoreano este a\u00f1o.<\/p>\n<p>Beijing proyecta fuerza militar en un momento de gran incertidumbre geopol\u00edtica, mientras Trump sacude las alianzas y asociaciones estadounidenses. Tambi\u00e9n ocurre en medio de la postura cada vez m\u00e1s firme de China hacia Taiw\u00e1n y sus disputas territoriales con pa\u00edses vecinos.<\/p>\n<p>Un total de 26 jefes de Estado y de gobierno extranjeros asistir\u00e1n al desfile, incluido el primer ministro de Pakist\u00e1n, Shehbaz Sharif, inform\u00f3 en una conferencia de prensa en Beijing el viceministro de Relaciones Exteriores, Hong Lei.<\/p>\n<p>Narendra Modi, el primer ministro de India, el rival hist\u00f3rico de Pakist\u00e1n, que estar\u00e1 este fin de semana en la ciudad china de Tianjin para una cumbre de la Organizaci\u00f3n de Cooperaci\u00f3n de Shangh\u00e1i, no figura entre los l\u00edderes que asistir\u00e1n al desfile.<\/p>\n<p>El jefe de la junta militar de Myanmar, Min Aung Hlaing, que ejerce como presidente interino de ese pa\u00eds tras el golpe de Estado de 2021 que derroc\u00f3 a un gobierno electo y sumi\u00f3 a la naci\u00f3n en una devastadora guerra civil, tambi\u00e9n estar\u00e1 presente.<\/p>\n<p>Otros invitados incluyen a l\u00edderes europeos cercanos a Rusia, como Aleksandar Vucic de Serbia y Robert Fico de Eslovaquia.<\/p>\n<p>Destaca la ausencia de dirigentes de las principales capitales occidentales, a pesar de que China fue un socio crucial de las potencias aliadas en el teatro del Pac\u00edfico durante la Segunda Guerra Mundial. La lucha del pa\u00eds contra la invasi\u00f3n a gran escala de Jap\u00f3n se convirti\u00f3 en un frente central de la guerra en Asia, que termin\u00f3 en 1945 con la rendici\u00f3n japonesa.<\/p>\n<p>El conflicto en China continu\u00f3 entre las fuerzas comunistas y nacionalistas hasta que las primeras finalmente triunfaron en 1949, lo que dio lugar a la creaci\u00f3n de la Rep\u00fablica Popular China que Xi dirige hoy.<\/p>\n<p>El desfile del mi\u00e9rcoles, de 70 minutos, contar\u00e1 con m\u00e1s de 10.000 militares, m\u00e1s de 100 aeronaves y cientos de piezas de equipo terrestre, en una demostraci\u00f3n del creciente poder militar de China bajo Xi, quien ha hecho de la modernizaci\u00f3n del Ej\u00e9rcito Popular de Liberaci\u00f3n una misi\u00f3n central de su mandato.<\/p>\n<p>El espect\u00e1culo, cuidadosamente coreografiado, ofrecer\u00e1 una rara mirada a la tecnolog\u00eda militar de r\u00e1pido avance de China. Las autoridades han dicho que todo el equipo en exhibici\u00f3n es de producci\u00f3n nacional y actualmente est\u00e1 en servicio, con muchos debutando en p\u00fablico: desde drones de \u00faltima generaci\u00f3n, sistemas de interferencia electr\u00f3nica, armas hipers\u00f3nicas, tecnolog\u00edas de defensa a\u00e9rea y antimisiles, hasta misiles estrat\u00e9gicos.<\/p>\n<p>Beijing ha sido durante d\u00e9cadas el principal apoyo pol\u00edtico y econ\u00f3mico de Corea del Norte, proporcionando un salvavidas crucial para su econom\u00eda, fuertemente sancionada. Corea del Norte es tambi\u00e9n el \u00fanico aliado formal de China, con un tratado de defensa mutua firmado en 1961.<\/p>\n<p>En los \u00faltimos a\u00f1os, Corea del Norte ha estrechado lazos con Rusia en medio de la prolongada guerra de Mosc\u00fa contra Ucrania, lo que ha complicado el equilibrio geopol\u00edtico de Asia oriental y los esfuerzos de China por mantener la estabilidad regional.<\/p>\n<p>Xi, el mayor respaldo de Putin, ha observado con cautela c\u00f3mo el l\u00edder ruso y Kim forjaron una nueva alianza que llev\u00f3 a Corea del Norte a enviar militares para unirse a la guerra de Rusia en Ucrania. El a\u00f1o pasado, Putin y Kim firmaron un hist\u00f3rico pacto de defensa en Pionyang y se comprometieron a brindar asistencia militar inmediata en caso de que uno de ellos sea atacado, un movimiento que ha inquietado a EE.UU. y a sus aliados en Asia.<\/p>\n<p>Hong, el viceministro de Relaciones Exteriores chino, elogi\u00f3 la \u201camistad tradicional\u201d entre China y Corea del Norte en la conferencia de prensa del jueves, recordando que ambos pa\u00edses se apoyaron mutuamente en la lucha contra la invasi\u00f3n japonesa hace ocho d\u00e9cadas.<\/p>\n<p>\u201cChina est\u00e1 dispuesta a seguir trabajando de la mano con Corea del Norte para reforzar los intercambios y la cooperaci\u00f3n, avanzar en la construcci\u00f3n socialista y colaborar estrechamente en la promoci\u00f3n de la paz y la estabilidad regional, as\u00ed como en la defensa de la equidad y la justicia internacionales\u201d, dijo Hong.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El l\u00edder norcoreano Kim Jong Un y el presidente ruso, Vladimir Putin, estar\u00e1n entre m\u00e1s de dos docenas de jefes de Estado extranjeros que asistir\u00e1n la pr\u00f3xima semana al enorme desfile militar de China, anunci\u00f3 este jueves el Ministerio de Relaciones Exteriores de ese pa\u00eds. El desfile, que se celebrar\u00e1 el 3 de septiembre en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465942","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad - Noticias\" \/>\n<meta property=\"og:description\" content=\"El l\u00edder norcoreano Kim Jong Un y el presidente ruso, Vladimir Putin, estar\u00e1n entre m\u00e1s de dos docenas de jefes de Estado extranjeros que asistir\u00e1n la pr\u00f3xima semana al enorme desfile militar de China, anunci\u00f3 este jueves el Ministerio de Relaciones Exteriores de ese pa\u00eds. El desfile, que se celebrar\u00e1 el 3 de septiembre en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T18:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad\",\"datePublished\":\"2025-08-28T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\"},\"wordCount\":1037,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\",\"name\":\"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-28T18:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad - Noticias","og_description":"El l\u00edder norcoreano Kim Jong Un y el presidente ruso, Vladimir Putin, estar\u00e1n entre m\u00e1s de dos docenas de jefes de Estado extranjeros que asistir\u00e1n la pr\u00f3xima semana al enorme desfile militar de China, anunci\u00f3 este jueves el Ministerio de Relaciones Exteriores de ese pa\u00eds. El desfile, que se celebrar\u00e1 el 3 de septiembre en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-28T18:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/"},"author":{"name":"","@id":""},"headline":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad","datePublished":"2025-08-28T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/"},"wordCount":1037,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","name":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-28T18:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/28\/putin-kim-xi-desfile-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/08\/28\/putin-kim-xi-desfile-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/08\/28\/putin-kim-xi-desfile-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-28T18:03:47Z","datePublished":"2025-08-28T18:03:47Z","dateModified":"2025-08-28T18:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Kim y Putin encabezan la lista de invitados de Xi para el gran desfile militar de China en una desafiante muestra de unidad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/08\\\/28\\\/putin-kim-xi-desfile-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/08\\\/28\\\/putin-kim-xi-desfile-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-28T18:03:47Z\",\"datePublished\":\"2025-08-28T18:03:47Z\",\"dateModified\":\"2025-08-28T18:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466317,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/10\/analisis-kim-reconocimiento-potencia-nuclear-concedido-xi-trax\/","url_meta":{"origin":1465942,"position":0},"title":"Kim ha buscado durante mucho tiempo el reconocimiento como potencia nuclear. Puede que Xi se lo haya concedido","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"De las m\u00e1s de decenas de l\u00edderes extranjeros invitados al masivo desfile militar de Xi Jinping en Beijing la semana pasada, nadie obtuvo mayores beneficios diplom\u00e1ticos que Kim Jong Un.El solitario l\u00edder de Corea del Norte acapar\u00f3 la atenci\u00f3n mundial con un debut de alto perfil en la diplomacia multilateral,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466068,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/02\/xi-jinping-putin-conversaciones-formales-trax\/","url_meta":{"origin":1465942,"position":1},"title":"Putin elogia relaciones &#171;sin precedentes&#187; con China durante conversaciones formales con Xi en Beijing","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"El presidente de Rusia, Vladimir Putin, afirm\u00f3 este martes que la relaci\u00f3n con Beijing est\u00e1 en \u201cun nivel sin precedentes\u201d, en sus primeras conversaciones formales con su anfitri\u00f3n Xi Jinping desde que lleg\u00f3 a China este domingo.La reuni\u00f3n de ambos en el Gran Sal\u00f3n del Pueblo en Beijing es la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466199,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/06\/xi-jinping-pide-elegir-guerra-paz-china-trax\/","url_meta":{"origin":1465942,"position":2},"title":"Xi Jinping pide al mundo que elija &#171;guerra o paz&#187;. \u00bfHacia d\u00f3nde se dirige China?","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"La imagen no podr\u00eda haber sido m\u00e1s impactante cuando el l\u00edder chino Xi Jinping lleg\u00f3 a un enorme desfile militar en Beijing flanqueado por el presidente de Rusia, Vladimir Putin, y el l\u00edder norcoreano Kim Jong Un, seguido por una veintena de otros l\u00edderes, incluidos los de Ir\u00e1n, Pakist\u00e1n, Belar\u00fas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465995,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/30\/china-encuentro-putin-modi-xi-trump-trax\/","url_meta":{"origin":1465942,"position":3},"title":"China despliega la alfombra roja para Putin y Modi mientras Trump altera las relaciones globales","author":"","date":"agosto 30, 2025","format":false,"excerpt":"Aut\u00f3cratas, populistas, amigos y enemigos, un hombre fuerte que libra una guerra en Europa y el primer ministro de la mayor democracia del mundo ser\u00e1n recibidos por el presidente de China, Xi Jinping, este fin de semana en una cumbre dise\u00f1ada para mostrar al pa\u00eds como un l\u00edder global capaz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466280,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/09\/kim-jong-prueba-nuevo-motor-cohete-trax\/","url_meta":{"origin":1465942,"position":4},"title":"Un envalentonado Kim Jong Un supervisa la prueba de nuevo y potente motor de cohete norcoreano d\u00edas despu\u00e9s de visitar China","author":"","date":"septiembre 9, 2025","format":false,"excerpt":"Kim Jong Un presenci\u00f3 este lunes una prueba del nuevo motor de cohete de alto empuje de Corea del Norte, un evento que prepara el escenario para que Pyongyang pruebe su m\u00e1s nuevo misil bal\u00edstico intercontinental (ICBM), el Hwasong-20, que, seg\u00fan dijeron medios estatales la semana pasada, ser\u00eda propulsado por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466130,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/03\/xi-putin-hablando-inmortalidad-trasplantes-organos-trax\/","url_meta":{"origin":1465942,"position":5},"title":"Xi y Putin fueron escuchados hablando sobre inmortalidad y trasplantes de \u00f3rganos","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"El l\u00edder chino Xi Jinping fue captado hablando sobre la posibilidad de vivir hasta los 150 a\u00f1os en un momento de micr\u00f3fono abierto con el presidente de Rusia, Vladimir Putin, y el l\u00edder de Corea del Norte, Kim Jong Un, este mi\u00e9rcoles.La conversaci\u00f3n entre el mandatario chino, de 72 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1465942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1465942"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1465942\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1465942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1465942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1465942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}