{"id":1468046,"date":"2025-11-05T04:03:47","date_gmt":"2025-11-05T12:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/"},"modified":"2025-11-05T04:03:47","modified_gmt":"2025-11-05T12:03:47","slug":"triunfo-zohran-mamdani-futuro-nueva-york-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","title":{"rendered":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York"},"content":{"rendered":"<p>Al d\u00eda siguiente del <a href=\"https:\/\/www.cnn.com\/2023\/11\/02\/politics\/fbi-search-fundraiser-adams-campaign-new-york\">allanamiento a la casa del principal recaudador de fondos de Eric Adams<\/a>, los nuevos l\u00edderes del Partido de las Familias Trabajadoras, la coalici\u00f3n de grupos progresistas y sindicatos, enviaron invitaciones a una reuni\u00f3n secreta en noviembre de 2023.<\/p>\n<p>La izquierda vislumbr\u00f3 una forma de derrotar al alcalde que odiaban. Solo necesitaban un plan.<\/p>\n<p>En la sala com\u00fan de un edificio de apartamentos en Long Island City se congregaron el contralor municipal Brad Lander, el presidente del distrito de Brooklyn, Antonio Reynoso, y la senadora estatal Jessica Ramos.<\/p>\n<p>Zellnor Myrie, otro senador estatal que finalmente se postul\u00f3, estaba invitado, pero no asisti\u00f3.<\/p>\n<p>Tambi\u00e9n presente estaba Zohran Mamdani.<\/p>\n<p>Todos se sorprendieron al ver a Mamdani all\u00ed.<\/p>\n<p>\u201c\u00bfZohran? \u00bfZohran est\u00e1 pensando en presentarse?\u201d, dijo a CNN Ana Mar\u00eda Archila, copresidenta del Partido de las Familias Trabajadoras, quien ayud\u00f3 a organizar la reuni\u00f3n, mientras se iban conociendo los votos, recordando las reacciones que hubo.<\/p>\n<p>\u201cYo le dije: \u2018No lo s\u00e9, pero s\u00e9 que est\u00e1 pensando en qui\u00e9n deber\u00eda postularse\u2019\u201d, dijo Archila.<\/p>\n<p>En esa primera reuni\u00f3n y en varias posteriores, los otros candidatos potenciales m\u00e1s cercanos al anuncio mantuvieron sus planes en secreto, pero Mamdani participaba con entusiasmo, presentando y proponiendo ideas.<\/p>\n<p>Durante las charlas informales, insist\u00eda en que necesitaban encontrar un candidato que se presentara con la promesa de congelar los alquileres. Cre\u00f3 una plataforma y un equipo de trabajo a partir de los Socialistas Democr\u00e1ticos de Am\u00e9rica.<\/p>\n<p>El verano pasado, Mamdani le comunic\u00f3 a Archila que se postulaba.<\/p>\n<p>Quer\u00eda combinar la estrategia de la representante Alexandria Ocasio-Cortez y el concejal de Brooklyn, Chi Oss\u00e9, para romper con la pol\u00edtica tradicional, con una presencia impactante en redes sociales y un plan para tocar un mill\u00f3n de puertas, explic\u00f3.<\/p>\n<p>Pregunt\u00f3 cu\u00e1ndo anunciar\u00eda el Partido de las Familias Trabajadoras (WFP, por sus siglas en ingl\u00e9s) qu\u00e9 candidato encabezar\u00eda su lista de primarias y les respondi\u00f3: \u201cDenme todo el tiempo que necesite para prepararme\u201d.<\/p>\n<p>Por aquel entonces, Mamdani segu\u00eda viajando a Albany con su amigo y aliado cercano, Jabari Brisport. En el coche, alternaban entre cantar a todo pulm\u00f3n una lista de reproducci\u00f3n de Mika y canciones de musicales: \u201cHamilton\u201d, pero tambi\u00e9n \u201cDear Evan Hansen\u201d.<\/p>\n<p>\u201cWaving Through a Window\u201d era una de sus favoritas, al menos hasta que Mamdani acababa hablando por tel\u00e9fono desde el asiento del copiloto, atendiendo llamadas sin parar mientras la campa\u00f1a cobraba impulso, y luego hasta altas horas de la noche en las habitaciones de hotel que compart\u00edan.<\/p>\n<p>Este martes, Mamdani <a href=\"https:\/\/www.cnn.com\/2025\/11\/04\/politics\/nyc-mayor-zohran-mamdani-wins\">se present\u00f3 en el escenario<\/a> ante un sal\u00f3n de baile repleto en Brooklyn y una audiencia nacional, citando al socialista Eugene Debs y declar\u00e1ndose orgulloso de todo lo que es, como el primer alcalde musulm\u00e1n de la ciudad de Nueva York y el m\u00e1s joven en un siglo.<\/p>\n<p>\u201cContra todo pron\u00f3stico, lo hemos logrado\u201d, declar\u00f3 Mamdani, anunciando el inicio de lo que, seg\u00fan \u00e9l, ser\u00e1 la agenda m\u00e1s ambiciosa para abordar el problema de la asequibilidad desde que Fiorello LaGuardia fue alcalde en la d\u00e9cada de 1940. \u201cEl futuro est\u00e1 en nuestras manos\u201d.<\/p>\n<p>La hist\u00f3rica candidatura de Mamdani resuena en todo el mundo y en la pol\u00edtica dem\u00f3crata.<\/p>\n<p>Sus aliados rechazan las cr\u00edticas que afirman que no es un verdadero dem\u00f3crata o que sus ideas solo funcionar\u00edan en la ciudad de Nueva York, basti\u00f3n dem\u00f3crata, en lugar de en los estados con mayor diversidad pol\u00edtica que los dem\u00f3cratas deber\u00e1n ganar para recuperar el poder nacional.<\/p>\n<p>\u201cCreo que nadie se lo esperaba\u201d, dijo el defensor p\u00fablico Jumaane Williams, quien tambi\u00e9n asisti\u00f3 a las reuniones secretas, no porque fuera a postularse, sino porque quer\u00edan prepararse por si Adams renunciaba y \u00e9l asum\u00eda la alcald\u00eda interina. \u201cPero todos dijimos que apoyar\u00edamos aquello en lo que creemos\u201d.<\/p>\n<p>Pero cuando vot\u00f3 por s\u00ed mismo este martes por la ma\u00f1ana en el gimnasio de una escuela, record\u00f3 aquellas reuniones secretas.  En la boleta electoral como candidato dem\u00f3crata, Mamdani vot\u00f3 por s\u00ed mismo en la lista del Partido de las Familias Trabajadoras, que apoya a otros partidos, seg\u00fan confirm\u00f3 un asesor a CNN.<\/p>\n<p>La alcald\u00eda de Mamdani supondr\u00e1 enormes cambios para la ciudad de Nueva York y su gobierno. Ha <a href=\"https:\/\/www.cnn.com\/2025\/11\/04\/politics\/policy-ideas-zohran-mamdani-nyc-election\">prometido medidas dr\u00e1sticas<\/a> para que el transporte p\u00fablico sea gratuito y reducir el coste de la vida, incluyendo la apertura de supermercados estatales.<\/p>\n<p>Seg\u00fan las conversaciones de CNN con tres docenas de asesores, pol\u00edticos, operadores, donantes y otras personas involucradas en la campa\u00f1a de Mamdani y en la pol\u00edtica municipal, su llegada hasta aqu\u00ed tras su victoria en las primarias y lo que sucede ahora fue mucho m\u00e1s agitado de lo que podr\u00eda haber parecido una contienda contra un exgobernador ca\u00eddo en desgracia como Andrew Cuomo y un personaje neoyorquino perpetuamente exc\u00e9ntrico como Curtis Sliwa.<\/p>\n<p>\u201cSab\u00edamos que esta no iba a ser la \u00faltima fase de la lucha\u201d, dijo Archila, recordando la noche de las primarias. \u201cLos multimillonarios no gastaron US$ 30 millones solo para retirarse\u201d.<\/p>\n<p>Las encuestas internas de la campa\u00f1a de Mamdani tras las primarias los sorprendieron: nada, ni positivo ni negativo, parec\u00eda influir en el voto.<\/p>\n<p>Abandonaron el intento de convencer a los votantes y optaron por anuncios y videos humor\u00edsticos que parodiaban programas como \u201cThe Bachelor\u201d y \u201cSurvivor\u201d, los cuales se viralizaron entre sus seguidores. \u201cNos dejamos llevar por la energ\u00eda\u201d, coment\u00f3 una persona involucrada en la estrategia de campa\u00f1a.<\/p>\n<p>Para finales del verano, Archila y otros estaban algo preocupados por la campa\u00f1a de Mamdani.<\/p>\n<p>A veces parec\u00eda que la energ\u00eda que lo hab\u00eda impulsado como candidato con menos recursos se hab\u00eda agotado en parte.<\/p>\n<p>Tras adoptar un mensaje antioligarquista y una estrategia de responder a todas las preguntas y asistir a todos los eventos, Mamdani se tom\u00f3 unas vacaciones para celebrar su boda y, a su regreso, realiz\u00f3 una <a href=\"https:\/\/www.cnn.com\/2025\/07\/16\/politics\/mamdani-business-leaders-meeting-new-york\">gira privada por grupos empresariales y l\u00edderes municipales<\/a> con el fin de tranquilizarlos y, tal vez, incluso cambiar algunas opiniones.<\/p>\n<p>Bernie Sanders tambi\u00e9n se involucr\u00f3.<\/p>\n<p>Seg\u00fan una persona familiarizada con sus conversaciones, el senador de Vermont orden\u00f3 a sus asesores que rechazaran la petici\u00f3n de la campa\u00f1a de Mamdani de que participara en un encuentro con los votantes en Brooklyn, ciudad natal de Sanders.<\/p>\n<p>El senador argument\u00f3 que era necesario evitar que la contienda se consolidara en su contra, y cre\u00eda que su presencia como figura p\u00fablica podr\u00eda impulsar ese cambio.<\/p>\n<p>Pens\u00f3 que marchar en el desfile del D\u00eda del Trabajo se convertir\u00eda en un espect\u00e1culo, que todas las c\u00e1maras captar\u00edan im\u00e1genes de los funcionarios electos que lo rodeaban a \u00e9l y a Mamdani, y que, a su vez, obligar\u00eda a <a href=\"https:\/\/www.cnn.com\/2025\/09\/14\/politics\/kathy-hochul-zohran-mamdani\">la gobernadora Kathy Hochul,<\/a> que se manten\u00eda al margen, a acercarse mientras caminaban juntos por la Quinta Avenida sosteniendo una pancarta de unidad.<\/p>\n<p>El d\u00eda anterior, el primer viernes de septiembre, Sanders pas\u00f3 por el estudio del podcast de Trevor Noah.<\/p>\n<p>Estaba saliendo del ba\u00f1o antes de que comenzara la grabaci\u00f3n cuando un asistente le mostr\u00f3 un tel\u00e9fono con el video <a href=\"https:\/\/www.cnn.com\/2025\/09\/05\/politics\/video\/mayor-adams-nyc-andrew-cuomo-snake-vrtc\" rel=\"noopener noreferrer\" target=\"_blank\">reci\u00e9n publicado de Eric Adams<\/a> en la Mansi\u00f3n Gracie, donde llamaba a Cuomo \u201cuna serpiente y un mentiroso\u201d, incluyendo al exgobernador junto con Mamdani como \u201cdos mocosos malcriados\u201d a los que estaba decidido a derrotar.<\/p>\n<p>\u201c\u00a1Muy bien!\u201d, exclam\u00f3 el senador de Vermont, levantando el pu\u00f1o.<\/p>\n<p>Seg\u00fan Sanders, la permanencia de Adams facilitar\u00eda la vuelta a la normalidad.<\/p>\n<p>\u201cAun as\u00ed, se retirar\u00e1\u201d, dijo el senador, seg\u00fan una persona que transmiti\u00f3 la reacci\u00f3n a CNN, \u201cpero esta es una muy buena noticia\u201d.<\/p>\n<p>Cuomo y sus asesores presenciaron el mismo evento de Adams, intentando convencerse de que no importaba mucho si Adams segu\u00eda en la contienda, seg\u00fan una persona familiarizada con el asunto.<\/p>\n<p>Pero el exgobernador llevaba meses obsesionado con sacar a Adams de la carrera, incluso antes de que Cuomo lanzara su campa\u00f1a para las primarias en febrero, bas\u00e1ndose en una sensaci\u00f3n de inevitabilidad.<\/p>\n<p>\u201cTengo que sacar a Adams y a Sliwa del poder y entonces ganar\u00e9\u201d, repet\u00eda Cuomo, seg\u00fan un colaborador que habl\u00f3 con \u00e9l, pero que no se uni\u00f3 a su campa\u00f1a. \u201cS\u00e9 a qui\u00e9n llamar, s\u00e9 a qui\u00e9n presionar\u201d.<\/p>\n<p>Tres semanas despu\u00e9s, cuando Adams se retir\u00f3 definitivamente \u2014ya fuera del plazo que los asesores de Sanders y Mamdani consideraban relevante\u2014, el equipo de Cuomo ten\u00eda dificultades para discrepar. <a href=\"https:\/\/www.cnn.com\/2025\/10\/20\/politics\/curtis-sliwa-nyc-mayoral-race\">Sliwa nunca lo hizo<\/a>. A lo sumo, seg\u00fan declar\u00f3 un asesor a CNN, ahora ten\u00edan \u201cuna oportunidad\u201d.<\/p>\n<p>\u201cTe enfrentas al candidato dem\u00f3crata en Nueva York, pero es un candidato dem\u00f3crata con muchos defectos\u201d, dijo el asesor, insistiendo sobre Mamdani: \u201cNo creo que el entusiasmo sea el mismo que en las primarias\u201d.<\/p>\n<p>El martes, Mamdani derrot\u00f3 a Cuomo con facilidad de todos modos.<\/p>\n<p>Cuando Sanders regres\u00f3 a Nueva York para el mitin de cierre de campa\u00f1a en el estadio Forest Hills de Queens el \u00faltimo domingo de octubre, se sent\u00eda m\u00e1s optimista sobre las posibilidades de Mamdani.<\/p>\n<p>Sin embargo, ten\u00eda otras preocupaciones, las cuales expuso en numerosas reuniones en su sala privada tras bambalinas, seg\u00fan una persona presente.<\/p>\n<p>Rechaz\u00f3 las peticiones de selfies y apretones de manos y, en cambio, exigi\u00f3 planes m\u00e1s detallados a <a href=\"https:\/\/www.cnn.com\/2025\/07\/25\/politics\/mamdani-names-new-campaign-manager\">la jefa de transici\u00f3n<\/a> de Mamdani, Elle Bisgaard-Church, y a la jefa de campa\u00f1a, Maya Handa.<\/p>\n<p>En un momento dado, Sanders le pidi\u00f3 a la expresidenta de la Comisi\u00f3n Federal de Comercio, Lina Khan, sus ideas sobre qu\u00e9 hacer en el Ayuntamiento.<\/p>\n<p>Sanders, quien tambi\u00e9n fue alcalde, se centr\u00f3 en los primeros 100 d\u00edas, dici\u00e9ndoles: \u201cIntentar\u00e1n aplastarlos\u201d, e inst\u00e1ndolos: \u201cTienen que darles a las personas un sentido de acci\u00f3n\u201d.<\/p>\n<p>Sanders les dijo: \u201cAprendan un poco de Trump: no se trata de pol\u00edtica <em>ni<\/em> de comunicaci\u00f3n, sino de verlas como lo mismo y que produzcan resultados\u201d.<\/p>\n<p>\u201c\u00bfHan investigado sus facultades ejecutivas? \u00bfTienen a alguien encargado de eso?\u201d, pregunt\u00f3 Sanders. Sus asesores ofrecieron ideas en las que hab\u00edan estado trabajando. \u201c\u00bfQu\u00e9 m\u00e1s tienen?\u201d, insisti\u00f3.<\/p>\n<p>El s\u00e1bado anterior a las elecciones, Mamdani y sus asesores ya vislumbraban la victoria. Y eso fue antes de que escuchara la voz de Barack Obama al tel\u00e9fono.<\/p>\n<p>Mamdani comenz\u00f3 agradeciendo a Obama el consejo que le dio en su \u00faltima llamada, durante el verano, sobre la necesidad de concentrarse en gobernar bien. Hab\u00eda estado pensando mucho en ello, manifest\u00f3 Mamdani.<\/p>\n<p>\u201cQuiero que seas un alcalde exitoso\u201d, reiter\u00f3 Obama, \u201cy eso significa brindar servicios y cubrir todas las necesidades b\u00e1sicas\u201d. \u201cNecesita contar con m\u00e1s profesionales a su alrededor\u201d, expres\u00f3 Obama en conversaciones privadas, expresando su preocupaci\u00f3n.<\/p>\n<p>Nunca se hab\u00edan conocido. Era solo la segunda vez que hablaban. Pero durante los 30 minutos, la atm\u00f3sfera, seg\u00fan la describi\u00f3 una persona familiarizada con la llamada, era palpable: no se mencion\u00f3 nada de los tuits anteriores de Mamdani en los que llamaba a Obama mentiroso y \u201cbastante malvado\u201d, sino que se mostr\u00f3 m\u00e1s acorde con la estrategia actual del expresidente, que combina su eterna fascinaci\u00f3n por otros candidatos j\u00f3venes y carism\u00e1ticos con el nuevo papel que est\u00e1 asumiendo como figura clave del partido, intentando comprender la cambiante pol\u00edtica de la izquierda.<\/p>\n<p>Mamdani tambi\u00e9n le agradeci\u00f3 su discurso sobre la raza de 2008, que, seg\u00fan dijo, le hab\u00eda servido de modelo para su propio discurso sobre islamofobia dos semanas antes, a diferencia de un discurso sobre antisemitismo que hab\u00eda revisado y decidido no pronunciar al principio de la campa\u00f1a.<\/p>\n<p>Sorprendi\u00f3 a Obama al <a href=\"https:\/\/www.cnn.com\/2021\/08\/02\/entertainment\/obama-in-pursuit-of-a-more-perfect-union-review\">usar el t\u00edtulo formal del discurso de 2008<\/a>: \u201cUna Uni\u00f3n M\u00e1s Perfecta\u201d.<\/p>\n<p>Eso es halagador, le dijo Obama, pero luego le devolvi\u00f3 la jugada: \u201cLa raz\u00f3n por la que has tenido tanto \u00e9xito es porque tienes un profundo sentido de lo que crees\u201d, le dijo el expresidente, seg\u00fan una persona familiarizada con la llamada.<\/p>\n<p>Obama le manifest\u00f3 que acudiera a \u00e9l si necesitaba consejo durante el proceso. Hicieron un plan informal para reunirse pronto.<\/p>\n<p>Hace semanas, Mamdani se quejaba entre bastidores con un amigo de que no entend\u00eda por qu\u00e9 todos le presionaban para que ya tuviera un plan de transici\u00f3n trazado.<\/p>\n<p>Junto con sus asesores m\u00e1s cercanos, ya estaba elaborando listas de posibles nombramientos para los puestos m\u00e1s importantes.<\/p>\n<p>Con algunos hab\u00eda hablado, con otros no.<\/p>\n<p>El martes comenzaron a realizarse llamadas a personas que llevaban semanas esperando noticias, inform\u00e1ndoles de que deb\u00edan esperar ser nombradas para una comisi\u00f3n de transici\u00f3n de Mamdani.<\/p>\n<p>A\u00fan queda pendiente su sorpresiva declaraci\u00f3n en el \u00faltimo debate para la alcald\u00eda, donde afirm\u00f3 que <a href=\"https:\/\/www.cnn.com\/2025\/10\/26\/politics\/jessica-tisch-zohran-mamdani-election\">le pedir\u00eda a la comisionada de polic\u00eda Jessica Tisch<\/a> que permaneciera en el cargo.<\/p>\n<p>Posteriormente, declar\u00f3 a CNN que no le hab\u00eda consultado directamente a Tisch.<\/p>\n<p>Dos posibles futuros asesores de Mamdani manifestaron a CNN su consternaci\u00f3n ante la negligencia que, a su juicio, representar\u00eda el hecho de que no hubiera recibido ninguna se\u00f1al de su parte y las implicaciones que esto podr\u00eda tener para su gesti\u00f3n futura.<\/p>\n<p>Una persona que por ahora est\u00e1 fuera de escena es Brad Lander, el interventor municipal que estuvo en esa primera reuni\u00f3n de Working Families y que m\u00e1s tarde se ali\u00f3 con Mamdani bajo el sistema de votaci\u00f3n por orden de preferencia de las primarias.<\/p>\n<p>Cuando las esperanzas de Lander en las primarias empezaron a desvanecerse en primavera, relanz\u00f3 su campa\u00f1a como una m\u00e1quina de desmantelar a Cuomo, con una estrategia expl\u00edcita de atacarlo sin piedad: reemplaz\u00f3 sus anuncios con uno anti-Cuomo, y bas\u00f3 cada evento y guion de llamadas autom\u00e1ticas en la negatividad, para que, seg\u00fan calcularon sus asesores, Mamdani pudiera cerrar con una imagen positiva y esperanzadora.<\/p>\n<p>Incluso envi\u00f3 a un asistente con mucha antelaci\u00f3n al lugar del debate para encontrar el asiento exacto donde el hijo de un hombre que falleci\u00f3 en una residencia de ancianos bajo la tutela de Cuomo durante la pandemia de covid-19 estuviera tanto en el encuadre como en el campo de visi\u00f3n del exgobernador.<\/p>\n<p>Y, quiz\u00e1s lo m\u00e1s importante, Lander, figurativa y literalmente, apoy\u00f3 incondicionalmente a Mamdani, d\u00e1ndole credibilidad ante los progresistas esc\u00e9pticos y, en particular, ante el electorado jud\u00edo.<\/p>\n<p>Pero durante el verano, Mamdani confes\u00f3 que Lander no le impresionaba mucho. \u201cEs un buen tipo, pero no parec\u00eda especialmente eficaz como contralor\u201d, indic\u00f3 Mamdani, seg\u00fan una persona familiarizada con sus comentarios.<\/p>\n<p>Pasaron semanas sin hablarse, y aunque Lander se pon\u00eda a la defensiva y culpaba a las vacaciones postelectorales que coincid\u00edan, todo su discurso de que \u00e9l ser\u00eda quien realmente gobernar\u00eda la ciudad el pr\u00f3ximo a\u00f1o hab\u00eda llegado a o\u00eddos de Mamdani y no le hab\u00eda sentado bien.<\/p>\n<p>El fin de semana previo a las elecciones, la esposa de Lander coment\u00f3 a sus amigos en una fiesta que Mamdani hab\u00eda llamado para decirle al contralor que no tendr\u00eda trabajo en la administraci\u00f3n, ya que no le hab\u00edan otorgado el puesto que deseaba.<\/p>\n<p>El d\u00eda antes de las elecciones, Lander contact\u00f3 a importantes donantes para solicitar compromisos de apoyo para su candidatura al Congreso contra el representante Dan Goldman, seg\u00fan una fuente cercana al asunto.<\/p>\n<p>Lander declin\u00f3 hacer comentarios sobre sus planes el martes por la noche.<\/p>\n<p>\u201cYo dir\u00eda que esto es el comienzo de algo, no el final\u201d, dijo Lander, \u201cy tenemos que seguir adelante\u201d.<\/p>\n<p>Incluso antes del martes por la noche, sus oponentes ya estaban haciendo sus propios planes para lo que viene a continuaci\u00f3n.<\/p>\n<p>Durante su recorrido por Hell\u2019s Kitchen el domingo por la noche, como parte de su campa\u00f1a final, el candidato republicano Curtis Sliwa predijo su propio papel tras una victoria de Mamdani.<\/p>\n<p>\u201cMe autoproclamar\u00e9 alcalde en el exilio, vigilar\u00e9 de cerca sus acciones como alcalde y, cada vez que se extralimite \u2014lo cual har\u00e1\u2014, organizar\u00e9 la oposici\u00f3n, protestar\u00e9, utilizar\u00e9 todos los medios necesarios, excepto la violencia, e intentar\u00e9 frenar sus iniciativas\u201d, declar\u00f3 Sliwa a CNN, a\u00f1adiendo que esperaba que Cuomo se mudara de nuevo fuera de la ciudad. (No est\u00e1 claro si Cuomo realmente lo har\u00e1).<\/p>\n<p>Si bien varios miembros potenciales de la administraci\u00f3n Mamdani han restado importancia a las consecuencias de las amenazas de Trump de retirar fondos a la ciudad o de tomar represalias, otros afirman creer que Mamdani podr\u00e1 ser el mensajero que los dem\u00f3cratas a nivel nacional necesitan.<\/p>\n<p>John Catsimatidis, el multimillonario amigo de Trump que intent\u00f3 impulsar a Cuomo y fracas\u00f3 en su intento de expulsar a Sliwa, estuvo diciendo regularmente a la gente durante todo el oto\u00f1o que alguna novedad iba a surgir contra Mamdani \u201cla semana que viene\u201d y luego \u201cla semana que viene\u201d otra vez.<\/p>\n<p>A pesar de todo lo que Mamdani supo aprovechar y de la campa\u00f1a que llev\u00f3 a cabo, Catsimatidis afirma que a\u00fan busca una explicaci\u00f3n a lo que para otros resulta tan obvio sobre el candidato y sobre lo que \u00e9l supo aprovechar.<\/p>\n<p>Ofreci\u00f3 una predicci\u00f3n potencialmente ominosa, dados los procesos judiciales del Departamento de Justicia contra personas que Trump considera enemigas, incluida la fiscal general de Nueva York, Tish James.<\/p>\n<p>\u201cHay algo m\u00e1s que no sabemos\u201d, dijo Catsimatidis, \u201cy alg\u00fan d\u00eda lo descubriremos\u201d.<\/p>\n<p>Pero por ahora, hay esperanza.<\/p>\n<p>El representante estadounidense Ro Khanna de California, el legislador de Silicon Valley convertido en seguidor de Sanders, acudi\u00f3 a Queens el \u00faltimo fin de semana para hablar como un destacado pol\u00edtico hind\u00fa en un mitin dirigido principalmente a votantes musulmanes de origen indio.<\/p>\n<p>Tuvo que esperar a que Mamdani terminara de hablar con Obama, tiempo que aprovech\u00f3 para charlar efusivamente con la madre de Mamdani, la cineasta india Mira Nair.<\/p>\n<p>Cuando la camioneta de Mamdani se detuvo en el Parque Major Mark, el candidato y Khanna apenas tuvieron un instante a solas. Mientras Nair permanec\u00eda con ellos, Khanna intent\u00f3 hablar un poco de hindi, aunque sab\u00eda que no lo dominaba con la misma fluidez que Mamdani.<\/p>\n<p>\u201c<em>Kahan se kahan<\/em>\u201d, manifest\u00f3, que significa: \u201cdesde donde empezaste hasta d\u00f3nde has llegado ahora\u201d.<\/p>\n<p>Mamdani le dedic\u00f3 una de sus grandes sonrisas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al d\u00eda siguiente del allanamiento a la casa del principal recaudador de fondos de Eric Adams, los nuevos l\u00edderes del Partido de las Familias Trabajadoras, la coalici\u00f3n de grupos progresistas y sindicatos, enviaron invitaciones a una reuni\u00f3n secreta en noviembre de 2023. La izquierda vislumbr\u00f3 una forma de derrotar al alcalde que odiaban. Solo necesitaban [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468046","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al d\u00eda siguiente del allanamiento a la casa del principal recaudador de fondos de Eric Adams, los nuevos l\u00edderes del Partido de las Familias Trabajadoras, la coalici\u00f3n de grupos progresistas y sindicatos, enviaron invitaciones a una reuni\u00f3n secreta en noviembre de 2023. La izquierda vislumbr\u00f3 una forma de derrotar al alcalde que odiaban. Solo necesitaban [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T12:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York\",\"datePublished\":\"2025-11-05T12:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\"},\"wordCount\":3158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\",\"name\":\"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-05T12:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York - Noticias","og_description":"Al d\u00eda siguiente del allanamiento a la casa del principal recaudador de fondos de Eric Adams, los nuevos l\u00edderes del Partido de las Familias Trabajadoras, la coalici\u00f3n de grupos progresistas y sindicatos, enviaron invitaciones a una reuni\u00f3n secreta en noviembre de 2023. La izquierda vislumbr\u00f3 una forma de derrotar al alcalde que odiaban. Solo necesitaban [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-05T12:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/"},"author":{"name":"","@id":""},"headline":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York","datePublished":"2025-11-05T12:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/"},"wordCount":3158,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","name":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-05T12:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La historia interna del triunfo de Zohran Mamdani y qu\u00e9 le depara el futuro a Nueva York","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/triunfo-zohran-mamdani-futuro-nueva-york-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-05T12:03:47Z","datePublished":"2025-11-05T12:03:47Z","dateModified":"2025-11-05T12:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La historia interna del triunfo de Zohran Mamdani y qu\\u00e9 le depara el futuro a Nueva York\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/05\\\/triunfo-zohran-mamdani-futuro-nueva-york-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/05\\\/triunfo-zohran-mamdani-futuro-nueva-york-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-05T12:03:47Z\",\"datePublished\":\"2025-11-05T12:03:47Z\",\"dateModified\":\"2025-11-05T12:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463965,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/26\/zohran-mamdani-alcaldia-nueva-york-mira-nair-trax\/","url_meta":{"origin":1468046,"position":0},"title":"Zohran Mamdani fue un disruptor en las primarias para la alcald\u00eda de Nueva York. Su madre hizo algo similar en Hollywood","author":"","date":"junio 26, 2025","format":false,"excerpt":"Si Zohran Mamdani se ve c\u00f3modo ante la c\u00e1mara, hay una raz\u00f3n para ello.El socialdem\u00f3crata de 33 a\u00f1os sorprendi\u00f3 al mundo pol\u00edtico tras recibir el respaldo de los votantes en las primarias dem\u00f3cratas a la alcald\u00eda el martes. El resultado oficial no se conocer\u00e1 hasta al menos el 1 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464126,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/01\/trump-arrestaria-zohran-mamdani-si-desafia-ice-nueva-york-trax\/","url_meta":{"origin":1468046,"position":1},"title":"Donald Trump dice que &#171;tendr\u00eda que arrestar&#187; a Zohran Mamdani si desaf\u00eda a los agentes de inmigraci\u00f3n en Nueva York","author":"","date":"julio 1, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump dijo que \u201ctendr\u00e1 que arrestar\u201d Zohran Mamdani \u2014quien se alz\u00f3 con la victoria en las primarias dem\u00f3cratas para la alcald\u00eda de Nueva York este martes\u2014 si desaf\u00eda al Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE) en la ciudad de Nueva\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469708,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/01\/zohran-mamdani-asume-alcalde-nueva-york-trax\/","url_meta":{"origin":1468046,"position":2},"title":"Zohran Mamdani asume como alcalde de la ciudad de Nueva York","author":"","date":"enero 1, 2026","format":false,"excerpt":"Zohran Mamdani, el socialista democr\u00e1tico que hizo campa\u00f1a con la promesa de enfrentar la crisis de asequibilidad en una de las ciudades m\u00e1s caras de Estados Unidos, jur\u00f3 este jueves como el 112.\u00ba alcalde de la ciudad de Nueva York.Mamdani, un inmigrante de 34 a\u00f1os originario de Uganda, hace historia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468037,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/04\/ideas-politicas-zohran-mamdani-trax\/","url_meta":{"origin":1468046,"position":3},"title":"Un vistazo a las ideas pol\u00edticas de Zohran Mamdani","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Zohran Mamdani, el candidato dem\u00f3crata y favorito en la carrera por la alcald\u00eda de la ciudad de Nueva York, tiene m\u00faltiples propuestas que han generado un inter\u00e9s significativo durante una campa\u00f1a en la que busc\u00f3 que la ciudad sea m\u00e1s asequible.Sus propuestas incluyen un plan para crear el primer programa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468525,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/19\/trump-reunion-alcalde-nueva-york-zohran-mamdani-trax\/","url_meta":{"origin":1468046,"position":4},"title":"Trump dice que se reunir\u00e1 con el alcalde electo de Nueva York, Zohran Mamdani, el viernes en la Oficina Oval","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 este mi\u00e9rcoles que planea recibir al alcalde electo de la ciudad de Nueva York, Zohran Mamdani, el viernes en la Oficina Oval, en la primera reuni\u00f3n cara a cara entre ambos desde que el joven pol\u00edtico gan\u00f3 los comicios a principios de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471546,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/22\/zohran-mamdani-prohibe-viajes-nyc-tormenta-nieve-trax\/","url_meta":{"origin":1468046,"position":5},"title":"Zohran Mamdani proh\u00edbe viajes por Nueva York debido a la tormenta de nieve","author":"","date":"febrero 22, 2026","format":false,"excerpt":"El alcalde de la ciudad de Nueva York, Zohran Mamdani, prohibi\u00f3 la mayor\u00eda de los viajes en la ciudad m\u00e1s grande del pa\u00eds desde las 9 p.m. del domingo hasta el mediod\u00eda del lunes, una medida extraordinaria que refleja la prueba que representa una ventisca hist\u00f3rica que azota la regi\u00f3n.Mamdani\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468046"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468046\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}