{"id":1468047,"date":"2025-11-05T05:03:49","date_gmt":"2025-11-05T13:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/"},"modified":"2025-11-05T05:03:49","modified_gmt":"2025-11-05T13:03:49","slug":"accidente-avion-ups-devasta-louisville-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","title":{"rendered":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos"},"content":{"rendered":"<p>Cuando los negocios empezaban a cerrar en Louisville, Kentucky, este martes, al atardecer, la calma se vio repentinamente interrumpida por una explosi\u00f3n gigantesca cerca del aeropuerto de la ciudad.<\/p>\n<p>Un avi\u00f3n de carga de UPS se estrell\u00f3 poco despu\u00e9s de despegar del Aeropuerto Internacional Muhammad Ali de Louisville, arrasando varios negocios, incluida una empresa de reciclaje de residuos que almacena tanques de petr\u00f3leo y propano.<\/p>\n<p>Con m\u00e1s de 38.000 galones de combustible a bordo del vuelo de carga con destino a Hawai, el accidente cre\u00f3 una enorme bola de fuego \u2014seguida por detonaciones m\u00e1s peque\u00f1as de material inflamable en tierra\u2014 y lanz\u00f3 una imponente columna de humo negro al cielo.<\/p>\n<p>Al menos siete personas murieron y once resultaron heridas en el accidente, seg\u00fan inform\u00f3 el gobernador de Kentucky, Andy Beshear, en las redes sociales el martes por la noche, advirtiendo que esas cifras podr\u00edan aumentar a medida que contin\u00faa la investigaci\u00f3n del accidente.<\/p>\n<p>Las \u00fanicas tres personas a bordo del vuelo \u2014todos miembros de la tripulaci\u00f3n\u2014 se presumen fallecidas, seg\u00fan informaron las autoridades.<\/p>\n<p>Las otras cuatro personas cuya muerte se confirm\u00f3 no se encontraban en el avi\u00f3n, declar\u00f3 el alcalde de Louisville, Craig Greenberg, en una rueda de prensa el martes por la noche.<\/p>\n<p>Una empleada de tierra declar\u00f3 a CNN que recibi\u00f3 un aviso de una explosi\u00f3n en la zona de UPS del aeropuerto y corri\u00f3 hacia all\u00ed para ver qu\u00e9 ocurr\u00eda. Una vez all\u00ed, escuch\u00f3 varios estallidos m\u00e1s mientras ve\u00eda c\u00f3mo aumentaba el humo.<\/p>\n<p>\u201cSegu\u00ed buscando a los bomberos y a los socorristas y no pod\u00eda respirar hasta que vi esas luces de emergencia intermitentes, los camiones de bomberos llegando\u201d, cont\u00f3 la empleada, que pidi\u00f3 permanecer en el anonimato.<\/p>\n<p>A cinco millas (8 km) del aeropuerto, Amanda Rhye, residente de Louisville, se encontraba en un supermercado cuando vio el humo e inmediatamente supo que \u201cten\u00eda que ser algo grave\u201d, declar\u00f3 a CNN.<\/p>\n<p>\u201cTodos los que me rodeaban tambi\u00e9n se dieron cuenta. Unas dos docenas de personas dejaron de hacer lo que estaban haciendo y se quedaron mirando c\u00f3mo la nube crec\u00eda r\u00e1pidamente\u2026 en 20 minutos, la enorme nube negra estaba sobre nosotros en el cielo\u201d, narr\u00f3.<\/p>\n<p>Cientos de bomberos fueron desplegados para contener el incendio y buscar v\u00edctimas en los alrededores, inform\u00f3 el jefe del Departamento de Bomberos de Louisville, Brian O\u2019Neill, en la rueda de prensa del martes.<\/p>\n<p>\u201cCuando se produce un incidente de tal magnitud y un incendio que se extiende por una zona tan extensa, tenemos que utilizar cientos de personas para rodearlo, contenerlo y luego controlarlo poco a poco\u201d, explic\u00f3 O\u2019Neill, y a\u00f1adi\u00f3 que el lugar ahora es lo suficientemente seguro para que los equipos puedan extinguir los focos de incendio restantes y \u201ccrear una cuadr\u00edcula formal\u201d para buscar en los alrededores.<\/p>\n<p>\u201cSe trata de bomberos capacitados de toda la regi\u00f3n que se est\u00e1n encargando de la b\u00fasqueda, cuadr\u00edcula por cuadr\u00edcula, con mucho cuidado para asegurarnos de encontrar a cualquier otra v\u00edctima\u201d, apunt\u00f3 el jefe de Bomberos.<\/p>\n<p>Josh Mitcham acababa de abordar un avi\u00f3n en el aeropuerto de Louisville cuando mir\u00f3 por la ventana y vio una oscura nube de humo que se elevaba hacia el cielo.<\/p>\n<p>\u201cRealmente no sab\u00edamos qu\u00e9 hab\u00eda pasado\u201d, dijo Mitcham a CNN. \u201cEl capit\u00e1n se acerc\u00f3 y dijo que hab\u00eda habido un accidente, que no era bueno y que recomendaban que baj\u00e1ramos del avi\u00f3n\u201d.<\/p>\n<p>El avi\u00f3n de carga MD-11 de UPS se estrell\u00f3 poco despu\u00e9s de las 5 p.m. tras despegar con destino a Honolulu, seg\u00fan la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s).<\/p>\n<p>La FAA est\u00e1 investigando las causas del accidente junto con la Junta Nacional de Seguridad del Transporte (NTSB, por sus siglas en ingl\u00e9s), inform\u00f3 la agencia.<\/p>\n<p>En un audio de los bomberos de Louisville, un operador intenta mantener la calma mientras llegan los primeros detalles sobre una \u201cposible explosi\u00f3n\u201d.<\/p>\n<p>Cuando una persona pregunta cu\u00e1ntos edificios est\u00e1n en llamas, alguien responde que son al menos dos estructuras.<\/p>\n<p>El gobernador Beshear declar\u00f3 posteriormente que al menos dos negocios resultaron afectados: una tienda de autopartes y la empresa Kentucky Petroleum Recycling.<\/p>\n<p>Una planta de Ford Motor cercana tambi\u00e9n se qued\u00f3 sin electricidad tras el accidente a\u00e9reo, a\u00f1adi\u00f3 Beshear.<\/p>\n<p>O\u2019Neill dijo que el choque rompi\u00f3 algunos tanques en la planta de reciclaje y provoc\u00f3 \u201cexplosiones secundarias\u201d.<\/p>\n<p>Se\u00f1al\u00f3 que algunas de las cosas que pudieron haber sonado como explosiones eran en realidad v\u00e1lvulas de alivio que liberaban presi\u00f3n como est\u00e1n dise\u00f1adas para hacerlo.<\/p>\n<p>El incendio generado por el accidente est\u00e1 en gran medida \u201ccontrolado y contenido\u201d, pero el \u00e1rea alrededor de las instalaciones \u201cseguir\u00e1 siendo un desastre\u2026 debido a las fugas de combustible y aceite\u201d, indic\u00f3 O\u2019Neill.<\/p>\n<p>El avi\u00f3n no transportaba ninguna carga peligrosa que pudiera generar un problema ambiental, declar\u00f3 Beshear. Sin embargo, las autoridades est\u00e1n monitoreando la calidad del aire en Louisville tras el accidente, inform\u00f3 el alcalde.<\/p>\n<p>Inicialmente se emiti\u00f3 una orden de confinamiento para todos los lugares ubicados dentro de un radio de cinco millas (8 km) del aeropuerto, pero posteriormente se redujo a un radio de una milla (1,6 km), seg\u00fan informaron los funcionarios de emergencia.<\/p>\n<p>Tras el accidente, Justin Dunn, residente de Louisville, y su hijo observaron c\u00f3mo ca\u00edan del cielo lo que parec\u00edan ser escombros.<\/p>\n<p>\u201cMi hijo me dijo: \u2018Oye, mira al cielo\u2019, y estaba cayendo del cielo y \u00e9l lo recogi\u00f3\u201d, dijo Dunn a <a href=\"https:\/\/www.wave3.com\/2025\/11\/05\/fell-out-sky-witnesses-find-aircraft-pieces-hawaiian-dresses-debris-after-ups-plane-crash\/\">la filial de CNN, WAVE<\/a>, mientras sosten\u00eda un trozo de papel que, seg\u00fan \u00e9l, estaba entre los escombros.<\/p>\n<p>\u201cDefinitivamente hay escombros por todas partes, probablemente en un radio de 16 kil\u00f3metros\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Las autoridades piden a los residentes que no toquen ning\u00fan resto que encuentren y que, en su lugar, tomen una fotograf\u00eda y lo reporten a las autoridades.<\/p>\n<p>Debido a la orden de confinamiento, las Escuelas P\u00fablicas del Condado de Jefferson de Louisville, el distrito escolar m\u00e1s grande de Kentucky, permanecer\u00e1n cerradas el mi\u00e9rcoles.<\/p>\n<p>El aeropuerto de Louisville detuvo las operaciones tras el accidente, pero se espera que vuelva a abrir el mi\u00e9rcoles, seg\u00fan el alcalde.<\/p>\n<p>Louisville alberga el centro de distribuci\u00f3n a\u00e9rea mundial de UPS, Worldport, que constituye un pilar fundamental de la econom\u00eda de la ciudad.<\/p>\n<p>Seg\u00fan la empresa, m\u00e1s de 12.000 empleados procesan m\u00e1s de 22 millones de paquetes al d\u00eda.<\/p>\n<p>\u201cNuestros pensamientos est\u00e1n con todos los afectados. UPS est\u00e1 comprometida con la seguridad de nuestros empleados, nuestros clientes y las comunidades a las que servimos. Esto es especialmente cierto en Louisville, sede de nuestra aerol\u00ednea y de miles de empleados de UPS\u201d, declar\u00f3 la compa\u00f1\u00eda en un comunicado.<\/p>\n<p>El puente Big Four, que conecta Louisville y Jeffersonville, Indiana, sobre el r\u00edo Ohio, se ilumin\u00f3 con luces amarillas el martes por la noche en honor al vuelo accidentado de UPS, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fx.com%2FLouisvilleMayor%2Fstatus%2F1985885264544149933&#038;data=05%7C02%7Ckarina.tsui%40cnn.com%7Cc0524ed7846743b49a8608de1c0ed91d%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638979047535038815%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=JW6eXa%2F88tYEnI4Spz1OQwXpQzTEt%2Bf4OEh%2B%2BxLit2A%3D&#038;reserved=0\">seg\u00fan inform\u00f3<\/a> Greenberg en las redes sociales.<\/p>\n<p>\u201cEsta tragedia ha afectado a todos los rincones de nuestra ciudad. Mientras el horizonte de Louisville se ilumina de amarillo, pensamos en las vidas perdidas, las familias que han cambiado para siempre y en toda la comunidad que llama a Louisville su hogar\u201d, escribi\u00f3, acompa\u00f1ando una fotograf\u00eda del puente.<\/p>\n<p>Louisville \u201ces una ciudad de UPS\u201d, dijo la concejala Betsy Ruhe en una conferencia de prensa el martes.<\/p>\n<p>\u201cMi primo es piloto de UPS. El compa\u00f1ero de tenis de mi asistente es piloto de UPS. El becario de mi oficina trabaja de noche en UPS para pagarse la universidad\u201d, dijo Ruhe.<\/p>\n<p>\u201cTodos conocemos a alguien que trabaja en UPS, y todos est\u00e1n enviando mensajes de texto a sus amigos y familiares, tratando de asegurarse de que todos est\u00e9n a salvo. Lamentablemente, es probable que algunos de esos mensajes queden sin respuesta\u201d, agreg\u00f3.<\/p>\n<p>La senadora estatal de Kentucky, Keturah Herron, describi\u00f3 el accidente como \u201cimpactante\u201d tras ocurrir \u201ctan cerca de casa\u201d.<\/p>\n<p>\u201cQue esto ocurra en un lugar que muchos de nosotros frecuentamos habitualmente, por donde muchos vemos pasar a nuestros familiares y seres queridos con regularidad\u2026 es muy doloroso\u201d, sostuvo.<\/p>\n<p>Dunn, residente de Louisville que encontr\u00f3 algunos restos del avi\u00f3n, coment\u00f3 que no hab\u00eda podido contactar con sus amigos que trabajan para UPS. \u201cSolo espero que todos est\u00e9n bien\u201d, expres\u00f3.<\/p>\n<p>El sindicato Teamsters, para el cual UPS es su <a href=\"https:\/\/about.ups.com\/us\/en\/newsroom\/negotiations\/negotiations-basics\/ups-and-the-teamsters.html\">mayor empleador en el pa\u00eds<\/a>, emiti\u00f3 un comunicado diciendo que estaba monitoreando los acontecimientos relacionados con el accidente.<\/p>\n<p>\u201cMientras se investiga esta horrible escena, las oraciones en nombre de toda nuestra Uni\u00f3n Internacional est\u00e1n con los muertos, heridos y afectados, incluyendo a sus familias, compa\u00f1eros de trabajo y seres queridos\u201d, <a href=\"https:\/\/x.com\/Teamsters\/status\/1985859953165492725\">escribi\u00f3 el sindicato en<\/a> X.<\/p>\n<p><em>Michelle Watson, Amanda Musa, Emma Tucker, Alexandra Skores, Pete Muntean, Cindy Von Quednow, Amanda Jackson y Jordan D. Brown, de CNN, contribuyeron a este informe<\/em>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando los negocios empezaban a cerrar en Louisville, Kentucky, este martes, al atardecer, la calma se vio repentinamente interrumpida por una explosi\u00f3n gigantesca cerca del aeropuerto de la ciudad. Un avi\u00f3n de carga de UPS se estrell\u00f3 poco despu\u00e9s de despegar del Aeropuerto Internacional Muhammad Ali de Louisville, arrasando varios negocios, incluida una empresa de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468047","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando los negocios empezaban a cerrar en Louisville, Kentucky, este martes, al atardecer, la calma se vio repentinamente interrumpida por una explosi\u00f3n gigantesca cerca del aeropuerto de la ciudad. Un avi\u00f3n de carga de UPS se estrell\u00f3 poco despu\u00e9s de despegar del Aeropuerto Internacional Muhammad Ali de Louisville, arrasando varios negocios, incluida una empresa de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T13:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos\",\"datePublished\":\"2025-11-05T13:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\"},\"wordCount\":1558,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\",\"name\":\"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-05T13:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos - Noticias","og_description":"Cuando los negocios empezaban a cerrar en Louisville, Kentucky, este martes, al atardecer, la calma se vio repentinamente interrumpida por una explosi\u00f3n gigantesca cerca del aeropuerto de la ciudad. Un avi\u00f3n de carga de UPS se estrell\u00f3 poco despu\u00e9s de despegar del Aeropuerto Internacional Muhammad Ali de Louisville, arrasando varios negocios, incluida una empresa de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-05T13:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/"},"author":{"name":"","@id":""},"headline":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos","datePublished":"2025-11-05T13:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/"},"wordCount":1558,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","name":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-05T13:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El accidente de un avi\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/accidente-avion-ups-devasta-louisville-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-05T13:03:49Z","datePublished":"2025-11-05T13:03:49Z","dateModified":"2025-11-05T13:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El accidente de un avi\\u00f3n de carga de UPS devasta Louisville, donde los lazos con el gigante del transporte son profundos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/05\\\/accidente-avion-ups-devasta-louisville-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/05\\\/accidente-avion-ups-devasta-louisville-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-05T13:03:49Z\",\"datePublished\":\"2025-11-05T13:03:49Z\",\"dateModified\":\"2025-11-05T13:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468069,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/ups-avion-md11-accidente-louisville-34-anios-trax\/","url_meta":{"origin":1468047,"position":0},"title":"Por qu\u00e9 UPS segu\u00eda volando el avi\u00f3n MD-11 de 34 a\u00f1os que se estrell\u00f3 cerca del aeropuerto de Louisville","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El avi\u00f3n de UPS que se estrell\u00f3 en Louisville era un jet de 34 a\u00f1os. Aunque eso es viejo para un avi\u00f3n de pasajeros, no lo es tanto en el mundo de la carga a\u00e9rea.En principio, no hay indicios de que la edad del McDonnell Douglas MD-11 haya sido de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468079,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/investigacion-accidente-aereo-ups-louisville-trax\/","url_meta":{"origin":1468047,"position":1},"title":"\u00bfQu\u00e9 factores ayudan (o perjudican) la investigaci\u00f3n del accidente a\u00e9reo de UPS en Louisville?","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Un equipo de investigadores lleg\u00f3 este mi\u00e9rcoles a Louisville, Kentucky, para investigar las causas del accidente de un avi\u00f3n de carga de UPS poco despu\u00e9s de despegar del aeropuerto de Louisville este martes, que caus\u00f3 la muerte de al menos 12 personas y destruy\u00f3 negocios y otras estructuras en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468159,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/08\/faa-vuelos-aviones-carga-md-11-ups-trax\/","url_meta":{"origin":1468047,"position":2},"title":"La FAA detiene vuelos de aviones de carga MD-11 y exige inspecciones tras accidente de UPS que deja a una comunidad de luto","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Las cenizas se han asentado sobre el vecindario calcinado de Louisville, donde nueve personas siguen desaparecidas y las familias se aferran a la esperanza mientras los investigadores examinan los restos del mortal accidente del avi\u00f3n de carga de UPS ocurrido el martes.Una aeronave McDonnell Douglas MD-11 se precipit\u00f3 desde el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468554,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/20\/accidente-avion-ups-louisville-fotos-trax\/","url_meta":{"origin":1468047,"position":3},"title":"Autoridades de EE.UU. dan a conocer fotograf\u00edas a detalle del accidente del avi\u00f3n de UPS en Louisville","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"La Junta Nacional de Seguridad en el Transporte de Estados Unidos (NTSB por sus siglas en ingl\u00e9s), ofreci\u00f3 un nuevo informe sobre el accidente del avi\u00f3n de UPS registrado a principios de este mes que se estrell\u00f3 en Louisville tan solo unos instantes despu\u00e9s del despegue.El reporte presentado muestra una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468085,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/desaparecidos-accidente-avion-ups-louisville-trax\/","url_meta":{"origin":1468047,"position":4},"title":"Tres empleados de una planta de Louisville est\u00e1n desaparecidos tras accidente a\u00e9reo de UPS que, seg\u00fan el due\u00f1o, fue aterrador","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Acababa de irse la luz y el suelo temblaba en Grade A Auto Parts cuando el propietario recibi\u00f3 una videollamada de p\u00e1nico de su directora financiera.En su pantalla, el CEO Sean Garber vio una enorme bola de fuego que envolv\u00eda la planta de reciclaje y fabricaci\u00f3n de autopartes de Louisville,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468151,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/08\/desastre-aereo-ups-conmociona-bar-local-trax\/","url_meta":{"origin":1468047,"position":5},"title":"La aleatoriedad del desastre a\u00e9reo de UPS conmociona a los clientes del &#171;happy hour&#187; de un popular bar local","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Los clientes habituales del \u201chappy hour\u201d ya se estaban reuniendo en Stooges Bar & Grill menos de dos horas antes del inicio del partido inaugural de la temporada de baloncesto masculino de la Universidad de Kentucky el martes por la noche.Unos 30 clientes ocupaban los taburetes de madera del local\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468047"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468047\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}