{"id":1468093,"date":"2025-11-06T11:03:45","date_gmt":"2025-11-06T19:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/"},"modified":"2025-11-06T11:03:45","modified_gmt":"2025-11-06T19:03:45","slug":"medicamentos-obesidad-acuerdo-medicare-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","title":{"rendered":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca"},"content":{"rendered":"<p>Ciertos medicamentos \u2014muy populares\u2014 contra <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/24\/salud\/nueva-definicion-obesidad-trax\">la obesidad <\/a>estar\u00e1n disponibles por tan solo US$ 149 al mes, y m\u00e1s beneficiarios de Medicare tendr\u00e1n acceso a ellos en virtud de dos acuerdos anunciados este jueves por el Gobierno de Trump.<\/p>\n<p>Los acuerdos con las farmac\u00e9uticas Eli Lilly y Novo Nordisk, que el presidente Donald Trump anticip\u00f3 en declaraciones el mes pasado, son la iniciativa m\u00e1s reciente del Gobierno para reducir los precios de los medicamentos. Como parte de estos nuevos acuerdos, las farmac\u00e9uticas tambi\u00e9n se comprometieron a reducir los precios de una gama m\u00e1s amplia de medicamentos en Medicaid y los precios de lista cuando sus medicamentos salen al mercado. A cambio, las farmac\u00e9uticas obtienen exenciones arancelarias sobre productos farmac\u00e9uticos importados y una revisi\u00f3n regulatoria mucho m\u00e1s r\u00e1pida para ciertos medicamentos.<\/p>\n<p>Sin embargo, los precios que pagar\u00e1n los consumidores variar\u00e1n seg\u00fan su cobertura y la forma en que adquieran los medicamentos, entre otros factores. El precio de lista actual de los medicamentos oscila aproximadamente entre US$ 1.000 y US$ 1.350, aunque el costo final para los consumidores depende de su seguro y de los descuentos.<\/p>\n<p>Seg\u00fan el acuerdo, quienes compren medicamentos inyectables de GLP-1 directamente de las compa\u00f1\u00edas pagar\u00e1n un promedio de US$ 350 al mes inicialmente, aunque los fabricantes se han comprometido a reducir el precio a alrededor de US$ 250 en los pr\u00f3ximos dos a\u00f1os, seg\u00fan altos funcionarios de la administraci\u00f3n. Si la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) aprueba las tabletas orales de GLP-1, la dosis m\u00e1s baja costar\u00e1 US$ 149.<\/p>\n<p>Estos precios estar\u00e1n disponibles cuando TrumpRx, el sitio web de venta directa al consumidor de la administraci\u00f3n, se lance a principios de 2026.<\/p>\n<p>Actualmente, Novo Nordisk ofrece una opci\u00f3n de compra directa al consumidor para quienes est\u00e9n dispuestos a pagar en efectivo por Ozempic y Wegovy, a US$ 499 al mes. Lilly tambi\u00e9n ofrece opciones de pago en efectivo para su medicamento para bajar de peso Zepbound, con precios a partir de US$ 349 al mes.<\/p>\n<p>Mientras tanto, los beneficiarios de Medicare que cumplan con los requisitos tendr\u00e1n un copago de US$ 50 para ciertos medicamentos de GLP-1 aprobados para la obesidad y la diabetes. Los fabricantes de medicamentos reducir\u00e1n los precios que paga Medicare a US$ 245, lo que ayudar\u00e1 a financiar la ampliaci\u00f3n de la cobertura de medicamentos para bajar de peso. Los precios entrar\u00e1n en vigor a mediados de 2026.<\/p>\n<p>Como parte del acuerdo, el Gobierno de Trump est\u00e1 ampliando el acceso a medicamentos para la obesidad para los beneficiarios de Medicare con ciertas afecciones m\u00e9dicas. Por ley, Medicare no puede cubrir medicamentos para bajar de peso, pero la administraci\u00f3n Biden propuso el a\u00f1o pasado reinterpretar la ley para permitir la cobertura del tratamiento de la obesidad como una enfermedad cr\u00f3nica.<\/p>\n<p>Los funcionarios de Trump detuvieron ese intento. La Casa Blanca se\u00f1al\u00f3 en una llamada con periodistas este jueves que lograron reducciones de precios, lo que har\u00e1 que la ampliaci\u00f3n sea econ\u00f3micamente neutra, mientras que la administraci\u00f3n Biden no incluy\u00f3 reducciones de precios. Se estim\u00f3 que la propuesta de Biden costar\u00eda a Medicare US$ 25.000 millones durante una d\u00e9cada.<\/p>\n<p>Seg\u00fan el nuevo acuerdo, los consumidores con sobrepeso y prediabetes, que hayan sufrido un derrame cerebral u otra enfermedad cardiovascular ser\u00e1n elegibles, al igual que aquellos con obesidad y diabetes o hipertensi\u00f3n arterial no controlada y obesidad severa.<\/p>\n<p>Aproximadamente el 10 % de los beneficiarios de Medicare ser\u00edan elegibles para un acceso ampliado gracias a estos acuerdos, seg\u00fan altos funcionarios de la administraci\u00f3n. Medicare ya cubre ciertos medicamentos para bajar de peso si tambi\u00e9n est\u00e1n aprobados para tratar ciertas afecciones m\u00e9dicas.<\/p>\n<p>Eli Lilly y Novo Nordisk tambi\u00e9n acordaron proporcionar estos medicamentos a precios m\u00e1s bajos a los programas estatales de Medicaid, aunque el momento depender\u00e1 de las negociaciones con cada estado. Unos 13 estados cubr\u00edan estos costosos medicamentos para bajar de peso hasta agosto de 2024, seg\u00fan una encuesta de KFF, aunque Carolina del Norte anunci\u00f3 recientemente que dejar\u00eda de hacerlo.<\/p>\n<p>Durante su segundo mandato, el presidente Donald Trump reactiv\u00f3 una iniciativa controvertida para basar los precios de los medicamentos en Estados Unidos en los de otros pa\u00edses desarrollados, conocida como precios de naci\u00f3n m\u00e1s favorecida. Sus esfuerzos actuales se centran en lograr que los fabricantes de medicamentos acepten voluntariamente reducir sus precios a cambio de diversos incentivos.<\/p>\n<p>Trump se ha enfocado particularmente en lograr un acuerdo para los medicamentos GLP-1, cuya popularidad se ha disparado en los \u00faltimos a\u00f1os para ayudar con la p\u00e9rdida de peso y diversas afecciones cr\u00f3nicas. El presidente se ha referido a ellas, tanto en p\u00fablico como en privado, como la \u201cdroga para adelgazar\u201d.<\/p>\n<p>\u201cEn lugar de US$ 1.300, ustedes pagar\u00e1n unos US$ 150\u201d, dijo Trump.<\/p>\n<p>Durante un evento a mediados de octubre en el que se destacaba otro acuerdo sobre el precio de los medicamentos, se mencion\u00f3 el uso de f\u00e1rmacos GLP-1, lo que llev\u00f3 al administrador de los Centros de Servicios de Medicare y Medicaid, Mehmet Oz, a intervenir para enfatizar que las negociaciones a\u00fan estaban en curso.<\/p>\n<p>Cabe destacar que Ozempic y Wegovy fueron seleccionados en enero para una segunda ronda de negociaciones sobre el precio de los medicamentos de Medicare, la cual se espera que genere ahorros para el programa y, posiblemente, para los beneficiarios, dependiendo de su cobertura.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciertos medicamentos \u2014muy populares\u2014 contra la obesidad estar\u00e1n disponibles por tan solo US$ 149 al mes, y m\u00e1s beneficiarios de Medicare tendr\u00e1n acceso a ellos en virtud de dos acuerdos anunciados este jueves por el Gobierno de Trump. Los acuerdos con las farmac\u00e9uticas Eli Lilly y Novo Nordisk, que el presidente Donald Trump anticip\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468093","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ciertos medicamentos \u2014muy populares\u2014 contra la obesidad estar\u00e1n disponibles por tan solo US$ 149 al mes, y m\u00e1s beneficiarios de Medicare tendr\u00e1n acceso a ellos en virtud de dos acuerdos anunciados este jueves por el Gobierno de Trump. Los acuerdos con las farmac\u00e9uticas Eli Lilly y Novo Nordisk, que el presidente Donald Trump anticip\u00f3 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T19:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca\",\"datePublished\":\"2025-11-06T19:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\"},\"wordCount\":960,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\",\"name\":\"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-06T19:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca - Noticias","og_description":"Ciertos medicamentos \u2014muy populares\u2014 contra la obesidad estar\u00e1n disponibles por tan solo US$ 149 al mes, y m\u00e1s beneficiarios de Medicare tendr\u00e1n acceso a ellos en virtud de dos acuerdos anunciados este jueves por el Gobierno de Trump. Los acuerdos con las farmac\u00e9uticas Eli Lilly y Novo Nordisk, que el presidente Donald Trump anticip\u00f3 en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-06T19:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/"},"author":{"name":"","@id":""},"headline":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca","datePublished":"2025-11-06T19:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/"},"wordCount":960,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","name":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-06T19:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Algunos medicamentos para la obesidad costar\u00e1n US$ 149 y Medicare comenzar\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/medicamentos-obesidad-acuerdo-medicare-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-06T19:03:45Z","datePublished":"2025-11-06T19:03:45Z","dateModified":"2025-11-06T19:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Algunos medicamentos para la obesidad costar\\u00e1n US$ 149 y Medicare comenzar\\u00e1 a cubrirlos a partir de acuerdos con Casa Blanca\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/06\\\/medicamentos-obesidad-acuerdo-medicare-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/06\\\/medicamentos-obesidad-acuerdo-medicare-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-06T19:03:45Z\",\"datePublished\":\"2025-11-06T19:03:45Z\",\"dateModified\":\"2025-11-06T19:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469429,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/19\/trump-acuerdos-farmaceuticas-bajar-precios-medicamentos-trax\/","url_meta":{"origin":1468093,"position":0},"title":"Trump anuncia acuerdos con nueve farmac\u00e9uticas con el objetivo de bajar los precios para los pacientes estadounidenses","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"En su m\u00e1s reciente esfuerzo por reducir los costos de los medicamentos, el presidente de EE.UU., Donald Trump, present\u00f3 este viernes acuerdos de precios de \u201cNaci\u00f3n M\u00e1s Favorecida\u201d con nueve compa\u00f1\u00edas farmac\u00e9uticas m\u00e1s.Los acuerdos voluntarios siguen a los realizados con cinco fabricantes de medicamentos \u2013incluidos los dos fabricantes de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465032,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/01\/trump-farmaceuticas-bajar-precios-60-dias-expertos-improbable-trax\/","url_meta":{"origin":1468093,"position":1},"title":"Trump exige a las farmac\u00e9uticas bajar los precios en 60 d\u00edas. Expertos de la industria dicen que es improbable que eso suceda","author":"","date":"agosto 1, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, aument\u00f3 la presi\u00f3n sobre las principales farmac\u00e9uticas para que igualen sus precios en EE.UU. con los mucho m\u00e1s bajos que se ofrecen a los pacientes en otros pa\u00edses, aunque los expertos de la industria no esperan que las compa\u00f1\u00edas farmac\u00e9uticas accedan.Trump envi\u00f3 cartas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470161,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/16\/atencion-medica-trump-trax\/","url_meta":{"origin":1468093,"position":2},"title":"\u00bfQu\u00e9 incluye el &#171;Gran Plan de Atenci\u00f3n M\u00e9dica&#187; de Trump? Todo lo que debes saber","author":"","date":"enero 16, 2026","format":false,"excerpt":"Buscando mostrar a los estadounidenses que le preocupa el problema de la asequibilidad, el presidente Donald Trump present\u00f3 este jueves su tan esperado plan para enfrentar el alto costo de la atenci\u00f3n m\u00e9dica.La propuesta, que no entra en detalles, es un marco general de las prioridades del presidente en materia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470938,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/06\/trumprx-precios-medicamentos-trax\/","url_meta":{"origin":1468093,"position":3},"title":"TrumpRx se pone en marcha, pero no est\u00e1 claro si reducir\u00e1 los precios de los medicamentos para la mayor\u00eda de los pacientes","author":"","date":"febrero 6, 2026","format":false,"excerpt":"TrumpRx, la esperada plataforma de venta directa de medicamentos al consumidor del Gobierno de Trump, se puso en funcionamiento el jueves.Un pilar clave de la iniciativa del presidente Donald Trump para reducir los costos de los medicamentos recetados, el sitio web servir\u00e1 como un centro de informaci\u00f3n que conectar\u00e1 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472815,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/02\/trump-impone-nuevos-aranceles-medicamentos-trax\/","url_meta":{"origin":1468093,"position":4},"title":"Trump impone nuevos aranceles a ciertos medicamentos y modifica los aranceles a los metales","author":"","date":"abril 2, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, impondr\u00e1 un nuevo arancel del 100 % a las compa\u00f1\u00edas farmac\u00e9uticas que no hayan alcanzado acuerdos para vender sus medicamentos directamente a los consumidores como parte de su iniciativa de precios de \u201cNaci\u00f3n m\u00e1s favorecida\u201d, anunci\u00f3 la Casa Blanca este jueves.El arancel, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467003,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/30\/trump-sitio-trumprx-medicamentos-descuento-pfizer-trax\/","url_meta":{"origin":1468093,"position":5},"title":"Trump anuncia acuerdo con Pfizer y un sitio web llamado &#171;TrumpRx&#187; para medicamentos con descuento","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"El presidente Donald Trump anunci\u00f3 el martes un esfuerzo multifac\u00e9tico dirigido a reducir los costos de los medicamentos en Estados Unidos, incluyendo la creaci\u00f3n de un sitio web directo al consumidor llamado \u201cTrumpRx\u201d donde los estadounidenses podr\u00e1n comprar medicinas a precios descontados y un amplio acuerdo con Pfizer para reducir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468093"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468093\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}