{"id":1468233,"date":"2025-11-11T10:03:43","date_gmt":"2025-11-11T18:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/"},"modified":"2025-11-11T10:03:43","modified_gmt":"2025-11-11T18:03:43","slug":"reino-unido-suspende-intercambio-inteligencia-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","title":{"rendered":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones"},"content":{"rendered":"<p>El Reino Unido ya no comparte informaci\u00f3n de inteligencia con Estados Unidos sobre embarcaciones sospechosas de ser usadas para el narcotr\u00e1fico en el Caribe, ya que no desea ser c\u00f3mplice de los ataques militares estadounidenses y considera que estos son ilegales, seg\u00fan informaron a CNN fuentes familiarizadas con el asunto.<\/p>\n<p>La decisi\u00f3n del Reino Unido representa una ruptura significativa con su aliado m\u00e1s cercano y socio en el intercambio de inteligencia, y subraya el creciente escepticismo sobre la legalidad de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/11\/eeuu\/ejercito-estadounidense-barcos-narcotraficantes-trax\">la campa\u00f1a militar estadounidense<\/a> en Am\u00e9rica Latina.<\/p>\n<p>Durante a\u00f1os, el Reino Unido, que controla varios territorios en el Caribe donde mantiene bases de inteligencia, ha ayudado a Estados Unidos a localizar embarcaciones sospechosas de transportar drogas para que la Guardia Costera estadounidense pudiera interceptarlas, indicaron las fuentes. Eso significaba que los barcos ser\u00edan interceptados, abordados, su tripulaci\u00f3n detenida y las drogas confiscadas.<\/p>\n<p>La informaci\u00f3n de inteligencia se enviaba generalmente al Grupo de Trabajo Interinstitucional Conjunto Sur, un grupo de trabajo con base en Florida que incluye representantes de varios pa\u00edses aliados y trabaja para reducir el narcotr\u00e1fico.<\/p>\n<p>Sin embargo, poco despu\u00e9s de que Estados Unidos comenzara a lanzar ataques letales contra embarcaciones, en septiembre, el Reino Unido empez\u00f3 a preocuparse de que Estados Unidos pudiera utilizar la informaci\u00f3n de inteligencia proporcionada por los brit\u00e1nicos para seleccionar objetivos. Funcionarios brit\u00e1nicos creen que los ataques militares estadounidenses, que han causado la muerte de 76 personas, violan el derecho internacional, seg\u00fan indicaron las fuentes. La interrupci\u00f3n del suministro de informaci\u00f3n de inteligencia comenz\u00f3 hace m\u00e1s de un mes, a\u00f1adieron.<\/p>\n<p>El alto comisionado de las Naciones Unidas para los Derechos Humanos, Volker T\u00fcrk, afirm\u00f3 el mes pasado que los ataques violan el derecho internacional y constituyen \u201cejecuciones extrajudiciales\u201d. El Reino Unido coincide con esa evaluaci\u00f3n, seg\u00fan informaron las fuentes a CNN.<\/p>\n<p>La embajada brit\u00e1nica en Washington, el Pent\u00e1gono y la Casa Blanca no respondieron a las solicitudes de comentarios.<\/p>\n<p>Antes de que las fuerzas militares estadounidenses comenzaran a hundir embarcaciones en septiembre, la lucha contra el narcotr\u00e1fico estaba a cargo de las fuerzas del orden y la Guardia Costera de EE.UU. Los miembros de c\u00e1rteles y narcotraficantes eran tratados como delincuentes con derecho a un debido proceso, algo en lo que el Reino Unido colaboraba con gusto, seg\u00fan las fuentes.<\/p>\n<p>Sin embargo, la administraci\u00f3n Trump ha argumentado que las Fuerzas Armadas de EE.UU. pueden matar legalmente a supuestos narcotraficantes porque representan una amenaza inminente para los estadounidenses y son \u201ccombatientes enemigos\u201d que se encuentran en un \u201cconflicto armado\u201d con EE.UU., seg\u00fan un memor\u00e1ndum enviado por la administraci\u00f3n al Congreso. La Oficina de Asesor\u00eda Legal del Departamento de Justicia emiti\u00f3 una opini\u00f3n, que a\u00fan est\u00e1 clasificada, reforzando ese argumento, seg\u00fan inform\u00f3 CNN, y Trump ha designado a varios c\u00e1rteles de la droga como \u201cgrupos terroristas extranjeros\u201d. La Casa Blanca ha afirmado repetidamente que las acciones del Gobierno \u201ccumplen plenamente con el Derecho de los Conflictos Armados\u201d, la rama del derecho internacional destinada a prevenir ataques contra civiles.<\/p>\n<p>Sin embargo, expertos legales se\u00f1alan que el Derecho de los Conflictos Armados se aplicar\u00eda incluso a civiles que trafican drogas, y que la designaci\u00f3n de un grupo como organizaci\u00f3n terrorista extranjera no autoriza autom\u00e1ticamente el uso de fuerza letal. Seg\u00fan CNN, varias embarcaciones atacadas por Estados Unidos se encontraban estacionarias o estaban dando la vuelta al momento del ataque, lo que contradice la afirmaci\u00f3n del Gobierno de que representaban una amenaza inminente que no pod\u00eda ser neutralizada mediante interceptaci\u00f3n y arresto.<\/p>\n<p>Altos funcionarios de defensa estadounidenses tambi\u00e9n han expresado escepticismo sobre la campa\u00f1a militar. El comandante del Comando Sur de Estados Unidos, el almirante Alvin Holsey, ofreci\u00f3 su renuncia durante una tensa reuni\u00f3n el mes pasado con el secretario de Defensa, Pete Hegseth, y el jefe del Estado Mayor Conjunto, tras cuestionar la legalidad de los ataques, seg\u00fan inform\u00f3 CNN. Holsey dejar\u00e1 su cargo en diciembre, apenas un a\u00f1o despu\u00e9s de haber asumido la direcci\u00f3n del Comando Sur.<\/p>\n<p>Abogados especializados en derecho internacional de la Oficina del Asesor Jur\u00eddico del Departamento de Defensa tambi\u00e9n han expresado su preocupaci\u00f3n por la legalidad de los ataques, seg\u00fan inform\u00f3 CNN. Varios abogados, tanto en activo como retirados, pertenecientes a las Fuerzas Armadas, declararon a CNN que los ataques no parecen ser legales. El portavoz de Hegseth ya hab\u00eda negado que alg\u00fan abogado involucrado en las operaciones hubiera manifestado su disconformidad.<\/p>\n<p>Canad\u00e1, otro aliado clave de Estados Unidos que ha ayudado a la Guardia Costera estadounidense a interceptar a presuntos narcotraficantes en el Caribe durante casi dos d\u00e9cadas, tambi\u00e9n se ha desvinculado de los ataques militares estadounidenses. Fuentes informaron a CNN que Canad\u00e1 tiene la intenci\u00f3n de continuar su colaboraci\u00f3n con la Guardia Costera, denominada operaci\u00f3n Caribe. Sin embargo, el pa\u00eds ha dejado claro a Estados Unidos que no desea que su inteligencia se utilice para seleccionar embarcaciones para ataques letales, seg\u00fan indicaron las fuentes a CNN.<\/p>\n<p>Un portavoz de la Defensa canadiense declar\u00f3 a la prensa canadiense el mes pasado que \u201ces importante se\u00f1alar que las actividades de las Fuerzas Armadas canadienses en el marco de la operaci\u00f3n Caribe, realizadas en coordinaci\u00f3n con la Guardia Costera de Estados Unidos, son independientes y distintas\u201d de los ataques militares estadounidenses contra embarcaciones sospechosas de ser usadas para el narcotr\u00e1fico.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Reino Unido ya no comparte informaci\u00f3n de inteligencia con Estados Unidos sobre embarcaciones sospechosas de ser usadas para el narcotr\u00e1fico en el Caribe, ya que no desea ser c\u00f3mplice de los ataques militares estadounidenses y considera que estos son ilegales, seg\u00fan informaron a CNN fuentes familiarizadas con el asunto. La decisi\u00f3n del Reino Unido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468233","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Reino Unido ya no comparte informaci\u00f3n de inteligencia con Estados Unidos sobre embarcaciones sospechosas de ser usadas para el narcotr\u00e1fico en el Caribe, ya que no desea ser c\u00f3mplice de los ataques militares estadounidenses y considera que estos son ilegales, seg\u00fan informaron a CNN fuentes familiarizadas con el asunto. La decisi\u00f3n del Reino Unido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T18:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones\",\"datePublished\":\"2025-11-11T18:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\"},\"wordCount\":975,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\",\"name\":\"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-11T18:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones - Noticias","og_description":"El Reino Unido ya no comparte informaci\u00f3n de inteligencia con Estados Unidos sobre embarcaciones sospechosas de ser usadas para el narcotr\u00e1fico en el Caribe, ya que no desea ser c\u00f3mplice de los ataques militares estadounidenses y considera que estos son ilegales, seg\u00fan informaron a CNN fuentes familiarizadas con el asunto. La decisi\u00f3n del Reino Unido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-11T18:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones","datePublished":"2025-11-11T18:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/"},"wordCount":975,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","name":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-11T18:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-11T18:03:43Z","datePublished":"2025-11-11T18:03:43Z","dateModified":"2025-11-11T18:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Exclusivo: Reino Unido suspende parte del intercambio de inteligencia con EE.UU. por desacuerdo sobre ataques a embarcaciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/reino-unido-suspende-intercambio-inteligencia-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-11T18:03:43Z\",\"datePublished\":\"2025-11-11T18:03:43Z\",\"dateModified\":\"2025-11-11T18:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468310,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/13\/ataque-bote-drogas-caribe-trax\/","url_meta":{"origin":1468233,"position":0},"title":"Hay cuatro muertos en vig\u00e9simo ataque de EE.UU. contra un presunto narcobote en el Caribe","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"El Pent\u00e1gono llev\u00f3 a cabo su vig\u00e9simo ataque contra una embarcaci\u00f3n que supuestamente traficaba drogas a principios de esta semana, dijo este jueves un funcionario del Departamento de Defensa.\u201cEl ataque ocurri\u00f3 en el Caribe y cuatro narco-terroristas murieron; no hubo sobrevivientes\u201d, confirm\u00f3 el funcionario en un comunicado a CNN. Funcionarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468402,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/16\/mueren-tres-personas-21-ataque-narcobote-trax\/","url_meta":{"origin":1468233,"position":1},"title":"Mueren tres personas en el ataque 21 de las Fuerzas Armadas de EE.UU. contra un presunto bote que transportada drogas","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El Pent\u00e1gono ejecut\u00f3 el s\u00e1bado el 21\u00b0 ataque conocido contra una presunta embarcaci\u00f3n de narcotr\u00e1fico, seg\u00fan anunci\u00f3 el Comando Sur de Estados Unidos este domingo.\u201cLa inteligencia confirm\u00f3 que la embarcaci\u00f3n estaba involucrada en el tr\u00e1fico il\u00edcito de drogas, transitando por una ruta conocida de narcotr\u00e1fico y transportando estupefacientes\u201d, public\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464266,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/06\/embarcaciones-atacan-buque-mercante-yemen-trax\/","url_meta":{"origin":1468233,"position":2},"title":"Peque\u00f1as embarcaciones atacan a un buque mercante cerca de la costa de Yemen, informa grupo naviero","author":"","date":"julio 6, 2025","format":false,"excerpt":"Una organizaci\u00f3n mar\u00edtima del Reino Unido inform\u00f3 haber recibido reportes de un ataque contra un buque mercante frente a la costa de Yemen, el primer incidente de este tipo en varios meses.La Oficina de Operaciones de Tr\u00e1fico Mar\u00edtimo del Reino Unido (UKMTO, por sus siglas en ingl\u00e9s) dijo haber recibido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473517,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/26\/iran-estrecho-ormuz-paralizado-trax\/","url_meta":{"origin":1468233,"position":3},"title":"El tr\u00e1fico en el estrecho de Ormuz permanece pr\u00e1cticamente paralizado tras una nueva advertencia de Ir\u00e1n","author":"","date":"abril 26, 2026","format":false,"excerpt":"El n\u00famero de buques que cruzan el estrecho de Ormuz, por donde normalmente pasa una quinta parte del petr\u00f3leo crudo mundial, sigue siendo muy limitado en comparaci\u00f3n con los niveles previos al conflicto de Estados Unidos e Israel con Ir\u00e1n, seg\u00fan datos de seguimiento mar\u00edtimo.Solo unos pocos buques han cruzado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469293,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/15\/ataque-tres-embarcaciones-pacifico-muertos-trax\/","url_meta":{"origin":1468233,"position":4},"title":"Fuerzas militares de EE.UU. atacan tres embarcaciones en el oc\u00e9ano Pac\u00edfico: reportan al menos ocho muertos","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Las Fuerzas Militares de EE.UU. atacaron tres embarcaciones presuntamente dedicadas al narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico el lunes, y reportaron ocho personas muertas, seg\u00fan el Comando Sur de EE.UU.\u201cEl 15 de diciembre, por orden de @SecWar Pete Hegseth, la Fuerza de Tarea Conjunta Southern Spear llev\u00f3 a cabo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469299,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/16\/ataques-botes-eeuu-caribe-pacifico-narco-venezuela-cronologia-orix\/","url_meta":{"origin":1468233,"position":5},"title":"25 botes destruidos, 95 muertos y una crisis que crece en el Caribe y el Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Las Fuerzas Militares de EE.UU. atacaron tres embarcaciones presuntamente dedicadas al narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico el lunes. Seg\u00fan el Comando Sur de EE.UU., al menos ocho personas murieron como resultado del operativo.Con ello, desde el 2 de septiembre suman 25 botes destruidos en 23 ataques efectuados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468233"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468233\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}