{"id":1468236,"date":"2025-11-11T13:03:58","date_gmt":"2025-11-11T21:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/"},"modified":"2025-11-11T13:03:58","modified_gmt":"2025-11-11T21:03:58","slug":"que-sigue-fin-cierre-del-gobierno-senado-camara-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","title":{"rendered":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?"},"content":{"rendered":"<p>Los senadores aprobaron un paquete de financiamiento para reabrir el Gobierno federal, enviando el acuerdo de compromiso a sus colegas en la C\u00e1mara.<\/p>\n<p>Dem\u00f3cratas centristas del Senado lograron un acuerdo durante el fin de semana con los republicanos para avanzar el paquete, sin asegurar la exigencia de su partido de garantizar una extensi\u00f3n de los subsidios mejorados de la Ley de Cuidado de Salud A Bajo Precio, que ayudan a millones de estadounidenses a pagar el seguro de salud. En \u00faltima instancia, ocho miembros de la asamblea partidista dem\u00f3crata cruzaron l\u00edneas para acercarse un paso m\u00e1s a romper el estancamiento en el Capitolio.<\/p>\n<p>Ahora, el enfoque est\u00e1 en la C\u00e1mara, donde los l\u00edderes republicanos creen que los legisladores pondr\u00e1n fin al estancamiento esta semana.<\/p>\n<p>Esto es lo que a\u00fan debe suceder en el Capitolio para reabrir el Gobierno federal.<\/p>\n<p>El paquete aprobado por el Senado financiar\u00eda al Gobierno hasta el 30 de enero y a algunas agencias clave por el resto del a\u00f1o fiscal 2026. Eso significa que si el Gobierno volviera a cerrar en los pr\u00f3ximos meses, la asistencia alimentaria federal clave conocida como Programa de Asistencia Nutricional Suplementaria (SNAP, por sus siglas en ingl\u00e9s) seguir\u00eda siendo financiada.<\/p>\n<p>El presidente de la C\u00e1mara, Mike Johnson, tiene que vender este paquete a su escasa mayor\u00eda republicana y probablemente necesitar\u00e1 la ayuda del presidente de EE.UU.<\/p>\n<p>Johnson dijo a sus miembros el lunes que comenzaran a regresar a Washington y los puso en aviso de votaci\u00f3n de 36 horas despu\u00e9s de que el Senado aprobara la resoluci\u00f3n continua, o CR (por sus siglas en ingl\u00e9s), para financiar el Gobierno.<\/p>\n<p>\u201cEstoy diciendo lo obvio: todos mis colegas, republicanos y dem\u00f3cratas en la C\u00e1mara, deben comenzar ahora mismo a regresar al Capitolio. Tenemos que hacer esto lo m\u00e1s r\u00e1pido posible\u201d, dijo el l\u00edder republicano el lunes.<\/p>\n<p>La C\u00e1mara planea comenzar a votar sobre el proyecto de ley aprobado por el Senado para reabrir el Gobierno federal el mi\u00e9rcoles, seg\u00fan un aviso del l\u00edder de la mayor\u00eda, Tom Emmer.<\/p>\n<p>La votaci\u00f3n tendr\u00e1 lugar a partir de las 4 p.m., seg\u00fan el aviso, que prev\u00e9 varias votaciones ese d\u00eda.<\/p>\n<p>El martes, se espera que la Comisi\u00f3n de Reglas de la C\u00e1mara considere el paquete del Senado para preparar la actividad en el pleno el mi\u00e9rcoles.<\/p>\n<p>La C\u00e1mara no ha votado ni ha estado en sesi\u00f3n legislativa desde el 19 de septiembre.<\/p>\n<p>Johnson tendr\u00e1 que trabajar de cerca con la Casa Blanca para impulsar este acuerdo en la C\u00e1mara, dado que no est\u00e1 claro cu\u00e1ntos dem\u00f3cratas apoyar\u00e1n el paquete y los republicanos tienen una mayor\u00eda estrecha.<\/p>\n<p>Catorce republicanos moderados de la C\u00e1mara quer\u00edan ver extendidos los subsidios mejorados de la Ley de Cuidado de Salud Asequible que est\u00e1n por expirar y ten\u00edan su propio proyecto de ley para abordar el tema en el centro de la lucha por el cierre.<\/p>\n<p>Mientras tanto, el liderazgo dem\u00f3crata de la C\u00e1mara trabaja para evitar que los miembros de base voten por este proyecto de ley porque dicen que no cumple con lo que los dem\u00f3cratas defendieron durante el cierre. El representante dem\u00f3crata Jared Golden, quien no busca la reelecci\u00f3n y es conocido por votar con los republicanos, est\u00e1 entre los que hay que observar.<\/p>\n<p>El l\u00edder de la minor\u00eda de la C\u00e1mara, Hakeem Jeffries, ha prometido luchar contra el paquete porque no llega tan lejos como \u00e9l quer\u00eda en las demandas de salud de los dem\u00f3cratas.<\/p>\n<p>Jeffries y su equipo esperan limitar el n\u00famero de dem\u00f3cratas que apoyan el plan, lo que maximizar\u00e1 la presi\u00f3n sobre los republicanos de la C\u00e1mara para conseguir los votos por s\u00ed mismos. Y los l\u00edderes dem\u00f3cratas de la C\u00e1mara est\u00e1n oficialmente presionando en contra del compromiso de financiamiento del Senado, seg\u00fan dos fuentes familiarizadas con los planes.<\/p>\n<p>El l\u00edder dem\u00f3crata de la C\u00e1mara reiter\u00f3 a Wolf Blitzer de CNN el martes que los dem\u00f3cratas \u201cse opondr\u00e1n firmemente a cualquier legislaci\u00f3n que no aborde de manera decisiva la crisis de salud republicana\u201d.<\/p>\n<p>\u201cQueremos reabrir el Gobierno. Continuaremos respaldando a nuestros trabajadores federales y servidores p\u00fablicos dedicados. Pero tenemos la responsabilidad de asegurarnos de que extendemos los cr\u00e9ditos fiscales de la Ley de Cuidado de Salud A Bajo Precio para que decenas de millones de estadounidenses no experimenten aumentos dr\u00e1sticos en los costos de atenci\u00f3n m\u00e9dica que les impedir\u00edan poder ver a un m\u00e9dico cuando lo necesiten\u201d, dijo Jeffries en \u201cThe Situation Room\u201d.<\/p>\n<p>Todav\u00eda no.<\/p>\n<p>Una vez aprobado en la C\u00e1mara, el proyecto de ley ir\u00e1 al escritorio del presidente Donald Trump para su firma.<\/p>\n<p>La Casa Blanca respald\u00f3 el plan del Senado para reabrir el Gobierno, calificando el acuerdo de financiaci\u00f3n como un \u201cavance positivo\u201d para poner fin al cierre gubernamental m\u00e1s largo de la historia.<\/p>\n<p>\u201cEl presidente Trump ha querido que el Gobierno se reabra desde el primer d\u00eda en que los dem\u00f3cratas lo cerraron\u201d, dijo un funcionario de la Casa Blanca en un comunicado. \u201cLa acci\u00f3n en el Senado es un avance positivo y esperamos ver su progreso\u201d.<\/p>\n<p>Y sumando a la expectativa de que Trump firmar\u00e1 la medida, el presidente le dijo a Kaitlan Collins de CNN: \u201cYo dir\u00eda que s\u00ed\u201d, cuando se le pregunt\u00f3 si personalmente aprobaba el acuerdo que avanzaba en el Capitolio.<\/p>\n<p>\u201cCreo que, seg\u00fan todo lo que escucho, no han cambiado nada, y tenemos el apoyo de suficientes dem\u00f3cratas, y vamos a reabrir nuestro pa\u00eds\u201d, dijo Trump el lunes. \u201cEs una l\u00e1stima que estuviera cerrado, pero vamos a reabrir nuestro pa\u00eds muy pronto\u201d.<\/p>\n<p>El proyecto de ley completo incluye un paquete de financiamiento m\u00e1s amplio negociado entre ambos partidos y una medida provisional hasta el 30 de enero.<\/p>\n<p>El paquete legislativo m\u00e1s amplio incluir\u00eda tres proyectos de ley de asignaciones para todo el a\u00f1o que abordan la construcci\u00f3n militar y asuntos de veteranos, la rama legislativa y el Departamento de Agricultura.<\/p>\n<p>Eso incluye US$ 203,5 millones en nuevo financiamiento para mejorar las medidas de seguridad y protecci\u00f3n para los miembros del Congreso, adem\u00e1s de US$ 852 millones para la Polic\u00eda del Capitolio de EE.UU., seg\u00fan un resumen del proyecto de ley para financiar la rama legislativa proporcionado por la principal dem\u00f3crata encargada de asignaciones, la senadora Patty Murray.<\/p>\n<p>El paquete no incluye una garant\u00eda de los republicanos para extender los subsidios mejorados de la Ley de Cuidado de Salud A Bajo Precio que est\u00e1n por expirar y que han estado en el centro de la disputa de financiaci\u00f3n.<\/p>\n<p>Como parte del acuerdo alcanzado entre los republicanos y los centristas dem\u00f3cratas del Senado, se espera que haya una votaci\u00f3n futura en el Senado sobre los subsidios.<\/p>\n<p>Detr\u00e1s de escena, los dem\u00f3cratas del Senado que apoyaron el acuerdo para reabrir el Gobierno dijeron que la creciente oposici\u00f3n de Trump en los \u00faltimos d\u00edas a extender los subsidios mejorados de Obamacare \u2014un punto clave para el Partido Dem\u00f3crata\u2014 los oblig\u00f3 a cambiar de posici\u00f3n y aceptar un compromiso para poner fin a un cierre gubernamental indefinido, seg\u00fan fuentes familiarizadas con su pensamiento.<\/p>\n<p>El acuerdo tambi\u00e9n incluye un compromiso para revertir los despidos federales durante el cierre y garantizar que todos los trabajadores federales reciban el pago que se les deb\u00eda durante el cierre.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los senadores aprobaron un paquete de financiamiento para reabrir el Gobierno federal, enviando el acuerdo de compromiso a sus colegas en la C\u00e1mara. Dem\u00f3cratas centristas del Senado lograron un acuerdo durante el fin de semana con los republicanos para avanzar el paquete, sin asegurar la exigencia de su partido de garantizar una extensi\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468236","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los senadores aprobaron un paquete de financiamiento para reabrir el Gobierno federal, enviando el acuerdo de compromiso a sus colegas en la C\u00e1mara. Dem\u00f3cratas centristas del Senado lograron un acuerdo durante el fin de semana con los republicanos para avanzar el paquete, sin asegurar la exigencia de su partido de garantizar una extensi\u00f3n de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T21:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?\",\"datePublished\":\"2025-11-11T21:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\"},\"wordCount\":1333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\",\"name\":\"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-11T21:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno? - Noticias","og_description":"Los senadores aprobaron un paquete de financiamiento para reabrir el Gobierno federal, enviando el acuerdo de compromiso a sus colegas en la C\u00e1mara. Dem\u00f3cratas centristas del Senado lograron un acuerdo durante el fin de semana con los republicanos para avanzar el paquete, sin asegurar la exigencia de su partido de garantizar una extensi\u00f3n de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-11T21:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/"},"author":{"name":"","@id":""},"headline":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?","datePublished":"2025-11-11T21:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/"},"wordCount":1333,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","name":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-11T21:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-11T21:03:58Z","datePublished":"2025-11-11T21:03:58Z","dateModified":"2025-11-11T21:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Senado envi\\u00f3 un proyecto de ley de financiamiento a la C\\u00e1mara. \\u00bfQu\\u00e9 sigue para poner fin al cierre del Gobierno?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-11T21:03:58Z\",\"datePublished\":\"2025-11-11T21:03:58Z\",\"dateModified\":\"2025-11-11T21:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468248,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","url_meta":{"origin":1468236,"position":0},"title":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"El Congreso se est\u00e1 moviendo r\u00e1pidamente para aprobar un paquete de financiamiento que pondr\u00eda fin al cierre federal m\u00e1s largo en la historia de Estados Unidos.La C\u00e1mara tiene previsto votar el mi\u00e9rcoles sobre un proyecto de ley de compromiso despu\u00e9s de que el Senado aprobara el paquete la noche del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470690,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/30\/senado-proyecto-ley-financiamiento-trump-fin-al-cierre-trax\/","url_meta":{"origin":1468236,"position":1},"title":"El Senado aprueba ley de financiamiento respaldada por Trump y presiona a la C\u00e1mara para poner fin al cierre del Gobierno","author":"","date":"enero 30, 2026","format":false,"excerpt":"El Senado ha dado un paso para que el Congreso evite otro cierre prolongado del Gobierno, al aprobar un importante acuerdo presupuestario alcanzado con la Casa Blanca que financia temporalmente al Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), permitiendo as\u00ed negociaciones a largo plazo sobre la pol\u00edtica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470498,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/26\/negociaciones-financiamiento-gobierno-ice-minneapolis-trax\/","url_meta":{"origin":1468236,"position":2},"title":"C\u00f3mo van las negociaciones sobre el financiamiento del Gobierno tras el tiroteo en Minneapolis","author":"","date":"enero 26, 2026","format":false,"excerpt":"La posibilidad de un cierre parcial del Gobierno para el final de la semana est\u00e1 creciendo, ya que el destino del financiamiento para el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) y otras agencias gubernamentales clave est\u00e1 en juego.Tras otro tiroteo mortal por parte de un agente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470618,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/01\/29\/senado-bloquea-proyecto-financiamiento-evitar-cierre-gobierno-trax\/","url_meta":{"origin":1468236,"position":3},"title":"El Senado bloquea un proyecto de financiamiento, en medio de negociaciones para evitar el cierre del Gobierno","author":"","date":"enero 29, 2026","format":false,"excerpt":"Senadores de ambos partidos bloquearon este jueves un importante proyecto de ley de gastos, mientras contin\u00faan las negociaciones de \u00faltima hora para evitar un costoso cierre parcial del Gobierno que podr\u00eda llegar al final de la semana.Todos los dem\u00f3cratas, que presionan para forzar cambios en las pol\u00edticas del Servicio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470777,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/02\/trump-congreso-cerca-fin-cierre-parcial-gobierno-trax\/","url_meta":{"origin":1468236,"position":4},"title":"Trump dice que el Congreso est\u00e1 cerca de una &#171;resoluci\u00f3n&#187; para poner fin al cierre parcial del Gobierno","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El presidente Donald Trump dijo el lunes que los l\u00edderes del Congreso est\u00e1n cerca de una \u201cresoluci\u00f3n\u201d para la suspensi\u00f3n parcial del financiamiento federal.\u201cCreo que est\u00e1n bastante cerca de una resoluci\u00f3n\u201d, dijo desde la Oficina Oval, se\u00f1alando que hab\u00eda hablado recientemente con el presidente de la C\u00e1mara de Representantes, Mike\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468283,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/12\/congreso-paquete-financiacion-reabrir-gobierno-trump-trax\/","url_meta":{"origin":1468236,"position":5},"title":"El Congreso aprueba paquete de financiamiento para reabrir el Gobierno federal y lo env\u00eda a Trump para su firma","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"Ambas c\u00e1maras del Congreso han votado a favor de poner fin al cierre federal m\u00e1s largo de la historia, y enviaron un proyecto de ley de financiamiento para reabrir el Gobierno al presidente Donald Trump para su firma.La C\u00e1mara de Representantes vot\u00f3 este mi\u00e9rcoles por la noche para dar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468236"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468236\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}