{"id":1468239,"date":"2025-11-11T14:03:50","date_gmt":"2025-11-11T22:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/"},"modified":"2025-11-11T14:03:50","modified_gmt":"2025-11-11T22:03:50","slug":"investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","title":{"rendered":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo"},"content":{"rendered":"<p>Autoridades de Michoac\u00e1n, en el suroeste de M\u00e9xico, investigan en qu\u00e9 circunstancias fue abatido el joven se\u00f1alado como el presunto autor del homicidio del alcalde de Uruapan, Carlos Manzo, ocurrido la noche del 1 de noviembre, dijeron el gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, y el secretario de Seguridad federal, Omar Garc\u00eda Harfuch.<\/p>\n<p>Durante <a href=\"https:\/\/www.facebook.com\/gobmichoacan\/videos\/1121113946551399\">una rueda de prensa el lunes<\/a>, Ram\u00edrez Bedolla dijo que la Fiscal\u00eda de Michoac\u00e1n mantiene abiertas diversas indagatorias en torno al caso. Una de ellas, expuso, es c\u00f3mo muri\u00f3 el presunto atacante de Manzo, a quien la semana pasada la Fiscal\u00eda <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/06\/mexico\/identifica-joven-17-anios-presunto-autor-homicidio-alcalde-uruapan-orix\">identific\u00f3 como un menor de 17 a\u00f1os<\/a>.<\/p>\n<p>Manzo fue atacado con un arma de fuego el 1 de noviembre, al t\u00e9rmino de una festividad local, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/02\/mexico\/matan-carlos-manzo-alcalde-uruapan-michoacan-orix\">y muri\u00f3 momentos despu\u00e9s<\/a> al ser llevado a un hospital, seg\u00fan inform\u00f3 la Fiscal\u00eda esa misma noche. En ese primer reporte, la Fiscal\u00eda tambi\u00e9n indic\u00f3 que el presunto agresor fue abatido.<\/p>\n<p>\u201cSe est\u00e1 investigando tambi\u00e9n por qu\u00e9 se dio el abatimiento en el lugar del homicida, porque al homicida lo detienen y momentos despu\u00e9s hay un forcejeo y hay un solo disparo que abate al homicida. Eso tambi\u00e9n se est\u00e1 investigando, est\u00e1 investigando la Fiscal\u00eda todo este tema\u201d, dijo Ram\u00edrez Bedolla el lunes.<\/p>\n<p>El secretario Garc\u00eda Harfuch tambi\u00e9n habl\u00f3 del asunto este martes, <a href=\"https:\/\/www.youtube.com\/watch?v=-zHK5DUcMS0\">durante la rueda de prensa diaria<\/a> de la presidenta de M\u00e9xico, Claudia Sheinbaum.<\/p>\n<p>Garc\u00eda Harfuch dijo que los polic\u00edas municipales van a volver a rendir una declaraci\u00f3n sobre los hechos. Ninguno est\u00e1 en calidad de detenido y todos acuden a declarar cada que se les llama, detall\u00f3.<\/p>\n<p>\u201cEntonces, las investigaciones contin\u00faan y son a cargo de la Fiscal\u00eda General de Justicia del Estado y lo van a informar m\u00e1s adelante\u201d, agreg\u00f3 Garc\u00eda Harfuch.<\/p>\n<p>La Fiscal\u00eda de Michoac\u00e1n dijo a CNN que por ahora no dar\u00e1 m\u00e1s informaci\u00f3n sobre el caso.<\/p>\n<p>El gobernador se\u00f1al\u00f3 el lunes que otros aspectos que siguen bajo investigaci\u00f3n son si hubo fallas en los c\u00edrculos de seguridad del alcalde \u2014el primero, conformado por ocho polic\u00edas municipales, y el segundo, integrado por 14 elementos de la Guardia Nacional\u2014, as\u00ed como qui\u00e9n est\u00e1 detr\u00e1s del ataque. Desde los posteriores al asesinato, las autoridades han atribuido el crimen a una banda del crimen organizado.<\/p>\n<p>\u201cAlgo fundamental, porque seguros estamos de que es un tema de delincuencia organizada, es establecer qu\u00e9 c\u00e9lula de la delincuencia organizada fue y cu\u00e1l fue el motivo real, espec\u00edfico, para arrebatarle la vida y atentar contra el presidente municipal. La motivaci\u00f3n del homicidio es muy importante\u201d, dijo Ram\u00edrez Bedolla.<\/p>\n<p>El asesinato de Manzo, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/03\/mexico\/quien-carlos-manzo-alcalde-uruapan-mexico-orix\">un pol\u00edtico que lleg\u00f3 a la Alcald\u00eda en 2024 tras ganar las elecciones como candidato independiente<\/a>, ha generado numerosas protestas y dio pie a que el Gobierno de Sheinbaum lanzara un nuevo plan para la seguridad en Michoac\u00e1n.<\/p>\n<p>Durante su gesti\u00f3n, Manzo reiteradamente denunci\u00f3 la situaci\u00f3n de inseguridad en Uruapan y pidi\u00f3 apoyo a los gobiernos federal y estatal. La semana pasada, el Congreso de Michoac\u00e1n nombr\u00f3 a su viuda, Grecia Quiroz, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/05\/mexico\/grecia-quiroz-alcaldesa-uruapan-perfil-orix\">como alcaldesa sustituta<\/a>. En su primer mensaje, ella prometi\u00f3 mantener la exigencia de que la localidad sea un lugar seguro.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades de Michoac\u00e1n, en el suroeste de M\u00e9xico, investigan en qu\u00e9 circunstancias fue abatido el joven se\u00f1alado como el presunto autor del homicidio del alcalde de Uruapan, Carlos Manzo, ocurrido la noche del 1 de noviembre, dijeron el gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, y el secretario de Seguridad federal, Omar Garc\u00eda Harfuch. Durante una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468239","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Autoridades de Michoac\u00e1n, en el suroeste de M\u00e9xico, investigan en qu\u00e9 circunstancias fue abatido el joven se\u00f1alado como el presunto autor del homicidio del alcalde de Uruapan, Carlos Manzo, ocurrido la noche del 1 de noviembre, dijeron el gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, y el secretario de Seguridad federal, Omar Garc\u00eda Harfuch. Durante una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T22:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo\",\"datePublished\":\"2025-11-11T22:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\"},\"wordCount\":597,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\",\"name\":\"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-11T22:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo - Noticias","og_description":"Autoridades de Michoac\u00e1n, en el suroeste de M\u00e9xico, investigan en qu\u00e9 circunstancias fue abatido el joven se\u00f1alado como el presunto autor del homicidio del alcalde de Uruapan, Carlos Manzo, ocurrido la noche del 1 de noviembre, dijeron el gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, y el secretario de Seguridad federal, Omar Garc\u00eda Harfuch. Durante una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-11T22:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/"},"author":{"name":"","@id":""},"headline":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo","datePublished":"2025-11-11T22:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/"},"wordCount":597,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","name":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-11T22:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fiscal\u00eda de Michoac\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-11T22:03:50Z","datePublished":"2025-11-11T22:03:50Z","dateModified":"2025-11-11T22:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fiscal\\u00eda de Michoac\\u00e1n investiga circunstancias de la muerte del presunto autor del homicidio del alcalde Carlos Manzo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/investigan-muerte-presunto-autor-homicidio-carlos-manzo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-11T22:03:50Z\",\"datePublished\":\"2025-11-11T22:03:50Z\",\"dateModified\":\"2025-11-11T22:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468356,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/14\/muertos-presuntos-implicados-asesinato-alcalde-uruapan-orix\/","url_meta":{"origin":1468239,"position":0},"title":"Dos j\u00f3venes presuntamente implicados en el asesinato del alcalde de Uruapan fueron hallados muertos, dice gobernador","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Dos j\u00f3venes que presuntamente estaban involucrados en el asesinato del acalde de Uruapan, Carlos Manzo, fueron encontrados muertos cerca de una carretera del estado de Michoac\u00e1n, dijo el jueves Alfredo Ram\u00edrez Bedolla, gobernador del estado del suroeste de M\u00e9xico.El hallazgo de los cuerpos ocurri\u00f3 el lunes en las inmediaciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468513,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/19\/detenido-presunto-autor-intelectual-carlos-manzo-orix\/","url_meta":{"origin":1468239,"position":1},"title":"Detienen a uno de los presuntos autores intelectuales del homicidio de Carlos Manzo, alcalde de Uruapan","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"Uno de los presuntos autores intelectuales del homicidio de Carlos Manzo, alcalde del municipio de Uruapan asesinado el 1 de noviembre, fue detenido este martes en la ciudad de Morelia, capital del estado de Michoac\u00e1n, informaron este mi\u00e9rcoles el secretario de Seguridad y Protecci\u00f3n Ciudadana del Gobierno federal de M\u00e9xico,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468045,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/05\/asesinato-carlos-manzo-que-sabemos-orix\/","url_meta":{"origin":1468239,"position":2},"title":"Un alcalde asesinado, un presunto atacante abatido y la sombra del crimen en Michoac\u00e1n: qu\u00e9 sabemos del caso de Carlos Manzo","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El alcalde de Uruapan, Carlos Manzo, muri\u00f3 la noche del s\u00e1bado tras ser atacado con arma de fuego en una plaza p\u00fablica del centro de este municipio del estado de Michoac\u00e1n, en el suroeste de M\u00e9xico.Manzo, de 40 a\u00f1os, encabezaba la alcald\u00eda de Uruapan desde el 1 de septiembre de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467958,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/02\/matan-carlos-manzo-alcalde-uruapan-michoacan-orix\/","url_meta":{"origin":1468239,"position":3},"title":"Matan a Carlos Manzo, alcalde de Uruapan, un crimen que se suma a la ola de violencia en el estado mexicano de Michoac\u00e1n","author":"","date":"noviembre 2, 2025","format":false,"excerpt":"El alcalde Uruapan, Carlos Manzo, muri\u00f3 este s\u00e1bado tras ser atacado con arma de fuego en el centro de esta ciudad del estado de Michoac\u00e1n, informaron el gabinete de seguridad de M\u00e9xico y el gobernador de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla.La agresi\u00f3n ocurri\u00f3 por la noche, cuando el funcionario estaba en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467994,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/03\/gobernador-michoacan-crimen-carlos-manzo-efe\/","url_meta":{"origin":1468239,"position":4},"title":"Gobernador de Michoac\u00e1n dice que hay &#171;indicios&#187; de que el crimen organizado est\u00e1 detr\u00e1s del asesinato de Carlos Manzo","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"El gobernador del estado de Michoac\u00e1n, Alfredo Ram\u00edrez Bedolla, afirm\u00f3 este lunes que el alcalde de Uruapan, Carlos Manzo, asesinado el s\u00e1bado, \u201csab\u00eda\u201d que asum\u00eda \u201cun riesgo por su lucha contra la delincuencia\u201d.Adem\u00e1s, el gobernador inform\u00f3 en conferencia de prensa que existen indicios de que la delincuencia organizada est\u00e1 detr\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468091,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/identifica-joven-17-anios-presunto-autor-homicidio-alcalde-uruapan-orix\/","url_meta":{"origin":1468239,"position":5},"title":"Fiscal\u00eda de Michoac\u00e1n identifica a un joven de 17 a\u00f1os como el presunto autor del homicidio del alcalde de Uruapan","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"La Fiscal\u00eda de Michoac\u00e1n identific\u00f3 este jueves a un adolescente de 17 a\u00f1os como el presunto autor material del homicidio del alcalde de Uruapan, Carlos Manzo, ocurrido el s\u00e1bado en la noche al t\u00e9rmino de la celebraci\u00f3n local del Festival de las Velas.\u201cLa tarde de ayer mi\u00e9rcoles 5 de noviembre,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468239"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468239\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}