{"id":1468248,"date":"2025-11-11T19:03:43","date_gmt":"2025-11-12T03:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/"},"modified":"2025-11-11T19:03:43","modified_gmt":"2025-11-12T03:03:43","slug":"que-contiene-proyecto-ley-fin-cierre-gobierno-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","title":{"rendered":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?"},"content":{"rendered":"<p>El Congreso se est\u00e1 moviendo r\u00e1pidamente para aprobar un paquete de financiamiento que pondr\u00eda fin al cierre federal m\u00e1s largo en la historia de Estados Unidos.<\/p>\n<p>La C\u00e1mara tiene previsto votar el mi\u00e9rcoles sobre un proyecto de ley de compromiso despu\u00e9s de que el<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/11\/eeuu\/senado-vota-fin-al-cierre-gobierno-proyecto-representantes-trax\"> Senado aprobara el paquete<\/a> la noche del lunes. <a href=\"https:\/\/www.cnn.com\/2025\/11\/10\/politics\/senators-government-shutdown-votes-vis\">Ocho senadores <\/a>dem\u00f3cratas desafiaron al liderazgo de su partido para apoyar la legislaci\u00f3n, abandonando su demanda clave de que la ley extendiera los <a href=\"https:\/\/www.cnn.com\/2025\/11\/09\/politics\/aca-enrollment-premiums-increase-impact\">subsidios mejorados de la Ley de Cuidado de Salud Asequible <\/a>que est\u00e1n por expirar a fin de a\u00f1o.<\/p>\n<p>Como parte del acuerdo, el Senado votar\u00e1 sobre los subsidios mejorados el pr\u00f3ximo mes. Es notable que el acuerdo con los republicanos no garantiza que la asistencia ampliada se extienda.<\/p>\n<p>Esto es lo que contiene el proyecto de ley, seg\u00fan los res\u00famenes proporcionados por el Congreso:<\/p>\n<p>El proyecto de ley proporcionar\u00eda fondos para la mayor\u00eda de las agencias federales hasta el 30 de enero.<\/p>\n<p>Eso significa que si los dos partidos no logran llegar a un acuerdo sobre otra medida temporal de gastos o un paquete que financie las agencias hasta el final del a\u00f1o fiscal, gran parte del Gobierno federal podr\u00eda volver a cerrar en menos de tres meses.<\/p>\n<p>Sin embargo, la legislaci\u00f3n proporciona financiamiento de todo el a\u00f1o para el Departamento de Agricultura de Estados Unidos (USDA, por sus siglas en ingl\u00e9s), la rama legislativa y las construcciones militares y asuntos de veteranos. As\u00ed que estas funciones continuar\u00edan incluso si se produce un nuevo estancamiento en el Capitolio.<\/p>\n<p>La legislaci\u00f3n financiar\u00eda completamente el programa de cupones de alimentos por el resto del a\u00f1o fiscal, que termina el 30 de septiembre.<\/p>\n<p>El Programa de Asistencia Nutricional Suplementaria (SNAP, por sus siglas en ingl\u00e9s) estuvo en el centro de atenci\u00f3n durante el cierre despu\u00e9s de que el USDA dijera que no recurrir\u00eda a un fondo de contingencia para proporcionar al menos beneficios parciales para noviembre. Se produjero<a href=\"https:\/\/www.cnn.com\/2025\/11\/10\/us\/snap-benefits-limbo-shutdown-court\">n batallas legales,<\/a> lo que result\u00f3 en que algunos de los <a href=\"https:\/\/www.cnn.com\/2025\/11\/11\/politics\/snap-benefits-recipients-struggling\">casi 42 millones de beneficiarios <\/a>de cupones de alimentos del pa\u00eds recibieran sus asignaciones completas la semana pasada, otros recibieran beneficios parciales y otros a\u00fan esperaran cualquier tipo de ayuda.<\/p>\n<p>El acuerdo tambi\u00e9n repondr\u00eda el fondo de contingencia de SNAP y los programas de nutrici\u00f3n infantil, incluidos los almuerzos escolares gratuitos y a precio reducido.<\/p>\n<p>Adem\u00e1s, proporciona US $8.200 millones para Programa Especial de Nutrici\u00f3n Suplementaria para Mujeres, Beb\u00e9s y Ni\u00f1os (conocido como WIC), que atiende a aproximadamente 7 millones de mujeres embarazadas, nuevas madres y ni\u00f1os peque\u00f1os. Eso es un aumento de US$ 603 millones en comparaci\u00f3n con el a\u00f1o fiscal anterior. El fondo de contingencia de WIC tambi\u00e9n ser\u00eda reabastecido.<\/p>\n<p>La legislaci\u00f3n proporciona US $460 millones para el Programa de Alimentos Complementarios para Productos B\u00e1sicos, que suministra cajas de alimentos mensuales a m\u00e1s de 700.000 adultos mayores de bajos ingresos.<\/p>\n<p>Preocupados por su propia seguridad y la de sus equipos, los legisladores incluyeron US$ 203,5 millones en nuevos fondos para reforzar las medidas de seguridad y proteger a los miembros de la C\u00e1mara y el Senado dentro del paquete. Tambi\u00e9n proporciona fondos para apoyar los requerimientos de seguridad f\u00edsica del complejo del Capitolio y las pr\u00e1cticas de ciberseguridad.<\/p>\n<p>El proyecto de ley tambi\u00e9n incluye US$ 852 millones para la Polic\u00eda del Capitolio de EE.UU. y proporciona US$ 28 millones adicionales para la protecci\u00f3n y seguridad de los jueces de la Corte Suprema.<\/p>\n<p>El paquete proporciona US$ 115.000 millones para la atenci\u00f3n m\u00e9dica discrecional de Asuntos de los Veteranos, un aumento de m\u00e1s de US$ 2.300 millones respecto al a\u00f1o fiscal anterior. Incluye fondos para el Fondo de Exposiciones T\u00f3xicas de la Guerra, salud rural, cuidadores, salud de la mujer, prevenci\u00f3n de la falta de vivienda de veteranos, salud mental y cuidado infantil.<\/p>\n<p>La legislaci\u00f3n tambi\u00e9n garantiza el pago retroactivo para aproximadamente 1,4 millones de trabajadores federales que fueron suspendidos o trabajaron sin paga durante el cierre. Muchos han perdido dos cheques de pago completos, adem\u00e1s de uno parcial.<\/p>\n<p>Aunque el presidente Donald Trump firm\u00f3 un proyecto de ley durante el estancamiento de 2018-2019 que aseguraba que los trabajadores federales recibir\u00edan el pago retroactivo, <a href=\"https:\/\/www.cnn.com\/2025\/10\/07\/politics\/government-workers-shutdown-compensation\">el Gobierno puso<\/a> en duda si los empleados suspendidos ser\u00edan compensados cuando terminara este cierre.<\/p>\n<p>El paquete tambi\u00e9n revierte los esfuerzos de varias agencias para implementar reducciones de personal durante el cierre, estableciendo que los niveles de fuerza laboral volver\u00e1n a lo que eran antes de la interrupci\u00f3n de las asignaciones presupuestarias. Tambi\u00e9n impide despidos adicionales de empleados federales hasta el 30 de enero.<\/p>\n<p>Al menos siete agencias enviaron avisos de reducci\u00f3n de personal a aproximadamente <a href=\"https:\/\/www.cnn.com\/2025\/10\/14\/politics\/federal-worker-layoffs-government-shutdown\">4.000 trabajadores<\/a> en octubre, aunque las acciones fueron suspendidas por un tribunal federal.<\/p>\n<p>El acuerdo incluye una secci\u00f3n que requerir\u00eda que el Departamento de Justicia y el FBI notifiquen al Senado cuando un legislador est\u00e9 bajo investigaci\u00f3n y si su informaci\u00f3n personal est\u00e1 siendo citada.<\/p>\n<p>El lenguaje<a href=\"https:\/\/www.appropriations.senate.gov\/imo\/media\/doc\/lbfy26aconf.pdf\">, incluido en uno de los proyectos de ley<\/a> de asignaciones presupuestarias, surge despu\u00e9s de que los republicanos del Senado publicaron registros del FBI relacionados con una investigaci\u00f3n denominada \u201cArctic Frost\u201d, que se refer\u00eda al plan de electores falsos de 2020 donde aliados de Trump presionaron a los electores republicanos para registrar votos del colegio electoral para Trump en estados en los que hab\u00eda ganado el expresidente Joe Biden.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso se est\u00e1 moviendo r\u00e1pidamente para aprobar un paquete de financiamiento que pondr\u00eda fin al cierre federal m\u00e1s largo en la historia de Estados Unidos. La C\u00e1mara tiene previsto votar el mi\u00e9rcoles sobre un proyecto de ley de compromiso despu\u00e9s de que el Senado aprobara el paquete la noche del lunes. Ocho senadores dem\u00f3cratas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468248","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Congreso se est\u00e1 moviendo r\u00e1pidamente para aprobar un paquete de financiamiento que pondr\u00eda fin al cierre federal m\u00e1s largo en la historia de Estados Unidos. La C\u00e1mara tiene previsto votar el mi\u00e9rcoles sobre un proyecto de ley de compromiso despu\u00e9s de que el Senado aprobara el paquete la noche del lunes. Ocho senadores dem\u00f3cratas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T03:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?\",\"datePublished\":\"2025-11-12T03:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\"},\"wordCount\":976,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\",\"name\":\"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-12T03:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.? - Noticias","og_description":"El Congreso se est\u00e1 moviendo r\u00e1pidamente para aprobar un paquete de financiamiento que pondr\u00eda fin al cierre federal m\u00e1s largo en la historia de Estados Unidos. La C\u00e1mara tiene previsto votar el mi\u00e9rcoles sobre un proyecto de ley de compromiso despu\u00e9s de que el Senado aprobara el paquete la noche del lunes. Ocho senadores dem\u00f3cratas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-12T03:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?","datePublished":"2025-11-12T03:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/"},"wordCount":976,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","name":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-12T03:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 contiene el proyecto de ley que pondr\u00eda fin al cierre del Gobierno m\u00e1s largo en la historia de EE.UU.?","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-12T03:03:43Z","datePublished":"2025-11-12T03:03:43Z","dateModified":"2025-11-12T03:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 contiene el proyecto de ley que pondr\\u00eda fin al cierre del Gobierno m\\u00e1s largo en la historia de EE.UU.?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/11\\\/que-contiene-proyecto-ley-fin-cierre-gobierno-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-12T03:03:43Z\",\"datePublished\":\"2025-11-12T03:03:43Z\",\"dateModified\":\"2025-11-12T03:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468236,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/11\/que-sigue-fin-cierre-del-gobierno-senado-camara-trax\/","url_meta":{"origin":1468248,"position":0},"title":"El Senado envi\u00f3 un proyecto de ley de financiamiento a la C\u00e1mara. \u00bfQu\u00e9 sigue para poner fin al cierre del Gobierno?","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"Los senadores aprobaron un paquete de financiamiento para reabrir el Gobierno federal, enviando el acuerdo de compromiso a sus colegas en la C\u00e1mara.Dem\u00f3cratas centristas del Senado lograron un acuerdo durante el fin de semana con los republicanos para avanzar el paquete, sin asegurar la exigencia de su partido de garantizar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468211,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/10\/senado-vota-fin-al-cierre-gobierno-proyecto-representantes-trax\/","url_meta":{"origin":1468248,"position":1},"title":"El Senado aprueba poner fin al cierre del Gobierno de EE.UU. y env\u00eda el plan de financiaci\u00f3n a la C\u00e1mara de Representantes","author":"","date":"noviembre 10, 2025","format":false,"excerpt":"Un peque\u00f1o grupo de senadores dem\u00f3cratas vot\u00f3 este lunes por la noche con los republicanos para aprobar una medida de financiaci\u00f3n para reabrir el Gobierno federal, sin lograr la exigencia de su partido de garantizar una extensi\u00f3n de los subsidios mejorados de la Ley de Cuidado de Salud Asequible, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468103,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/06\/senadores-avanzan-acuerdo-fin-cierre-gobierno-trax\/","url_meta":{"origin":1468248,"position":2},"title":"Senadores avanzan hacia un acuerdo para poner fin al cierre del Gobierno mientras persisten los \u00faltimos obst\u00e1culos","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Los l\u00edderes del Senado se acercan a preparar las votaciones para terminar con el cierre del Gobierno, ya que los negociadores se reunieron nuevamente este jueves por la ma\u00f1ana en un intento de concretar los detalles finales, seg\u00fan fuentes de ambos partidos.Se espera que esos detalles vuelvan a ser presentados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468178,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/09\/senado-intentar-poner-fin-cierre-gobierno-sin-precedentes-trax\/","url_meta":{"origin":1468248,"position":3},"title":"El Senado se re\u00fane para continuar conversaciones e intentar poner fin al cierre de Gobierno sin precedentes","author":"","date":"noviembre 9, 2025","format":false,"excerpt":"El Senado regresa la tarde de este domingo para continuar las conversaciones que buscan poner fin al cierre de Gobierno sin precedentes en Estados Unidos, despu\u00e9s de que la C\u00e1mara Alta concluyera la noche del s\u00e1bado sin llegar a un acuerdo.El Senado se re\u00fane de nuevo a la 1:30 p.m.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468141,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/08\/democratas-bloquean-proyecto-republicano-cierre-gobierno-trax\/","url_meta":{"origin":1468248,"position":4},"title":"Dem\u00f3cratas del Senado bloquean proyecto republicano para pagar a trabajadores federales y se agrava el cierre del Gobierno","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"El Senado de EE.UU. no logr\u00f3 aprobar un proyecto de ley este viernes para pagar a los trabajadores federales forzados a trabajar sin sueldo durante el cierre del Gobierno, ya que los dem\u00f3cratas se negaron a ceder ante los intentos republicanos de financiar cualquier parte del aparato gubernamental sin importantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468283,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/12\/congreso-paquete-financiacion-reabrir-gobierno-trump-trax\/","url_meta":{"origin":1468248,"position":5},"title":"El Congreso aprueba paquete de financiamiento para reabrir el Gobierno federal y lo env\u00eda a Trump para su firma","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"Ambas c\u00e1maras del Congreso han votado a favor de poner fin al cierre federal m\u00e1s largo de la historia, y enviaron un proyecto de ley de financiamiento para reabrir el Gobierno al presidente Donald Trump para su firma.La C\u00e1mara de Representantes vot\u00f3 este mi\u00e9rcoles por la noche para dar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468248"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468248\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}