{"id":1468257,"date":"2025-11-12T05:03:41","date_gmt":"2025-11-12T13:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/"},"modified":"2025-11-12T05:03:41","modified_gmt":"2025-11-12T13:03:41","slug":"monte-nemrut-colosales-dioses-piedra-turquia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","title":{"rendered":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os"},"content":{"rendered":"<p>El monte Nemrut se eleva m\u00e1s de 2.000 metros sobre la provincia de Ad\u0131yaman, en Turqu\u00eda, mientras sus laderas se desvanecen desde olivares a roca desnuda.<\/p>\n<p>Desde la distancia, parece un pico cualquiera de la cordillera oriental del Tauro, hasta que las colosales cabezas aparecen a la vista.<\/p>\n<p>Se asientan en una l\u00ednea solemne cerca de la cima: grandes rostros de piedra, sus rasgos suavizados por siglos de terremotos, heladas y sol. Muy abajo, las cabras se abren paso entre la hierba seca mientras el viento sopla por el paisaje.<\/p>\n<p>Es dif\u00edcil saber qu\u00e9 es m\u00e1s sorprendente: encontrarse con estas cabezas gigantes cerca de la cima de una de las monta\u00f1as m\u00e1s altas del sureste de Turqu\u00eda, o el hecho de que alguien creyera que durar\u00edan para siempre.<\/p>\n<p>Pero ese era el sue\u00f1o del rey Ant\u00edoco: construir una monta\u00f1a donde pudiera sentarse entre deidades, su poder tallado en piedra y encerrado en una eterna competencia de miradas con el horizonte.<\/p>\n<p>Ant\u00edoco I gobern\u00f3 un estado llamado Comagene que floreci\u00f3 brevemente hace 2.000 a\u00f1os en una regi\u00f3n al norte de Siria y el r\u00edo \u00c9ufrates, despu\u00e9s de la desintegraci\u00f3n del imperio de Alejandro Magno. Fue un lugar donde chocaron las tradiciones griega, persa, asiria y armenia.<\/p>\n<p>Con la esperanza de mantener su influencia sobre la regi\u00f3n incluso despu\u00e9s de la muerte, Ant\u00edoco mand\u00f3 construir su tumba en Nemrut, flanqueada por figuras de piedra que representaban el singular mosaico de mitolog\u00edas que rodeaban su reino.<\/p>\n<p>El propio Ant\u00edoco estaba sentado entre ellas, code\u00e1ndose con la inmortalidad.<\/p>\n<p>El tiempo y la naturaleza ten\u00edan otros planes. Hoy, las estatuas yacen decapitadas y agrietadas, pero a\u00fan vigilan la cima de la monta\u00f1a, conocida localmente como el \u201cTrono de los Dioses\u201d.<\/p>\n<p>El paisaje bien vale la subida, con vistas espectaculares del sureste de Turqu\u00eda, por no mencionar los hermosos amaneceres y atardeceres.<\/p>\n<p>Pero el flujo constante de visitantes que llegan hasta aqu\u00ed, ya sea a pie o por la carretera que serpentea por la mayor parte de la monta\u00f1a, est\u00e1n aqu\u00ed por las maravillas arqueol\u00f3gicas.<\/p>\n<p>El aislamiento de la cima de la monta\u00f1a ofrece espacio para imaginar el rico pasado de Comagene y las complejas batallas y tratados que definieron la b\u00fasqueda de nuevos territorios por parte de un reino.<\/p>\n<p>Llegar a la cima de Nemrut es relativamente sencillo. Los visitantes pueden caminar, pero tambi\u00e9n hay una carretera que lleva la mayor parte del camino, accesible en auto o con una visita guiada.<\/p>\n<p>El trayecto de 50 minutos en autom\u00f3vil desde el distrito de Kahta de Ad\u0131yaman hasta la entrada del Parque Nacional del Monte Nemrut forma parte de la experiencia.<\/p>\n<p>A lo largo del camino, las cabras y las vacas que pastan al borde de la carretera crean escenas pastorales que probablemente han cambiado poco a lo largo de los siglos.<\/p>\n<p>M\u00e1s arriba, el puente Septimio Severo, una maravilla de la ingenier\u00eda romana, todav\u00eda cruza el r\u00edo Cendere, mientras que el t\u00famulo de Karaku\u015f conmemora a las mujeres de la familia real de Comagene, ofreciendo una rara visi\u00f3n de la vida cotidiana y ceremonial del reino.<\/p>\n<p>La ruta tambi\u00e9n pasa por las ruinas de Arsemia, el antiguo santuario real. Tallada en los acantilados se encuentra una de las inscripciones griegas antiguas m\u00e1s largas encontradas en esta regi\u00f3n. Se sit\u00faa sobre un relieve bien conservado que representa un \u201capret\u00f3n de manos de los dioses\u201d: el rey Mitr\u00eddates I estrechando la mano del h\u00e9roe Heracles.<\/p>\n<p>Justo antes del ascenso final, vale la pena detenerse para contemplarlo todo. En la hora dorada, el sol proyecta una luz dram\u00e1tica sobre el antiguo reino.<\/p>\n<p>En las estribaciones del Nemrut, el pueblo agr\u00edcola de Kahta ofrece otra mirada al pasado, uno que a\u00fan vive. Aqu\u00ed, las estructuras de dos pisos construidas de piedra se han mantenido sin cambios durante generaciones.<\/p>\n<p>El piso inferior sirve de almacenamiento y refugio para ovejas y cabras, el nivel superior es una casa familiar. Osman Aksoy, que ofrece t\u00e9 a los visitantes en su granja, describe a la comunidad como \u201cun activo superviviente de la historia de la regi\u00f3n\u201d.<\/p>\n<p>M\u00e1s arriba en la monta\u00f1a, la carretera llega a un moderno aparcamiento e instalaciones, incluido un centro de visitantes.<\/p>\n<p>En su apogeo, hace dos milenios, este lugar era un sitio sagrado o complejo real, y habr\u00eda estado repleto de fieles y funcionarios.<\/p>\n<p>Despu\u00e9s de pagar una entrada de aproximadamente US$ 12, los visitantes se enfrentan a una caminata de 25 minutos para llegar a las terrazas de la cima.<\/p>\n<p>Se recomienda usar calzado resistente y ropa de abrigo, especialmente al amanecer y al atardecer, incluso en pleno verano. La subida implica una caminata de 500 metros por aproximadamente 300 escalones, algunos bastante empinados.<\/p>\n<p>El aire se enrarece con cada paso ascendente en la antigua escalera de piedra, y el mundo comienza a desvanecerse abajo.<\/p>\n<p>Pronto, una inmensa cima artificial de piedra triturada \u2014el t\u00famulo\u2014 domina todo el horizonte.<\/p>\n<p>Es aqu\u00ed donde la monumental ambici\u00f3n de Nemrut se hace evidente.<\/p>\n<p>Mucho antes de que se formaran las fronteras modernas de Turqu\u00eda, el Reino de Comagene floreci\u00f3 aqu\u00ed: un feudo peque\u00f1o, pero rico que fusion\u00f3 las tradiciones de la regi\u00f3n m\u00e1s amplia en algo completamente propio.<\/p>\n<p>Las figuras de piedra en Nemrut combinan tradiciones griegas, persas y armenias: Zeus, Apolo y Heracles reimaginados a trav\u00e9s de s\u00edmbolos y estilo orientales, junto con una diosa local de la fertilidad y el propio Ant\u00edoco.<\/p>\n<p>Los monumentos, que se cree que alguna vez alcanzaron m\u00e1s de 15 metros de altura, fueron dise\u00f1ados para asegurar su inmortalidad. Pero despu\u00e9s de que los romanos conquistaron Comagene, el santuario fue abandonado a la intemperie.<\/p>\n<p>Hoy en d\u00eda, las cabezas derribadas son un recordatorio inquietante de la ambici\u00f3n eterna de un rey.<\/p>\n<p>Se cree que el t\u00famulo de 50 metros de altura que corona Nemrut alberga el lugar de descanso final de Ant\u00edoco I, pero el misterio de la tumba oculta del rey ha desconcertado a los arque\u00f3logos durante m\u00e1s de un siglo.<\/p>\n<p>Karl Sester, un ingeniero alem\u00e1n que trabajaba en la regi\u00f3n, inform\u00f3 por primera vez sobre el sitio a la Academia Prusiana de Ciencias en 1881.<\/p>\n<p>M\u00e1s tarde, la arque\u00f3loga estadounidense Theresa Goell pas\u00f3 d\u00e9cadas excavando t\u00faneles a trav\u00e9s de las laderas de la monta\u00f1a, buscando la c\u00e1mara, pero nunca la encontr\u00f3. Algunos comparan su complejo dise\u00f1o interno con el ingenio de las pir\u00e1mides egipcias.<\/p>\n<p>En 2006, la Universidad T\u00e9cnica de Medio Oriente en Ankara lanz\u00f3 un nuevo programa de investigaci\u00f3n, utilizando tecnolog\u00eda moderna para continuar lo que Goell comenz\u00f3, pero sin perturbar el sitio.<\/p>\n<p>\u201cNo ha sido posible ning\u00fan intento de excavaci\u00f3n desde 1987\u201d, apunta el gu\u00eda autorizado Salih Abursu. \u201cEsa protecci\u00f3n garantiza que el misterio de la c\u00e1mara oculta del rey Ant\u00edoco, y su contenido, permanezca intacto. Mantiene los secretos m\u00e1s profundos del sitio a salvo de los saqueadores de tumbas y del paso del tiempo\u201d.<\/p>\n<p>Hoy en d\u00eda, Nemrut es un parque nacional protegido, cuidadosamente restaurado y estabilizado para los visitantes, incluyendo el uso de \u201cnano cal\u201d inyectada en finas grietas para proteger las fr\u00e1giles estatuas de piedra de los fuertes vientos, la nieve y el calor del verano.<\/p>\n<p>En la cima, tres terrazas \u2014este, norte y oeste\u2014 se despliegan como un antiguo escenario.<\/p>\n<p>La terraza norte nunca se complet\u00f3, pero la este revela una disposici\u00f3n procesional de deidades colosales, relieves ancestrales y un altar ritual.<\/p>\n<p>Las cinco figuras principales dominan: Zeus, Apolo, Heracles, la diosa de la fertilidad Comagene y Ant\u00edoco, flanqueados por un le\u00f3n y un \u00e1guila, s\u00edmbolos del poder terrenal y celestial.<\/p>\n<p>En la terraza oeste, siglos de terremotos y erosi\u00f3n han dejado las estatuas dispersas y decapitadas. Sus enormes cabezas se encuentran ahora entre las im\u00e1genes m\u00e1s ic\u00f3nicas de Turqu\u00eda.<\/p>\n<p>Beste Tomay, acad\u00e9mica y experta en arqueolog\u00eda del Nemrut en la Universidad de Ad\u0131yaman, afirma que un relieve en la terraza oeste que representa un le\u00f3n marcado con estrellas y una luna creciente es muy significativo.<\/p>\n<p>\u201cEsta losa de piedra se considera el calendario astrol\u00f3gico m\u00e1s antiguo conocido del mundo\u201d, sostiene. Tambi\u00e9n fija la fecha de la entronizaci\u00f3n del rey Ant\u00edoco I el 7 de julio del 62 a.C.<\/p>\n<p>Las inscripciones talladas en griego en los respaldos de los tronos revelan 237 l\u00edneas de decreto real: detalles del linaje divino de Ant\u00edoco, sus leyes y su deseo de que las generaciones futuras lo celebren con fiestas y reverencia.<\/p>\n<p>Debajo de la cima, la vista es vasta: barrancos que se precipitan a ambos lados, las monta\u00f1as Tauro que se alzan al norte y las doradas llanuras de Mesopotamia que se extienden infinitamente hacia el sur, hacia el r\u00edo \u00c9ufrates.<\/p>\n<p>Al caer la tarde, los turistas se re\u00fanen entre los dioses ca\u00eddos para ver c\u00f3mo el sol se oculta en el horizonte.<\/p>\n<p>\u201cNos impresion\u00f3 mucho su profunda herencia antigua y la vista espectacular\u201d, comenta Julian Boschmann, quien visitaba el lugar desde Chicago con un amigo.<\/p>\n<p>La luz comienza a cambiar. Las estatuas brillan rojas, luego \u00e1mbar, antes de desvanecerse en el sol poniente. Las sombras se extienden sobre los rostros de piedra mientras la monta\u00f1a se hunde de nuevo en el silencio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El monte Nemrut se eleva m\u00e1s de 2.000 metros sobre la provincia de Ad\u0131yaman, en Turqu\u00eda, mientras sus laderas se desvanecen desde olivares a roca desnuda. Desde la distancia, parece un pico cualquiera de la cordillera oriental del Tauro, hasta que las colosales cabezas aparecen a la vista. Se asientan en una l\u00ednea solemne cerca [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468257","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"El monte Nemrut se eleva m\u00e1s de 2.000 metros sobre la provincia de Ad\u0131yaman, en Turqu\u00eda, mientras sus laderas se desvanecen desde olivares a roca desnuda. Desde la distancia, parece un pico cualquiera de la cordillera oriental del Tauro, hasta que las colosales cabezas aparecen a la vista. Se asientan en una l\u00ednea solemne cerca [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T13:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os\",\"datePublished\":\"2025-11-12T13:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\"},\"wordCount\":1650,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\",\"name\":\"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-12T13:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os - Noticias","og_description":"El monte Nemrut se eleva m\u00e1s de 2.000 metros sobre la provincia de Ad\u0131yaman, en Turqu\u00eda, mientras sus laderas se desvanecen desde olivares a roca desnuda. Desde la distancia, parece un pico cualquiera de la cordillera oriental del Tauro, hasta que las colosales cabezas aparecen a la vista. Se asientan en una l\u00ednea solemne cerca [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-12T13:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/"},"author":{"name":"","@id":""},"headline":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os","datePublished":"2025-11-12T13:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/"},"wordCount":1650,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","name":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-12T13:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Monte Nemrut, en Turqu\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\u00f1os","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/12\/monte-nemrut-colosales-dioses-piedra-turquia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-12T13:03:41Z","datePublished":"2025-11-12T13:03:41Z","dateModified":"2025-11-12T13:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Monte Nemrut, en Turqu\\u00eda, un lugar donde colosales dioses de piedra custodian un misterio que ya tiene 2.000 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/12\\\/monte-nemrut-colosales-dioses-piedra-turquia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/12\\\/monte-nemrut-colosales-dioses-piedra-turquia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-12T13:03:41Z\",\"datePublished\":\"2025-11-12T13:03:41Z\",\"dateModified\":\"2025-11-12T13:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455326,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/10\/23\/quien-estaria-detras-ataque-terrorista-ankara-turquia-trax\/","url_meta":{"origin":1468257,"position":0},"title":"\u00bfQui\u00e9n estar\u00eda detr\u00e1s del ataque terrorista en Ankara, Turqu\u00eda, que dej\u00f3 al menos 5 muertos?","author":"","date":"octubre 23, 2024","format":false,"excerpt":"(CNN) -- Los ministros del Interior y Defensa de Turqu\u00eda sugirieron que el Partido de los Trabajadores del Kurdist\u00e1n (PKK) estaba detr\u00e1s del ataque del mi\u00e9rcoles en la sede de la compa\u00f1\u00eda nacional de aeroespacial de Turqu\u00eda cerca de la capital, Ankara. El PKK est\u00e1 clasificado como una organizaci\u00f3n terrorista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452400,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/03\/organizacion-juvenil-turca-agreden-infantes-marina-estadounidenses-trax\/","url_meta":{"origin":1468257,"position":1},"title":"Miembros de una organizaci\u00f3n juvenil nacionalista de Turqu\u00eda son detenidos tras agredir a infantes de Marina estadounidenses","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 M\u00e1s de una decena de miembros de una organizaci\u00f3n juvenil nacionalista de Turqu\u00eda fueron detenidos en la ciudad turca de Esmirna despu\u00e9s de que, seg\u00fan las autoridades locales, agredieran a dos infantes de Marina estadounidenses.Los infantes de Marina, asignados a la 24\u00aa Unidad Expedicionaria de Marines, estaban en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456717,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/18\/por-que-otros-paises-atacan-siria-assad-isis-trax\/","url_meta":{"origin":1468257,"position":2},"title":"Por qu\u00e9 las potencias extranjeras siguen apuntando a Siria tras la ca\u00edda del r\u00e9gimen de Assad","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Pese a que Bashar al-Assad y su r\u00e9gimen de a\u00f1os de duraci\u00f3n cay\u00f3 en Siria, el pa\u00eds sigue siendo un campo de batalla para una serie de actores que buscan asegurar sus intereses en lo que puede convertirse en un peligroso vac\u00edo de poder.Mientras el Hayat Tahrir al-Sham (HTS) asume\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446746,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/09\/pan-turquia-mas-antiguo-mundo-trax\/","url_meta":{"origin":1468257,"position":3},"title":"Descubren el &#171;pan m\u00e1s antiguo del mundo&#187;, con 8.600 a\u00f1os de antig\u00fcedad, en Turqu\u00eda","author":"","date":"marzo 9, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Arque\u00f3logos en Turqu\u00eda aseguran que descubrieron el pan m\u00e1s antiguo del mundo conocido hasta ahora, que data del 6600 antes de Cristo.Una estructura de horno, destruida en su mayor parte, fue hallada en un \u00e1rea llamada \u201cMekan 66\u201d, donde hay casas contiguas de adobe, dentro del sitio arqueol\u00f3gico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469530,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/23\/jefe-ejercito-libia-muere-accidente-aereo-turquia-trax\/","url_meta":{"origin":1468257,"position":4},"title":"El jefe del Ej\u00e9rcito de Libia muere en accidente a\u00e9reo en Turqu\u00eda","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"El jefe del Ej\u00e9rcito de Libia muri\u00f3 en un accidente a\u00e9reo mientras regresaba a Tr\u00edpoli tras una visita oficial a Turqu\u00eda, inform\u00f3 el primer ministro Abdulhamid al-Dbeibah.El teniente general Mohamed al-Haddad falleci\u00f3 junto a cuatro acompa\u00f1antes en un \u201ctr\u00e1gico accidente\u201d durante el vuelo de regreso desde Ankara, seg\u00fan el comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448814,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/03\/turquia-comercio-israel-gaza-trax\/","url_meta":{"origin":1468257,"position":5},"title":"Turqu\u00eda suspende el comercio con Israel por la guerra en Gaza","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN) -- Turqu\u00eda suspendi\u00f3 todas las transacciones de importaci\u00f3n y exportaci\u00f3n con Israel en protesta por la guerra en Gaza.\"Todas las transacciones de importaci\u00f3n y exportaci\u00f3n relacionadas con Israel, incluidos todos los productos, han sido detenidas\", dijo el Ministerio de Comercio de Turqu\u00eda en un comunicado el jueves. \"Turqu\u00eda implementar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468257"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468257\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}