{"id":1468819,"date":"2025-11-29T11:03:38","date_gmt":"2025-11-29T19:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/"},"modified":"2025-11-29T11:03:38","modified_gmt":"2025-11-29T19:03:38","slug":"tom-stoppard-muere-shakespeare-in-love-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","title":{"rendered":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;"},"content":{"rendered":"<p>El galardonado dramaturgo y guionista brit\u00e1nico Tom Stoppard ha fallecido, seg\u00fan su agencia de talentos, United Agents. Ten\u00eda 88 a\u00f1os.<\/p>\n<p>Stoppard, nacido en Checoslovaquia, gan\u00f3 recientemente el Premio Tony 2023 por su obra \u201cLeopoldstadt\u201d.<\/p>\n<p>Stoppard era conocido en Estados Unidos por su guion ganador del Oscar de la pel\u00edcula de 1998 \u201cShakespeare in Love\u201d, que coescribi\u00f3 con Marc Norman.<\/p>\n<p>\u201cNos entristece profundamente anunciar que nuestro querido cliente y amigo, Tom Stoppard, ha fallecido en paz en su hogar en Dorset, rodeado de su familia\u201d, declar\u00f3 United Agents en un comunicado publicado en su sitio web.<\/p>\n<p>\u201cSer\u00e1 recordado por sus obras, por su brillantez y humanidad, y por su ingenio, su irreverencia, su generosidad y su profundo amor por el ingl\u00e9s\u201d, continu\u00f3 el comunicado. \u201cFue un honor trabajar con Tom y conocerlo\u201d.<\/p>\n<p>CNN se ha puesto en contacto con United Agents para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p><em>Esta historia est\u00e1 en desarrollo y ser\u00e1 actualizada. <\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El galardonado dramaturgo y guionista brit\u00e1nico Tom Stoppard ha fallecido, seg\u00fan su agencia de talentos, United Agents. Ten\u00eda 88 a\u00f1os. Stoppard, nacido en Checoslovaquia, gan\u00f3 recientemente el Premio Tony 2023 por su obra \u201cLeopoldstadt\u201d. Stoppard era conocido en Estados Unidos por su guion ganador del Oscar de la pel\u00edcula de 1998 \u201cShakespeare in Love\u201d, que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468819","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &quot;Shakespeare in Love&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &quot;Shakespeare in Love&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El galardonado dramaturgo y guionista brit\u00e1nico Tom Stoppard ha fallecido, seg\u00fan su agencia de talentos, United Agents. Ten\u00eda 88 a\u00f1os. Stoppard, nacido en Checoslovaquia, gan\u00f3 recientemente el Premio Tony 2023 por su obra \u201cLeopoldstadt\u201d. Stoppard era conocido en Estados Unidos por su guion ganador del Oscar de la pel\u00edcula de 1998 \u201cShakespeare in Love\u201d, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-29T19:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;\",\"datePublished\":\"2025-11-29T19:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\"},\"wordCount\":191,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\",\"name\":\"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por \\\"Shakespeare in Love\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-29T19:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por \"Shakespeare in Love\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por \"Shakespeare in Love\" - Noticias","og_description":"El galardonado dramaturgo y guionista brit\u00e1nico Tom Stoppard ha fallecido, seg\u00fan su agencia de talentos, United Agents. Ten\u00eda 88 a\u00f1os. Stoppard, nacido en Checoslovaquia, gan\u00f3 recientemente el Premio Tony 2023 por su obra \u201cLeopoldstadt\u201d. Stoppard era conocido en Estados Unidos por su guion ganador del Oscar de la pel\u00edcula de 1998 \u201cShakespeare in Love\u201d, que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-29T19:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/"},"author":{"name":"","@id":""},"headline":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;","datePublished":"2025-11-29T19:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/"},"wordCount":191,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","name":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por \"Shakespeare in Love\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-29T19:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere a los 88 a\u00f1os el dramaturgo brit\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;","url":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2025\/11\/29\/tom-stoppard-muere-shakespeare-in-love-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-29T19:03:38Z","datePublished":"2025-11-29T19:03:38Z","dateModified":"2025-11-29T19:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere a los 88 a\\u00f1os el dramaturgo brit\\u00e1nico Tom Stoppard, ganador del Oscar por &#171;Shakespeare in Love&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/29\\\/tom-stoppard-muere-shakespeare-in-love-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2025\\\/11\\\/29\\\/tom-stoppard-muere-shakespeare-in-love-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-29T19:03:38Z\",\"datePublished\":\"2025-11-29T19:03:38Z\",\"dateModified\":\"2025-11-29T19:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473222,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/16\/shakespeare-casa-londres-estudio-trax\/","url_meta":{"origin":1468819,"position":0},"title":"Shakespeare pose\u00eda una casa en Londres. Finalmente sabemos d\u00f3nde estaba","author":"","date":"abril 16, 2026","format":false,"excerpt":"Un hallazgo fortuito en un archivo londinense ha permitido a un investigador determinar por primera vez la ubicaci\u00f3n exacta de la casa londinense de William Shakespeare.Desde hac\u00eda tiempo se sab\u00eda que el dramaturgo pose\u00eda una casa en Blackfriars, un convento dominico del siglo XIII, y se cre\u00eda que estaba situada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471284,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/16\/muere-actor-robert-duvall-95-anos-trax\/","url_meta":{"origin":1468819,"position":1},"title":"Muere el actor ganador del Oscar Robert Duvall a los 95 a\u00f1os","author":"","date":"febrero 16, 2026","format":false,"excerpt":"Robert Duvall, el actor ganador del Oscar m\u00e1s conocido por \u201cThe Godfather\u201d, \u201cApocalypse Now\u201d y muchos otros papeles de hombre duro a lo largo de una aclamada carrera en pantalla que se extendi\u00f3 por seis d\u00e9cadas, muri\u00f3. Ten\u00eda 95 a\u00f1os.Duvall muri\u00f3 \u201cen paz\u201d en su casa en Middleburg, Virginia, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467359,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/14\/muere-dangelo-michael-eugene-archer-musico-trax\/","url_meta":{"origin":1468819,"position":2},"title":"Muere D\u2019Angelo, cantante de R&#038;B ganador del Grammy, a los 51 a\u00f1os","author":"","date":"octubre 14, 2025","format":false,"excerpt":"El cantante estadounidense D\u2019Angelo, cuyas geniales melod\u00edas y un videoclip impactante lo convirtieron en una leyenda del neo-soul, ha fallecido, seg\u00fan un comunicado de su familia. Ten\u00eda 51 a\u00f1os.\u201cLa estrella brillante de nuestra familia apag\u00f3 su luz en esta vida\u201d, dijo su familia en un comunicado que proporcion\u00f3 a CNN\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442918,"url":"https:\/\/noticiasya.com\/midland-odessa\/2023\/12\/30\/muere-tom-wilkinson-protagonista-de-the-full-monty-y-de-michael-clayton\/","url_meta":{"origin":1468819,"position":3},"title":"Muere Tom Wilkinson, protagonista de &#171;The Full Monty&#187; y de &#171;Michael Clayton&#187;","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"(CNN) --\u00a0Tom Wilkinson, actor dos veces nominado al Oscar por pel\u00edculas como \"Shakespeare in Love\", \"The Full Monty\" y \"Michael Clayton\", falleci\u00f3 este s\u00e1bado a los 75 a\u00f1os.La noticia fue confirmada por la familia de Wilkinson en un comunicado compartido con CNN por la publicista de Wilkinson, Nancy Seltzer.\"Con gran\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451953,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","url_meta":{"origin":1468819,"position":4},"title":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) --Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os.\u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467303,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","url_meta":{"origin":1468819,"position":5},"title":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton","author":"","date":"octubre 11, 2025","format":false,"excerpt":"La muerte de la aclamada actriz Diane Keaton, quien protagoniz\u00f3 \u201cAnnie Hall\u201d y \u201cEl Padrino\u201d, ha sido recibida con gran dolor y sorpresa.La muerte de Keaton fue confirmada a CNN por Dori Rath, una productora que trabaj\u00f3 en varias de sus pel\u00edculas m\u00e1s recientes. No se revel\u00f3 la causa de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1468819"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1468819\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1468819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1468819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1468819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}