{"id":1473095,"date":"2026-04-13T07:03:37","date_gmt":"2026-04-13T14:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/"},"modified":"2026-04-13T07:03:37","modified_gmt":"2026-04-13T14:03:37","slug":"peru-incidentes-ensombrecen-elecciones-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","title":{"rendered":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa"},"content":{"rendered":"<p>Per\u00fa tuvo este domingo una larga jornada electoral, marcada por retrasos que desde temprano dificultaron la apertura de muchos centros de votaci\u00f3n, generaron molestia entre candidatos y ciudadanos, derivaron en que se ampliara el horario para votar y demoraron el escrutinio.<\/p>\n<p>Hasta la ma\u00f1ana de este lunes se ha computado poco m\u00e1s del 52 % de los votos, seg\u00fan la Oficina Nacional de Procesos Electorales (ONPE). Por ahora, los <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnx2zeh10000356rdvc3ca18\">candidatos punteros<\/a> son Keiko Fujimori, de Fuerza Popular, con casi el 17 %, y Rafael L\u00f3pez Aliaga, con casi el 15 %, aunque no se descartan cambios.<\/p>\n<p>En una contienda que tuvo 35 candidatos presidenciales, donde ninguno obtendr\u00eda los votos suficientes para ganar en primera vuelta, los dos punteros ir\u00edan a un balotaje el 7 de junio.<\/p>\n<p>Los electores de Per\u00fa tambi\u00e9n votaron este domingo para elegir senadores y diputados \u2014el pa\u00eds volver\u00e1 a tener un Congreso bicameral\u2014, as\u00ed como representantes del Parlamento Andino.<\/p>\n<p>Desde temprano, se registraron <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnvwnnx80001356qupndobot\">retrasos en la apertura de centros de votaci\u00f3n<\/a>, particularmente en el sur de Lima.<\/p>\n<p>La ONPE dijo que la situaci\u00f3n se debi\u00f3 a problemas log\u00edsticos en la entrega del material electoral. Argument\u00f3 que la empresa encargada del transporte incumpli\u00f3 con su trabajo, por lo que las autoridades electorales debieron activar un plan de contingencia.<\/p>\n<p>El organismo asegur\u00f3 que estos rezagos afectaban solamente al 0,072 % de los m\u00e1s de 10.000 centros de votaci\u00f3n del pa\u00eds. Sin embargo, tanto algunos candidatos como ciudadanos comenzaron a expresar quejas, que m\u00e1s tarde se traducir\u00edan en acusaciones de posible \u201cfraude\u201d.<\/p>\n<p>Por la tarde, luego de los retrasos en la apertura de centros de votaci\u00f3n, el Jurado Nacional de Elecciones (JNE) anunci\u00f3 que el horario para votar <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnw0tjnz001b356qsfqki4oc\">se ampliar\u00eda por una hora<\/a> hasta las 6:00 p.m., hora local (7:00 p.m. ET).<\/p>\n<p>A la par, la Fiscal\u00eda de Per\u00fa inform\u00f3 que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwa8x2p000d356qc8bo4pfk\">realizaba diligencias en la sede de la ONPE<\/a> por el rezago en la entrega del material y para establecer \u201ccoordinaciones necesarias con los \u00f3rganos electorales para garantizar el normal desarrollo de la jornada\u201d.<\/p>\n<p>Hasta la tarde de este domingo, la Fiscal\u00eda no hab\u00eda abierto una investigaci\u00f3n por el asunto.<\/p>\n<p>Frente a los retrasos, el JNE no solo ampli\u00f3 el horario para votar en la mayor parte del pa\u00eds. Tambi\u00e9n inform\u00f3 que se extend\u00eda hasta este lunes a las 6:00 p.m. <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwh6j5o0027356qtrjf1esx\">el plazo para votar en los centros que no pudieron instalarse el domingo<\/a>.<\/p>\n<p>En principio, la ONPE dijo <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwb4vh2000o356qdrbjai90\">que 15 centros no hab\u00edan podido abrir<\/a>, lo que se traduc\u00eda en unos 63.000 electores afectados. M\u00e1s tarde, corrigi\u00f3 la cifra y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwknene002z356qr7t7kgca\">se\u00f1al\u00f3 que fueron 13 centros<\/a>, es decir, unos 52.000 electores.<\/p>\n<p>Los centros donde se prev\u00e9 que se pueda votar hasta la tarde de este lunes est\u00e1n ubicados en Lima y en dos circunscripciones de Estados Unidos: Orlando, en Florida, y Paterson, en Nueva Jersey.<\/p>\n<p>Aunque algunas figuras p\u00fablicas e instituciones respaldaron las decisiones del JNE para ampliar los horarios de votaci\u00f3n debido a los retrasos \u2014como <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwluzlj0036356qodsvt9hr\">el presidente Jos\u00e9 Mar\u00eda Balc\u00e1zar<\/a>, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwj7fi1002t356qafgrwwti\">la Defensor\u00eda del Pueblo<\/a> y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwmm9zp003o356q8fsmg8q2\">la Misi\u00f3n de Observaci\u00f3n Electoral de la Organizaci\u00f3n de los Estados Americanos<\/a>\u2014, algunos actores pol\u00edticos recalcaron su inconformidad con la jornada.<\/p>\n<p>El candidato Rafael L\u00f3pez Aliaga, candidato de Renovaci\u00f3n Popular y exalcalde de Lima, dio una conferencia el domingo en la que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwfi5f6001p356qrvsmhdcw\">acus\u00f3 un supuesto \u201cfraude\u201d<\/a>, estim\u00f3 haber perdido unos 100.000 votos por los centros que no pudieron abrir y critic\u00f3 los sondeos a boca de urna.<\/p>\n<p>De forma similar, Ricardo Belmont, aspirante del Partido C\u00edvico Obras y tambi\u00e9n exalcalde de Lima, dijo que no fue a votar <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/12\/latinoamerica\/live-news\/elecciones-presidenciales-peru-resultados-orix?post-id=cmnwfi5f6001p356qrvsmhdcw\">porque en las elecciones habr\u00e1 un \u201cfraude jam\u00e1s visto\u201d<\/a>. Belmont previ\u00f3 que quedar\u00e1 fuera de la segunda vuelta.<\/p>\n<p>Ninguno de los dos candidatos present\u00f3 pruebas de sus acusaciones.<\/p>\n<p>El conteo de votos tambi\u00e9n comenz\u00f3 con demora debido a los retrasos del d\u00eda.<\/p>\n<p>Hasta la ma\u00f1ana de este lunes, <a href=\"https:\/\/resultadoelectoral.onpe.gob.pe\/main\/resumen\">seg\u00fan los datos de la ONPE<\/a>, los candidatos punteros y quienes pasar\u00edan a la segunda vuelta son Keiko Fujimori, de Fuerza Popular, con casi el 17 % de los votos y Rafael L\u00f3pez Aliaga, de Renovaci\u00f3n Popular, con casi el 15 %.<\/p>\n<p>Detr\u00e1s de ellos est\u00e1n Jorge Nieto, del Partido del Buen Gobierno, con casi el 13 %; Ricardo Belmont, del Partido C\u00edvico Obras, con casi el 10 %; Carlos \u00c1lvarez, de Pa\u00eds para Todos, con casi el 8,5 %, y Roberto S\u00e1nchez, con casi el 8 %.<\/p>\n<p>Sin embargo, dado que apenas se ha contabilizado poco m\u00e1s del 52 % de los votos y en 13 centros a\u00fan se podr\u00e1 votar hasta la tarde de este lunes, especialistas se\u00f1alan que las preferencias a\u00fan pueden moverse y no est\u00e1 definido qui\u00e9nes avanzar\u00edan al balotaje.<\/p>\n<p>Per\u00fa inicia esta semana con un resultado electoral que todav\u00eda es de pron\u00f3stico reservado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per\u00fa tuvo este domingo una larga jornada electoral, marcada por retrasos que desde temprano dificultaron la apertura de muchos centros de votaci\u00f3n, generaron molestia entre candidatos y ciudadanos, derivaron en que se ampliara el horario para votar y demoraron el escrutinio. Hasta la ma\u00f1ana de este lunes se ha computado poco m\u00e1s del 52 % [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473095","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Per\u00fa tuvo este domingo una larga jornada electoral, marcada por retrasos que desde temprano dificultaron la apertura de muchos centros de votaci\u00f3n, generaron molestia entre candidatos y ciudadanos, derivaron en que se ampliara el horario para votar y demoraron el escrutinio. Hasta la ma\u00f1ana de este lunes se ha computado poco m\u00e1s del 52 % [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T14:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa\",\"datePublished\":\"2026-04-13T14:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\"},\"wordCount\":842,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\",\"name\":\"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-13T14:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa - Noticias","og_description":"Per\u00fa tuvo este domingo una larga jornada electoral, marcada por retrasos que desde temprano dificultaron la apertura de muchos centros de votaci\u00f3n, generaron molestia entre candidatos y ciudadanos, derivaron en que se ampliara el horario para votar y demoraron el escrutinio. Hasta la ma\u00f1ana de este lunes se ha computado poco m\u00e1s del 52 % [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-13T14:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/"},"author":{"name":"","@id":""},"headline":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa","datePublished":"2026-04-13T14:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/"},"wordCount":842,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","name":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-13T14:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa","url":"http:\/\/noticiasya.com\/midland-odessa\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-13T14:03:37Z","datePublished":"2026-04-13T14:03:37Z","dateModified":"2026-04-13T14:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"As\\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\\u00fa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2026\\\/04\\\/13\\\/peru-incidentes-ensombrecen-elecciones-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2026\\\/04\\\/13\\\/peru-incidentes-ensombrecen-elecciones-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-13T14:03:37Z\",\"datePublished\":\"2026-04-13T14:03:37Z\",\"dateModified\":\"2026-04-13T14:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473104,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/13\/peru-detienen-exfuncionario-oficina-elecciones-orix\/","url_meta":{"origin":1473095,"position":0},"title":"Detienen a exfuncionario de la Oficina Nacional de Procesos Electorales de Per\u00fa por presuntas omisiones en las elecciones","author":"","date":"abril 13, 2026","format":false,"excerpt":"La Polic\u00eda Nacional de Per\u00fa detuvo este lunes a Jos\u00e9 Edilberto Samam\u00e9 Blas, exgerente de Gesti\u00f3n Electoral de la Oficina Nacional de Procesos Electorales (ONPE), a quien se\u00f1ala como presunto responsable del delito de omisi\u00f3n de actos funcionales durante las elecciones generales que el pa\u00eds tuvo este domingo.En un comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465586,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/17\/rodrigo-paz-pereira-jorge-tuto-quiroga-segunda-vuelta-bolivia-orix\/","url_meta":{"origin":1473095,"position":1},"title":"Rodrigo Paz Pereira y Jorge &#171;Tuto&#187; Quiroga ir\u00e1n a segunda vuelta por la presidencia de Bolivia, seg\u00fan resultados preliminares","author":"","date":"agosto 17, 2025","format":false,"excerpt":"Los candidatos Rodrigo Paz Pereira, del Partido Dem\u00f3crata Cristiano, y Jorge \u201cTuto\u201d Quiroga, de Libertad y Democracia, disputar\u00e1n la presidencia de Bolivia en una segunda vuelta el 19 de octubre, seg\u00fan los resultados preliminares de la primera vuelta anunciados por el Tribunal Supremo Electoral (TSE) la noche de este domingo.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471353,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/17\/congreso-peru-censura-jose-jeri-orix\/","url_meta":{"origin":1473095,"position":2},"title":"El Congreso de Per\u00fa destituye al presidente Jos\u00e9 Jer\u00ed tras aprobar voto de censura","author":"","date":"febrero 17, 2026","format":false,"excerpt":"El Congreso de Per\u00fa aprob\u00f3 este martes una moci\u00f3n de censura contra el presidente interino, Jos\u00e9 Jer\u00ed, cuatro meses despu\u00e9s de que asumiera el cargo y a dos meses de las elecciones generales de abril. Es el octavo cambio de mandatario en casi una d\u00e9cada de inestabilidad pol\u00edtica en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465231,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/07\/favorito-elecciones-bolivia-encuestas-2025-orix\/","url_meta":{"origin":1473095,"position":3},"title":"\u00bfQui\u00e9nes son los favoritos de cara a las elecciones presidenciales en Bolivia 2025?","author":"","date":"agosto 7, 2025","format":false,"excerpt":"A poco m\u00e1s de una semana para las elecciones del 17 de agosto en Bolivia, dos candidatos presidenciales son punteros en las preferencias y, si ninguno de ellos gana por el margen m\u00ednimo establecido en la ley, el pa\u00eds se perfilar\u00e1 a que deba realizarse una segunda vuelta electoral el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472977,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/08\/peru-record-candidatos-presenciales-35-elecciones-orix\/","url_meta":{"origin":1473095,"position":4},"title":"Ning\u00fan pa\u00eds en la regi\u00f3n ha tenido tantos candidatos presidenciales como Per\u00fa. \u00bfQu\u00e9 significa?","author":"","date":"abril 8, 2026","format":false,"excerpt":"Los peruanos estar\u00e1n este domingo frente a la c\u00e9dula de sufragio m\u00e1s grande de su historia: tendr\u00e1 la foto y el s\u00edmbolo del partido de cada uno de los 35 candidatos a la presidencia. La boleta mide m\u00e1s de 42 cent\u00edmetros de ancho, m\u00e1s de 40 de largo y tiene\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471413,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/18\/jose-balcazar-presidente-congreso-peru-orix\/","url_meta":{"origin":1473095,"position":5},"title":"Jos\u00e9 Mar\u00eda Balc\u00e1zar es elegido presidente interino de Per\u00fa tras la destituci\u00f3n de Jos\u00e9 Jer\u00ed","author":"","date":"febrero 18, 2026","format":false,"excerpt":"Jos\u00e9 Mar\u00eda Balc\u00e1zar, del partido Per\u00fa Libre, fue elegido este mi\u00e9rcoles presidente interino de Per\u00fa un d\u00eda despu\u00e9s de la destituci\u00f3n de Jos\u00e9 Jer\u00ed, convirti\u00e9ndose en el octavo mandatario desde la presidencia de Pedro Pablo Kuczynski, en medio de una d\u00e9cada de inestabilidad pol\u00edtica en el pa\u00eds.Con un total de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1473095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1473095"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1473095\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1473095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1473095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1473095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}