{"id":1473190,"date":"2026-04-15T05:03:43","date_gmt":"2026-04-15T12:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/"},"modified":"2026-04-15T05:03:43","modified_gmt":"2026-04-15T12:03:43","slug":"larry-devoe-nuevo-fiscal-general-perfil-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","title":{"rendered":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?"},"content":{"rendered":"<p>Larry Devoe fue elegido por la Asamblea Nacional de Venezuela como el nuevo fiscal general del pa\u00eds, un cargo en el que reemplaza a Tarek William Saab \u2014quien ocup\u00f3 esa posici\u00f3n durante casi una d\u00e9cada\u2014 y al que llega tanto con la promesa de promover los derechos humanos como con cuestionamientos de algunas organizaciones no gubernamentales y especialistas por su desempe\u00f1o en esta materia.<\/p>\n<p>El nombramiento de Devoe, quien ha ocupado otros puestos desde los que ha defendido al chavismo, se suma a otros movimientos institucionales que el Gobierno ha impulsado desde que Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada, luego del operativo militar del 3 de enero en el que Estados Unidos captur\u00f3 a Nicol\u00e1s Maduro.<\/p>\n<p>Devoe fung\u00eda como fiscal encargado desde el 25 de febrero. Tom\u00f3 el mando de la Fiscal\u00eda el mismo d\u00eda que Saab <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/venezuela\/tarek-william-saab-alfredo-ruiz-angulo-renuncias-orix\">comunic\u00f3 su renuncia a la Asamblea Nacional<\/a>, con el argumento de que ya hab\u00eda cumplido su ciclo al frente de la instituci\u00f3n.<\/p>\n<p>El presidente de la Asamblea Nacional, Jorge Rodr\u00edguez \u2014hermano de la presidenta encargada\u2014, fue quien propuso a Devoe mientras se llevaba a cabo el proceso para elegir un relevo definitivo. <a href=\"https:\/\/www.asambleanacional.gob.ve\/storage\/documentos\/documentos\/lista-de-ciudadanas-y-ciudadanos-postulados-a-fiscal-general-20260316133835.pdf\">Se inscribieron en la convocatoria m\u00e1s de 70 personas<\/a>, de las que Devoe <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/09\/venezuela\/larry-devoe-nuevo-fiscal-asamblea-orix\">fue elegido el jueves pasado<\/a>.<\/p>\n<p>Devoe es un abogado egresado de la Universidad Cat\u00f3lica Andr\u00e9s Bello (UCAB), tiene un m\u00e1ster en Derecho Constitucional por la Universidad de Valencia y uno en Democracia, Derechos Humanos y Estado de Derecho por la Universidad de Alcal\u00e1 de Henares, ambas en Espa\u00f1a, y tambi\u00e9n estudi\u00f3 especializaciones en Derecho Penal y Criminal\u00edstica, <a href=\"https:\/\/www.asambleanacional.gob.ve\/noticias\/an-juramenta-a-fiscal-general-y-a-defensor-del-pueblo-temporales\">seg\u00fan dijo Jorge Rodr\u00edguez<\/a> cuando lo propuso como fiscal encargado.<\/p>\n<p>Antes, ocup\u00f3 otras posiciones en el sector p\u00fablico durante el Gobierno de Maduro, quien asumi\u00f3 la presidencia de Venezuela en 2013 tras la muerte de Hugo Ch\u00e1vez.<\/p>\n<p>Devoe fue representante de Venezuela ante el Consejo de Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU) y ante la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH). Desde all\u00ed, reiteradamente rechaz\u00f3 que en su pa\u00eds se cometieran abusos y cuestion\u00f3 la labor de los organismos internacionales. En 2019, por ejemplo, critic\u00f3 que la CIDH expresara preocupaci\u00f3n por las detenciones que se realizaban en Venezuela en el marco de las protestas sociales de ese a\u00f1o.<\/p>\n<p>\u201cLa CIDH contin\u00faa violando el derecho internacional al pronunciarse sin requerir informaci\u00f3n al Estado concernido. Pareciera que olvidan que no son una ONG sino un organismo internacional sujeto a reglas que deben respetar\u201d, <a href=\"https:\/\/x.com\/LarryDevoe\/status\/1091442984703397888\">dijo entonces en X<\/a>.<\/p>\n<p>El defensor de derechos humanos y soci\u00f3logo venezolano Rafael Uzc\u00e1tegui consider\u00f3 que estas posturas muestran que Devoe es \u201cun convencido\u201d de la labor de los gobiernos chavistas.<\/p>\n<p>\u201c\u00c9l siempre fue un negacionista de las violaciones de derechos humanos. Si t\u00fa buscas sus discursos, \u00e9l era el abogado defensor del Estado venezolano. En ese sentido, era una persona de confianza de las autoridades, del propio Nicol\u00e1s Maduro, aunque no estuvo muy cercano al c\u00edrculo de Diosdado Cabello (actual ministro del Interior) y nunca tuvo buenas relaciones con Tarek William Saab, porque sabemos que ten\u00eda la apetencia de llegar a ser fiscal\u201d, dijo Uzc\u00e1tegui a CNN.<\/p>\n<p>Devoe tambi\u00e9n fue secretario ejecutivo del Consejo Nacional de Derechos Humanos (CNDH), un organismo gubernamental creado en 2014. Adem\u00e1s, en enero de este a\u00f1o la presidenta encargada lo incluy\u00f3 en un nuevo Programa para la Convivencia Democr\u00e1tica y la Paz, una iniciativa que busca promover \u201cla estabilidad, la armon\u00eda social y el di\u00e1logo pol\u00edtico nacional\u201d, <a href=\"https:\/\/www.mincultura.gob.ve\/noticias\/presidenta-encargada-delcy-rodriguez-lanza-programa-para-la-paz-y-convivencia-democratica\/\">seg\u00fan se inform\u00f3 entonces<\/a>.<\/p>\n<p>La defensa de Devoe en favor del Gobierno y su negaci\u00f3n de que en Venezuela se hayan cometido violaciones a los derechos humanos no han pasado inadvertidas fuera del pa\u00eds. En 2019, el Gobierno de Canad\u00e1 lo incluy\u00f3 en una lista de 43 personas a quienes impuso sanciones econ\u00f3micas por participar en \u201cel deterioro de la democracia en Venezuela\u201d, <a href=\"https:\/\/gazette.gc.ca\/rp-pr\/p2\/2019\/2019-05-01\/html\/sor-dors106-eng.html\">seg\u00fan inform\u00f3 entonces<\/a>.<\/p>\n<p>En repetidas ocasiones, Maduro y otros funcionarios y exfuncionarios venezolanos han rechazado este tipo de medidas, que tachan de arbitrarias.<\/p>\n<p>Dentro de Venezuela, mientras tanto, algunas organizaciones no gubernamentales expresan dudas sobre la trayectoria de Devoe y consideran que \u00e9l ahora tiene el reto de demostrar independencia como fiscal para que la instituci\u00f3n no pueda ser usada para perseguir opositores, una denuncia constante durante la presidencia de Maduro, que el derrocado mandatario constantemente neg\u00f3.<\/p>\n<p>\u201cLa Fiscal\u00eda no puede continuar siendo una instituci\u00f3n central en la persecuci\u00f3n por motivos pol\u00edticos. Debe estar al servicio de la justicia, sin discriminaci\u00f3n, y contribuir a superar los vicios actualmente existentes en esa instituci\u00f3n y en el Poder Judicial\u201d, dijo el viernes la organizaci\u00f3n Programa Venezolano de Educaci\u00f3n Acci\u00f3n en Derechos Humanos (<a href=\"https:\/\/provea.org\/actualidad\/fiscalia\/\">Provea<\/a>).<\/p>\n<p>Juanita Goebertus, directora para las Am\u00e9ricas de Human Rights Watch (HRW), se pronunci\u00f3 de forma similar en un comunicado enviado a CNN.<\/p>\n<p>\u201cLa designaci\u00f3n de Larry Devoe, cuestionada por su cercan\u00eda con el r\u00e9gimen y un proceso poco transparente, genera preocupaciones leg\u00edtimas de la sociedad civil. Bajo el escrutinio de los venezolanos y de la comunidad internacional, Devoe deber\u00e1 demostrar su voluntad de romper con las pr\u00e1cticas del pasado e impedir que la Fiscal\u00eda siga siendo un instrumento de persecuci\u00f3n, como ocurri\u00f3 con su antecesor. Para empezar, deber\u00eda impulsar la liberaci\u00f3n de todos los presos pol\u00edticos\u201d, dijo.<\/p>\n<p>CNN contact\u00f3 a la Fiscal\u00eda para pedir comentarios sobre estos se\u00f1alamientos y est\u00e1 en espera de respuesta.<\/p>\n<p>El 25 de febrero, el diputado Jorge Rodr\u00edguez dijo que su propuesta para que Devoe asumiera como fiscal encargado \u2014y a la postre como fiscal titular\u2014 era \u201cun mensaje claro\u201d de que al chavismo le interesa la defensa de los derechos humanos.<\/p>\n<p>Dentro de esa l\u00ednea, el primer comunicado de la Fiscal\u00eda ya bajo el mando de Devoe <a href=\"https:\/\/www.instagram.com\/p\/DW-Gn5UiUA5\/\">inform\u00f3 este viernes<\/a> sobre una visita que funcionarios hicieron a la c\u00e1rcel Rodeo I para observar las condiciones de los detenidos, luego de que algunos de ellos recientemente realizaron una protesta por la situaci\u00f3n de hacinamiento y supuestos malos tratos que dicen vivir en el centro penitenciario.<\/p>\n<p>\u201cEl Ministerio P\u00fablico ratifica que, en el marco de sus atribuciones constitucionales y legales, continuar\u00e1 velando por el respeto y garant\u00eda de los derechos humanos en las c\u00e1rceles y dem\u00e1s establecimientos de reclusi\u00f3n\u201d, dijo.<\/p>\n<p>A pesar de estas declaraciones, algunos especialistas dudan que en realidad vaya a haber cambios en la Fiscal\u00eda con la llegada de Devoe.<\/p>\n<p>\u201cCreo que va a haber una l\u00ednea de continuidad. Es un Tarek William Saab discreto\u201d, dijo Uzc\u00e1tegui, con el argumento de que no hasta ahora hay se\u00f1ales para estimar que habr\u00e1 m\u00e1s cooperaci\u00f3n con organismos internacionales en temas como justicia o combate a la impunidad.<\/p>\n<p>\u201c\u00c9l no es un reformador. Creo que viene a contener denuncias, a contener actuaciones independientes de la Fiscal\u00eda, y no s\u00e9 si va a tener la capacidad de fortalecer a la propia instituci\u00f3n, que est\u00e1 muy deteriorada, con cursos de formaci\u00f3n de personal o cosas as\u00ed\u201d, a\u00f1adi\u00f3 Uzc\u00e1tegui, en sinton\u00eda con los puntos de vista de otros expertos.<\/p>\n<p>As\u00ed, Devoe inicia su camino al frente de la Fiscal\u00eda de Venezuela con el respaldo del chavismo, pero tambi\u00e9n con dudas sobre qu\u00e9 har\u00e1 desde esa posici\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Larry Devoe fue elegido por la Asamblea Nacional de Venezuela como el nuevo fiscal general del pa\u00eds, un cargo en el que reemplaza a Tarek William Saab \u2014quien ocup\u00f3 esa posici\u00f3n durante casi una d\u00e9cada\u2014 y al que llega tanto con la promesa de promover los derechos humanos como con cuestionamientos de algunas organizaciones no [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473190","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Larry Devoe fue elegido por la Asamblea Nacional de Venezuela como el nuevo fiscal general del pa\u00eds, un cargo en el que reemplaza a Tarek William Saab \u2014quien ocup\u00f3 esa posici\u00f3n durante casi una d\u00e9cada\u2014 y al que llega tanto con la promesa de promover los derechos humanos como con cuestionamientos de algunas organizaciones no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T12:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?\",\"datePublished\":\"2026-04-15T12:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\"},\"wordCount\":1287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\",\"name\":\"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-15T12:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab? - Noticias","og_description":"Larry Devoe fue elegido por la Asamblea Nacional de Venezuela como el nuevo fiscal general del pa\u00eds, un cargo en el que reemplaza a Tarek William Saab \u2014quien ocup\u00f3 esa posici\u00f3n durante casi una d\u00e9cada\u2014 y al que llega tanto con la promesa de promover los derechos humanos como con cuestionamientos de algunas organizaciones no [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-15T12:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?","datePublished":"2026-04-15T12:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/"},"wordCount":1287,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","name":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-15T12:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?","url":"http:\/\/noticiasya.com\/midland-odessa\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2026\/04\/15\/larry-devoe-nuevo-fiscal-general-perfil-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-15T12:03:43Z","datePublished":"2026-04-15T12:03:43Z","dateModified":"2026-04-15T12:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es Larry Devoe, el nuevo fiscal general de Venezuela que reemplaza a Tarek William Saab?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2026\\\/04\\\/15\\\/larry-devoe-nuevo-fiscal-general-perfil-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2026\\\/04\\\/15\\\/larry-devoe-nuevo-fiscal-general-perfil-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-15T12:03:43Z\",\"datePublished\":\"2026-04-15T12:03:43Z\",\"dateModified\":\"2026-04-15T12:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473016,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/09\/larry-devoe-nuevo-fiscal-asamblea-orix\/","url_meta":{"origin":1473190,"position":0},"title":"Confirman a Larry Devoe como el nuevo fiscal general de Venezuela en reemplazo de Tarek William Saab","author":"","date":"abril 9, 2026","format":false,"excerpt":"El abogado Larry Daniel Devoe M\u00e1rquez, especialista en derechos humanos, ser\u00e1 el nuevo fiscal general de Venezuela, seg\u00fan lo defini\u00f3 la Asamblea Nacional en su sesi\u00f3n de este jueves.La elecci\u00f3n de Devoe se produce mes y medio despu\u00e9s de la renuncia de Tarek William Saab, un hombre cercano al derrocado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471649,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/25\/tarek-william-saab-alfredo-ruiz-angulo-renuncias-orix\/","url_meta":{"origin":1473190,"position":1},"title":"Tarek William Saab renuncia como fiscal de Venezuela y asume como defensor del Pueblo encargado","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Tarek William Saab y Alfredo Jos\u00e9 Ruiz Angulo renunciaron este mi\u00e9rcoles a sus cargos como fiscal general y defensor del Pueblo en Venezuela, respectivamente, inform\u00f3 el presidente de la Asamblea Nacional, Jorge Rodr\u00edguez.Durante la sesi\u00f3n del \u00f3rgano legislativo, Rodr\u00edguez ley\u00f3 ambas cartas de renuncia.En la suya, Ruiz Angulo dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471790,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/02\/quien-es-tarek-william-saab-por-que-dejo-fiscal-delcy-orix\/","url_meta":{"origin":1473190,"position":2},"title":"\u00bfQu\u00e9 hay detr\u00e1s de la salida de Tarek William Saab y de los cambios en el Gabinete de Delcy Rodr\u00edguez?","author":"","date":"marzo 2, 2026","format":false,"excerpt":"Al presentar su renuncia como fiscal general de Venezuela, un cargo que ocup\u00f3 por casi 10 a\u00f1os, Tarek William Saab fue nombrado de inmediato como defensor del pueblo encargado. Ese cargo, seg\u00fan analistas consultados por CNN, representa un cambio significativo: aunque tiene menor visibilidad p\u00fablica que en su posici\u00f3n anterior,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455110,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/10\/15\/cancilleria-venezuela-distancia-declaraciones-tarek-william-saab-lula-da-silva-orix\/","url_meta":{"origin":1473190,"position":3},"title":"Canciller\u00eda de Venezuela se distancia de las declaraciones del fiscal general Tarek William Saab y reitera su &#171;respeto&#187; por Lula da Silva","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Ministerio de Relaciones Exteriores de Venezuela se distanci\u00f3 este martes de las declaraciones que hizo el fiscal general de Venezuela, Tarek William Saab, en una entrevista difundida por el canal Globovisi\u00f3n este domingo, donde dijo que el presidente de Brasil, Luiz In\u00e1cio Lula da Silva, era\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456582,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","url_meta":{"origin":1473190,"position":4},"title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457410,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/09\/fiscal-acusa-machado-fingir-detencion-orix\/","url_meta":{"origin":1473190,"position":5},"title":"Fiscal de Venezuela acusa a Machado de fingir detenci\u00f3n para &#171;desatar actos de violencia&#187; previo a toma de posesi\u00f3n de Maduro","author":"","date":"enero 9, 2025","format":false,"excerpt":"El fiscal general de Venezuela, Tarek William Saab, dijo este jueves en un comunicado que la l\u00edder opositora Mar\u00eda Corina Machado fingi\u00f3 haber sido detenida luego de una protesta opositora, como medida para \u201cdesatar actos de violencia\u201d y \u201csembrar el caos\u201d de cara a la juramentaci\u00f3n del presidente Nicol\u00e1s Maduro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1473190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1473190"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1473190\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1473190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1473190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1473190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}