{"id":1473731,"date":"2026-05-02T08:03:45","date_gmt":"2026-05-02T15:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/"},"modified":"2026-05-02T08:03:45","modified_gmt":"2026-05-02T15:03:45","slug":"berkshire-hathaway-reservas-record-greg-abel-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","title":{"rendered":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO"},"content":{"rendered":"<p>Berkshire Hathaway (BRK.B) anunci\u00f3 este s\u00e1bado ganancias operativas de US$ 11.350 millones y una reserva de efectivo r\u00e9cord en el primer trimestre bajo la direcci\u00f3n de Greg Abel, sucesor del renombrado inversor Warren Buffett.<\/p>\n<p>La enorme reserva de efectivo de Berkshire Hathaway ascendi\u00f3 a m\u00e1s de US$ 397.000 millones en el primer trimestre, frente a los 373.000 millones previstos para finales de 2025. Las ganancias operativas aumentaron casi un 18 % con respecto al a\u00f1o anterior, pero no alcanzaron las estimaciones de US$ 11.560 millones, seg\u00fan datos de FactSet.<\/p>\n<p>El beneficio neto atribuible a los accionistas de Berkshire en el primer trimestre se situ\u00f3 en torno a los US$ 10.100 millones, m\u00e1s del doble de los 4.600 millones del a\u00f1o anterior.<\/p>\n<p>Berkshire obtuvo US$ 1.700 millones en ingresos por suscripci\u00f3n de seguros, un aumento del 28 % con respecto al mismo per\u00edodo del a\u00f1o anterior. Sin embargo, Geico, l\u00edder del negocio de suscripci\u00f3n de seguros del conglomerado, report\u00f3 una ca\u00edda del 34 % en sus ganancias.<\/p>\n<p>Este es el primer informe trimestral de Abel como director de Berkshire. Asumi\u00f3 el cargo a principios de 2026 y redact\u00f3 la carta anual a los accionistas en febrero. Abel ser\u00e1 el protagonista este s\u00e1bado en el evento de Berkshire conocido como el \u201cWoodstock de los Capitalistas\u201d, que se celebrar\u00e1 en el centro de Omaha, Nebraska, ciudad natal del exdirector ejecutivo Buffett.<\/p>\n<p>Abel tiene ante s\u00ed el enorme desaf\u00edo de estar a la altura de su predecesor. Buffett, de 95 a\u00f1os, atra\u00eda a multitudes masivas al evento; miles de personas acud\u00edan en masa para escuchar la sabidur\u00eda de mercado del \u201cOr\u00e1culo de Omaha\u201d. Buffett, quien ahora ejerce como presidente del consejo de Berkshire, sol\u00eda convertirse con frecuencia en la mascota publicitaria de marcas como Squishmallow, Fruit of the Loom y otras compa\u00f1\u00edas pertenecientes a Berkshire.<\/p>\n<p>Los propietarios de Berkshire a\u00fan est\u00e1n conociendo a Abel, quien forma parte del conglomerado desde el a\u00f1o 2000 y fue nombrado miembro del consejo de administraci\u00f3n en 2018, aunque su perfil p\u00fablico era menos visible que el de Buffett y el del expresidente adjunto Charlie Munger. Abel asumi\u00f3 oficialmente el cargo de director ejecutivo el 1 de enero de 2026.<\/p>\n<p>\u201cWarren aport\u00f3 a Berkshire un compromiso extraordinario y una profunda comprensi\u00f3n. Y quiero que (los propietarios) sepan que eso perdura; que existe un equipo \u2014en el que me incluyo\u2014 que est\u00e1 absolutamente comprometido y posee un profundo conocimiento de Berkshire, y que aportamos esa misma pasi\u00f3n cada d\u00eda\u201d, declar\u00f3 Abel a CNBC.<\/p>\n<p>Abel se\u00f1al\u00f3 que el evento incluir\u00e1 una charla sobre la \u201cevoluci\u00f3n\u201d de Berkshire, as\u00ed como la presentaci\u00f3n de otros directivos.<\/p>\n<p>Buffett, quien dirigi\u00f3 Berkshire durante seis d\u00e9cadas, asisti\u00f3 este s\u00e1bado a la reuni\u00f3n anual.<\/p>\n<p>\u201cGreg est\u00e1 haciendo todo lo que yo hac\u00eda, y m\u00e1s a\u00fan; y en todos los casos, lo est\u00e1 haciendo mejor. Es la persona id\u00f3nea. Por lo tanto, en lo que respecta a esa decisi\u00f3n, nos damos una puntuaci\u00f3n del 100 %\u201d, afirm\u00f3 desde su asiento entre el p\u00fablico.<\/p>\n<p>La mayor participaci\u00f3n de Berkshire corresponde a Apple, se\u00f1al\u00f3 Buffett este s\u00e1bado. El gigante tecnol\u00f3gico report\u00f3 unos beneficios superiores a lo esperado, y las ventas del iPhone aumentaron un 22 % en comparaci\u00f3n con el a\u00f1o anterior. Las acciones de la compa\u00f1\u00eda han subido cerca de un 36 % respecto a hace un a\u00f1o, y Tim Cook anunci\u00f3 recientemente que dejar\u00e1 su cargo como director ejecutivo.<\/p>\n<p>Estas inversiones generan rendimientos \u201csin que nosotros tengamos que realizar trabajo alguno, lo cual constituye nuestra forma preferida de operar\u201d, coment\u00f3 Buffett.<\/p>\n<p><em>Esta noticia est\u00e1 en desarrollo y ser\u00e1 actualizada.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berkshire Hathaway (BRK.B) anunci\u00f3 este s\u00e1bado ganancias operativas de US$ 11.350 millones y una reserva de efectivo r\u00e9cord en el primer trimestre bajo la direcci\u00f3n de Greg Abel, sucesor del renombrado inversor Warren Buffett. La enorme reserva de efectivo de Berkshire Hathaway ascendi\u00f3 a m\u00e1s de US$ 397.000 millones en el primer trimestre, frente a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473731","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO - Noticias\" \/>\n<meta property=\"og:description\" content=\"Berkshire Hathaway (BRK.B) anunci\u00f3 este s\u00e1bado ganancias operativas de US$ 11.350 millones y una reserva de efectivo r\u00e9cord en el primer trimestre bajo la direcci\u00f3n de Greg Abel, sucesor del renombrado inversor Warren Buffett. La enorme reserva de efectivo de Berkshire Hathaway ascendi\u00f3 a m\u00e1s de US$ 397.000 millones en el primer trimestre, frente a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-02T15:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO\",\"datePublished\":\"2026-05-02T15:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\"},\"wordCount\":649,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\",\"name\":\"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-02T15:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO - Noticias","og_description":"Berkshire Hathaway (BRK.B) anunci\u00f3 este s\u00e1bado ganancias operativas de US$ 11.350 millones y una reserva de efectivo r\u00e9cord en el primer trimestre bajo la direcci\u00f3n de Greg Abel, sucesor del renombrado inversor Warren Buffett. La enorme reserva de efectivo de Berkshire Hathaway ascendi\u00f3 a m\u00e1s de US$ 397.000 millones en el primer trimestre, frente a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-02T15:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/"},"author":{"name":"","@id":""},"headline":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO","datePublished":"2026-05-02T15:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/"},"wordCount":649,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","name":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-02T15:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO","url":"http:\/\/noticiasya.com\/midland-odessa\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-02T15:03:45Z","datePublished":"2026-05-02T15:03:45Z","dateModified":"2026-05-02T15:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"As\\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2026\\\/05\\\/02\\\/berkshire-hathaway-reservas-record-greg-abel-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2026\\\/05\\\/02\\\/berkshire-hathaway-reservas-record-greg-abel-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-02T15:03:45Z\",\"datePublished\":\"2026-05-02T15:03:45Z\",\"dateModified\":\"2026-05-02T15:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449505,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/15\/warren-buffett-revela-misteriosa-empresa-inversion-miles-de-millones-de-dolares-trax\/","url_meta":{"origin":1473731,"position":0},"title":"Warren Buffett finalmente revela la misteriosa empresa en la que invirti\u00f3 miles de millones de d\u00f3lares","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN) --\u00a0 El misterio termin\u00f3: Berkshire Hathaway de Warren Buffett revel\u00f3 una importante participaci\u00f3n en la compa\u00f1\u00eda de seguros Chubb, revelando finalmente la inversi\u00f3n que mantiene en secreto desde el a\u00f1o pasado.Berkshire revel\u00f3 que adquiri\u00f3 casi 26 millones de acciones de Chubb en una presentaci\u00f3n de este mi\u00e9rcoles ante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459441,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/03\/warren-buffett-aranceles-acto-de-guerra-trax\/","url_meta":{"origin":1473731,"position":1},"title":"Warren Buffett: Los aranceles son \u2018un acto de guerra\u2019","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Los aranceles podr\u00edan ser la palabra favorita del presidente Donald Trump. Pero, para el legendario inversor Warren Buffett, hay menos motivos para emocionarse.\u201cLos aranceles son en realidad \u2014hemos tenido mucha experiencia con ellos\u2014 un acto de guerra, hasta cierto punto\u201d, dijo Buffett en una entrevista con CBS que se emiti\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461931,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/03\/warren-buffett-aranceles-comercio-arma-trax\/","url_meta":{"origin":1473731,"position":2},"title":"Warren Buffett dice que &#171;el comercio no deber\u00eda ser un arma&#187;","author":"","date":"mayo 3, 2025","format":false,"excerpt":"Warren Buffett finalmente dijo lo que piensa sobre los aranceles.El c\u00e9lebre inversor y consejero delegado del holding conglomerado multinacional Berkshire Hathaway habl\u00f3 este s\u00e1bado sobre la guerra comercial de Estados Unidos, y defini\u00f3 como \u201cgran error\u201d lo que est\u00e1 sucediento en la reuni\u00f3n anual de accionistas de la firma en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448499,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","url_meta":{"origin":1473731,"position":3},"title":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458004,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/29\/elon-musk-boeing-air-force-one-trax\/","url_meta":{"origin":1473731,"position":4},"title":"Elon Musk visita Boeing por el retraso de los nuevos aviones Air Force One","author":"","date":"enero 29, 2025","format":false,"excerpt":"Elon Musk aprovech\u00f3 su nuevo rol dedicado a la eficiencia gubernamental para visitar las operaciones de su competidor Boeing y analizar la demora en la renovaci\u00f3n de dos aviones 747 para convertirlos en la pr\u00f3xima generaci\u00f3n de aviones Air Force One, dijo el martes el CEO de Boeing, Kelly Ortberg.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449608,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/20\/trump-media-perdida-300-millones-trimestre-trax\/","url_meta":{"origin":1473731,"position":5},"title":"Trump Media perdi\u00f3 m\u00e1s de US$ 300 millones el \u00faltimo trimestre con ingresos muy escasos","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- Trump Media & Technology Group perdi\u00f3 m\u00e1s de US$ 300 millones durante el primer trimestre y gener\u00f3 muy pocos ingresos, anunci\u00f3 este lunes el propietario de Truth Social en un comunicado de prensa.Los resultados plantear\u00e1n preguntas adicionales sobre la valoraci\u00f3n multimillonaria de la nueva empresa p\u00fablica, que es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1473731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1473731"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1473731\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1473731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1473731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1473731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}