{"id":1450892,"date":"2024-07-05T06:03:46","date_gmt":"2024-07-05T13:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/"},"modified":"2024-07-05T06:03:46","modified_gmt":"2024-07-05T13:03:46","slug":"cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","title":{"rendered":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Copa Am\u00e9rica entra en la fase en la que no se puede fallar. Una derrota significa despedirse del torneo de selecciones m\u00e1s antiguo del mundo.<\/p>\n<p>Argentina es el primer semifinalista tras un pase ag\u00f3nico y emocionante en penaltis sobre Ecuador y sigue hasta ahora con \u00e9xito en la defensa del t\u00edtulo.\u00a0 La albiceleste hab\u00eda sido l\u00edder indiscutible del grupo A, hizo 9 puntos de 9 posibles. Contra Canad\u00e1, Chile y Per\u00fa no hubo triunfos abultados, pero Argentina fue la \u00fanica selecci\u00f3n que no recibi\u00f3 un gol en contra en la fase de grupos.<\/p>\n<p>La imbatibilidad del \u201cDibu\u201d Mart\u00ednez se confirm\u00f3 de nuevo en los cuartos de final contra Ecuador, que hab\u00eda sido el segundo del grupo B.<\/p>\n<p>El portero argentino Emiliano Mart\u00ednez durante el partido contra Chile en el estadio MetLife en East Rutherford, Nueva Jersey, el 25 de junio de 2024. Cr\u00e9dito: EDUARDO MU\u00d1OZ\/AFP v\u00eda Getty Images<\/p>\n<p>Venezuela, por su parte, buscar\u00e1 ratificar su buen momento futbol\u00edstico contra Canad\u00e1. La \u201cvinotinto\u201d gan\u00f3 todos los partidos del grupo B y espera dar la sorpresa de avanzar a semifinales si derrota a uno de los equipos de la Concacaf.<\/p>\n<p>Resultados y tabla de posiciones de la Copa Am\u00e9rica 2024 en vivo: partidos y clasificaci\u00f3n por grupos<\/p>\n<p>Canad\u00e1 est\u00e1 en cuartos de final gracias un solo gol: hizo 4 puntos producto de una victoria contra Per\u00fa (1-0), un empate contra Chile (0-0) y una derrota contra Argentina (2-0).<\/p>\n<p>Uruguay sell\u00f3 su paso a cuartos tambi\u00e9n con 9 puntos de 9 posibles. Es primero del grupo C y se enfrentar\u00e1 con el segundo del grupo D, Brasil, que no logr\u00f3 ser primera de grupo tras empatar ante Colombia. Panam\u00e1 logr\u00f3 clasificar a cuartos y en el camino qued\u00f3 la selecci\u00f3n anfitriona, Estados Unidos.<\/p>\n<p>Colombia, primera del grupo D tras una gran fase de grupos en la que destac\u00f3 como una de las mejores selecciones del torneo, ser\u00e1 el rival de Panam\u00e1.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Copa Am\u00e9rica entra en la fase en la que no se puede fallar. Una derrota significa despedirse del torneo de selecciones m\u00e1s antiguo del mundo. Argentina es el primer semifinalista tras un pase ag\u00f3nico y emocionante en penaltis sobre Ecuador y sigue hasta ahora con \u00e9xito en la defensa del t\u00edtulo.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450892","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La Copa Am\u00e9rica entra en la fase en la que no se puede fallar. Una derrota significa despedirse del torneo de selecciones m\u00e1s antiguo del mundo. Argentina es el primer semifinalista tras un pase ag\u00f3nico y emocionante en penaltis sobre Ecuador y sigue hasta ahora con \u00e9xito en la defensa del t\u00edtulo.\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-05T13:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios\",\"datePublished\":\"2024-07-05T13:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\",\"name\":\"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-05T13:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La Copa Am\u00e9rica entra en la fase en la que no se puede fallar. Una derrota significa despedirse del torneo de selecciones m\u00e1s antiguo del mundo. Argentina es el primer semifinalista tras un pase ag\u00f3nico y emocionante en penaltis sobre Ecuador y sigue hasta ahora con \u00e9xito en la defensa del t\u00edtulo.\u00a0 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-05T13:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/"},"author":{"name":"","@id":""},"headline":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios","datePublished":"2024-07-05T13:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","name":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-05T13:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-05T13:03:46Z","datePublished":"2024-07-05T13:03:46Z","dateModified":"2024-07-05T13:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los cruces de la Copa Am\\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/07\\\/05\\\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/07\\\/05\\\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-05T13:03:46Z\",\"datePublished\":\"2024-07-05T13:03:46Z\",\"dateModified\":\"2024-07-05T13:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450565,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/06\/20\/mejores-participaciones-mexico-copa-america-orix\/","url_meta":{"origin":1450892,"position":0},"title":"Las mejores participaciones de M\u00e9xico en la Copa Am\u00e9rica","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La selecci\u00f3n mayor masculina de M\u00e9xico es una de las 16 que participar\u00e1n en la Copa Am\u00e9rica 2024, que este a\u00f1o celebra su edici\u00f3n n\u00famero 48.Gracias al t\u00edtulo de Copa Oro obtenido en 2023, M\u00e9xico es cabeza de serie del Grupo B de la Copa Am\u00e9rica, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466492,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/15\/copa-libertadores-2025-cuartos-partidos-horarios-como-ver-orix\/","url_meta":{"origin":1450892,"position":1},"title":"Copa Libertadores 2025: previa de los cuartos de final, partidos, horarios y c\u00f3mo verlos en vivo por TV e internet","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"El torneo de f\u00fatbol m\u00e1s importante de Sudam\u00e9rica vuelve al ruedo esta semana con las llaves de cuartos de final entre los mejores ocho equipos del continente.A pesar de la superioridad que han mostrado los clubes brasile\u00f1os en los \u00faltimos tiempos, la mitad de los equipos que sobreviven en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451108,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/14\/argentina-megacampeon-copa-america-scaloneta-analisis-orix\/","url_meta":{"origin":1450892,"position":2},"title":"Argentina, megacampe\u00f3n: la Scaloneta, un equipo que solo sabe ganar","author":"","date":"julio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Argentina sabe de finales peleadas, ag\u00f3nicas. Tanto en el triunfo como en la derrota, pero la Argentina de Lionel Scaloni solo sabe ganar. Y esta vez triunf\u00f3 haciendo valer su dominio en el f\u00fatbol en la \u00faltima d\u00e9cada, cerrando \u2014quiz\u00e1\u2014 una era hist\u00f3rica con jugadores legendarios y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450484,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/06\/18\/messi-copa-america-brasil-2021-orix\/","url_meta":{"origin":1450892,"position":3},"title":"Messi, sus gemas en la Copa Am\u00e9rica y su resplandeciente consagraci\u00f3n en Brasil 2021","author":"","date":"junio 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Es el m\u00e1ximo h\u00e9roe moderno del f\u00fatbol mundial. Lionel Messi tuvo en el FC Barcelona una carrera futbol\u00edstica digna de un guion de superh\u00e9roes. Exitosa, brillante, predestinada. Lo dicen los 34 t\u00edtulos que conquist\u00f3 en el club catal\u00e1n. Paralelamente, su andar en la Selecci\u00f3n Argentina estaba en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450560,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/06\/20\/numeros-messi-seleccion-argentina-partidos-goles-titulos-orix\/","url_meta":{"origin":1450892,"position":4},"title":"Los n\u00fameros de Messi con la selecci\u00f3n de Argentina: partidos, goles, t\u00edtulos","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El astro del f\u00fatbol Lionel Messi gan\u00f3 el Mundial de Qatar 2022 en una estupenda forma con la selecci\u00f3n de Argentina. Ahora busca repetir el t\u00edtulo de Copa Am\u00e9rica con la albiceleste y quiz\u00e1 empezar a dar cierre a una de las mejores carreras en la historia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450842,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/02\/cruces-eurocopa-2024-cuartos-final-camino-espana-orix\/","url_meta":{"origin":1450892,"position":5},"title":"Los cruces de la Eurocopa 2024 desde cuartos hasta la final. As\u00ed ser\u00eda el camino de Espa\u00f1a","author":"","date":"julio 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Eurocopa 2024 se encuentra en sus fases de eliminaci\u00f3n directa. Espa\u00f1a clasific\u00f3 a cuartos y sigue su avance como uno de los favoritos.Espa\u00f1a derrot\u00f3 con contundencia a Georgia en octavos de final y se enfrentar\u00e1 a Alemania (que derrot\u00f3 a Dinamarca en octavos) el 5 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1450892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1450892"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1450892\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1450892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1450892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1450892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}