{"id":1451645,"date":"2024-08-07T01:03:48","date_gmt":"2024-08-07T08:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/"},"modified":"2024-08-07T01:03:48","modified_gmt":"2024-08-07T08:03:48","slug":"muhammad-yunus-bangladesh-gobierno-economia-nobel-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","title":{"rendered":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh?"},"content":{"rendered":"<p>(CNN)&#8211; El Premio Nobel de Econom\u00eda conocido como el &#171;banquero de los pobres&#187; intentar\u00e1 llevar la estabilidad a tras responder a la petici\u00f3n de los manifestantes estudiantiles de que dirija temporalmente el convulso pa\u00eds despu\u00e9s de semanas de mort\u00edferas manifestaciones antigubernamentales.<\/p>\n<p>Muhammad Yunus, de 84 a\u00f1os, encabezar\u00e1 un gobierno interino tras el derrocamiento del primer ministro del pa\u00eds surasi\u00e1tico y la disoluci\u00f3n del parlamento, seg\u00fan el secretario de prensa del presidente de Bangladesh.<\/p>\n<p>Yunus es un empresario social y banquero que gan\u00f3 el Premio Nobel de la Paz en 2006 por su labor pionera en microfinanciaci\u00f3n, que ayud\u00f3 a aliviar la pobreza en Bangladesh y fue ampliamente adoptada en todo el mundo.<\/p>\n<p>El premio Nobel Yunus regresar\u00e1 a Bangladesh para presidir el gobierno interino<\/p>\n<p>Tambi\u00e9n critic\u00f3 durante mucho tiempo a la exprimera ministra Sheikh Hasina, que dimiti\u00f3 a principios de esta semana y huy\u00f3 del pa\u00eds tras a\u00f1os de gobierno cada vez m\u00e1s autoritarios.<\/p>\n<p>Su renuncia provoc\u00f3 la alegr\u00eda del movimiento estudiantil que la oblig\u00f3 a abandonar el poder, pero tambi\u00e9n cierta inquietud por la posibilidad de que los militares intervinieran para llenar el vac\u00edo de liderazgo.<\/p>\n<p>Manifestantes antigubernamentales exhiben la bandera nacional de Banglad\u00e9s despu\u00e9s de asaltar el palacio de la ex primera ministra Sheikh Hasina en Dhaka el 5 de agosto de 2024.(Cr\u00e9dito: K M Asad\/AFP\/Getty Images)<\/p>\n<p>Una fuente declar\u00f3 esta semana a CNN que Yunus se encontraba en Francia para someterse a una intervenci\u00f3n m\u00e9dica menor, pero que regresar\u00eda pronto a Bangladesh para asumir el cargo de l\u00edder interino.<\/p>\n<p>El grupo Estudiantes contra la Discriminaci\u00f3n tambi\u00e9n confirm\u00f3 su regreso, y lo comunic\u00f3 a CNN en un mensaje de texto: &#171;Estamos muy contentos de decir que el Dr. Yunus acept\u00f3 este reto para salvar Bangladesh seg\u00fan la petici\u00f3n de nuestros estudiantes&#187;.<\/p>\n<p>\u00bfQui\u00e9n es Muhammad Yunus?<\/p>\n<p>Yunus naci\u00f3 en 1940 en Chittagong, una ciudad portuaria del sureste de Bangladesh, seg\u00fan su perfil en el sitio web del Premio Nobel. Estudi\u00f3 en la Universidad de Dhaka, antes de recibir la prestigiosa beca Fulbright para asistir a la Universidad de Vanderbilt, en Estados Unidos, donde se doctor\u00f3 en Econom\u00eda.<\/p>\n<p>En 1972, un a\u00f1o despu\u00e9s de que Bangladesh se independizara de Pakist\u00e1n, regres\u00f3 para ense\u00f1ar en la Universidad de Chittagong.<\/p>\n<p>Estos son los objetos que manifestantes en Bangladesh se llevaron de la residencia de la ex primera ministra<\/p>\n<p>Pero pronto sobrevino el desastre. Una grave hambruna asol\u00f3 el pa\u00eds en 1974 acab\u00f3 con la vida de aproximadamente 1,5 millones de personas.<\/p>\n<p>&#171;Me resultaba dif\u00edcil ense\u00f1ar elegantes teor\u00edas de econom\u00eda en el aula universitaria, con el tel\u00f3n de fondo de una terrible hambruna en Bangladesh. De repente, sent\u00ed el vac\u00edo de esas teor\u00edas ante el hambre y la pobreza aplastantes&#187;, dijo Yunus en su discurso del Nobel de 2006 tras recibir el premio.<\/p>\n<p>&#171;Quer\u00eda hacer algo inmediato para ayudar a la gente que me rodeaba, aunque solo fuera un ser humano, a pasar un d\u00eda m\u00e1s con un poco m\u00e1s de facilidad&#187;, dijo.<\/p>\n<p>Empez\u00f3 a conceder peque\u00f1os pr\u00e9stamos de su propio bolsillo a los residentes m\u00e1s pobres de su comunidad, y acab\u00f3 fundando el Banco Grameen en 1983, que se convertir\u00eda en l\u00edder mundial en la mitigaci\u00f3n de la pobreza a trav\u00e9s del microcr\u00e9dito.<\/p>\n<p>El banco creci\u00f3 r\u00e1pidamente, con diferentes sucursales y modelos similares que ahora operan en todo el mundo.<\/p>\n<p>Yunus y el Banco Grameen fueron galardonados con el Premio Nobel de la Paz en 2006, tras prestar un total de unos US$ 6.000 millones en pr\u00e9stamos para vivienda, estudiantes y microempresas, y espec\u00edficamente en apoyo de las mujeres de Bangladesh.<\/p>\n<p>Dimite la primera ministra de Bangladesh en medio de mort\u00edferas manifestaciones antigubernamentales<\/p>\n<p>Tambi\u00e9n es el fundador del Centro Yunus, un grupo de reflexi\u00f3n con sede en Dhaka que ayuda a desarrollar nuevas empresas sociales.<\/p>\n<p>Muhammad Yunus posa para una foto durante una entrevista con Reuters en su oficina en Dhaka, Banglad\u00e9s, el 4 de junio de 2024. (Cr\u00e9dito: Mohammad Ponir Hossain\/Reuters)<\/p>\n<p>Algunos cr\u00edticos se mostraron esc\u00e9pticos con Yunus y el Banco Grameen, argumentando que los elevados tipos de inter\u00e9s de algunos microprestamistas hab\u00edan empobrecido a los prestatarios, ya que los prestamistas obten\u00edan grandes beneficios de los peque\u00f1os pr\u00e9stamos.<\/p>\n<p>Yunus rebati\u00f3 estas afirmaciones y declar\u00f3 a CNN a principios de a\u00f1o que el Banco Grameen no pretende ganar dinero, sino ayudar a los pobres y potenciar las peque\u00f1as empresas.<\/p>\n<p>Fricciones con el gobierno de Hasina<\/p>\n<p>A lo largo de los a\u00f1os, Yunus se enfrent\u00f3 repetidamente a la exprimera ministra Hasina, que le ha acusado de &#171;chupar la sangre de los pobres&#187;, seg\u00fan Reuters.<\/p>\n<p>En 2007, Yunus propuso brevemente formar un nuevo partido pol\u00edtico antes de las elecciones parlamentarias, algo que Hasina censur\u00f3 en su momento, afirmando que los reci\u00e9n llegados a la pol\u00edtica eran &#171;elementos peligrosos&#8230; a los que hay que mirar con recelo&#187;, inform\u00f3 Reuters.<\/p>\n<p>Finalmente, Yunus no sigui\u00f3 adelante con la creaci\u00f3n del partido.<\/p>\n<p>En 2011, el banco central de Bangladesh, controlado por el Gobierno, destituy\u00f3 a Yunus como director gerente del Grameen Bank, alegando que hab\u00eda superado la edad de jubilaci\u00f3n obligatoria.<\/p>\n<p>En los a\u00f1os siguientes, Yunus se vio envuelto en m\u00faltiples causas judiciales que, seg\u00fan sus partidarios, se deb\u00edan a que las autoridades lo hab\u00edan perseguido injustamente.<\/p>\n<p>Los sitios web de la primera ministra, la polic\u00eda nacional y el banco central de Bangladesh parecen haber sido pirateados<\/p>\n<p>Entre ellos, una demanda por difamaci\u00f3n, un caso de seguridad alimentaria y acusaciones de irregularidades fiscales, que \u00e9l neg\u00f3.<\/p>\n<p>En enero, un tribunal de Bangladesh conden\u00f3 a Yunus a seis meses de prisi\u00f3n por infracciones de la legislaci\u00f3n laboral, pero el banquero volvi\u00f3 a negar haber cometido delito alguno.<\/p>\n<p>En otro caso, fue acusado en junio de malversaci\u00f3n de fondos.<\/p>\n<p>El gobierno de Hasina hab\u00eda insistido en que sus acciones contra Yunus no ten\u00edan motivaciones pol\u00edticas, pero el banquero no estaba de acuerdo. Actualmente no est\u00e1 claro qu\u00e9 ocurrir\u00e1 con estos procesos ahora que Hasina ha dejado el poder.<\/p>\n<p>En febrero, en declaraciones a CNN mientras se encontraba en libertad bajo fianza tras apelar su condena de prisi\u00f3n, Yunus afirm\u00f3 que las acusaciones de corrupci\u00f3n contra \u00e9l carec\u00edan de fundamento y las calific\u00f3 de acoso.<\/p>\n<p>&#171;No estoy en el \u00e1mbito pol\u00edtico, no hay pruebas de que est\u00e9 implicado en pol\u00edtica&#187;, dijo entonces Yunus, advirtiendo de que Bangladesh se estaba convirtiendo en una &#171;civilizaci\u00f3n en autodestrucci\u00f3n&#187;.<\/p>\n<p>Bangladesh estall\u00f3 por los puestos de trabajo reservados a los hijos de los &#171;luchadores por la libertad&#187;. Esto es lo que hay que saber<\/p>\n<p>En otra entrevista concedida a Reuters en junio, afirm\u00f3 que Bangladesh se hab\u00eda convertido en un Estado de &#171;partido \u00fanico&#187;, en el que el partido gobernante acababa con toda competencia pol\u00edtica.<\/p>\n<p>En una entrevista con CNN tras la dimisi\u00f3n de Hasina este lunes, Yunus dijo que quer\u00eda ver c\u00f3mo el ej\u00e9rcito ced\u00eda el control del pa\u00eds a un gobierno civil. Arremeti\u00f3 contra Hasina, diciendo que &#171;nos ha torturado, ha hecho este pa\u00eds invivible para la gente&#187;.<\/p>\n<p>&#171;La gente lo est\u00e1 celebrando en la calle y millones de personas en todo Bangladesh [lo est\u00e1n] celebrando como si fuera el d\u00eda de nuestra liberaci\u00f3n&#187;, afirm\u00f3.<\/p>\n<p>Dirigiendo su mensaje al movimiento de protesta en Bangladesh, a\u00f1adi\u00f3: &#171;Han hecho un gran trabajo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN)&#8211; El Premio Nobel de Econom\u00eda conocido como el &#171;banquero de los pobres&#187; intentar\u00e1 llevar la estabilidad a tras responder a la petici\u00f3n de los manifestantes estudiantiles de que dirija temporalmente el convulso pa\u00eds despu\u00e9s de semanas de mort\u00edferas manifestaciones antigubernamentales. Muhammad Yunus, de 84 a\u00f1os, encabezar\u00e1 un gobierno interino tras el derrocamiento del primer [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451645","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN)&#8211; El Premio Nobel de Econom\u00eda conocido como el &#171;banquero de los pobres&#187; intentar\u00e1 llevar la estabilidad a tras responder a la petici\u00f3n de los manifestantes estudiantiles de que dirija temporalmente el convulso pa\u00eds despu\u00e9s de semanas de mort\u00edferas manifestaciones antigubernamentales. Muhammad Yunus, de 84 a\u00f1os, encabezar\u00e1 un gobierno interino tras el derrocamiento del primer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T08:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh?\",\"datePublished\":\"2024-08-07T08:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\"},\"wordCount\":1322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\",\"name\":\"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-07T08:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh? - Noticias","og_description":"(CNN)&#8211; El Premio Nobel de Econom\u00eda conocido como el &#171;banquero de los pobres&#187; intentar\u00e1 llevar la estabilidad a tras responder a la petici\u00f3n de los manifestantes estudiantiles de que dirija temporalmente el convulso pa\u00eds despu\u00e9s de semanas de mort\u00edferas manifestaciones antigubernamentales. Muhammad Yunus, de 84 a\u00f1os, encabezar\u00e1 un gobierno interino tras el derrocamiento del primer [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-07T08:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh?","datePublished":"2024-08-07T08:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/"},"wordCount":1322,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","name":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-07T08:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es Muhammad Yunus, el l\u00edder premiado con el Nobel del gobierno interino de Bangladesh?","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-07T08:03:48Z","datePublished":"2024-08-07T08:03:48Z","dateModified":"2024-08-07T08:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es Muhammad Yunus, el l\\u00edder premiado con el Nobel del gobierno interino de Bangladesh?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/07\\\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/07\\\/muhammad-yunus-bangladesh-gobierno-economia-nobel-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-07T08:03:48Z\",\"datePublished\":\"2024-08-07T08:03:48Z\",\"dateModified\":\"2024-08-07T08:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468422,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/17\/condenan-muerte-sheikh-hasina-bangladesh-trax\/","url_meta":{"origin":1451645,"position":0},"title":"Condenan a muerte a Sheikh Hasina, l\u00edder derrocada de Bangladesh, por cr\u00edmenes contra la humanidad","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"Sheikh Hasina, ex primera ministra de Bangladesh, fue condenada a muerte tras ser declarada culpable de cr\u00edmenes de lesa humanidad por la violenta represi\u00f3n de las protestas estudiantiles del a\u00f1o pasado que provocaron el colapso de su Gobierno.Un panel de tres jueces del Tribunal Internacional de Cr\u00edmenes (TIC), el tribunal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452230,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/28\/bangladesh-inundaciones-culpan-india-presa-trax\/","url_meta":{"origin":1451645,"position":1},"title":"Millones de personas en Bangladesh est\u00e1n varadas por las inundaciones. Muchos culpan al pa\u00eds vecino","author":"","date":"agosto 28, 2024","format":false,"excerpt":"Feni, Bangladesh (CNN) -- Cientos de personas vadean aguas lodosas que les llegan a la altura del pecho y se dirigen lentamente hacia un lugar seguro, con sus pertenencias sostenidas en alto por encima de sus cabezas para mantenerlas secas.Al entrar en la ciudad de Feni, en el sureste de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467277,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/10\/trump-habla-machado-premio-nobel-paz-trax\/","url_meta":{"origin":1451645,"position":2},"title":"Trump habla con Machado despu\u00e9s de que su Gobierno criticara la decisi\u00f3n de otorgarle el Premio Nobel de la Paz","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, habl\u00f3 este viernes con la opositora venezolana y ganadora del Premio Nobel de la Paz, Mar\u00eda Corina Machado, seg\u00fan inform\u00f3 la Casa Blanca, despu\u00e9s de que el Gobierno de EE.UU. criticara al comit\u00e9 que le otorg\u00f3 el galard\u00f3n.Trump ha manifestado en varias ocasiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468612,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/22\/bangladesh-india-hasina-ejecucion-trax\/","url_meta":{"origin":1451645,"position":3},"title":"Hay un obst\u00e1culo importante en el plan de Bangladesh de ejecutar a su ex primera ministra: la India","author":"","date":"noviembre 22, 2025","format":false,"excerpt":"En su momento, fue considerada una hero\u00edna laica, hija de un l\u00edder revolucionario, cuyo brutal asesinato en la d\u00e9cada de 1970 defini\u00f3 su ascenso pol\u00edtico.Pero el ascenso de Sheikh Hasina a la cima de la pol\u00edtica de Bangladesh precedi\u00f3 a una impactante ca\u00edda del poder al autoexilio en India.Una sentencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470152,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/16\/revocar-nobel-paz-machado-trump-orix\/","url_meta":{"origin":1451645,"position":4},"title":"\u00bfSe puede revocar el Premio Nobel de Paz? El gesto de Machado y Trump desata pol\u00e9mica","author":"","date":"enero 16, 2026","format":false,"excerpt":"Mar\u00eda Corina Machado llev\u00f3 la medalla del Nobel de Paz que le otorgaron a la Casa Blanca. Se la entreg\u00f3 a Donald Trump. Se tomaron una foto. Trump public\u00f3 en su red social: \u201cMar\u00eda me present\u00f3 su Premio Nobel de la Paz\u201d. El Centro Nobel de la Paz hab\u00eda tuiteado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467278,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/10\/premio-nobel-paz-latinoamericanos-orix\/","url_meta":{"origin":1451645,"position":5},"title":"Adem\u00e1s de Mar\u00eda Corina Machado, otros seis latinoamericanos han sido galardonados con el Premio Nobel de la Paz","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Mar\u00eda Corina Machado se ha convertido en la s\u00e9ptima persona en Am\u00e9rica Latina en recibir el Premio Nobel de la Paz. La l\u00edder opositora de Venezuela recibi\u00f3 un reconocimiento que en la historia de los premios recibieron en total 112 personas.El Comit\u00e9 Noruego del Nobel afirm\u00f3 que Machado hab\u00eda ayudado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451645"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451645\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}